{"id":10243,"date":"2022-08-18T07:38:35","date_gmt":"2022-08-18T12:38:35","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/como-preparar-un-sermon\/"},"modified":"2022-08-18T07:38:35","modified_gmt":"2022-08-18T12:38:35","slug":"como-preparar-un-sermon","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/como-preparar-un-sermon\/","title":{"rendered":"C\u00f3mo preparar un serm\u00f3n"},"content":{"rendered":"<p>Los j\u00f3venes suelen preguntarme, \u00bfc\u00f3mo preparo los mensajes? Aqu\u00ed hay algunos pasos sobre c\u00f3mo preparar un mensaje o un serm\u00f3n. Lo primero, si quieres predicar en cualquier lugar o en tu servicio dominical, preg\u00fantale al Se\u00f1or qu\u00e9 hay exactamente en Su coraz\u00f3n. \u00bfQu\u00e9 quiere \u00c9l que hables o compartas? Obtenga el tema de Su coraz\u00f3n y luego lea esas escrituras o ese tema de la Biblia. Si hay un pasaje, lea ese pasaje completo y lea lo que est\u00e1 antes de ese pasaje y lo que est\u00e1 despu\u00e9s de ese pasaje. Si es necesario, lea algunos cap\u00edtulos antes de ese pasaje y despu\u00e9s del pasaje para que obtenga un contexto completo y claro, el escenario completo de esa porci\u00f3n sobre qui\u00e9n habl\u00f3, por qu\u00e9 habl\u00f3, cu\u00e1ndo habl\u00f3 y los hechos hist\u00f3ricos. De esta manera, te aclaras el tema y luego comienzas a orar y buscar a Dios y preguntarle al Se\u00f1or qu\u00e9 quiere que sepas de esa porci\u00f3n. \u00bfQu\u00e9 quiere \u00c9l que entiendas y transmitas a la gente?<\/p>\n<p>Entonces lo siguiente es, empieza a ver a Jes\u00fas en esa porci\u00f3n. Tienes que entrenarte para ver a Jes\u00fas en cada porci\u00f3n de las Escrituras. En su lectura diaria de la Biblia, ya sea del Antiguo Testamento, Nuevo Testamento, Salmos, los profetas, o de cualquier parte, o poes\u00eda, debe ver a Jes\u00fas en cada p\u00e1gina de su lectura diaria de la Biblia. Si no ha visto a Jes\u00fas en su lectura diaria de la Biblia, significa que no ha le\u00eddo la Biblia ese d\u00eda. Entonces, volviendo a preparar el mensaje, vea a Jes\u00fas en la porci\u00f3n de las Escrituras que le ha dado y vea lo que est\u00e1 diciendo. Debes ver el coraz\u00f3n de Jes\u00fas en esa porci\u00f3n, obtener el Coraz\u00f3n de Jes\u00fas y luego comunicarlo a la gente. Luego, encuentre verdades similares, verdades paralelas de ese mensaje y esa porci\u00f3n de la escritura, en otros lugares de las escrituras.<\/p>\n<p>Y luego, finalmente, traiga su testimonio acerca de esa escritura en cuanto a c\u00f3mo esa escritura ha trabajado en tu vida en el pasado o en el presente y as\u00ed se habla. Y cuando hablas, hablas totalmente dependiendo del Se\u00f1or y en la absoluta nada de ti mismo. Transmites el coraz\u00f3n de Dios a la gente. As\u00ed se prepara un mensaje; o m\u00e1s bien t\u00fa mismo te conviertes en el mensaje. \u00a1Alabado sea el Se\u00f1or!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los j\u00f3venes suelen preguntarme, \u00bfc\u00f3mo preparo los mensajes? Aqu\u00ed hay algunos pasos sobre c\u00f3mo preparar un mensaje o un serm\u00f3n. Lo primero, si quieres predicar en cualquier lugar o en tu servicio dominical, preg\u00fantale al Se\u00f1or qu\u00e9 hay exactamente en Su coraz\u00f3n. \u00bfQu\u00e9 quiere \u00c9l que hables o compartas? Obtenga el tema de Su coraz\u00f3n &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/como-preparar-un-sermon\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abC\u00f3mo preparar un serm\u00f3n\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10243","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/10243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=10243"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/10243\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=10243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=10243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=10243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}