{"id":10252,"date":"2022-08-18T07:38:56","date_gmt":"2022-08-18T12:38:56","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/la-eterna-enemistad-y-la-conquista-de-jesus\/"},"modified":"2022-08-18T07:38:56","modified_gmt":"2022-08-18T12:38:56","slug":"la-eterna-enemistad-y-la-conquista-de-jesus","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/la-eterna-enemistad-y-la-conquista-de-jesus\/","title":{"rendered":"La eterna enemistad y la conquista de Jes\u00fas"},"content":{"rendered":"<p>Lunes despu\u00e9s de Pentecost\u00e9s<\/p>\n<p>Si la historia no fuera la mayor tragedia de la historia humana, esta lectura del primer cap\u00edtulo del G\u00e9nesis ser\u00eda casi una farsa francesa. Vemos justo antes de estos versos a la virgen Eva (as\u00ed la ven los Padres de la Iglesia) sucumbiendo a la voz seductora de una serpiente, escuchando sus mentiras sobre Dios. Ella y Ad\u00e1n ya est\u00e1n hechos a imagen y semejanza de Dios, pero la serpiente le dice que si desobedece el \u00fanico mandato negativo de su Hacedor, ser\u00e1 \u201ccomo Dios\u201d. Entonces ella come la fruta. Ahora pregunto con Scott Hahn, \u201c\u00bfd\u00f3nde estaba Adam cuando todo esto estaba pasando? \u00bfNo se supon\u00eda que deb\u00eda apoyar y defender a su esposa? De todos modos, \u00e9l viene y escucha las mentiras de la serpiente repetidas por su hermosa esposa, y tambi\u00e9n desobedece. La historia contin\u00faa hoy.<\/p>\n<p>El Se\u00f1or sabe d\u00f3nde est\u00e1n y lo que han hecho. Su pregunta, \u00ab\u00bfd\u00f3nde est\u00e1s?\u00bb est\u00e1 dise\u00f1ado para ver si sus criaturas humanas tienen alguna idea de lo que acaban de abandonar, lo que acaban de hacer. Entonces Ad\u00e1n derrama todo menos el pecado que ha cometido. Dios va directo al grano: ustedes, idiotas, hicieron lo \u00fanico que les dije que no hicieran. Y Ad\u00e1n, en lugar de asumir la responsabilidad de su estupidez y desobediencia, culpa a Eva. Dios le hace la pregunta simple, la l\u00f3gica, \u00ab\u00bfpor qu\u00e9?\u00bb Es como \u00c9l dice: \u201cTe hice a mi imagen y semejanza; \u00bfPor qu\u00e9 pensaste que haciendo lo que te dije que no hicieras te caer\u00eda bien? \u00a1Ya eras como yo!\u201d As\u00ed que Eva, actuando como una ni\u00f1a de diez a\u00f1os que acaba de robar un durazno del \u00e1rbol del vecino, culp\u00f3 al \u00fanico otro personaje hablante que quedaba: la serpiente. En otras palabras, ella dice \u201cel diablo me oblig\u00f3 a hacerlo\u201d.<\/p>\n<p>El \u00fanico di\u00e1logo que tenemos aqu\u00ed es el destierro de la serpiente por parte de Dios, porque la Iglesia est\u00e1 tratando en esta fiesta de enfatizar la enemistad eterna entre los El Maligno y la Mujer. La enemistad en la historia es entre el Padre de las Mentiras y Eva, pero los Padres de la Iglesia desde el principio vieron a la verdadera mujer profetizada aqu\u00ed como la virgen de Nazaret, el h\u00e9roe galileo llamado Mar\u00eda. Su descendencia, Jesucristo, Hijo de Dios e hijo de Mar\u00eda, vencer\u00eda a Satan\u00e1s ya todos los esp\u00edritus malignos y restaurar\u00eda a aquellos que creen en \u00c9l a nuestro estado original en la imagen de Dios. C\u00f3mo y cu\u00e1ndo es identificado por el evangelista Juan. Se muestra a Jes\u00fas colgado del instrumento de ejecuci\u00f3n favorito de los romanos, una cruz. Su madre y John y otras dos mujeres tambi\u00e9n est\u00e1n all\u00ed. Jes\u00fas entrega a Su madre, a quien identifica como la Mujer profetizada por Mois\u00e9s, al cuidado de Juan y el resto de Su Iglesia. Luego comienza el acto final de esta sant\u00edsima liturgia. Pide lo que Hahn llama \u201cla cuarta copa\u201d. Est\u00e1 a punto de completar la Pascua, la verdadera Pascua para todos los seres humanos que creer\u00e1n. Toma un sorbo de la esponja y declara que la Pascua est\u00e1 completa. \u00c9l entrega su Esp\u00edritu, el Esp\u00edritu que celebramos ayer en Pentecost\u00e9s, el Esp\u00edritu Santo que animar\u00e1 a la Iglesia. Despu\u00e9s de la muerte hay un don divino m\u00e1s. El soldado, sin saberlo, hace que suceda. Atraviesa el coraz\u00f3n de Jes\u00fas y sale su preciosa sangre y agua. Los Padres siempre compartieron el significado oculto, que estos simbolizaban el bautismo y el banquete eucar\u00edstico que Jes\u00fas orden\u00f3 a todos los cristianos.<\/p>\n<p>Entonces, \u00bfqu\u00e9 significa todo esto para nosotros? Primero, tenemos la responsabilidad, como profetiz\u00f3 Mar\u00eda antes del nacimiento de Jes\u00fas, de llamarla \u201cbienaventurada\u201d. Debemos meditar en su vida y su dolor y su triunfo en la Resurrecci\u00f3n de su Hijo, Jes\u00fas. Debemos meditar en nuestro coraz\u00f3n el Evangelio, como lo hizo ella. Debemos orar siempre con la Iglesia, como ella lo hizo en el aposento alto. En segundo lugar, siempre debemos celebrar con la Iglesia cuando los hombres, las mujeres y los ni\u00f1os se relacionan con Jes\u00fas y la Iglesia, como en el bautismo. Debemos agradecer a Dios por nuestra propia relaci\u00f3n con Jes\u00fas en la Iglesia. Y debemos esforzarnos por atraer a m\u00e1s de nuestros semejantes a esa relaci\u00f3n que significa vida eterna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lunes despu\u00e9s de Pentecost\u00e9s Si la historia no fuera la mayor tragedia de la historia humana, esta lectura del primer cap\u00edtulo del G\u00e9nesis ser\u00eda casi una farsa francesa. Vemos justo antes de estos versos a la virgen Eva (as\u00ed la ven los Padres de la Iglesia) sucumbiendo a la voz seductora de una serpiente, escuchando &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/la-eterna-enemistad-y-la-conquista-de-jesus\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa eterna enemistad y la conquista de Jes\u00fas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10252","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/10252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=10252"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/10252\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=10252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=10252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=10252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}