{"id":24057,"date":"2022-08-21T05:45:18","date_gmt":"2022-08-21T10:45:18","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/sabiduria-para-las-mamas\/"},"modified":"2022-08-21T05:45:18","modified_gmt":"2022-08-21T10:45:18","slug":"sabiduria-para-las-mamas","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/sabiduria-para-las-mamas\/","title":{"rendered":"Sabidur\u00eda para las mam\u00e1s"},"content":{"rendered":"<p>Sabidur\u00eda para las mam\u00e1s<\/p>\n<p>2 Juan 1-13<\/p>\n<p>El predicador G. Campbell Morgan tuvo cuatro hijos y todos se convirtieron en ministros del evangelio. En una reuni\u00f3n familiar, un amigo le pregunt\u00f3 a uno de los hijos: \u00ab\u00bfCu\u00e1l Morgan es el mejor predicador?\u00bb Mientras aquel hijo miraba a su padre, le respondi\u00f3: \u00abMam\u00e1\u00bb.<\/p>\n<p>Un antiguo proverbio espa\u00f1ol dice: &#8220;Una onza de madre vale una libra de clero.<\/p>\n<p> 1. Apertura reveladora<\/p>\n<p>El anciano a la se\u00f1ora elegida y a sus hijos, a quienes amo en verdad, y no s\u00f3lo yo, sino tambi\u00e9n todos los que conocen la verdad, por la verdad que permanece en nosotros y ser\u00e1 con nosotros para siempre: (v. 1-2)<\/p>\n<p>En estos dos primeros vers\u00edculos vemos a dos personas: (1) El salutor (Anciano), y (2) El salutee (se\u00f1ora elegida y sus hijos) .<\/p>\n<p>Vemos tambi\u00e9n el reconocimiento del Esp\u00edritu Santo (En verdad).<\/p>\n<p>2. Bendici\u00f3n apost\u00f3lica<\/p>\n<p>La gracia, la misericordia y la paz sean con nosotros, de Dios Padre y de Jesucristo Hijo del Padre, en la verdad y en el amor. (v. 3)<\/p>\n<p>El ap\u00f3stol Juan otorga tres bendiciones a la mujer, a sus hijos ya s\u00ed mismo:<\/p>\n<p>A) Gracia: el favor inmerecido de Dios<\/p>\n<p>B ) Misericordia: la disciplina retenida por Dios<\/p>\n<p>C) Paz: la presencia innegable de Dios<\/p>\n<p>3. Reconocimiento apost\u00f3lico<\/p>\n<p>Me alegr\u00e9 mucho al encontrar a algunos de vuestros hijos andando en la verdad, tal como nos lo hab\u00eda mandado el Padre. (v. 4)<\/p>\n<p>Juan reconoce la instrucci\u00f3n adecuada que los hijos han recibido.<\/p>\n<p>La vara y la reprensi\u00f3n dan sabidur\u00eda, pero el ni\u00f1o abandonado a s\u00ed mismo averg\u00fcenza a su madre. (Proverbios 29:15)<\/p>\n<p>4. Petici\u00f3n apost\u00f3lica<\/p>\n<p>Y ahora te pido, querida se\u00f1ora, no como escribi\u00e9ndote un mandamiento nuevo, sino el que hemos tenido desde el principio, que nos amemos los unos a los otros. Y este es el amor, que andemos seg\u00fan sus mandamientos; este es el mandamiento, tal como lo hab\u00e9is o\u00eddo desde el principio, para que and\u00e9is en \u00e9l. (v. 5-6)<\/p>\n<p>El amor es el gran motivador de todas las cosas. Esto es especialmente cierto en la vida del cristiano, porque sin amor es imposible obedecer a Dios.<\/p>\n<p>5. Advertencia apost\u00f3lica<\/p>\n<p>Porque muchos enga\u00f1adores han salido por el mundo, los que no confiesan la venida de Jesucristo en la carne. Tal persona es el enga\u00f1ador y el anticristo. Velad por vosotros mismos, para que no perd\u00e1is aquello por lo que hemos trabajado, sino que gan\u00e9is una recompensa completa. (v. 7-8)<\/p>\n<p>Cualquier ense\u00f1anza que contradiga el Evangelio tiene un dise\u00f1o enga\u00f1oso y se origina en el reino espiritual de Satan\u00e1s. Juan advierte a la mujer que est\u00e9 alerta, para que no se desv\u00ede de las ense\u00f1anzas apost\u00f3licas del Evangelio.<\/p>\n<p>6. Reprensi\u00f3n apost\u00f3lica<\/p>\n<p>Todo el que se desv\u00eda y no permanece en la ense\u00f1anza de Cristo, no tiene a Dios. Quien permanece en la ense\u00f1anza tiene tanto al Padre como al Hijo. Si alguno viene a vosotros y no trae esta ense\u00f1anza, no lo recib\u00e1is en vuestra casa ni le deis ning\u00fan saludo, porque cualquiera que le saluda participa en sus malas obras. (v. 9-11)<\/p>\n<p>Aqu\u00ed, Juan amonesta a los falsos maestros, afirmando que no tienen a Dios y est\u00e1n participando en obras perversas.<\/p>\n<p>7. Visita apost\u00f3lica y palabras de clausura.<\/p>\n<p>Aunque tengo mucho que escribirles, prefiero no usar papel y tinta. En cambio, espero ir a ti y hablar cara a cara, para que nuestra alegr\u00eda sea completa. Los hijos de tu hermana elegida te saludan. (v. 12-13)<\/p>\n<p>A menudo, nos sentimos solos en nuestro caminar con Dios. Puede parecer que todo el mundo va en la direcci\u00f3n equivocada. En sus \u00faltimas palabras, John expresa su deseo de ver a la mujer y a sus hijos, y le recuerda que otros en la fe est\u00e1n pensando en ella.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabidur\u00eda para las mam\u00e1s 2 Juan 1-13 El predicador G. Campbell Morgan tuvo cuatro hijos y todos se convirtieron en ministros del evangelio. En una reuni\u00f3n familiar, un amigo le pregunt\u00f3 a uno de los hijos: \u00ab\u00bfCu\u00e1l Morgan es el mejor predicador?\u00bb Mientras aquel hijo miraba a su padre, le respondi\u00f3: \u00abMam\u00e1\u00bb. Un antiguo proverbio &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/sabiduria-para-las-mamas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abSabidur\u00eda para las mam\u00e1s\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24057","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/24057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=24057"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/24057\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=24057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=24057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=24057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}