{"id":24059,"date":"2022-08-21T05:45:22","date_gmt":"2022-08-21T10:45:22","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/no-tendras-dolor-de-vientre\/"},"modified":"2022-08-21T05:45:22","modified_gmt":"2022-08-21T10:45:22","slug":"no-tendras-dolor-de-vientre","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/no-tendras-dolor-de-vientre\/","title":{"rendered":"No tendr\u00e1s dolor de vientre"},"content":{"rendered":"<p>Mois\u00e9s 12 NO TENDR\u00c1S DOLOR DE VIENTRE<\/p>\n<p>\u00c9xodo 15:22-19:1<\/p>\n<p>16:7<\/p>\n<p>&#8220;\u00c9l (Dios) ha o\u00eddo vuestras murmuraciones contra el Se\u00f1or. Porque \u00bfqui\u00e9nes somos nosotros (Mois\u00e9s y Aar\u00f3n) para que pod\u00e1is murmurar contra nosotros?<\/p>\n<p>Salmo 106:25<\/p>\n<p>&#8220;Refunfu\u00f1aron en sus tiendas y no obedecieron al Se\u00f1or. &#8221;<\/p>\n<p>N\u00fameros 11:11-15<\/p>\n<p>&#8220;Mois\u00e9s escuch\u00f3 al pueblo gritar en sus tiendas (por no tener carne para comer).. y el Se\u00f1or&amp;# 8217; la ira de s ardi\u00f3. .Y Mois\u00e9s dijo al Se\u00f1or,&#8217; \u00bfPor qu\u00e9 has tratado tan duramente a tu siervo? \u00bfPor qu\u00e9 pones sobre m\u00ed la carga de todo este pueblo? \u00bfLos par\u00ed yo? La carga es demasiado pesada para m\u00ed. Si me vas a tratar as\u00ed, m\u00e1tame ahora mismo. Para que no siga mirando mi miseria. #8217;&#8221;<\/p>\n<p>Un joven se uni\u00f3 a una orden mon\u00e1stica y se comprometi\u00f3 con su voto de completo silencio. Pod\u00eda decir dos palabras cada cinco a\u00f1os.<\/p>\n<p>Despu\u00e9s de los primeros cinco a\u00f1os, sali\u00f3 y dijo: &#8220;\u00a1A la cama!&#8221; y volvi\u00f3 a su celda. Despu\u00e9s de diez a\u00f1os sali\u00f3, dijo &#8220;\u00a1Celda fr\u00eda!&#8221; y volvi\u00f3 a su celda. Sali\u00f3 despu\u00e9s de los quince a\u00f1os y dijo: &#8220;\u00a1Comida mala!&#8221; y volvi\u00f3 a su celda. Sali\u00f3 despu\u00e9s del a\u00f1o veinte y dijo: &#8220;\u00a1Renuncio!&#8221;<\/p>\n<p>El Consejo al o\u00edr esto, dijo. &#8220;Eso no nos sorprende; todo lo que ha hecho desde que estuvo aqu\u00ed es quejarse, quejarse, quejarse.<\/p>\n<p>La historia de los 40 a\u00f1os en el desierto de Israel es quejarse, quejarse, quejarse. . (\u00c9xodo 16:7; N\u00fameros 14:2; 17:5, etc.). La King James lo llama MURMURING, debido al sonido que hizo de dos millones de personas insatisfechas &#8211; &#8220;MUR-MUR-MUR-MUR.&#8221;<\/p>\n<p>LAS ESCENAS<\/p>\n<p>Dios podr\u00eda haberle dicho a Israel en el desierto: &#8220;Todo lo que has hecho desde que saliste de Egipto es quejarte, quejarte, quejarte.&#8221; A\u00fan m\u00e1s triste, \u00c9l podr\u00eda decirnos a nosotros que cosechamos los beneficios del sacrificio de Su Hijo, &#8220;Todo lo que han hecho desde que di a Mi Hijo por ustedes es quejarse, quejarse, quejarse.&#8221; <\/p>\n<p>Apenas hab\u00edan salido los israelitas de Egipto cuando el fara\u00f3n los persigui\u00f3. El pueblo no llev\u00f3 este problema en oraci\u00f3n al Dios poderoso de las diez plagas que los sac\u00f3; dijeron a Mois\u00e9s: &#8220;\u00bfEs porque no hab\u00eda sepulcros en Egipto que nos sacaste a este desierto para morir?&#8221; (\u00c9xodo 14:11). Comenzaron los murmullos.<\/p>\n<p>Esas quejas sarc\u00e1sticas marcaron la pauta durante los siguientes cuarenta a\u00f1os. Dios los libr\u00f3 de Fara\u00f3n ese d\u00eda, pero antes de que las aguas del Mar Rojo se calmaran se quejaron porque las aguas de Mara eran amargas (Ex. 15:22-27).<\/p>\n<p>Se quejaron de nuevo porque hab\u00edan sin alimento (16:1-26). Despu\u00e9s de que Dios les dio Man\u00e1, se quejaron porque ten\u00edan sed (17:1-7).<\/p>\n<p>En todos los casos, Dios satisfizo su necesidad, pero no los hizo recurrir a la oraci\u00f3n cuando surgi\u00f3 la siguiente necesidad. Siendo la naturaleza humana lo que es, prefieren quejarse.<\/p>\n<p>Un a\u00f1o en el Sina\u00ed, conociendo a Dios y prometiendo servirle, no los cambi\u00f3 en lo m\u00e1s m\u00ednimo. Nuestro texto muestra que lo primero que hizo Israel cuando salieron del Sina\u00ed fue retomar su viejo h\u00e1bito de lloriquear.<\/p>\n<p>Al cabo de un par de d\u00edas en el desierto comenzaron a quejarse, primero por las dificultades del desierto en s\u00ed (11: 1-3) y luego sobre la dieta del man\u00e1 (11:4-10A). Estaban hartos y cansados de comer lo mismo de siempre. Fue entonces cuando Mois\u00e9s, el otrora poderoso guerrero de Egipto, se hart\u00f3 y arremeti\u00f3 contra Dios y le pidi\u00f3 que lo matara.<\/p>\n<p>A\u00f1os m\u00e1s tarde vemos al esp\u00edritu quejoso vivo y coleando por la falta de de agua en Cades (N\u00fam. 20:1-13) y finalmente sobre los planes de batalla del Se\u00f1or para tomar Cana\u00e1n (N\u00fam. 21:4-8). Demasiados de nosotros hacemos de las quejas una forma de vida.<\/p>\n<p>Nada va bien con las personas que conoces<\/p>\n<p>Quienes tienen su hogar en la Calle de las Quejas<\/p>\n<p>Si no ten\u00eda problemas, no hay duda<\/p>\n<p>Se quejar\u00edan de nada de qu\u00e9 quejarse.<\/p>\n<p>LA SERIEDAD<\/p>\n<p>1. Quejarse es Injurioso (N\u00fameros 11)<\/p>\n<p>Al Hogar<\/p>\n<p>. Una esposa le dijo a su esposo: &#8220;Cari\u00f1o, no dijiste nada sobre la cena.&#8221; &#8220;\u00bfPor qu\u00e9?&#8221; \u00e9l respondi\u00f3, &#8220;hab\u00eda algo mal con eso?&#8221; Este no es un pecado peque\u00f1o, insignificante, insignificante. Destruye hogares. Una esposa le dijo a su esposo: &#8220;Cari\u00f1o, no dijiste nada sobre la gran cena que prepar\u00e9 esta noche.&#8221; \u00c9l dijo: &#8216;\u00bfPor qu\u00e9? \u00bfHubo algo malo con eso?&#8221; Piensa en lo mucho que esto hiri\u00f3 su alma y corta un pedacito de su amor por ese hombre.<\/p>\n<p>\u00bfQuieres destruir tu hogar? Es f\u00e1cil. Esposos: comiencen a quejarse de todo lo que hace su esposa y de c\u00f3mo lo hace. Esposas, hagan lo mismo con su marido. Padres: quejaos de vuestros hijos. Ni\u00f1os: quejaos a vuestros padres. Nada matar\u00e1 el amor y crear\u00e1 desarmon\u00eda m\u00e1s r\u00e1pido que un esp\u00edritu cr\u00edtico y una queja cr\u00f3nica.<\/p>\n<p>A la Iglesia<\/p>\n<p>Quejarse, con la ira y las heridas que la cr\u00edtica crea en su interior, destruir\u00e1 una iglesia. m\u00e1s r\u00e1pido que cualquier otra cosa. En el fondo de cada divisi\u00f3n de la iglesia, encontrar\u00e1 dos cosas: personas que critican algo que no les gusta y lo hacen con enojo.<\/p>\n<p>El pastor<\/p>\n<p>Se necesita el coraz\u00f3n correcto de un pastor. Despu\u00e9s de escuchar d\u00eda y noche el incesante murmullo contra \u00e9l y Dios, el pastor Mois\u00e9s arremeti\u00f3 contra Dios y le pidi\u00f3 que lo dejara morir. (N\u00fameros 11).<\/p>\n<p>Un predicador que conoc\u00ed en la d\u00e9cada de 1960 ten\u00eda una historia extra\u00f1a sobre una vez que renunci\u00f3 a una iglesia. Estaba a punto de entrar al santuario con un evangelista visitante. Un ni\u00f1o peque\u00f1o se acerc\u00f3, se puso el abrigo y dijo: \u00abPredicador\u00bb. No hay papel higi\u00e9nico en el ba\u00f1o.<\/p>\n<p>Esa semana, cuando termin\u00f3 el avivamiento, el predicador entreg\u00f3 su renuncia, diciendo que simplemente no pod\u00eda soportarlo. m\u00e1s. Ahora, un ni\u00f1o peque\u00f1o no llev\u00f3 a ese predicador a la desesperaci\u00f3n, sino una gran cantidad de peque\u00f1as cosas molestas. Esa fue la \u00faltima de muchas gotas.<\/p>\n<p>Dr. Criswell dijo que no muchos predicadores son como Jon\u00e1s y son tragados por ballenas, pero muchos de ellos mueren mordisqueados por pececillos<\/p>\n<p>La psicolog\u00eda<\/p>\n<p>La mayor\u00eda de los pastores, si se les pregunta qu\u00e9 La parte m\u00e1s dif\u00edcil de ser pastor es, dir\u00eda, caminar a trav\u00e9s de horribles valles de dolor incre\u00edble con personas en las bancas que \u00e9l ama. Tu dolor se traslada a tu pastor y \u00e9l duele contigo; llora contigo y sangra contigo. Muere un poco cada vez que entra en un valle como este.<\/p>\n<p>Los psic\u00f3logos cristianos est\u00e1n de acuerdo, pero contin\u00faan diciendo que ir de inmediato, en sus deberes, de estos lugares horribles a lugares felices como bodas o fiestas en la iglesia, no es natural y afecta su salud emocional y f\u00edsica.<\/p>\n<p>No s\u00e9 nada de esto. Conf\u00edo en su palabra. Pero s\u00e9 lo que me pasa. Es pasar de alguien que est\u00e1 profundamente dolido a alguien que no lo est\u00e1 y escucharlo quejarse del termostato, d\u00f3nde estacionamos el autob\u00fas o c\u00f3mo no le gusta caminar 200 pies desde su clase hasta el santuario. Esto es como echar gasolina al fuego<\/p>\n<p>Queremos decir: &#8220;Si me acompa\u00f1an un d\u00eda a un asilo de ancianos y ven a personas que no pueden limpiarse a s\u00ed mismas o a un ni\u00f1o&amp; #8217;s la sala del hospital y ves tubos saliendo de peque\u00f1as cabezas, sabr\u00edas cu\u00e1l es el verdadero problema. Y no te quejar\u00edas por nada.<\/p>\n<p>Nosotros no lo hacemos, por supuesto. Queremos mantener nuestros trabajos. As\u00ed que reprimimos nuestra ira. Tratamos de ser amables y eso nos carcome hasta que, como Mois\u00e9s, nos quemamos y rezamos para morir.<\/p>\n<p>Esta es la causa ra\u00edz de la mayor\u00eda de los ataques severos de depresi\u00f3n. Muchos psic\u00f3logos hoy en d\u00eda definen la depresi\u00f3n como &#8220;La ira hacia adentro&#8221;.<\/p>\n<p>2) Quejarse es contagioso (11:10)<\/p>\n<p>Cuando Israel sali\u00f3 de Egipto un &amp;#8220 ;multitud mixta&#8221; (Ex. 12:38) partieron con ellos y probablemente eran esclavos de otros pa\u00edses. De todos modos, incitaron a Israel contra el man\u00e1 hasta que su descontento se extendi\u00f3 por todas las tiendas.<\/p>\n<p>La queja se extiende como gangrena. Por eso Dios dice que una de las seis cosas que odia es la persona que siembra discordia entre hermanos (Prov. 6)<\/p>\n<p>Yo ten\u00eda en una de mis iglesias un hombre que era experto en contagiar a la gente con su esp\u00edritu amargo. En una fiesta de la clase u otra reuni\u00f3n, pasaba de una persona a otra y dec\u00eda algo como esto: &#8220;\u00bfNo crees que ____ canta demasiados solos?&#8221;<\/p>\n<p>Cuando el la persona no est\u00e1 en desacuerdo lo toma como un &#8220;S\u00ed&#8221; y pasar a otra persona, y otra, y as\u00ed sucesivamente. Lo sab\u00eda, pero viv\u00ed con ello hasta que me trajo una lista de quejas sobre nuestro Ministro de M\u00fasica, cosas que \u00e9l y &#8220;muchos otros&#8221; (??) estaban preocupados.<\/p>\n<p>Dos que recuerdo eran: &#8220;Es demasiado pesado y canta demasiados solos.&#8221; (Apostar\u00eda mil d\u00f3lares si fuera un apostador a que en alg\u00fan lugar de Estados Unidos esa misma semana otro grupo le estaba diciendo a su Pastor que el Ministro de M\u00fasica es demasiado flaco y necesita cantar m\u00e1s solos).<\/p>\n<p>I le pregunt\u00f3 qui\u00e9n estaba molesto como \u00e9l y dijo (como siempre hace la gente as\u00ed), &#8220;prefiero no decirlo.&#8221; Le pregunt\u00e9 si se hab\u00eda enamorado para hablar y orar con el miembro del personal y me dijo: &#8220;\u00a1No!&#8221; Le suger\u00ed que hiciera eso. Por supuesto que no porque era un hombre con un esp\u00edritu amargo que siempre buscaba algo de qu\u00e9 quejarse.<\/p>\n<p>He pastoreado ahora durante 31 a\u00f1os y he enfrentado todo tipo de personas y problemas, pero ese hombre estuvo m\u00e1s cerca de dividir nuestra iglesia y sacarme del ministerio que todas las dem\u00e1s personas y problemas juntos.<\/p>\n<p>LA SALVACI\u00d3N<\/p>\n<p>1. Mira Tus Bendiciones<\/p>\n<p>Para m\u00ed este peque\u00f1o poema lo dice todo:<\/p>\n<p>Hoy en un autob\u00fas vi a una chica de cabello dorado<\/p>\n<p>La envidi\u00e9 , y dese\u00e9 ser tan justa<\/p>\n<p>Cuando de repente se levant\u00f3 para irse, la vi<\/p>\n<p>cojeando por el pasillo,<\/p>\n<p>Ten\u00eda una pierna y pero qu\u00e9 a<\/p>\n<p>Dulce, dulce sonrisa<\/p>\n<p>Oh, Dios, perd\u00f3name cuando me quejo, tengo dos piernas, el mundo es m\u00edo.<\/p>\n<p>Y luego me detuve a comprar unos dulces<\/p>\n<p>El chico que los vend\u00eda ten\u00eda un encanto<\/p>\n<p>Habl\u00e9 con \u00e9l, parec\u00eda tan contento,<\/p>\n<p>Si llegaba tarde no me pasar\u00eda nada. <\/p>\n<p>Y al salir me dijo &#8220;gracias se\u00f1or,<\/p>\n<p>ha sido tan amable.<\/p>\n<p>Es&amp;# 8217 Es agradable hablar con la gente, \u00bfves?<\/p>\n<p>\u00c9l dijo: \u00abSoy ciego\u00bb.<\/p>\n<p>Oh, Dios, perd\u00f3name cuando \u00a1Me quejo, tengo dos<\/p>\n<p>ojos! El mundo es m\u00edo.<\/p>\n<p>Despu\u00e9s caminando por la calle, vi a un ni\u00f1o<\/p>\n<p>con ojos azules,<\/p>\n<p>Se par\u00f3 y mir\u00f3 a los dem\u00e1s jugar,<\/p>\n<p>Parec\u00eda que no sab\u00eda qu\u00e9 hacer<\/p>\n<p>Me detuve un momento y luego dije:<\/p>\n<p>&#8220;\u00bfPor qu\u00e9 no te unes a los dem\u00e1s? \u00bfAll\u00ed?&#8221;<\/p>\n<p>Mir\u00f3 al frente sin decir una palabra, y entonces<\/p>\n<p>Yo supe, \u00e9l no pod\u00eda escuchar.<\/p>\n<p>Oh Dios, perd\u00f3name cuando Me quejo, tengo dos<\/p>\n<p>orejas, el mundo es m\u00edo.<\/p>\n<p>Con piernas para llevarme a donde voy<\/p>\n<p>Con ojos para ver el atardecer&amp;#8217 ;s resplandor<\/p>\n<p>Con o\u00eddos para escuchar lo que quisiera saber<\/p>\n<p>Oh Dios, perd\u00f3name cuando bebo, soy bendecido<\/p>\n<p>Ciertamente, el el mundo es m\u00edo.<\/p>\n<p>&#8211; Autor desconocido<\/p>\n<p>2. Mira a tu Se\u00f1or (Heb. 12:1-3)<\/p>\n<p>La Biblia dice: &#8220;Mirad a Jes\u00fas, el autor y consumador de vuestra fe&#8230; quien soport\u00f3 la cruz&#8230; y la verg\u00fcenza&#039; 8221; (Hebreos 12)<\/p>\n<p>Nuestro ejemplo supremo de victoria sobre las quejas es el Hijo de Dios manchado de sangre que se abri\u00f3 camino a trav\u00e9s de las fuerzas del infierno, termin\u00f3 en el madero de Roma, y nunca gimi\u00f3, gimi\u00f3, o se quej\u00f3.<\/p>\n<p>Qu\u00e9 insulto es para \u00c9l y para el cristianismo cuando actuamos como peque\u00f1os beb\u00e9s llorones porque no nos salimos con la nuestra. La bendici\u00f3n m\u00e1s grande de toda la Biblia se encuentra en N\u00fameros al final de los a\u00f1os del desierto. Los sacerdotes, en el culto, bendijeron al pueblo con estas palabras:<\/p>\n<p>&#8220;El Se\u00f1or os bendiga y os guarde. El Se\u00f1or haga resplandecer su rostro sobre ti, y tenga de ti misericordia. El Se\u00f1or alce sobre ti su rostro y te d\u00e9 la paz.&#8221; (6:24-25)<\/p>\n<p>Los beb\u00e9s llorones con dolor de barriga deshonran a Dios e insultan a Jes\u00fas al mirar siempre lo que Dios no les da en lugar de lo que \u00c9l hace.<\/p>\n<p>En un encendedor lado:<\/p>\n<p>Mientras viajas por este camino<\/p>\n<p>Que esta sea tu meta<\/p>\n<p>Mant\u00e9n tu mirada en la rosquilla<\/p>\n<p>Y no en el todo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mois\u00e9s 12 NO TENDR\u00c1S DOLOR DE VIENTRE \u00c9xodo 15:22-19:1 16:7 &#8220;\u00c9l (Dios) ha o\u00eddo vuestras murmuraciones contra el Se\u00f1or. Porque \u00bfqui\u00e9nes somos nosotros (Mois\u00e9s y Aar\u00f3n) para que pod\u00e1is murmurar contra nosotros? Salmo 106:25 &#8220;Refunfu\u00f1aron en sus tiendas y no obedecieron al Se\u00f1or. &#8221; N\u00fameros 11:11-15 &#8220;Mois\u00e9s escuch\u00f3 al pueblo gritar en sus tiendas (por &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/no-tendras-dolor-de-vientre\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNo tendr\u00e1s dolor de vientre\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24059","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/24059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=24059"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/24059\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=24059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=24059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=24059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}