{"id":24072,"date":"2022-08-21T05:45:50","date_gmt":"2022-08-21T10:45:50","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/la-busqueda-de-la-sabiduria\/"},"modified":"2022-08-21T05:45:50","modified_gmt":"2022-08-21T10:45:50","slug":"la-busqueda-de-la-sabiduria","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/la-busqueda-de-la-sabiduria\/","title":{"rendered":"La B\u00fasqueda de la Sabidur\u00eda"},"content":{"rendered":"<p>Un estudio del Libro de Eclesiast\u00e9s<\/p>\n<p>Encontrar Satisfacci\u00f3n en la Vida<\/p>\n<p>Serm\u00f3n # 2<\/p>\n<p>&#8220;La En busca de la sabidur\u00eda:<\/p>\n<p>Eclesiast\u00e9s 1:12-18<\/p>\n<p>Como se indica en el primer mensaje, creo que aunque algunos eruditos modernos creen que Eclesiast\u00e9s fue escrito por alguien que escribi\u00f3 como Salom\u00f3n. Creo que el autor de Eclesiast\u00e9s es Salom\u00f3n. Sin embargo, en el vers\u00edculo once, el escritor se identifica m\u00e1s a s\u00ed mismo, &#8220;yo, el Predicador, hijo de David, rey sobre Israel.&#8221; Aunque el autor nunca da directamente su nombre sino que usa el t\u00edtulo &#8220;Koheleth&#8221; o el predicador. &#8220;Esta descripci\u00f3n solo se ajusta a la vida de Salom\u00f3n, porque aunque Roboam y otros descendientes de David gobernaron en Jerusal\u00e9n, ninguno de ellos gobern\u00f3 sobre Israel. Despu\u00e9s de Salom\u00f3n, el reino se dividi\u00f3 entre el norte y el sur, quien reinaba en Jerusal\u00e9n solo gobernaba sobre el reino del sur de Judea, no sobre el reino del norte de Israel. As\u00ed que este rey debe ser Salom\u00f3n.&#8221; [Philip Graham Ryken. &#8220;Eclesiast\u00e9s: Por qu\u00e9 todo importa.&#8221; (Wheaton, ILL: Crossway, 2010) p\u00e1g. 36]<\/p>\n<p>Primero, La B\u00fasqueda de la Sabidur\u00eda. (1:13)<\/p>\n<p>&#8220;Y puse mi coraz\u00f3n a buscar y escudri\u00f1ar con sabidur\u00eda todo lo que se hace debajo del cielo; esta ardua tarea que Dios ha dado a los hijos del hombre, por la cual pueden ser ejercitados.&#8221;<\/p>\n<p>&#8226; Su b\u00fasqueda fue sincera.<\/p>\n<p>Uno de los conceptos err\u00f3neos que creo que tenemos (al menos yo lo tuve) fue que este maravilloso don de la sabidur\u00eda se produjo de alguna manera m\u00e1gica. Como si Salom\u00f3n simplemente &#8220;poof&#8221; entendido todo. Ahora creo que aunque estaba dotado de una gran &#8220;capacidad&#8221; para la acumulaci\u00f3n de sabidur\u00eda todav\u00eda ten\u00eda que aplicarse a la b\u00fasqueda del conocimiento. Y eso es exactamente lo que hizo &#8211; dedic\u00f3 su vida al aprendizaje.<\/p>\n<p>&#8226; Su b\u00fasqueda fue intensa. (v. 13)<\/p>\n<p>En el vers\u00edculo trece Salom\u00f3n relata, &#8220;Y puse mi coraz\u00f3n a buscar y escudri\u00f1ar con sabidur\u00eda todo lo que se hace debajo del cielo; esta gravosa tarea que Dios ha dado a los hijos del hombre, por la cual pueden ser ejercitados.&#8221; Para transmitir cu\u00e1n completo fue su esfuerzo, Salom\u00f3n dice que puso su coraz\u00f3n en &#8220;buscar y escudri\u00f1ar&#8221; o &#8220;estudiar y explorar&#8221; indicando la seriedad de sus esfuerzos. Koheleth fue el hombre original del Renais-sance. Quer\u00eda saber todo lo que pudiera sobre todo lo que pudiera.<\/p>\n<p>&#8226; Bajo el cielo.<\/p>\n<p>Su esfuerzo era abarcar todo &#8220;todo lo que se hace debajo del cielo.&#8221; Koheleth dice que se dedic\u00f3 a buscar sabidur\u00eda en &#8220;Todo lo que se hace debajo del cielo&#8221; que es otra forma de decir; \u00abbajo el sol.\u00bb El Predicador usa este t\u00e9rmino &#8220;bajo el sol&#8221; m\u00e1s de veinticinco veces en Eclesiast\u00e9s para describir el mundo podemos ver el mundo material &#8211; vida sin una perspectiva eterna.<\/p>\n<p>&#8220;Esta sabidur\u00eda es la de aquellos que nos gu\u00edan a una vida mejor en el aqu\u00ed y ahora; c\u00f3mo vivir una vida m\u00e1s sana, m\u00e1s feliz y m\u00e1s pr\u00f3spera. Esta sabidur\u00eda&#8230; tiene su valor y muchas vidas ser\u00edan mejores para seguirlo. Sin embargo, excluye una verdadera apreciaci\u00f3n de la eternidad y nuestras responsabilidades para con el mundo venidero; esta sabidur\u00eda no tiene una respuesta verdadera al sinsentido de la vida. Solo nos muestra c\u00f3mo vivir mejor nuestras vidas sin sentido.&#8221; [David Guzik. Comentario de David Guzik sobre la Biblia. Eclesiast\u00e9s 1. www.studylight.org\/commentaries\/guz\/view.cgi?bk=20&amp;ch=1 ]<\/p>\n<p>&#8220;&#8230;.esta pesada tarea que Dios ha dado a los hijos del hombre , por el cual pueden ser ejercitados.&#8221;<\/p>\n<p>Esta es la primera vez que se menciona a Dios en Eclesiast\u00e9s y el nombre se usa aqu\u00ed (y en todas partes en Eclesiast\u00e9s es Elohim no Yahweh, el nombre del pacto Dios le hab\u00eda dado a Israel. Lo m\u00e1s probable es que la raz\u00f3n sea que Eclesiast\u00e9s ten\u00eda como objetivo llegar a una audiencia m\u00e1s all\u00e1 de Israel. Por lo tanto, se usa Elohim (el Dios del creador &#8211; G\u00e9nesis 1: 1). La frase &#8220;hijos del hombre&#8220; 8221; es literalmente los &#8220;hijos de Ad\u00e1n&#8221;&#8211; por lo que la referencia no es a la masa de la humanidad sino a la naturaleza del hombre. La tarea se hace a\u00fan m\u00e1s dif\u00edcil debido al hombre&amp;#8217 Su condici\u00f3n ca\u00edda.<\/p>\n<p>Todo el trabajo, los logros y la b\u00fasqueda de sabidur\u00eda del hombre parecen no ser nada. De hecho, Dios ha construido deliberadamente un sistema donde la vida parece sin sentido y vac\u00eda, sin el entendimiento de un Dios vivo a quien debemos dar cuenta. Puede parecer cruel por parte de Dios idear tal sistema, pero en realidad es una evidencia de su gran amor y misericordia. \u00c9l construy\u00f3 dentro de nosotros el deseo y la necesidad de aquello que da significado y satisfacci\u00f3n a la vida. Como escribi\u00f3 Agust\u00edn, &#8220;el Creador hizo un espacio en forma de Dios en cada uno de nosotros, que solo \u00c9l puede llenar.&#8221;<\/p>\n<p>Muchas personas, incluso aquellas que son ricas y ricas -conocido, puede dar fe de ese vac\u00edo. Por ejemplo, HG Wells dijo a los 61 a\u00f1os: &#8220;No tengo paz. Toda vida est\u00e1 al final de la cuerda.&#8221; El poeta Byron dijo: &#8220;Mis d\u00edas est\u00e1n en hojas amarillas, las flores y los frutos de la vida se han ido, el gusano y el chancro, y el dolor son solo m\u00edos.&#8221; Thoreau dijo: &#8220;La mayor\u00eda de los hombres viven una vida de silenciosa desesperaci\u00f3n.&#8221; Ernest Hemingway, dijo esto sobre su vida: &#8220;Vivo en un vac\u00edo que es tan solitario como una radio&#8230; cuando las bater\u00edas est\u00e1n muertas y no hay corriente para enchufar.&#8221; Hemingway vivi\u00f3 su vida de una manera que ser\u00eda la envidia de cualquier persona que haya comprado los valores de este mundo. Pero un domingo por la ma\u00f1ana en Idaho, se peg\u00f3 un tiro en la cabeza.<\/p>\n<p>Un caricaturista llamado Ralph Barton dej\u00f3 esta nota clavada en su almohada antes de quitarse la vida: &#8220;He tenido pocas dificultades, muchos amigos, grandes \u00e9xitos; He ido de mujer en mujer, de casa en casa, visitado grandes pa\u00edses del mundo, pero estoy harto de inventar artilugios para llenar las veinticuatro horas del d\u00eda.<\/p>\n<p> Esta incompletitud aparte de Dios no solo se encuentra no solo en nosotros como personas, sino tambi\u00e9n en toda la Creaci\u00f3n. Dios tambi\u00e9n someti\u00f3 la creaci\u00f3n a esta futilidad hasta que un d\u00eda traiga el cumplimiento prometido. Pablo describi\u00f3 esto a la iglesia en Roma cuando escribi\u00f3: &#8220;Porque la creaci\u00f3n fue sujetada a vanidad, no voluntariamente, sino por causa de Aquel que la sujet\u00f3 en esperanza&#8221;. (Romanos 8:20). Pero un d\u00eda, cuando el Se\u00f1or Jes\u00fas regrese, la creaci\u00f3n ser\u00e1 liberada de esta esclavitud. &#8220;Cuando somos testigos de la vida &#8216;Bajo el sol&#8221; marcados por el sufrimiento, desbordados por la opresi\u00f3n, infectados por la injusticia, arrastr\u00e1ndose por el crimen, traumatizados por los terroristas, contaminados por la impureza, sabemos que no son s\u00f3lo las cosas as\u00ed&#8230; Al contrario, no es lo que podr\u00eda haber sido&amp; #8221; &#8211; es lo que ha hecho el pecado. [Douglas Sean O&#8217;Donnell. &#8220;Eclesiast\u00e9s.&#8221; Comentario expositivo reformado. (Philipsburg, Nueva Jersey: P &amp; R Publishing, 2014) p\u00e1g. 37]<\/p>\n<p>Segundo, El Descubrimiento Sobre La Sabidur\u00eda. (1:14-15)<\/p>\n<p>&#8220;He visto todas las obras que se hacen debajo del sol; y en verdad, todo es vanidad y af\u00e1n de viento.&#8221; (15) Lo torcido no se puede enderezar, y lo que falta no se puede contar.&#8221;<\/p>\n<p>&#8226; Agarrando Para El Viento. (v. 14)<\/p>\n<p>Quiz\u00e1s hayas escuchado la frase &#8220;Eso es tan dif\u00edcil como arrear gatos.&#8221; Esto se ilustr\u00f3 hace unos a\u00f1os en un comercial durante un Super Bowl que se llam\u00f3 &#8220;gato pastoreo&#8221;? El comercial presentaba varios miles de gatos corriendo en todas direcciones excepto en la direcci\u00f3n en la que los rancheros en sus caballos quer\u00edan que los gatos corrieran. La palabra hebrea para &#8220;agarrar&#8221; o &#8220;esforzarse&#8221; es muy similar a &#8220;pasar.&#8221; Y as\u00ed, el Predicador literalmente est\u00e1 diciendo que todo lo que se hace sin tener en cuenta a Dios es como pastorear el viento&#8230; \u00a1no se puede hacer!<\/p>\n<p>&#8226; \u00a1La sabidur\u00eda no puede cambiar la realidad! (v. 15)<\/p>\n<p>La primera parte del vers\u00edculo quince dice &#8220;lo torcido no se puede enderezar&#8221; es darse cuenta de que hay algunas cosas en la vida que no se arreglar\u00e1n. Algunas de nuestras circunstancias no se pueden desenredar por mucho que lo intentemos. No importa cu\u00e1n grande sea el esfuerzo que ejerzamos, no podemos doblarlos para alinearlos. Una de las grandes frustraciones de la vida es que no importa cu\u00e1nto te esfuerces, \u00a1hay algunas cosas que no puedes corregir! Salom\u00f3n est\u00e1 diciendo que \u00abel pasado no se puede cambiar y es una tonter\u00eda preocuparse por lo que se podr\u00eda haber hecho\u00bb. Sin embargo, debemos recordarnos a nosotros mismos que Dios tiene el poder para enderezar lo torcido y esta falto de. \u00c9l no puede cambiar el pasado, pero puede cambiar la forma en que el pasado nos afecta.&#8221; [Warren Wiersbe. &#8220;Estar Satisfecho: Buscando la Respuesta al Sentido de la Vida.&#8221; (Wheaton, ILL: Victor Books, 1990) p\u00e1gs. 30-31]<\/p>\n<p>Vers\u00edculo quince &#8220;lo que falta no se puede numerar&#8221; significa simplemente &#8220;\u00a1no podemos contar lo que no tenemos!&#8221;<\/p>\n<p>Tercero, La decepci\u00f3n con respecto a la sabidur\u00eda. (1:16-18)<\/p>\n<p>&#8220;Comulgu\u00e9 en mi coraz\u00f3n, diciendo: &#8220;Mira, he alcanzado grandeza, y he adquirido m\u00e1s sabidur\u00eda que todos los que fueron antes de m\u00ed en Jerusal\u00e9n . Mi coraz\u00f3n ha entendido gran sabidur\u00eda y ciencia.&#8221;<\/p>\n<p>La declaraci\u00f3n de Salom\u00f3n en el vers\u00edculo diecis\u00e9is puede sonar como una simple jactancia cuando dice: &#8220;Me he hecho grande y he ganado m\u00e1s sabidur\u00eda que todos los que fueron antes de m\u00ed en Jerusal\u00e9n&#8221; pero de hecho es una simple declaraci\u00f3n de hecho. Simplemente est\u00e1 haciendo eco de lo que la Escritura dice acerca de \u00e9l en 1 Reyes 3:12: \u201cHe aqu\u00ed, he hecho conforme a tus palabras; Mira, te he dado un coraz\u00f3n sabio y entendido, de modo que no ha habido otro como t\u00fa antes de ti, ni otro como t\u00fa se levantar\u00e1 despu\u00e9s de ti. Y en 1 Reyes 4:29-34 leemos, &#8220;Dios dio a Salom\u00f3n sabidur\u00eda y un entendimiento muy grande,&#8230; (30) As\u00ed super\u00f3 la sabidur\u00eda de Salom\u00f3n a la sabidur\u00eda de todos los hombres de Oriente y a toda la sabidur\u00eda de Egipto. (34) Y hombres de todas las naciones, de todos los reyes de la tierra que hab\u00edan o\u00eddo hablar de su sabidur\u00eda, vinieron a o\u00edr la sabidur\u00eda de Salom\u00f3n. Finalmente en 1 Reyes 10:23-24, leemos el resumen, &#8220;Y el rey Salom\u00f3n super\u00f3 a todos los reyes de la tierra en riquezas y sabidur\u00eda. (24) Ahora toda la tierra buscaba la presencia de Salom\u00f3n para o\u00edr su sabidur\u00eda, la cual Dios hab\u00eda puesto en su coraz\u00f3n.&#8221;<\/p>\n<p>&#8226; Locura y Locura. (v.17a)<\/p>\n<p>Verso diecisiete, &#8220;Y puse mi coraz\u00f3n a conocer la sabidur\u00eda ya conocer la locura y la insensatez. Percib\u00ed que esto tambi\u00e9n es aferrarse al viento.&#8221; El Predicador no est\u00e1 sugiriendo como F\u00e9lix le hizo al Ap\u00f3stol Pablo &#8220;que mucho saber lo ha vuelto loco&#8221; (Hechos 26:24). Cuando Salom\u00f3n se refiere a &#8220;locura e insensatez&#8221; (v. 17) \u00e9l al no hablar de locura sino de inmoralidad. El Predicador est\u00e1 usando &#8220;locura&#8221; y &#8220;locura&#8221; en la forma en que se usan habitualmente en el Antiguo Testamento &#8211; para referirse a la locura de vivir en desobediencia a Dios.<\/p>\n<p>&#8226; La sabidur\u00eda aumenta el dolor. (v.18)<\/p>\n<p>&#8220;Porque en la mucha sabidur\u00eda hay mucho dolor, Y el que aumenta el conocimiento aumenta la tristeza.&#8221;<\/p>\n<p>Todos hemos escuchado la declaraci\u00f3n, &#8220;La ignorancia es dicha.&#8221; \u00a1Y hasta cierto punto esto es cierto! El erudito del Antiguo Testamento HC Leupold expres\u00f3 esto de una manera erudita, cuando dijo que obtener sabidur\u00eda &#8216;lleva al hombre a descubrir muchas cosas perturbadoras que pueden ir en contra de su paz mental&#8217;. [HC Leupold. &#8220;Exposici\u00f3n de Eclesiast\u00e9s.&#8221; (Grand Rapids: Baker, 1952) p\u00e1g. 55]<\/p>\n<p>As\u00ed es en el mundo en general, aprendemos tantas cosas que preferir\u00edamos no saber en absoluto &#8211; cosas sobre la crueldad de otros seres humanos &#8211; sobre los muchos tipos de sufrimiento humano que hay en el mundo. Tambi\u00e9n es cierto de nuestras relaciones con los dem\u00e1s. Por ejemplo, cuando te unes a una nueva iglesia, tienes cierta percepci\u00f3n de las personas a medida que las conoces y luego&#8230; con el tiempo descubres que algunos no son lo que pensabas que eran. Por eso no entiendo a la gente a la que le gusta escuchar chismes. Despu\u00e9s de treinta y cinco a\u00f1os en el ministerio, he o\u00eddo m\u00e1s de lo que jam\u00e1s hubiera querido saber acerca de la gente. Eso puede sonar calloso pero es cierto que hay muchas cosas en este mundo que para tu tranquilidad es mejor no saber.<\/p>\n<p>Conclusi\u00f3n<\/p>\n<p>En la pel\u00edcula &amp;# 8220;Annie Pasillo&#8221; el personaje Alvy Singer hace el comentario c\u00f3mico y tr\u00e1gico sobre la seriedad de la vida. Dice &#8220;Siento que la vida se divide en lo horrible y lo miserable. Esas son las dos categor\u00edas. Los horribles son como, no s\u00e9, casos terminales, ciegos y discapacitados. No s\u00e9 c\u00f3mo se las arreglan para vivir. Es incre\u00edble para m\u00ed. Y los miserables son todos los dem\u00e1s. As\u00ed que (deber\u00edas) estar agradecido de ser miserable, porque es una suerte ser (simplemente) miserable. [O&#8217;Donnell. pags. 37]<\/p>\n<p>Entonces, si la sabidur\u00eda mundana (educaci\u00f3n) fuera la clave para comprender el significado de la vida, entonces los campus universitarios de este pa\u00eds deber\u00edan ser bastiones de paz y satisfacci\u00f3n. Pero este no es el caso. Charles Swindoll los describe como, &#8220;olla hirviendo de controversia&#8230;activismo pol\u00edtico, esforzarse m\u00e1s en el humanismo&#8230; donde todo tipo de ideas extra\u00f1as, profesores insatisfechos y desilusionados junto con un mont\u00f3n de &#8216;estudiantes profesionales que no encuentran satisfacci\u00f3n bajo el sol&#8221;. [Charles Swindoll. &#8220;Viviendo en el borde desigual: Afrontando la realidad.&#8221; (Waco, TX: Word Books, 1985) p\u00e1g. 34]<\/p>\n<p>Malcolm Muggeridge dijo sobre las filosof\u00edas de este mundo y lo que nos hace, lo que tiene para ofrecernos. \u201cLa educaci\u00f3n, el gran galimat\u00edas y fraude de todos los tiempos, pretende equiparnos para vivir, y se prescribe como un remedio universal para todo, desde la delincuencia juvenil hasta la senilidad prematura. En su mayor parte, solo sirve para agrandar la estupidez, inflar la presunci\u00f3n, aumentar la credulidad [tener una tendencia a creer con demasiada facilidad] y poner a quienes est\u00e1n sujetos a ella a merced de lavadores de cerebro con imprentas, radio y televisi\u00f3n a su disposici\u00f3n. &#8221; No es que la educaci\u00f3n sea mala, pero debe hacerse en Cristo y no aparte de \u00c9l.<\/p>\n<p>Si la b\u00fasqueda de la sabidur\u00eda terrenal es tan in\u00fatil, \u00bfc\u00f3mo es la sabidur\u00eda divina? En el Antiguo Testamento el profeta Jerem\u00edas dice: &#8220;No se alabe el sabio en su sabidur\u00eda, ni en su valent\u00eda se alabe el valiente, ni en sus riquezas se alabe el rico;(24) sino el que glorias gloriarse en esto, en que me entiende y me conoce, que yo soy el SE\u00d1OR, que ejerzo misericordia, juicio y justicia en la tierra. Porque en estos me deleito,&#8221; dice el SE\u00d1OR.&#8221; (Jerem\u00edas 9:23-24)<\/p>\n<p>Santiago advierte a sus santos del Nuevo Testamento, &#8220;\u00bfQui\u00e9n es sabio y entendido entre ustedes? Que muestre con buena conducta que sus obras se hacen con mansedumbre de sabidur\u00eda. (14) Pero si ten\u00e9is celos amargos y ego\u00edsmo en vuestros corazones, no os jact\u00e9is ni mint\u00e1is contra la verdad. (15) Esta sabidur\u00eda no desciende de lo alto, sino que es terrenal, sensual, diab\u00f3lica. (16) Porque donde hay envidia y ego\u00edsmo, all\u00ed hay confusi\u00f3n y toda maldad. (17) Pero la sabidur\u00eda que es de lo alto es primeramente pura, luego pac\u00edfica, amable, generosa, llena de misericordia y de buenos frutos, sin parcialidad y sin hipocres\u00eda.&#8221; (Santiago 3:13-17) Eclesiast\u00e9s es evidencia de que Dios destruye la pretensi\u00f3n de la sabidur\u00eda humana al mostrar cu\u00e1n vac\u00edo y sin sentido es todo nuestro aprendizaje sin \u00c9l.&#8195;<\/p>\n<p>&#8220;La b\u00fasqueda de Sabidur\u00eda&#8221;<\/p>\n<p>Eclesiast\u00e9s 1:12-18<\/p>\n<p>Primero, la b\u00fasqueda de la sabidur\u00eda. (1:13)<\/p>\n<p>Si bien Salom\u00f3n fue dotado de una gran &#8220;capacidad&#8221; para la acumulaci\u00f3n de sabidur\u00eda, todav\u00eda ten\u00eda que dedicarse a la b\u00fasqueda del conocimiento.<\/p>\n<p>&#8226; Su b\u00fasqueda fue sincera.<\/p>\n<p>&#8226; Su b\u00fasqueda fue intensa. (v. 13)<\/p>\n<p>Cuando se menciona a Dios en Eclesiast\u00e9s y el nombre se usa aqu\u00ed (y en todas partes en Eclesiast\u00e9s es Elohim, no Yahweh), lo m\u00e1s probable es que la raz\u00f3n sea que Eclesiast\u00e9s ten\u00eda como objetivo llegar a una audiencia m\u00e1s all\u00e1 de Israel. .<\/p>\n<p>Segundo, El Descubrimiento de la Sabidur\u00eda.(1:14-15)<\/p>\n<p>&#8226;Aferrarse al Viento.(v. 14)<\/p>\n<p> &#8226;\u00a1La sabidur\u00eda no puede cambiar la realidad!(v. 15)<\/p>\n<p>Tercero, La decepci\u00f3n con respecto a la sabidur\u00eda.(1:16-18)<\/p>\n<p>( 1 Reyes 3:12, 4 :29-34, 10:23-24)<\/p>\n<p>&#8226;Locura y Tonter\u00eda.(v. 17) \u00e9l al no hablar de locura sino de inmoralidad.<\/p>\n<p>&amp;# 8226;La sabidur\u00eda aumenta el dolor.(v.18)<\/p>\n<p>\u00bfC\u00f3mo es la sabidur\u00eda divina?(Jerem\u00edas 9:23-24, Santiago 3:13-17)&#8195;<\/p>\n<p>&#8195;<\/p>\n<p>&#8220;La b\u00fasqueda de la sabidur\u00eda&#8221;<\/p>\n<p>Eclesiast\u00e9s 1:12-18<\/p>\n<p>Primero, el _____________________ de la sabidur\u00eda (1:13)<\/p>\n<p>Aunque Salom\u00f3n fue dotado de una vasta &#8220;capacidad&#8221; para la acumulaci\u00f3n de sabidur\u00eda, todav\u00eda ten\u00eda que dedicarse a la b\u00fasqueda del conocimiento.&lt;\/p <\/p>\n<p>&#8226; Su B\u00fasqueda fue _________________.<\/p>\n<p>&#8226; Su B\u00fasqueda fue _________________. (v. 13)<\/p>\n<p>Cuando se menciona a Dios en Eclesiast\u00e9s y el nombre se usa aqu\u00ed (y en todas partes en Eclesiast\u00e9s es Elohim, no Yahweh), lo m\u00e1s probable es que la raz\u00f3n sea que Eclesiast\u00e9s ten\u00eda como objetivo llegar a una audiencia m\u00e1s all\u00e1 de Israel. .<\/p>\n<p>Segundo, El _________________________ Sobre la Sabidur\u00eda.(1:14-15)<\/p>\n<p>&#8226;________________________ Para el Viento.(v. 14)<\/p>\n<p> &#8226;\u00a1La sabidur\u00eda no puede cambiar _____________________! (v. 15)<\/p>\n<p>Tercero, El _______________________ Acerca de la sabidur\u00eda.(1:16-18)<\/p>\n<p>( 1 Reyes 3:12, 4 :29-34, 10:23-24)<\/p>\n<p>&#8226;________________ y Locura.(v. 17) \u00e9l al no hablar de locura sino de ______________________.<\/p>\n<p>&amp;# 8226 La sabidur\u00eda aumenta ____________________ (v.18)<\/p>\n<p>\u00bfC\u00f3mo es la sabidur\u00eda divina?(Jerem\u00edas 9:23-24, Santiago 3:13-17)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un estudio del Libro de Eclesiast\u00e9s Encontrar Satisfacci\u00f3n en la Vida Serm\u00f3n # 2 &#8220;La En busca de la sabidur\u00eda: Eclesiast\u00e9s 1:12-18 Como se indica en el primer mensaje, creo que aunque algunos eruditos modernos creen que Eclesiast\u00e9s fue escrito por alguien que escribi\u00f3 como Salom\u00f3n. Creo que el autor de Eclesiast\u00e9s es Salom\u00f3n. Sin &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/la-busqueda-de-la-sabiduria\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa B\u00fasqueda de la Sabidur\u00eda\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24072","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/24072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=24072"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/24072\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=24072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=24072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=24072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}