{"id":3945,"date":"2022-08-18T04:13:30","date_gmt":"2022-08-18T09:13:30","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/la-causa-de-dios-para-nuestro-mundo\/"},"modified":"2022-08-18T04:13:30","modified_gmt":"2022-08-18T09:13:30","slug":"la-causa-de-dios-para-nuestro-mundo","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/la-causa-de-dios-para-nuestro-mundo\/","title":{"rendered":"La causa de Dios para nuestro mundo"},"content":{"rendered":"<p>La causa de Dios para nuestro mundo<\/p>\n<p>Salmo 74:22<\/p>\n<p>Ver: https:\/\/studio.youtube.com\/ video\/h-WkxN1Y4XU\/edit?c=UCnsKqgXUXKLZ13J7FrnC6uQ<\/p>\n<p>La otra semana me vi obligado a considerar detenidamente lo que el salmista le pide a Dios que haga, que en muchos sentidos es o deber\u00eda ser el coraz\u00f3n de nuestras oraciones a Dios.<\/p>\n<p>\u201cLev\u00e1ntate, oh Dios, defiende tu propia causa\u201d (Salmo 74:22 NVI)<\/p>\n<p>Ahora bien, esto es algo que en su mayor\u00eda nos es ajeno, es decir, , pidiendo que Dios defienda su causa, porque normalmente le pedimos a Dios que defienda nuestra causa, y derrote a los que vienen contra nosotros.<\/p>\n<p>\u201cDefiende mi causa, oh Se\u00f1or, con los que luchan conmigo; lucha contra los que luchan contra m\u00ed. Echa mano del escudo y del pav\u00e9s, y lev\u00e1ntate en mi ayuda. (Salmo 35:1-2 NVI)<\/p>\n<p>\u201cHazme justicia, oh Dios, y defiende mi causa contra una naci\u00f3n imp\u00eda; \u00a1Oh, l\u00edbrame del hombre enga\u00f1oso e injusto! (Salmo 43:1 NVI)<\/p>\n<p>Pero no es as\u00ed en nuestro pasaje, aqu\u00ed el pueblo de Dios, que probablemente le pidi\u00f3 a Dios que defendiera su causa cuando estos invasores extranjeros vinieron contra ellos y los tomaron cautivos, ahora le est\u00e1n pidiendo a Dios que defienden Su causa, porque saben que las promesas de Dios se mantienen, por lo que b\u00e1sicamente est\u00e1n diciendo: \u00abOye, Se\u00f1or, cumple Tu promesa\u00bb o \u00abDefiende Tu causa\u00bb.<\/p>\n<p>Al final de nuestro tiempo juntos, aclarar\u00e9 c\u00f3mo se ve esto.<\/p>\n<p>Ahora, el Salmo 74 se\u00f1ala el tiempo que sigui\u00f3 a la destrucci\u00f3n de la naci\u00f3n de Israel, que incluir\u00eda las diez tribus del norte de Israel y las dos tribus del sur. de Israel conocido como Jud\u00e1.<\/p>\n<p>Asiria conquist\u00f3 el reino del norte en el 722 a.C., y Babilonia conquist\u00f3 el reino del sur durante los a\u00f1os 605-587 a.C. El pueblo fue llevado cautivo a tierras extranjeras y a fines del 587 a.C. el templo de Jerusal\u00e9n fue destruido (2 Reyes 25:8-12). Ahora, sin el centro de su vida religiosa, la gente se siente cortada y separada de Dios. Peor que eso, los a\u00f1os de cautiverio los llevaron a dudar de la fidelidad de Dios.<\/p>\n<p>Pero la infidelidad no era de parte de Dios, sino de parte de los pueblos. Ellos fueron los que desobedecieron la ley de Dios y continuaron rebel\u00e1ndose contra \u00c9l. Pero aun as\u00ed, la promesa de Dios ha sido y siempre ser\u00e1 Su causa sin importar lo que hagamos.<\/p>\n<p>\u201cSi somos infieles, \u00c9l permanece fiel; \u00c9l no puede negarse a s\u00ed mismo\u201d. (2 Timoteo 2:13 RVR1960)<\/p>\n<p>De ah\u00ed el clamor del salmista para que Dios se levante y para que \u00c9l abogue, es decir, que defienda su causa.<\/p>\n<p>Y esta es la oraci\u00f3n del salmista del Salmo 74.<\/p>\n<p>&#183; En los vers\u00edculos 1-3, el pueblo invit\u00f3 a Dios a ir e inspeccionar las ruinas de la ciudad y el templo. Tal vez eso lo despertar\u00eda a recordar Su pacto y los traer\u00eda de regreso a su tierra natal. Y esto no es diferente para nosotros cuando le pedimos a Dios que nos reviva, es decir, a la iglesia una vez m\u00e1s, porque como se\u00f1alamos con tanto entusiasmo que el mal est\u00e1 floreciendo.<\/p>\n<p>&#183; En los vers\u00edculos 4-9, el salmista describe la profanaci\u00f3n del templo por parte del enemigo, ya que levantaron estandartes a sus dioses y destruyeron el templo, erradicando cualquier indicio de Dios, adem\u00e1s de eliminar a todos los profetas de Dios.<\/p>\n<p>&amp; #183; Y luego en los vers\u00edculos 10-23 es un llamado a actuar en contra de estas atrocidades y silenciar a aquellos que deshonran Su nombre. Y se\u00f1ala cu\u00e1n poderoso es Dios y que nada puede detenerlo. Por lo tanto, la s\u00faplica para que Dios defienda Su causa y rescate a Su pueblo.<\/p>\n<p>Y as\u00ed, llegamos a nuestro vers\u00edculo. \u201cLev\u00e1ntate, oh Dios, defiende tu propia causa\u201d (Salmo 74:22 NVI)<\/p>\n<p>Ahora, primero me gustar\u00eda echar un vistazo a dos palabras que se encuentran en este pasaje.<\/p>\n<p>Levantarse<\/p>\n<p>Levantarse es un llamado a la batalla<\/p>\n<p>El salmista est\u00e1 llamando a Dios a ir a la batalla por ellos, es decir, a ir a la batalla por su pueblo, que es, en el fondo, la causa de Dios, como se ve en este Salmo cuando dice en los primeros vers\u00edculos, \u201clas ovejas de tu prado\u201d, \u201ctu congregaci\u00f3n\u201d y \u201ctribu de tu heredad\u201d.<\/p>\n<p>La realidad es que la batalla, mientras nos unimos, es realmente la batalla de Dios y \u00c9l nos llama a seguir adelante y tomar posesi\u00f3n de lo que \u00c9l ya ha ganado.<\/p>\n<p>Al Rey Josafat sobre la pr\u00f3xima batalla contra Moab y Am\u00f3n, cuyo ej\u00e9rcito era mucho m\u00e1s grande que el de Jud\u00e1, el Se\u00f1or dijo: \u201cNo tem\u00e1is ni desmay\u00e9is a causa de esta gran multitud, porque la batalla no es vuestra, sino de Dios\u201d. (2 Cr\u00f3nicas 20:15b NVI)<\/p>\n<p>Al final, el enemigo luch\u00f3 contra s\u00ed mismo, e Israel simplemente entr\u00f3 despu\u00e9s y recogi\u00f3 el bot\u00edn, y dice que les tom\u00f3 tres d\u00edas hacerlo. .<\/p>\n<p>Vemos esto mismo a lo largo de las Escrituras, es decir, la batalla es finalmente de Dios, porque el enemigo no viene contra nosotros tanto como viene contra Dios.<\/p>\n<p>Pero esto se pone claramente de manifiesto a trav\u00e9s de lo que el Se\u00f1or dijo por medio del profeta Zacar\u00edas, en que es nadie menos que el Se\u00f1or quien pelea nuestras batallas.<\/p>\n<p>\u201c&#8217;No con ej\u00e9rcito ni con poder, sino con Esp\u00edritu m\u00edo&#8217;, dice el Se\u00f1or de los ej\u00e9rcitos\u201d. (Zacar\u00edas 4:6 NVI)<\/p>\n<p>La siguiente parte de este vers\u00edculo a la que me gustar\u00eda que prestemos atenci\u00f3n es cuando le pidi\u00f3 a Dios que \u00ababogue\u00bb por su causa.<\/p>\n<p>Abogar <\/p>\n<p>Abogar significa esforzarse o contender. A uno se le ocurre la idea de dar una defensa de lo que cree.<\/p>\n<p>Pero al pedirle a Dios que defienda Su causa frente a tal devastaci\u00f3n y destrucci\u00f3n, b\u00e1sicamente significa que le est\u00e1n pidiendo que defienda Su causa por cualquier medio. los medios son necesarios.<\/p>\n<p>Por eso algunas traducciones dicen: \u201cLev\u00e1ntate, oh Dios, y defiende tu causa\u201d<\/p>\n<p>Pues, porque est\u00e1 en juego el honor de Dios. Vemos esto mismo cuando el Se\u00f1or le dijo al profeta Ezequiel: \u201cAs\u00ed dice el Se\u00f1or Dios: &#8216;No hago esto por ustedes, oh casa de Israel, sino por mi santo nombre, que ustedes tienen. profanado entre las naciones adonde fuisteis.&#8217;\u201d (Ezequiel 36:22 NVI)<\/p>\n<p>Y as\u00ed, el salmista le pide a Dios que defienda su causa, es decir, la causa de Dios porque el honor de Dios y el honor de su nombre est\u00e1 en juego.<\/p>\n<p>Y Dios est\u00e1 mirando para ver si entraremos en Su causa y pelearemos estas batallas. Vemos esto y cu\u00e1n complacido estaba Dios con David, y cuando David se uni\u00f3 a la causa de Dios, se logr\u00f3 una gran victoria. Fue cuando David grit\u00f3 cuando el gigante Goliat desafi\u00f3 a Israel, y por lo tanto desafi\u00f3 a Dios.<\/p>\n<p>David dijo: \u201c\u00bfNo hay una causa?\u201d (1 Samuel 17:29 NVI)<\/p>\n<p>Y cuando se enfrent\u00f3 a Goliat, dijo: \u201cT\u00fa vienes a m\u00ed con espada, lanza y jabalina. Mas yo vengo a vosotros en el nombre del Se\u00f1or de los ej\u00e9rcitos, el Dios de los escuadrones de Israel, a quien vosotros hab\u00e9is provocado. El Se\u00f1or te entregar\u00e1 hoy en mi mano\u201d. (1 Samuel 17:45-46 NKJV)<\/p>\n<p>Cuando miramos a nuestro alrededor y vemos las cosas que est\u00e1n pasando, como esta pandemia de COVID-19 y la guerra actual entre Rusia y Ucrania, hay una pregunta t\u00e1cita , y eso es, \u201c\u00bfQu\u00e9 est\u00e1 tramando Dios?\u201d \u201c\u00bfCu\u00e1l es la causa de Dios?\u201d Y luego, \u00ab\u00bfC\u00f3mo encajo en Su causa por este mundo?\u00bb<\/p>\n<p>Lo que Dios har\u00e1 es que cuando entremos en la fe en Jesucristo, \u00c9l colocar\u00e1 dentro de nosotros el Esp\u00edritu Santo que nos dar\u00e1 d\u00e1ndonos el coraje y la fuerza para seguir Su palabra y mandamientos.<\/p>\n<p>\u201cPondr\u00e9 Mi Esp\u00edritu dentro de ti y te har\u00e9 caminar en Mis estatutos, y guardar\u00e1s Mis juicios y los cumplir\u00e1s. (Ezequiel 36:27 NVI)<\/p>\n<p>Y vemos esto mismo cuando Pablo le dice a la Iglesia de Corinto: \u201c\u00bfNo sab\u00e9is que vuestro cuerpo es templo del Esp\u00edritu Santo que est\u00e1 en vosotros, a quien vosotros tienes de Dios, y no eres tuyo? Porque hab\u00e9is sido comprados por precio; glorificad, pues, a Dios en vuestro cuerpo y en vuestro esp\u00edritu, los cuales son de Dios.\u201d (1 Corintios 6:19-20 NVI)<\/p>\n<p>Esto me lleva exactamente a lo que hizo el salmista, y eso es la oraci\u00f3n.<\/p>\n<p>La oraci\u00f3n de fe<\/p>\n<p>La maravilla de este salmo es la oraci\u00f3n del salmista. Nada iba bien; fue uno de los per\u00edodos m\u00e1s dolorosos de la historia de Israel; pero el salmista continu\u00f3 apelando a Dios, hasta la \u00faltima palabra.<\/p>\n<p>Mirando esto, considere la par\u00e1bola de Jes\u00fas del juez injusto, que estaba destinada a ense\u00f1arnos a orar siempre y no desanimarnos en el proceso, es decir, no rendirse. Una par\u00e1bola es sobre una viuda que vendr\u00eda todos los d\u00edas a defender su caso ante el juez, y finalmente \u00c9l concedi\u00f3 su pedido.<\/p>\n<p>En la historia, el juez dijo: \u201cAunque no temo a Dios ni mira hombre, pero porque esta viuda me es molesta, le har\u00e9 justicia, no sea que viniendo de continuo me canse. Entonces el Se\u00f1or dijo: &#8216;Escucha lo que dijo el juez injusto. \u00bfY acaso Dios no vengar\u00e1 a sus escogidos que claman a \u00e9l d\u00eda y noche, aunque les sea tolerante? os digo que pronto se vengar\u00e1 de ellos&#8217;.\u201d (Lucas 18:4b-8a NVI)<\/p>\n<p>Y de la misma manera necesitamos seguir orando, intercediendo por la causa de Dios, y eso es para Su honor, y para que Su gloria se revele en nuestras vidas y en el mundo.<\/p>\n<p>Mientras observo esta s\u00faplica por parte del salmista, pienso en lo que Jes\u00fas les dijo a sus disc\u00edpulos acerca de c\u00f3mo orar.<\/p>\n<p>\u201cPadre nuestro que est\u00e1s en los cielos, santificado sea tu nombre. Venga tu reino. H\u00e1gase tu voluntad en la tierra como en el cielo. Danos hoy nuestro pan de cada d\u00eda. Y perd\u00f3nanos nuestras deudas, como nosotros perdonamos a nuestros deudores. Y no nos dejes caer en tentaci\u00f3n, mas l\u00edbranos del maligno. Porque tuyo es el reino y el poder y la gloria por siempre. Am\u00e9n.\u00bb (Mateo 6:9-13 NVI)<\/p>\n<p>&#183; Ahora bien, aunque nuestra primera respuesta a Dios siempre debe ser honrarlo y glorificarlo, y buscar su causa sobre la nuestra, \u201cPadre nuestro que est\u00e1s en los cielos, santificado sea tu nombre. Venga tu reino. H\u00e1gase tu voluntad en la tierra como en el cielo\u201d. (Vers\u00edculos 9-10)<\/p>\n<p>&#183; Hay muchas necesidades que tenemos, y tambi\u00e9n debemos ped\u00edrselas a Dios. \u00abDanos hoy nuestro pan de cada d\u00eda.\u00bb (Verso 11)<\/p>\n<p>&#183; Tambi\u00e9n vemos que debemos orar por aquellas cosas que Dios nos ha llamado a hacer. \u201cY perd\u00f3nanos nuestras deudas, as\u00ed como nosotros perdonamos a nuestros deudores\u201d. (Verso 12).<\/p>\n<p>&#183; Y hay muchos enemigos de los que debemos buscar la protecci\u00f3n de Dios y que \u00c9l vencer\u00eda, lo cual, como hemos visto, est\u00e1 ligado a lo que dice el salmista. Pero aqu\u00ed Jes\u00fas nos dice que oremos: \u201cY no nos dejes caer en tentaci\u00f3n, mas l\u00edbranos del maligno\u201d. (Verso 13)<\/p>\n<p>En esencia, el Se\u00f1or nos est\u00e1 llamando a interceder en Su nombre por Su causa. Es como se\u00f1al\u00e9 anteriormente que Dios nos llama a ser sus instrumentos en esta batalla.<\/p>\n<p>La fuerza para hacer todo esto solo puede venir a trav\u00e9s del poder del Esp\u00edritu Santo, y la misericordia y la gracia de Dios. el Padre, que es el Dios de todas las misericordias.<\/p>\n<p>La Causa de Dios<\/p>\n<p>Su Creaci\u00f3n<\/p>\n<p>Ahora, por Su Creaci\u00f3n quiero decir, t\u00fa y yo. Este fue el clamor del salmista a Dios, y en el comienzo del Salmo vemos esta causa.<\/p>\n<p>\u201cOh Dios, \u00bfpor qu\u00e9 nos has desechado para siempre? \u00bfPor qu\u00e9 humea tu ira contra las ovejas de tu prado? Acu\u00e9rdate de tu congregaci\u00f3n, la que compraste desde el principio, la tribu de tu heredad, la que redimiste. (Salmo 74:1-2 NVI)<\/p>\n<p>La causa de Dios era entonces por Su pueblo, es decir, t\u00fa y yo, y lo vemos en lo que leemos, \u201cdesechadnos\u201d, \u201clas ovejas de tu pasto\u201d \u201ctu congregaci\u00f3n\u201d \u201ctribu de tu heredad\u201d. La causa de Dios es entonces por Su pueblo, aunque ellos y nosotros le hayamos desobedecido y rebelado contra \u00c9l.<\/p>\n<p>Pero como vemos a trav\u00e9s de la palabra de Dios, Su causa no fue solo por Su pueblo y su protecci\u00f3n del maligno , como dijo Jes\u00fas en la oraci\u00f3n del disc\u00edpulo: \u201cY no nos dejes caer en la tentaci\u00f3n, mas l\u00edbranos del maligno\u201d, sino tambi\u00e9n para toda la humanidad, y es que todos hemos sido hechos a su imagen y conforme a su semejanza. .<\/p>\n<p>Fue por esta causa que Dios se levant\u00f3 y envi\u00f3 a Su Hijo, Jesucristo, a morir por nosotros para que pudi\u00e9ramos tener vida eterna con \u00c9l.<\/p>\n<p>\u201cPorque de tal manera am\u00f3 Dios el mundo que ha dado a su Hijo unig\u00e9nito, para que todo aquel que en \u00e9l cree no se pierda, mas tenga vida eterna.\u201d (Juan 3:16 NVI)<\/p>\n<p>Y aunque Jes\u00fas gan\u00f3 la batalla all\u00ed sobre la cruz, y la sell\u00f3 en la resurrecci\u00f3n, todav\u00eda nos llama a entrar en esta batalla con \u00c9l. Y vemos esto en la Gran Comisi\u00f3n dada por Jes\u00fas.<\/p>\n<p>Despu\u00e9s de su resurrecci\u00f3n, Jes\u00fas dijo: \u201cToda potestad me es dada en el cielo y en la tierra. Id, pues, y haced disc\u00edpulos a todas las naciones, bautiz\u00e1ndolos en el nombre del Padre y del Hijo y del Esp\u00edritu Santo, ense\u00f1\u00e1ndoles a guardar todas las cosas que os he mandado\u201d. (Mateo 28:18-20 NVI)<\/p>\n<p>Y as\u00ed, la Causa de Dios para Su Creaci\u00f3n est\u00e1 envuelta en Su pacto, tanto el Antiguo como el Nuevo. Vemos que se habla de esto en el Salmo 74 cuando el pueblo, en el vers\u00edculo 20, le pidi\u00f3 al Se\u00f1or que recordara Su pacto.<\/p>\n<p>Pero el pueblo realmente no pod\u00eda entrar y guardar el pacto de Dios.<\/p>\n<p> &gt;\u201cHe aqu\u00ed que vienen d\u00edas, dice Jehov\u00e1, en que har\u00e9 un nuevo pacto\u2026 no como el pacto que hice con sus padres el d\u00eda que los tom\u00e9 de la mano para sacarlos de la tierra de Egipto, mi pacto que ellos violaron&#8230; Pero este es el pacto que har\u00e9&#8230; Pondr\u00e9 mi ley en su mente, y la escribir\u00e9 en su coraz\u00f3n; y yo ser\u00e9 a ellos por Dios, y ellos me ser\u00e1n a m\u00ed por pueblo. (Jerem\u00edas 31:31-33 NVI)<\/p>\n<p>Debido a que el pueblo quebrant\u00f3 el antiguo pacto, la Ley de Mois\u00e9s, Dios defendi\u00f3 su causa enviando a Jes\u00fas para ser el mediador del nuevo pacto que \u00c9l mismo promulg\u00f3 sobre nuestros esto es, por nosotros.<\/p>\n<p>\u201cPor tanto, \u00c9l (Jes\u00fas) es el Mediador del nuevo pacto, por medio de muerte, para la remisi\u00f3n de las transgresiones bajo el primer pacto, para que aquellos los que son llamados reciban la promesa de la herencia eterna.\u201d (Hebreos 9:15 NVI)<\/p>\n<p>Ahora, adem\u00e1s de usted y yo y el Nuevo Pacto que Dios promulg\u00f3, otra causa fue para Su reino.<\/p>\n<p>Su Reino<\/p>\n<p>El reino de Dios es una de las principales causas de Dios, lo cual se ve en la oraci\u00f3n de Jes\u00fas. \u201cVenga tu reino. H\u00e1gase tu voluntad en la tierra como en el cielo\u201d. (Mateo 6:10 NVI)<\/p>\n<p>Y as\u00ed, que el reino de Dios venga es Su voluntad en la tierra como lo es en el cielo, y por lo tanto Su causa.<\/p>\n<p>Ahora, el reino de Dios est\u00e1 dondequiera que Dios est\u00e9. Y cuando Jes\u00fas estuvo aqu\u00ed en la tierra, entonces fue el Reino de Dios.<\/p>\n<p>Jes\u00fas dijo: \u201cPero si con el dedo de Dios echo fuera demonios, ciertamente el reino de Dios ha llegado a vosotros\u201d. (Lucas 11:20 NVI)<\/p>\n<p>Y Marcos nos registra que Jes\u00fas vino predicando el evangelio diciendo: \u201cEl tiempo se ha cumplido, y el reino de Dios se ha acercado. Arrepent\u00edos y creed en el evangelio\u201d. (Marcos 1:15 NVI)<\/p>\n<p>Y eso es clave para nosotros hoy, mientras Jes\u00fas no est\u00e1 con nosotros f\u00edsicamente en la tierra, el reino de Dios todav\u00eda est\u00e1 aqu\u00ed. Est\u00e1 aqu\u00ed en el coraz\u00f3n y en el alma de cada creyente, es decir, el Reino de Dios est\u00e1 dentro de nosotros.<\/p>\n<p>Jes\u00fas dijo: \u201cEl que me ama, mi palabra guardar\u00e1; y Mi Padre lo amar\u00e1, y vendremos a \u00e9l y haremos Nuestra morada con \u00e9l.\u201d (Juan 14:23 NVI)<\/p>\n<p>Y una vez m\u00e1s, Jes\u00fas nos pide que entremos en esta batalla justo despu\u00e9s de haber ense\u00f1ado a sus disc\u00edpulos a orar.<\/p>\n<p>\u201cPero busquen primero el reino de Dios y su justicia, y todas estas cosas os ser\u00e1n a\u00f1adidas\u201d. (Mateo 6:33 NVI)<\/p>\n<p>Ahora, hay algo aqu\u00ed que necesitamos ver, y es que la justicia est\u00e1 en el coraz\u00f3n del reino de Dios. Pero como todos sabemos, ya que tenemos dentro de nosotros la naturaleza de pecado, la justicia que define el reino de Dios no es nuestra justicia, sino que es la justicia de Cristo que reside dentro de nosotros.<\/p>\n<p>Por lo tanto, el Reino de Dios y la justicia de Cristo est\u00e1 viva dentro de nosotros, y lo que esto significa es que siendo el Reino de Dios una de las principales causas de Dios, nosotros, en quienes reside el Se\u00f1or Jes\u00fas y Su justicia, somos la causa de Dios y por lo tanto la causa le estamos pidiendo que interceda.<\/p>\n<p>El ap\u00f3stol Juan revela a Jes\u00fas intercediendo por su causa, que es nuestra santificaci\u00f3n cuando dijo: \u201cEstas cosas os escribo para que no pequ\u00e9is. Y si alguno peca, Abogado tenemos para con el Padre, a Jesucristo el justo.\u201d (1 Juan 2:1 NVI)<\/p>\n<p>Ahora bien, en el idioma griego la palabra \u201cabogado\u201d, significa uno que viene al lado, uno que viene en ayuda e intercede por otro, es decir, hablan en nombre de otra persona. Y as\u00ed, Jes\u00fas es quien ahora habla en nuestro nombre contra las acusaciones presentadas contra nosotros por Satan\u00e1s.<\/p>\n<p>En esencia, Jes\u00fas est\u00e1 abogando por Su causa, la causa por la que vino a esta tierra, y esa es morir para acabar con el pecado y la muerte, morir en nuestro lugar. Por lo tanto, una vez m\u00e1s, nosotros, es decir, t\u00fa y yo, somos la causa de Dios, porque el Reino de Dios hoy reside dentro de nosotros.<\/p>\n<p>Y as\u00ed, como vemos dentro de estas dos primeras causas, es decir, La creaci\u00f3n de Dios y el reino de Dios, estamos en el coraz\u00f3n de la causa de Dios por la que le pedimos que interceda.<\/p>\n<p>Su Iglesia<\/p>\n<p>En nuestro Salmo, el escritor le pide a Dios que camine a trav\u00e9s del ruinas de la ciudad y ver como el enemigo ha destruido el templo de Dios, el lugar donde el pueblo de Dios se reun\u00eda para adorarle.<\/p>\n<p>Y para m\u00ed esto describe a la iglesia porque la iglesia es el lugar donde el pueblo de Dios se reun\u00eda para adorarlo \u00c9l.<\/p>\n<p>Y este es el clamor del pueblo de Dios hoy, es decir, restaurar la iglesia a lo que Dios ha llamado a ser. Esto es lo que estamos haciendo cuando clamamos a Dios para que nos reviva. Y lo que vemos es que es dentro de la iglesia donde tambi\u00e9n habita el reino de Dios.<\/p>\n<p>Vemos esto en lo que Jes\u00fas dijo: \u201cPorque donde est\u00e1n dos o tres reunidos en mi nombre, all\u00ed estoy yo en el medio de ellos.\u201d (Mateo 18:20 NVI)<\/p>\n<p>Recuerden, donde est\u00e1 Jes\u00fas, all\u00ed est\u00e1 el Reino de Dios.<\/p>\n<p>Pero no solo est\u00e1 Jes\u00fas en medio de la iglesia, sino que \u00c9l es el cabeza de \u00e9l tambi\u00e9n. A la iglesia de Colosenses el Ap\u00f3stol Pablo dijo que Jes\u00fas es la cabeza del cuerpo, la iglesia. Y a la iglesia en \u00c9feso, dijo que Dios el Padre ha puesto todas las cosas bajo los pies de Jes\u00fas, haci\u00e9ndolo la cabeza sobre todas las cosas pertenecientes a la iglesia. Y a Pedro, Jes\u00fas le dijo que \u00c9l, es decir, Jes\u00fas, edificar\u00eda Su iglesia, y las puertas del infierno no prevalecer\u00e1n contra ella.<\/p>\n<p>Y as\u00ed, el establecimiento de la iglesia, y su funci\u00f3n aqu\u00ed sobre la tierra es otra de las causas de Dios.<\/p>\n<p>Y una vez m\u00e1s nosotros, como Su pueblo, somos llamados a la batalla por ella.<\/p>\n<p>\u201cY consider\u00e9monos unos a otros para levantando el amor y las buenas obras, no dejando de congregarnos, como algunos tienen por costumbre, sino exhort\u00e1ndonos, y tanto m\u00e1s cuanto veis que aquel d\u00eda se acerca.\u201d (Hebreos 10:24-25 NVI)<\/p>\n<p>Pero lo que me gustar\u00eda que veamos en esta causa es que una vez m\u00e1s nosotros como pueblo de Dios somos la causa de Dios, porque Jes\u00fas est\u00e1 en medio de la iglesia. donde nosotros como creyentes venimos a adorarlo.<\/p>\n<p>Conclusi\u00f3n<\/p>\n<p>Y as\u00ed, el Se\u00f1or nos ha llamado a todos a la oraci\u00f3n, especialmente viendo el tiempo en que estamos, con temor, enga\u00f1o, y la guerra aumenta en todo el mundo. Y en nuestra oraci\u00f3n, necesitamos pedirle a Dios que una vez m\u00e1s abogue por Su causa, y eso es por la redenci\u00f3n y protecci\u00f3n de Su pueblo y Su iglesia.<\/p>\n<p>Y amo entonces lo que el Se\u00f1or nos dijo a trav\u00e9s de el profeta Jerem\u00edas.<\/p>\n<p>\u201cPor tanto, as\u00ed dice el Se\u00f1or: &#8216;He aqu\u00ed, yo defender\u00e9 tu caso&#8217;\u201d (Jerem\u00edas 51:36a NVI)<\/p>\n<p>Y por lo tanto, al pedirle a Dios que defienda Su causa es, en esencia, pedirle a Dios que defienda nuestra causa. Entonces, no necesitamos irnos de aqu\u00ed hoy sinti\u00e9ndonos culpables por pedirle a Dios que defienda nuestra causa, porque nuestra causa es Su causa, y luego Su causa es nuestra causa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La causa de Dios para nuestro mundo Salmo 74:22 Ver: https:\/\/studio.youtube.com\/ video\/h-WkxN1Y4XU\/edit?c=UCnsKqgXUXKLZ13J7FrnC6uQ La otra semana me vi obligado a considerar detenidamente lo que el salmista le pide a Dios que haga, que en muchos sentidos es o deber\u00eda ser el coraz\u00f3n de nuestras oraciones a Dios. \u201cLev\u00e1ntate, oh Dios, defiende tu propia causa\u201d (Salmo 74:22 &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/la-causa-de-dios-para-nuestro-mundo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa causa de Dios para nuestro mundo\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3945","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/3945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=3945"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/3945\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=3945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=3945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=3945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}