{"id":39722,"date":"2022-09-22T11:00:54","date_gmt":"2022-09-22T16:00:54","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/estudio-biblico-mateo-primera-parte\/"},"modified":"2022-09-22T11:00:54","modified_gmt":"2022-09-22T16:00:54","slug":"estudio-biblico-mateo-primera-parte","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/estudio-biblico-mateo-primera-parte\/","title":{"rendered":"Estudio b\u00edblico: Mateo (primera parte)"},"content":{"rendered":"<p> Estudio b\u00edblico: Mateo (primera parte) <\/p>\n<h3>\u00c9nfasis de Mateo en el reinado de Jes\u00fas y las ra\u00edces jud\u00edas<br \/> #BS-MA01<br \/> John W. Ritenbaugh <br \/>Dado 15-jul-81; 82 minutos <\/h3>\n<p> Vaya a Mateo (serie de estudios b\u00edblicos)  <\/p>\n<p>descripci\u00f3n: (ocultar) Mateo es parte de los evangelios sin\u00f3pticos (\u00abver juntos\u00bb), en gran parte un adorno del bosquejo m\u00e1s conciso de eventos b\u00e1sicos que se encuentran en Marcos. Evidentemente, tanto Mateo como Lucas estaban destinados a audiencias diferentes, con la intenci\u00f3n de exponer o ampliar principios doctrinales espec\u00edficos. Mateo, un publicano meticuloso, bien educado y bien organizado, parec\u00eda ser el principal responsable de recopilar y sistematizar los dichos espec\u00edficos de Jes\u00fas. Mateo escribi\u00f3 su relato pensando en el pueblo jud\u00edo, diciendo repetidamente: \u00abEsto se hizo para cumplir a los profetas\u00bb. enfatizando la ley y el Reino de Dios, as\u00ed como una genealog\u00eda detallada que demuestra su linaje desde el rey David y Abraham, incluyendo gentiles y mujeres antepasadas, legitimando la realeza de Jes\u00fas y su nacimiento virginal, concebido por el Esp\u00edritu Santo, el poder creador de Dios. Jes\u00fas ten\u00eda por lo menos siete hermanos, medios hermanos y hermanas. Lucas, un gentil, nunca incluy\u00f3 estos detalles. [NB: Esta serie de Estudios B\u00edblicos de 1981-82 est\u00e1 incompleta.] <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudio b\u00edblico: Mateo (primera parte) \u00c9nfasis de Mateo en el reinado de Jes\u00fas y las ra\u00edces jud\u00edas #BS-MA01 John W. Ritenbaugh Dado 15-jul-81; 82 minutos Vaya a Mateo (serie de estudios b\u00edblicos) descripci\u00f3n: (ocultar) Mateo es parte de los evangelios sin\u00f3pticos (\u00abver juntos\u00bb), en gran parte un adorno del bosquejo m\u00e1s conciso de eventos b\u00e1sicos &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/estudio-biblico-mateo-primera-parte\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio b\u00edblico: Mateo (primera parte)\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39722","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/39722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=39722"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/39722\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=39722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=39722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=39722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}