{"id":3975,"date":"2022-08-18T04:14:32","date_gmt":"2022-08-18T09:14:32","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/liberacion-divina\/"},"modified":"2022-08-18T04:14:32","modified_gmt":"2022-08-18T09:14:32","slug":"liberacion-divina","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/liberacion-divina\/","title":{"rendered":"Liberaci\u00f3n divina"},"content":{"rendered":"<p>Salmo 91:15, dice: \u201c\u00c9l me invocar\u00e1, y yo le responder\u00e9; estar\u00e9 con \u00e9l en la angustia; Yo lo librar\u00e9 y lo honrar\u00e9\u201d. (AFV)<\/p>\n<p>A medida que continuamos nuestra meditaci\u00f3n basada en el Salmo 91, nos detendremos en el aspecto de Dios que nos libera en este estudio.<\/p>\n<p>Los israelitas se multiplicaron grandemente<\/p>\n<p>Leemos en \u00c9xodo 1:7, \u201cY los hijos de Israel fueron fecundos, y crecieron mucho, y se multiplicaron, y se hicieron muy poderosos. Y la tierra se llen\u00f3 de ellos.\u201d (AFV)<\/p>\n<p>El pueblo de Israel que son los descendientes de Abraham, habitaron en la tierra de Egipto. Hay tres palabras en el vers\u00edculo mencionado anteriormente que describen mejor al pueblo de Israel mientras habitaban en la tierra de Egipto, fueron fruct\u00edferos, crecieron, se multiplicaron y tambi\u00e9n fueron extremadamente poderosos. La raz\u00f3n de este aumento fue que Dios hab\u00eda hecho un pacto con sus antepasados Abraham, Isaac y Jacob de que esto ser\u00eda as\u00ed, y Dios fue fiel en cumplirlo.<\/p>\n<p>Aqu\u00ed est\u00e1 la promesa de Dios como se menciona en G\u00e9nesis 17:6, \u201cY te har\u00e9 fecundo en gran manera,\u201d (AFV)<\/p>\n<p>Por lo tanto, como la bendici\u00f3n de Dios permaneci\u00f3 sobre los israelitas, fue evidente en la forma en que crecieron y crecieron en fuerza para fuerza. Fara\u00f3n, el rey de Egipto no estaba muy complacido con este incremento en la poblaci\u00f3n de los israelitas y quer\u00eda impedirlo de alguna manera. De lo que Fara\u00f3n no se dio cuenta fue que este crecimiento se debi\u00f3 enteramente a que la mano del Se\u00f1or estaba sobre ellos.<\/p>\n<p>El profeta Isa\u00edas lo dice de esta manera en Isa\u00edas 14:27, \u201cPorque Jehov\u00e1 de los ej\u00e9rcitos ha determinado, \u00bfy qui\u00e9n lo revertir\u00e1? Y su mano est\u00e1 extendida, \u00bfy qui\u00e9n la har\u00e1 retroceder? (AFV)<\/p>\n<p>Tengamos la seguridad de que los planes y prop\u00f3sitos que Dios ha decidido cumplir a trav\u00e9s de nosotros, nunca podr\u00e1n ser frustrados por ning\u00fan hombre ni ninguna autoridad en la tierra.<\/p>\n<p>Fara\u00f3n esquemas para sofocar el crecimiento<\/p>\n<p>\u2022 El primer complot<\/p>\n<p>Leemos en \u00c9xodo 1:10-11: \u201cDebemos hacer planes para evitar que crezcan m\u00e1s fuertes. \u00a1Si hay una guerra, podr\u00edan unirse a nuestros enemigos, derrotarnos y escapar de la tierra! Los egipcios decidieron hacerles la vida dif\u00edcil a los israelitas, por lo que pusieron amos de esclavos sobre el pueblo. Estos amos obligaron a los israelitas a construir las ciudades de Pitom y Rams\u00e9s para el rey. El rey us\u00f3 estas ciudades para almacenar grano y otras cosas.\u201d(ERV)<\/p>\n<p>La primera trampa del fara\u00f3n fue convertir a los israelitas en esclavos de los egipcios, someti\u00e9ndolos as\u00ed a trabajos forzados y tambi\u00e9n aplastando sus esp\u00edritus. Us\u00f3 a los israelitas para trabajar muy duro y construir las ciudades de Pitom y Rams\u00e9s.<\/p>\n<p>A pesar de todo lo que hizo Fara\u00f3n, este fue el resultado, como se registra en \u00c9xodo 1:12: \u201cLos egipcios obligaron a los israelitas a trabajar m\u00e1s y m\u00e1s duro. Pero cuanto m\u00e1s trabajaban, m\u00e1s crec\u00edan y se extend\u00edan, y m\u00e1s les ten\u00edan miedo los egipcios\u201d. (ERV)<\/p>\n<p>Cuanto m\u00e1s Fara\u00f3n intentaba reprimirlos, los israelitas se hac\u00edan m\u00e1s fuertes y se convert\u00edan en una fuerza con la que Fara\u00f3n no pod\u00eda contar. Esto fue simplemente porque la mano del Se\u00f1or estaba con los israelitas y el poderoso poder de Dios no fue rival para los planes astutos del Fara\u00f3n.<\/p>\n<p>Como hijos de Dios, nosotros tambi\u00e9n podemos enfrentar planes malvados de aquellos que buscan nuestra ruina. Sin embargo, nunca debemos tener miedo ni desanimarnos, porque podemos estar seguros de que los prop\u00f3sitos de Dios siempre prevalecer\u00e1n sobre todos los planes malvados de los hombres. Esto ser\u00e1 aplicable a cualquiera que haya hecho de Dios su fortaleza. En medio de toda nuestra aflicci\u00f3n podemos estar seguros que Dios nos dar\u00e1 el crecimiento y la fortaleza para superar todos los desaf\u00edos que encontremos.<\/p>\n<p>La iglesia primitiva es un gran ejemplo de aquellos que triunfaron sobre tales oposiciones. que fueron confrontados.<\/p>\n<p>En Hechos 11:21, leemos: \u201cY la mano del Se\u00f1or estaba con ellos, y muchos creyeron y se convirtieron al Se\u00f1or\u201d. (AFV)<\/p>\n<p>La mano del Se\u00f1or estaba con la iglesia primitiva y por lo tanto, ninguna animosidad o resistencia de los hombres pod\u00eda impedir su crecimiento y expansi\u00f3n.<\/p>\n<p>El secreto de nuestra vida victoriosa es que la mano del Se\u00f1or permanezca con nosotros. Si esto es as\u00ed, podemos estar seguros de que podemos superar cada desaf\u00edo<\/p>\n<p>\u2022 La segunda trama<\/p>\n<p>Leemos en \u00c9xodo 1:15-16, \u201cY el rey de Egipto habl\u00f3 a las parteras hebreas, de las cuales el nombre de una era Sifra, y el nombre de la otra Puah. Y \u00e9l dijo: Cuando des de parte a las hebreas, y mires las heces de parto, si es var\u00f3n, entonces lo matar\u00e1s. Pero si es una hija, entonces vivir\u00e1.\u201d\u201d (AFV)<\/p>\n<p>El segundo plan del fara\u00f3n era m\u00e1s cruel en el que quer\u00eda destruir a todos los beb\u00e9s varones, evitando as\u00ed que la poblaci\u00f3n creciera. m\u00e1s lejos. Fara\u00f3n orden\u00f3 a las parteras que mataran a los beb\u00e9s varones al nacer, poniendo as\u00ed fin al aumento entre los israelitas.<\/p>\n<p>Esto es lo que sucedi\u00f3 como se registra en \u00c9xodo 1:17, \u201cPero las parteras tem\u00edan a Dios, y no hicieron como les mand\u00f3 el rey de Egipto, sino que dieron vida a los ni\u00f1os varones. (AFV)<\/p>\n<p>Las parteras sin embargo, tem\u00edan m\u00e1s a Dios y no obedecieron la orden del rey y dejaron vivir a los beb\u00e9s. Estoy seguro de que Fara\u00f3n pudo haber sobornado a estas parteras con regalos y ofertas para llevar a cabo su malvado plan. No obstante, estas mujeres estaban tan movidas por el temor piadoso que no pod\u00edan ser tentadas a ser parte del malvado complot de Fara\u00f3n. Hicieron lo recto ante los ojos de Dios.<\/p>\n<p>Esto es lo que les sucedi\u00f3 a estas parteras como resultado de su fidelidad a Dios. Leemos en \u00c9xodo 1:21: \u201cY por cuanto las parteras tem\u00edan a Dios [con profunda reverencia], \u00c9l estableci\u00f3 familias y casas para ellas\u201d. (Amplificado)<\/p>\n<p>El Se\u00f1or bendijo y estableci\u00f3 las familias de estas parteras debido a su temible reverencia hacia \u00c9l. Una vez m\u00e1s, el siguiente esquema del Fara\u00f3n tampoco se materializ\u00f3.<\/p>\n<p>Tambi\u00e9n nosotros debemos tener este sentido de temor y reverencia por Dios. El que teme a Dios no tendr\u00e1 necesidad de temer a ning\u00fan hombre. Recordemos que la palabra de Dios nos asegura que ninguna arma forjada contra nosotros prosperar\u00e1. Cuando estamos seguros bajo la protecci\u00f3n de Dios, nada que est\u00e9 dirigido a nosotros podr\u00e1 vencernos. Muchas personas est\u00e1n en constante temor cuando se enteran de que las personas est\u00e1n conspirando en su contra, pero a tales d\u00e9jenme consolarlos que Dios los mantendr\u00e1 a salvo de todo da\u00f1o y ataques de aquellos que vienen contra ustedes.<\/p>\n<p>\u2022 El tercer complot<\/p>\n<p>Fara\u00f3n no se rindi\u00f3 cuando fracas\u00f3 su segundo plan. Ahora ten\u00eda una tercera que quer\u00eda ejecutar. Cuando las conspiraciones secretas no dieron resultado, Fara\u00f3n tuvo un complot que fue abierto y escandaloso.<\/p>\n<p>En \u00c9xodo 1:22, leemos, Fara\u00f3n mand\u00f3 a todo su pueblo, diciendo: \u201cEchar\u00e9is a todo hijo que nazca en el r\u00edo, ya toda hija la salvar\u00e1s con vida. (WEB)<\/p>\n<p>Esta orden brutal del fara\u00f3n requer\u00eda que todo beb\u00e9 var\u00f3n reci\u00e9n nacido, nacido en la familia israelita, fuera arrojado al r\u00edo Nilo y que s\u00f3lo las ni\u00f1as deb\u00edan ser salvadas. Fue en esta situaci\u00f3n, donde muchas familias perdieron a sus beb\u00e9s y estaban de luto, que naci\u00f3 un beb\u00e9 de una de esas familias israelitas. Los padres de este beb\u00e9, especialmente su madre, ten\u00edan tanta fe en Dios y no temiendo el decreto del rey decidi\u00f3 esconder al beb\u00e9, porque cre\u00eda que Dios pod\u00eda salvar a su beb\u00e9.<\/p>\n<p>Le\u00edmos sobre esto en Hebreos 11:23, \u201cPor la fe Mois\u00e9s, despu\u00e9s que naci\u00f3, fue escondido por sus padres por tres meses, porque le vieron que era un ni\u00f1o hermoso; y no temieron el decreto del rey.\u201d (AFV)<\/p>\n<p>Hay momentos en los que tenemos que mantener algo oculto, ya sea que no se hable o se haga abiertamente. Tambi\u00e9n es importante para nosotros como creyentes hacer todo con fe y sabidur\u00eda.<\/p>\n<p>No tenemos idea de c\u00f3mo estos padres lograron mantener escondido a su beb\u00e9 durante tres meses. Sin embargo, despu\u00e9s de tres meses, cuando no pudieron esconder al beb\u00e9, no tuvieron coraz\u00f3n para arrojar al beb\u00e9 al r\u00edo seg\u00fan la orden del rey. Su fe en Dios a\u00fan era fuerte y esto fue lo que hicieron.<\/p>\n<p>Un beb\u00e9 se salva<\/p>\n<p>Leemos en \u00c9xodo 2:3-6, Pero cuando ella ya no pudo esconderlo m\u00e1s , tom\u00f3 para \u00e9l un arca de papiro, la calafate\u00f3 con bet\u00fan y brea, y puso en ella al ni\u00f1o. Y lo puso entre los juncos a la orilla del r\u00edo. Y su hermana se qued\u00f3 a lo lejos para saber lo que le suceder\u00eda. Y la hija de Fara\u00f3n baj\u00f3 a ba\u00f1arse al r\u00edo. Y sus doncellas paseaban junto al r\u00edo. Y cuando vio el arca entre los juncos, envi\u00f3 a su esclava para que se la trajera. Y ella la abri\u00f3, y vio al ni\u00f1o. Y he aqu\u00ed, un ni\u00f1o lloraba. Y ella tuvo piedad de \u00e9l, y dijo: &quot;Este es uno de los hebreos&quot; hijos.\u201d(AFV)<\/p>\n<p>En lugar de arrojar al beb\u00e9 directamente al r\u00edo, la madre decidi\u00f3 colocarlo en un arca hecha de papiro, habi\u00e9ndola recubierto con brea y brea y luego lo coloc\u00f3 en el r\u00edo Nilo. La hermana del beb\u00e9 se par\u00f3 entre los juncos y cuid\u00f3 al beb\u00e9 en la canasta. Yo creo que la mam\u00e1 del beb\u00e9 puso all\u00ed al ni\u00f1o despu\u00e9s de orar mucho y confiar en que Dios har\u00eda lo necesario para salvar al beb\u00e9. El escenario era perfecto, cuando la hija del fara\u00f3n, la princesa, ven\u00eda con sus doncellas a ba\u00f1arse en el r\u00edo. Al ver este arca, se despert\u00f3 su curiosidad y le llevaron el arca a la princesa, quien al abrirla descubri\u00f3 que en ella hab\u00eda un hermoso beb\u00e9. Cuando el beb\u00e9 llor\u00f3, el coraz\u00f3n de la princesa se derriti\u00f3 y comprendi\u00f3 que se trataba de un beb\u00e9 hebreo.<\/p>\n<p>Es tan asombroso que el tiempo y los caminos de Dios sean asombrosos. Dios estaba en control y era el momento perfecto para que la princesa viniera al r\u00edo, para ver el arca y que el beb\u00e9 realmente llorara en ese momento cuando abri\u00f3 el arca. La princesa se conmovi\u00f3, aunque se dio cuenta de que se trataba de un beb\u00e9 israelita que estaba condenado a muerte.<\/p>\n<p>Fue la princesa quien nombr\u00f3 al beb\u00e9 como Mois\u00e9s diciendo &#8216;Yo lo saqu\u00e9 del agua&#8217;. La hermana del beb\u00e9 Mois\u00e9s, que estaba cuidando al beb\u00e9, se acerc\u00f3 r\u00e1pidamente a la princesa y se ofreci\u00f3 a buscar una mujer para amamantar al beb\u00e9. La hermana de Mois\u00e9s trajo a su propia madre a la princesa, quien le entreg\u00f3 al beb\u00e9 para que lo cuidara hasta que fuera destetado.<\/p>\n<p>El Se\u00f1or espera que hagamos todo lo posible de nuestra parte, tal como lo hizo la madre de Mois\u00e9s. Esas cosas que est\u00e1n m\u00e1s all\u00e1 de nosotros, podemos dejarlas en las manos de Dios y \u00c9l las manejar\u00e1 a Su manera. En las bodas de Can\u00e1, donde Jes\u00fas fue invitado, hubo escasez de vino. El Se\u00f1or mand\u00f3 que las tinajas de piedra se llenaran de agua, la cual cuando se serv\u00eda a los invitados se convert\u00eda en el vino m\u00e1s delicioso. Sin embargo, para que sucediera ese milagro, Jes\u00fas hizo su parte de convertir el agua en vino, pero los hombres tambi\u00e9n tuvieron que hacer su parte de llenar las tinajas con agua.<\/p>\n<p>Los caminos de Dios siempre son asombrosos y van m\u00e1s all\u00e1. a nosotros. Fara\u00f3n plane\u00f3 matar a todos los beb\u00e9s varones hebreos, pero el Se\u00f1or intervino para salvar a un beb\u00e9 nacido en ese mismo momento. Dios no solo protegi\u00f3 al beb\u00e9, sino que hizo que la princesa tomara la custodia del beb\u00e9. El beb\u00e9 Mois\u00e9s fue entregado a su propia madre con total protecci\u00f3n y su madre probablemente recibi\u00f3 un salario para criar al beb\u00e9 hasta que pudiera ser entregado a la princesa. Cuando Mois\u00e9s fue un poco mayor, fue entregado a la princesa y fue criado como el hijo de la hija de Fara\u00f3n en el palacio de Fara\u00f3n. Mois\u00e9s creci\u00f3 como un pr\u00edncipe en el palacio de Fara\u00f3n y cuando era un hombre adulto, Dios llam\u00f3 a Mois\u00e9s y lo us\u00f3 para liberar a su pueblo de la cruel esclavitud de los egipcios. Fara\u00f3n no ten\u00eda ni idea de que aquel a quien Dios usar\u00eda para derrotarlo y liberar a la gran naci\u00f3n de Israel estaba siendo criado en su propio palacio.<\/p>\n<p>\u00bfNo es asombroso que los caminos de Dios sean misteriosos y est\u00e9n m\u00e1s all\u00e1 de nuestros comprensi\u00f3n. Son planes que est\u00e1n mucho m\u00e1s all\u00e1 del pensamiento y la comprensi\u00f3n humana. Los planes de Dios nunca pueden ser derrotados por ninguna estrategia humana. Los prop\u00f3sitos de Dios siempre prevalecer\u00e1n sobre cada situaci\u00f3n. No importa quien se oponga a nosotros, quien hable en contra de nosotros o nos acuse falsamente, o cu\u00e1n peligrosa sea nuestra situaci\u00f3n, Dios intervendr\u00e1 para cambiar nuestras situaciones precarias para convertirlas en aquellas que nos son propicias.<\/p>\n<p>Somos siendo recordado de nuevo el Salmo 91:15, dice: \u201c\u00c9l me invocar\u00e1, y yo le responder\u00e9; estar\u00e9 con \u00e9l en la angustia; Yo lo librar\u00e9 y lo honrar\u00e9\u201d. (AFV)<\/p>\n<p>Dios hizo esto por Mois\u00e9s, cuando lo liber\u00f3, lo salv\u00f3 de problemas y luego lo us\u00f3 para someter a Fara\u00f3n y honr\u00f3 a Mois\u00e9s entre todo el pueblo de Israel. Si nos aferramos a este Dios y lo invocamos, \u00c9l tambi\u00e9n nos librar\u00e1 de toda circunstancia problem\u00e1tica en la que nos encontremos, traer\u00e1 paz en nuestra confusi\u00f3n y ciertamente nos honrar\u00e1 a su debido tiempo.<\/p>\n<p>Pastor F Andrew Dixon<\/p>\n<p>www.goodnewsfriends.net<\/p>\n<p>Transcrito por Sis. Esther Collins<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salmo 91:15, dice: \u201c\u00c9l me invocar\u00e1, y yo le responder\u00e9; estar\u00e9 con \u00e9l en la angustia; Yo lo librar\u00e9 y lo honrar\u00e9\u201d. (AFV) A medida que continuamos nuestra meditaci\u00f3n basada en el Salmo 91, nos detendremos en el aspecto de Dios que nos libera en este estudio. Los israelitas se multiplicaron grandemente Leemos en \u00c9xodo &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/liberacion-divina\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLiberaci\u00f3n divina\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3975","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/3975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=3975"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/3975\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=3975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=3975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=3975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}