{"id":3995,"date":"2022-08-18T04:15:11","date_gmt":"2022-08-18T09:15:11","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/nuestra-salvacion-solo-en-jesus\/"},"modified":"2022-08-18T04:15:11","modified_gmt":"2022-08-18T09:15:11","slug":"nuestra-salvacion-solo-en-jesus","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/nuestra-salvacion-solo-en-jesus\/","title":{"rendered":"Nuestra salvaci\u00f3n s\u00f3lo en Jes\u00fas"},"content":{"rendered":"<p>A medida que avanzamos en el libro de Efesios, nos estamos preparando para la transici\u00f3n de las bendiciones introductorias a la esencia de este libro. Quiero reiterar el tema dominante de Efesios. Eso deber\u00eda ser evidente por el t\u00edtulo de nuestra serie, Solo Jes\u00fas.<\/p>\n<p>La fe cristiana siempre, siempre perder\u00e1 su influencia cuando trate de adaptarse al mundo. Obtienes los resultados opuestos. En estos d\u00edas, muchas iglesias han ca\u00eddo en esta trampa. He asistido a conferencias y le\u00eddo libros que dicen que si quiero hacer crecer una iglesia, todo lo que tengo que hacer es averiguar lo que el mundo quiere y luego llegar al mundo con ese deseo. Adem\u00e1s, les dicen a los l\u00edderes de la iglesia que lo peor que puede hacer una iglesia es actuar como una iglesia.<\/p>\n<p>Aqu\u00ed hay una verdad muy simple: para que alcancemos al mundo, debemos ser iglesia sin concesiones, la iglesia que Cristo llam\u00f3. la Iglesia a ser. Si queremos que el mundo llegue a conocer el asombroso amor y la salvaci\u00f3n de Jes\u00fas, primero debemos aferrarnos a todas las ense\u00f1anzas de Jes\u00fas y hacer lo que manda el Se\u00f1or de la Iglesia. Eso significa que no estamos enfocados en c\u00f3mo entretener a los santos o sorprender al mundo. No estamos enfocados en temas sociales, sino \u00fanicamente en la voluntad de Jes\u00fas de cumplir la Gran Comisi\u00f3n.<\/p>\n<p>Si quieres saber m\u00e1s sobre c\u00f3mo vamos a hacer eso, entonces qu\u00e9date conmigo en este estudiar en Efesios. Este es el libro de instrucciones de Dios sobre lo que debemos hacer como iglesia. No hay una palabra en \u00e9l sobre lo que quiere el mundo. Nada sobre c\u00f3mo participar pol\u00edtica, social y culturalmente. Se trata de c\u00f3mo seguir al Se\u00f1or que es la cabeza de la iglesia, c\u00f3mo ser consumidos con Cristo. Es por eso que la ep\u00edstola comienza esencialmente en el vers\u00edculo 3, \u201cBendito sea el Dios y Padre de nuestro Se\u00f1or Jesucristo, que nos ha bendecido con toda bendici\u00f3n espiritual en los lugares celestiales en Cristo\u201d.<\/p>\n<p>If you can fog un espejo, entonces puedes decir que las cosas no est\u00e1n bien en el mundo. No han estado bien por un tiempo y no est\u00e1n mejorando; est\u00e1n empeorando y van a seguir empeorando. La Biblia nos dice que es una tonter\u00eda creer que las respuestas a estos problemas hechos por el hombre son soluciones hechas por el hombre. La iglesia est\u00e1 en medio de lo que est\u00e1 pasando en nuestro mundo hoy. Estamos en medio de esto porque se\u00f1alamos al mundo la respuesta. Y nuestra responsabilidad no es de alguna manera descubrir c\u00f3mo arreglar el mundo, sino c\u00f3mo proclamar el evangelio que puede liberar a la gente del mundo.<\/p>\n<p>Todo est\u00e1 en Cristo. Se trata de nuestra relaci\u00f3n con Cristo. Se trata de conocerlo, amarlo, adorarlo, proclamarlo y ayudarse unos a otros en el camino para llegar a ser m\u00e1s como \u00c9l. Eso es lo que la iglesia necesita ser. Eso es lo que seremos y, a medida que el mundo se acelere m\u00e1s r\u00e1pidamente hacia el final, estaremos aqu\u00ed para dar la bienvenida a casa a aquellos que buscan respuestas.<\/p>\n<p>Durante las \u00faltimas semanas en nuestra introducci\u00f3n a Efesios hemos visto algunas verdades asombrosas que Pablo comparti\u00f3 al comienzo de Efesios. Vimos las bendiciones que existen solo en Jes\u00fas. Decimos nuestra redenci\u00f3n s\u00f3lo en Jes\u00fas. Vimos nuestra adopci\u00f3n en Jes\u00fas. Vimos nuestra predestinaci\u00f3n en Jes\u00fas y vimos nuestra herencia en Jes\u00fas. Hoy, antes de avanzar hacia c\u00f3mo debemos vivir en estas maravillosas bendiciones, vamos a ver nuestra salvaci\u00f3n que se nos da solo en Jes\u00fas.<\/p>\n<p>15 Por esta raz\u00f3n, porque he o\u00eddo hablar de vuestra fe en el Se\u00f1or Jes\u00fas y vuestro amor por todos los santos, 16 no ceso de dar gracias por vosotros, acord\u00e1ndome de vosotros en mis oraciones, 17 para que el Dios de nuestro Se\u00f1or Jesucristo, el Padre de gloria, os d\u00e9 la Esp\u00edritu de sabidur\u00eda y de revelaci\u00f3n en el conocimiento de \u00e9l, 18 alumbrando los ojos de vuestro coraz\u00f3n, para que sep\u00e1is cu\u00e1l es la esperanza a la cual \u00e9l os ha llamado, cu\u00e1les las riquezas de su gloriosa herencia en los santos, 19 y cu\u00e1l es la inconmensurable grandeza de su poder para con nosotros los que creemos, seg\u00fan la operaci\u00f3n de su gran poder 20 que obr\u00f3 en Cristo cuando lo resucit\u00f3 de entre los muertos y lo sent\u00f3 a su diestra en los lugares celestiales, 21 muy por encima de todo principado y autoridad y poder y se\u00f1or\u00edo, y sobre todo nombre que se nombra, no s\u00f3lo en esta ag e sino tambi\u00e9n en el por venir. 22 Y someti\u00f3 todas las cosas bajo sus pies, y lo dio por cabeza sobre todas las cosas a la iglesia, 23 la cual es su cuerpo, la plenitud de aquel que todo lo llena en todo. (Efesios 1:15-23)<\/p>\n<p>I. Necesitamos una fe creciente en Cristo y amor mutuo (vv.15-16)<\/p>\n<p>Esta \u00faltima secci\u00f3n del Cap\u00edtulo 1 es una oraci\u00f3n de Pablo por la Iglesia de \u00c9feso y las iglesias de todo el mundo. Est\u00e1 lleno de verdad centrada en Cristo. La oraci\u00f3n de Pablo es que la iglesia se centre en comprender plenamente lo que nos ha sido dado a trav\u00e9s de Jes\u00fas y que se encuentra solo en Jes\u00fas. As\u00ed que echemos un vistazo a esa oraci\u00f3n. Vers\u00edculo 15, \u201cPor esta raz\u00f3n\u201d. \u00bfQue raz\u00f3n? \u00bfQu\u00e9 impulsa esta intercesi\u00f3n? Las bendiciones incomparables de Cristo se enumeran desde los vers\u00edculos 3 al 14 que hemos pasado estudiando las \u00faltimas semanas.<\/p>\n<p>Paul contin\u00faa. 15 Por tanto, porque he o\u00eddo hablar de tu fe en el Se\u00f1or Jes\u00fas y de tu amor para con todos los santos, 16 no ceso de dar gracias por ti, acord\u00e1ndome de ti en mis oraciones&#8230; S\u00e9 que eres creyente por dos cosas : Primero tienes una fe viva y activa en Jes\u00fas. Segundo, que la fe se manifiesta en el amor de Dios que debe evidenciarse en todas las iglesias. \u00bfCu\u00e1l es el deseo de Pablo para una iglesia? Que conozcan a Cristo profunda y profundamente. Por eso Pablo en Colosenses 3:16 dice: \u201cQue la palabra de Cristo more en abundancia en vosotros.\u201d<\/p>\n<p>Pablo escribi\u00f3 en 1 Tesalonicenses 1:2-3 Siempre damos gracias a Dios por todos vosotros, record\u00e1ndonos constantemente en nuestras oraciones, 3 recordando delante de nuestro Dios y Padre vuestra obra de fe y trabajo de amor y firmeza de esperanza en nuestro Se\u00f1or Jesucristo. Esta es la marca de un verdadero creyente y de una iglesia viva en Cristo: su fe est\u00e1 en Cristo y esa fe se manifiesta en su amor mutuo. Esta es la oraci\u00f3n por la iglesia en \u00c9feso. Dicho sea de paso, esta ser\u00e1 la preocupaci\u00f3n de Jes\u00fas a Efesios, que perdieron su primer amor (Apocalipsis 2:4). Su amor por Cristo y su amor mutuo.<\/p>\n<p>Y la esperanza no nos averg\u00fcenza, porque el amor de Dios ha sido derramado en nuestros corazones por medio del Esp\u00edritu Santo que nos ha sido dado. . (Romanos 5:5)<\/p>\n<p>Porque este es el amor de Dios, que guardemos sus mandamientos. (1 Juan 5:3)<\/p>\n<p>Por amor a \u00e9l, lo he perdido todo, y lo tengo por basura, para ganar a Cristo. (Filipenses 3:8).<\/p>\n<p>\u00bfConoces a Cristo en ese tipo de capacidad? As\u00ed debe vivir la iglesia. Debemos vivir con esta preocupaci\u00f3n consumidora por la persona de Jesucristo. A pesar del creciente secularismo y materialismo de nuestra cultura, existe un hambre cada vez m\u00e1s profunda de realizaci\u00f3n espiritual que no puede ocurrir sin Cristo. Sin embargo, el resultado de la verdadera fe es agua viva que da vida para ti y que tambi\u00e9n dar\u00e1 vida a otros.<\/p>\n<p>Hab\u00eda un hombre que se perdi\u00f3 en el desierto. Despu\u00e9s de deambular durante mucho tiempo, se deshidrat\u00f3 peligrosamente hasta el punto de morir. En ese momento vio una peque\u00f1a choza en la distancia. Se dirigi\u00f3 a la choza y encontr\u00f3 una bomba de agua con una peque\u00f1a jarra de agua y una nota: \u00abVierta toda el agua de esta jarra en la parte superior de la bomba para cebarla\u00bb. Si haces esto, tendr\u00e1s toda el agua que necesitas.\u201d<\/p>\n<p>Ahora el hombre ten\u00eda que tomar una decisi\u00f3n, si ten\u00eda fe en las instrucciones que se encuentran en la nota y verti\u00f3 el agua y funcion\u00f3, tendr\u00eda toda el agua que necesitaba. Si no funcionaba, todav\u00eda tendr\u00eda sed y podr\u00eda morir. Por otro lado, pod\u00eda simplemente beber el agua de la jarra y obtener una satisfacci\u00f3n inmediata.<\/p>\n<p>Despu\u00e9s de pensarlo, el hombre decidi\u00f3 confiar en las instrucciones. Verti\u00f3 toda la jarra en la bomba y comenz\u00f3 a manipular la manija. Al principio, no pas\u00f3 nada, y se pregunt\u00f3 si se hab\u00eda equivocado. Pero sigui\u00f3 bombeando con la poca fuerza que le quedaba hasta que empez\u00f3 a salir un poco de agua del surtidor. De repente ten\u00eda tanta agua que bebi\u00f3 todo lo que quiso, se duch\u00f3 y llen\u00f3 todos sus recipientes.<\/p>\n<p>Ahora la nota tambi\u00e9n dec\u00eda: despu\u00e9s de que haya terminado, por favor rellene la jarra para el pr\u00f3ximo viajero. \u201d El hombre volvi\u00f3 a llenar la jarra y a\u00f1adi\u00f3 a la nota: \u201c\u00a1Prende la bomba, cr\u00e9eme que funciona!\u201d<\/p>\n<p>Eso es fe y amor. \u00bfNos aferramos a nuestro propio entendimiento y lo que tenemos o lo dejamos todo y confiamos en las palabras de Cristo para vivir por ellas y nos aseguramos de compartirlo con otros para que ellos tambi\u00e9n no perezcan? Creo que la elecci\u00f3n es obvia. Necesitamos verter toda el agua para recibir el agua viva en nuestras vidas y compartirla con los dem\u00e1s. \u00a1El pozo nunca se secar\u00e1!<\/p>\n<p>Luego, una vez que hayamos experimentado lo que Dios tiene para ofrecer, el agua viva, debemos decirle a otras personas: \u00ab\u00a1Adelante, cebe la bomba, cr\u00e9anme que funciona!\u00bb (Randy Lekliter, Serm\u00f3n Central)<\/p>\n<p>II. Necesitamos una percepci\u00f3n espiritual m\u00e1s profunda<\/p>\n<p>para que el Dios de nuestro Se\u00f1or Jesucristo, el Padre de gloria, os d\u00e9 esp\u00edritu de sabidur\u00eda y de revelaci\u00f3n en el conocimiento de \u00e9l, 18 teniendo los ojos de vuestros corazones iluminados, para que sep\u00e1is cu\u00e1l es la esperanza a la que \u00e9l os ha llamado, cu\u00e1les las riquezas de su gloriosa herencia en los santos,<\/p>\n<p>Alguien me pregunt\u00f3 una vez c\u00f3mo podr\u00edamos fortalecer mejor a la iglesia hoy. Adem\u00e1s de la alfabetizaci\u00f3n b\u00edblica, les dije construyendo familias. Un estudio de investigaci\u00f3n de Barna encontr\u00f3 que si tanto mam\u00e1 como pap\u00e1 asisten a la iglesia regularmente, el 72% de sus hijos permanecen fieles m\u00e1s all\u00e1 de la escuela secundaria. Si pap\u00e1 asistiera a la iglesia, el 55% permanece fiel. Si mam\u00e1 permaneciera fiel, 15%. Si ninguno de los padres asist\u00eda a la iglesia regularmente, solo el 6% permanece fiel.<\/p>\n<p>Nuestras pr\u00f3ximas generaciones han perdido las habilidades de car\u00e1cter y pensamiento cr\u00edtico. Tus convicciones son los pilares inamovibles de tu car\u00e1cter que est\u00e1n arraigados m\u00e1s fuerte de tus padres. Lo segundo que tienes que tener es pensamiento cr\u00edtico. Nos hemos convertido en una cultura que cree ciegamente en las cosas que vemos en los medios. Uno de los mayores catalizadores para pensar m\u00e1s cr\u00edticamente es ver las cosas con la sabidur\u00eda de Dios a trav\u00e9s del Esp\u00edritu Santo. Esta fue la oraci\u00f3n continua de Pablo por los efesios.<\/p>\n<p>Abraham Lincoln dijo: &quot;Me he puesto de rodillas muchas veces por la abrumadora convicci\u00f3n de que no ten\u00eda ad\u00f3nde ir. Mi propia sabidur\u00eda y la de todos los que me rodean parec\u00edan insuficientes para el d\u00eda.\u201d<\/p>\n<p>Las universidades en estos d\u00edas est\u00e1n preocupadas por las ideolog\u00edas. As\u00ed es como funciona una ideolog\u00eda: \u201c\u00bfQu\u00e9 est\u00e1 mal en Estados Unidos? Privilegio blanco. \u00bfQu\u00e9 est\u00e1 mal en Estados Unidos? Racismo sist\u00e9mico. \u00bfQu\u00e9 est\u00e1 mal en Estados Unidos? Abuso de mujeres\u201d. Quieren que creas en el hecho de que todo lo que est\u00e1 mal en Estados Unidos puede explicarse por una ideolog\u00eda. No quieren que pienses cr\u00edticamente al respecto. En cambio, quieren que seas absorbido por una ideolog\u00eda de \u00abtalla \u00fanica\u00bb. De esa manera, no tiene que pensar en el problema, solo puede asignar la culpa.<\/p>\n<p>En el centro de esto est\u00e1 el enga\u00f1o masivo y el enga\u00f1o hoy en d\u00eda es una epidemia mayor que el COVID. El problema es que la iglesia est\u00e1 tan atrapada en los enga\u00f1os como el resto del mundo.<\/p>\n<p>Una se\u00f1ora fue al carnicero a comprar un pollo para la cena de su familia. Al carnicero solo le quedaba un pollo. Ella le pidi\u00f3 que lo pesara y estaba claro que era peque\u00f1o. Cuando ella le pregunt\u00f3 si le entregaba otro pollo, \u00e9l dijo que s\u00ed y se llev\u00f3 el pollo a la trastienda. Unos minutos m\u00e1s tarde regres\u00f3 con el mismo pollo y lo coloc\u00f3 en la balanza junto con un poco de presi\u00f3n extra con su pulgar. A la dama tampoco le impresion\u00f3 demasiado este p\u00e1jaro, as\u00ed que dijo: Me llevar\u00e9 los dos pollos&#8230;<\/p>\n<p>Paul nos advierte continuamente sobre quedar atrapados en los enga\u00f1os de este mundo y eso es lo que est\u00e1 conectado con su oraci\u00f3n aqu\u00ed en Efesios. Parte de la sabidur\u00eda de Dios es tener un entendimiento y discernimiento sobrenatural de lo que sucede a tu alrededor.<\/p>\n<p>No cre\u00e1is a todo esp\u00edritu, sino probad los esp\u00edritus si son de Dios, porque muchos falsos profetas han salido al mundo. (1 Juan 4:1)<\/p>\n<p>Mirad que nadie os enga\u00f1e con filosof\u00edas y huecas sutilezas, seg\u00fan la tradici\u00f3n humana, seg\u00fan los esp\u00edritus elementales del mundo, y no seg\u00fan Cristo. (Colosenses 2:8)<\/p>\n<p>Todas las naciones fueron enga\u00f1adas por vuestra hechicer\u00eda. (Apocalipsis 18:23)<\/p>\n<p>Pablo les dice a los efesios que est\u00e1n iluminados en estas cosas para que puedan conocer \u201cla esperanza de su llamado\u201d (v. 19). \u00bfCu\u00e1l es la esperanza de su llamado? La iglesia tiene un llamado en medio de estos d\u00edas y no es para arreglar el mundo. En cambio, debe ser la iglesia. La oraci\u00f3n de Pablo por los efesios y mi oraci\u00f3n por nosotros hoy es que nos demos cuenta de que para que la iglesia alcance al mundo no podemos seguir tratando de ser como el mundo. Tenemos un llamado muy claro y es el de ense\u00f1ar a predicar el evangelio de Jesucristo y todo el consejo de las Escrituras. Al hacerlo permitimos que la Palabra de Dios nos transforme a trav\u00e9s del poder del Esp\u00edritu de Dios.<\/p>\n<p>III. El Mundo Necesita Una Iglesia Viva En El Evangelio<\/p>\n<p>20 que obr\u00f3 en Cristo cuando lo resucit\u00f3 de entre los muertos y lo sent\u00f3 a su diestra en los lugares celestiales, 21 muy por encima de todo principado y autoridad y poder y se\u00f1or\u00edo, y sobre todo nombre que se nombra, no s\u00f3lo en este siglo, sino tambi\u00e9n en el venidero. 22 Y someti\u00f3 todas las cosas bajo sus pies, y lo dio por cabeza sobre todas las cosas a la iglesia, 23 la cual es su cuerpo, la plenitud de aquel que todo lo llena en todo. (Efesios 1:20\u201323).<\/p>\n<p>\u00bfC\u00f3mo haces que el poder espiritual sea evidente para el pueblo de Dios que est\u00e1 preocupado y oprimido por este mundo material? Me dijeron que una terapia que se usa para tratar a los ni\u00f1os autistas es nublar la mitad inferior de sus anteojos. Ciertos tipos de autismo aparentemente se manifiestan cuando el ni\u00f1o se enfoca completamente en alguna dimensi\u00f3n de su experiencia. Un ni\u00f1o as\u00ed puede concentrarse tanto en una actividad hasta el punto de que un solo aspecto se convierte en el mundo entero del ni\u00f1o. As\u00ed, las gafas empa\u00f1adas en la parte inferior pero claras en las lentes superiores obligan al ni\u00f1o a mirar hacia arriba. Del mismo modo, el Ap\u00f3stol Pablo quiere que levantemos la mirada de este mundo para centrarnos en lo de arriba. Nuestra esperanza reside en comprender el poder del Evangelio. (Bryan Chapell).<\/p>\n<p>Quiero que vean aqu\u00ed hoy la asombrosa esperanza que tenemos en Cristo debido a su autoridad sobre todas las cosas. Pablo nos dice que el Padre sent\u00f3 a Cristo a Su diestra en el Cielo para tener autoridad sobre toda autoridad, poder y dominio. Debido a la victoria de Jes\u00fas sobre la muerte y la tumba, se le da poder sobre toda autoridad en el cielo y la tierra. Las batallas que est\u00e1s enfrentando y que este mundo est\u00e1 soportando finalmente caer\u00e1n bajo los pies de Cristo.<\/p>\n<p>Sabemos que el Se\u00f1or est\u00e1 sobre todo y m\u00e1s a\u00fan, es la Cabeza de la iglesia. Si \u00e9l es la cabeza, entonces nosotros somos el cuerpo y, por lo tanto, tambi\u00e9n estamos bajo su autoridad. La pregunta es, \u00bfa qui\u00e9n eliges como Se\u00f1or hoy?<\/p>\n<p>para que yo le conozca a \u00e9l y el poder de su resurrecci\u00f3n y la participaci\u00f3n en sus padecimientos, haci\u00e9ndome semejante a su muerte (Filipenses 3:10)<\/p>\n<p>Porque no me averg\u00fcenzo del evangelio, porque es poder de Dios para salvaci\u00f3n a todo aquel que cree. (Romanos 1:16)<\/p>\n<p>Agust\u00edn dijo: Conf\u00eda el pasado a la misericordia de Dios, el presente al amor de Dios y el futuro a la providencia de Dios.&quot; Cuando conf\u00edas en Cristo como Salvador, la Biblia dice que tienes todos estos preciosos dones y muchos, muchos m\u00e1s desde el primer d\u00eda de tu salvaci\u00f3n. Y sin embargo\u2026todav\u00eda no comprendemos completamente todo lo que somos y tenemos en Cristo.<\/p>\n<p>\u00c9l quiere que lo conozcas en la salvaci\u00f3n. Si no has llegado a conocer a Jes\u00fas o descubierto la vida, o el gozo en su plenitud, o la paz que sobrepasa todo entendimiento, o la libertad de la culpa de los pecados. La Biblia dice que cuando conf\u00edas en \u00c9l, \u00a1\u00c9l ser\u00e1 tu Salvador hoy! Si ya eres creyente, \u00c9l est\u00e1 llamando a su iglesia a vivir la revelaci\u00f3n de su poder como el Se\u00f1or Jesucristo. \u00bfVendr\u00e1s a \u00c9l hoy?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A medida que avanzamos en el libro de Efesios, nos estamos preparando para la transici\u00f3n de las bendiciones introductorias a la esencia de este libro. Quiero reiterar el tema dominante de Efesios. Eso deber\u00eda ser evidente por el t\u00edtulo de nuestra serie, Solo Jes\u00fas. La fe cristiana siempre, siempre perder\u00e1 su influencia cuando trate de &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/nuestra-salvacion-solo-en-jesus\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNuestra salvaci\u00f3n s\u00f3lo en Jes\u00fas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3995","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/3995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=3995"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/3995\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=3995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=3995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=3995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}