{"id":4021,"date":"2022-08-18T04:16:01","date_gmt":"2022-08-18T09:16:01","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/tienes-leche\/"},"modified":"2022-08-18T04:16:01","modified_gmt":"2022-08-18T09:16:01","slug":"tienes-leche","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/tienes-leche\/","title":{"rendered":"\u00bfTienes leche?"},"content":{"rendered":"<p>Estoy seguro de que la mayor\u00eda de ustedes ha visto los comerciales de televisi\u00f3n que anuncian leche con el eslogan pegadizo que dice: \u00ab\u00bfTienes leche?\u00bb Tal vez recuerdes los comerciales de a\u00f1os pasados que dec\u00edan: \u201cLeche, le hace bien al cuerpo\u201d. Lo que se puede deducir de estos esl\u00f3ganes es que la leche es buena para la salud f\u00edsica de una persona. La leche tiene un alto contenido de calcio, que es vital para tener huesos fuertes, y los huesos fuertes son necesarios para sostener los m\u00fasculos y el sistema nervioso del cuerpo humano.<\/p>\n<p>Espiritualmente hablando, \u00abla leche tambi\u00e9n hace bien al alma\u00bb. . Sin embargo, no estoy hablando de la leche que sale de una vaca, sino que estoy hablando de lo que Pedro llama \u201cla leche pura de la Palabra\u201d (1 Pedro 2:2). Las palabras de la Biblia se asemejan a la leche, y son tan esenciales para nuestro crecimiento espiritual como lo es la leche para el crecimiento del cuerpo humano. As\u00ed como la leche de vaca es buena para el cuerpo, la leche de la Palabra de Dios es buena para nuestra alma, porque la Biblia contiene un mensaje que nos lleva a encontrar la vida eterna en Jesucristo. Si deseas la vida f\u00edsica, bebe leche de vaca; sin embargo, si deseas una vida espiritual, entonces bebe la leche de la Palabra de Dios.<\/p>\n<p>Te animo a que prestes mucha atenci\u00f3n esta ma\u00f1ana, porque si no lo haces, este mensaje podr\u00eda deslizarse \u201cm\u00e1s all\u00e1 de tus ojos\u201d ( pasteurizado). Los insto a que escuchen atentamente mientras observamos tres pasajes prominentes de las Escrituras sobre la leche de la Palabra de Dios, porque perder el mensaje que Dios quiere que recibamos podr\u00eda resultar en un \u00abcaos total\u00bb (caos absoluto) en nuestra relaci\u00f3n con el Se\u00f1or. .<\/p>\n<p>Los j\u00f3venes cristianos deben desear la Palabra (1 Pedro 2:2-3)<\/p>\n<p>2 Como ni\u00f1os reci\u00e9n nacidos, desead la leche pura de la Palabra, para que por ella crezc\u00e1is, 3 si en verdad hab\u00e9is gustado que el Se\u00f1or es misericordioso.<\/p>\n<p>En el Salmo 34:8 leemos: \u201cGustad, y ved que es bueno el Se\u00f1or; bienaventurado el hombre que en \u00e9l conf\u00eda.\u201d Cualquiera que alguna vez le haya dado una oportunidad a Dios y que verdaderamente haya probado el amor de Jesucristo, sabr\u00e1 que Dios es vivo y real. Jes\u00fas dijo en Juan 7:17 que \u201cCualquiera que quiera hacer la voluntad de Dios sabr\u00e1 si mi ense\u00f1anza es de Dios o es simplemente m\u00eda\u201d (NTV). Jes\u00fas declar\u00f3 con confianza: \u201cSi tan solo le das una oportunidad al Se\u00f1or, ver\u00e1s que \u00c9l es real y deseable\u201d. Cualquiera que intente gustar de la bondad de Dios ser\u00e1 bienaventurado, porque esa persona recibir\u00e1 la vida eterna por medio de Jesucristo nuestro Se\u00f1or (Romanos 6:23).<\/p>\n<p>En Juan 3:3 leemos que cuando aceptamos a Cristo como nuestro Se\u00f1or y Salvador somos \u201cnacidos de nuevo\u201d. Comenzamos nuestra nueva vida en Cristo como un infante comienza su nueva vida en el mundo. Si recientemente ha aceptado a Jesucristo como su Se\u00f1or y Salvador personal, entonces es un beb\u00e9 reci\u00e9n nacido y pronto desear\u00e1 ser alimentado. Pedro nos insta a \u201cdesear la leche pura de la Palabra\u201d (v. 2). \u00c9l compara la Palabra de Dios con la leche, porque la Palabra es tan esencial para el crecimiento de un cristiano como lo es la leche para el crecimiento de un beb\u00e9. Por un momento, veamos la importancia de la leche materna para su beb\u00e9.<\/p>\n<p>Una madre produce [leche que contiene] anticuerpos contra agentes infecciosos a los que podr\u00eda estar expuesto un reci\u00e9n nacido. Si una madre amamanta a su reci\u00e9n nacido, se produce un proceso conocido como inmunidad diat\u00e9lica, en el que el beb\u00e9 recibe los anticuerpos necesarios para combatir infecciones. Durante las primeras setenta y dos a noventa y seis horas despu\u00e9s del parto, la leche materna contiene calostro, que transporta inmunoglobulinas que mejoran en gran medida la inmunidad del reci\u00e9n nacido contra las enfermedades. Los beb\u00e9s privados de calostro tienen tasas considerablemente m\u00e1s altas de infecciones virales y bacterianas.(1)<\/p>\n<p>As\u00ed como la leche materna ayuda al sistema inmunol\u00f3gico del beb\u00e9 a defenderse de las infecciones, la Palabra de Dios ayudar\u00e1 a los cristianos reci\u00e9n nacidos a defenderse de los ataques infecciosos de Sat\u00e1n. El diablo es como un virus que busca un anfitri\u00f3n d\u00e9bil para devorar. 1 Pedro 5:8 advierte que nuestro \u201cadversario el diablo, como le\u00f3n rugiente, anda alrededor buscando a quien devorar\u201d. Satan\u00e1s se enoja cuando alguien entrega su vida a Jesucristo, y tratar\u00e1 de atacar a esa persona mientras a\u00fan es d\u00e9bil en su fe, tratando de hacerla tropezar y caer. \u00c9l quiere que los nuevos cristianos renuncien a Dios antes de que comiencen a crecer en \u00c9l. Warren Wiersbe dice: \u201cLa sabidur\u00eda del hombre no es rival para la astucia de Satan\u00e1s. Nuestra \u00fanica defensa es la Palabra inspirada de Dios.\u201d(2)<\/p>\n<p>Algunos cristianos permanecen como ni\u00f1os (1 Corintios 3:1-3)<\/p>\n<p>1 Y yo, hermanos, no pude os hablo como a espirituales, pero como a carnales, como a ni\u00f1os en Cristo. 2 Os sustent\u00e9 con leche y no con alimento s\u00f3lido; porque hasta ahora no hab\u00e9is podido recibirlo, y a\u00fan ahora no pod\u00e9is; 3 porque todav\u00eda sois carnales. Porque donde hay envidia, contiendas y divisiones entre vosotros, \u00bfno sois carnales y os comportais como simples hombres?<\/p>\n<p>Al igual que Pedro, Pablo habl\u00f3 de c\u00f3mo los j\u00f3venes cristianos deben beber la leche espiritual; sin embargo, expres\u00f3 que llega un momento en que deben crecer y comer alimentos s\u00f3lidos. El prop\u00f3sito de que los beb\u00e9s beban leche es para su crecimiento y salud. Para los cristianos, beber la leche de la Palabra debe producir crecimiento espiritual y salud. Sin embargo, cuando Pablo lleg\u00f3 a la escena en Corinto, not\u00f3 que la gente estaba haciendo algunas cosas que revelaban que no hab\u00edan logrado crecer espiritualmente. En la iglesia de Corinto hab\u00eda envidias, contiendas y divisiones, cosas que no son propias de un grupo maduro de creyentes. No hab\u00edan pasado de la leche a la carne.<\/p>\n<p>Cuando nace un ni\u00f1o, su sistema digestivo es tal que la leche es lo \u00fanico que puede manejar. A medida que contin\u00faan bebiendo la leche, comienzan a crecer y antes de que te des cuenta, quieren m\u00e1s leche. De repente, llegan a un punto en el que la leche simplemente no satisface su hambre. Ya no va a satisfacer sus necesidades, as\u00ed que empiezas a poner un poco de cereal en la leche, y a medida que crece su apetito aumenta hasta el punto en que la leche con cereal tampoco satisface, y la mam\u00e1 finalmente dice que este ni\u00f1o est\u00e1 listo para empieza a comer comida o carne de verdad. Para crecer y madurar, el ni\u00f1o debe pasar de la leche a la carne. La leche es un gran comienzo, pero una dieta prolongada de leche equivaldr\u00e1 a la inanici\u00f3n.(3)<\/p>\n<p>El t\u00e9rmino \u00abbeb\u00e9 de leche\u00bb es utilizado por ciertos profesionales de servicios sociales cuando se refieren a beb\u00e9s y ni\u00f1os peque\u00f1os, que solo han sido dado leche, cuando deber\u00edan haber recibido alimentos s\u00f3lidos. Esta forma de descuido nutricional hace que el beb\u00e9 aumente de peso en exceso, mientras que carece de los nutrientes que su cuerpo en desarrollo necesita tan desesperadamente. La leche es vital para los ni\u00f1os durante la infancia, pero a medida que crecen, se requieren alimentos s\u00f3lidos para un crecimiento y desarrollo adecuados. Asimismo, en la Palabra de Dios, vemos que hay un tiempo en nuestras vidas para la leche espiritual, y luego un tiempo para la [carne o pan] espiritual.(4)<\/p>\n<p>Si tuvieras un hijo que solo beb\u00eda leche y no estaban creciendo, entonces su preocupaci\u00f3n por su hijo posiblemente crecer\u00eda hasta el punto de la indignaci\u00f3n. Este es el estado de \u00e1nimo en el que encontramos a Pablo cuando escribe a la iglesia de Corinto.(5) Regres\u00f3 a la iglesia que hab\u00eda comenzado unos pocos a\u00f1os antes, y cuando lleg\u00f3 a la escena, la gente no hab\u00eda crecido. espiritualmente Si estamos experimentando divisiones y conflictos dentro de la iglesia entre hermanos cristianos, entonces este es un buen indicador de que algunas personas no han hecho un intento de crecer en una relaci\u00f3n m\u00e1s profunda con Cristo. Todav\u00eda est\u00e1n solo en el nivel de la superficie. Contin\u00faan bebiendo lo que beben los beb\u00e9s porque eso es todo lo que son: beb\u00e9s grandes.<\/p>\n<p>Dios ha llamado a las iglesias y a los cristianos individuales a alimentarse de la leche de Su Palabra y crecer espiritualmente para entrar en la edad adulta cristiana, a fin de reproducirse espiritualmente y hacer m\u00e1s nuevos beb\u00e9s en Cristo. Como seguidores y disc\u00edpulos de Jes\u00fas debemos estar haciendo nuevos cristianos y ayud\u00e1ndolos a alimentarlos con la leche de la Palabra de Dios. No necesitamos pasar toda nuestra vida teniendo a alguien que nos alimente con la Palabra. Debemos crecer y desear la carne de la Palabra de Dios en lugar de la leche. La leche es el conocimiento introductorio de Dios; sin embargo, la carne proviene de la caza y la b\u00fasqueda. Obtenemos el alimento de la Palabra de Dios cuando hacemos una b\u00fasqueda profunda de ella, y solo un adulto ir\u00e1 a la caza. En lugar de clamar por m\u00e1s leche para nosotros, deber\u00edamos alimentar con leche a los nuevos creyentes en Cristo.<\/p>\n<p>El deseo de Dios es que crezcamos (Hebreos 5:12-14)<\/p>\n<p>12 Porque aunque ya deb\u00e9is ser maestros, ten\u00e9is necesidad de que alguien os ense\u00f1e de nuevo los primeros principios de los or\u00e1culos de Dios; y has llegado a necesitar leche y no alimentos s\u00f3lidos. 13 Porque todo el que toma s\u00f3lo leche es inexperto en la palabra de justicia, porque es ni\u00f1o. 14 Pero el alimento s\u00f3lido pertenece a los mayores de edad, es decir, a los que por el uso tienen los sentidos ejercitados en el discernimiento del bien y del mal.<\/p>\n<p>\u201cT\u00fa sabes\u201d, dijo el padre de cinco hijos. mientras limpiaba los juguetes en el patio, \u201cdesde que estoy casado, he aprendido el significado de esas palabras de la Biblia que dicen: &#8216;Cuando fui hombre, dej\u00e9 las cosas de ni\u00f1o&#8217;\u201d(6). ) En 1 Corintios 13:11 leemos: \u201cCuando yo era ni\u00f1o, pensaba como ni\u00f1o, pensaba como ni\u00f1o; pero cuando llegu\u00e9 a ser hombre, dej\u00e9 las cosas de ni\u00f1o.\u201d La Escritura indica claramente que Dios espera que los creyentes crezcan y dejen de pensar como ni\u00f1os.<\/p>\n<p>El escritor de Hebreos, que algunos creen que fue Pablo, dijo que el pueblo deber\u00eda haber sido ellos mismos maestros; sin embargo, todav\u00eda eran meros ni\u00f1os que no hab\u00edan crecido en los caminos del Se\u00f1or. En lugar de ense\u00f1ar a otros, siempre se les ense\u00f1aba, porque todav\u00eda eran beb\u00e9s. Se hab\u00edan negado a profundizar en la Palabra de Dios, porque les faltaba la pasi\u00f3n para conocer a Dios m\u00e1s de cerca e \u00edntimamente.<\/p>\n<p>Vemos aqu\u00ed que para crecer debemos desear \u201calimento s\u00f3lido\u201d (vv. 12). , 14). La Palabra de Dios es leche para los que son j\u00f3venes en el Se\u00f1or, pero se convierte en pan y carne para los que tienen hambre profunda de conocer a Dios de manera \u00edntima. Cuando Jes\u00fas estaba ayunando en el desierto, buscando una relaci\u00f3n m\u00e1s cercana con el Se\u00f1or, el Diablo lo tent\u00f3 a convertir las piedras en pan; pero Jes\u00fas respondi\u00f3: \u201cNo s\u00f3lo de pan vivir\u00e1 el hombre, sino de toda palabra que sale de la boca de Dios\u201d (Mateo 4:3-4). Jes\u00fas se dio cuenta que la Palabra de Dios lo sustentar\u00eda m\u00e1s que cualquier tipo de alimento f\u00edsico; pero f\u00edjate c\u00f3mo dijo que la Palabra era m\u00e1s grande que el pan. El pan es un alimento s\u00f3lido; por lo tanto, la Palabra de Dios es s\u00f3lida y sustancial para aquellos que buscan conocerlo.<\/p>\n<p>Una persona solo puede manejar tanta leche antes de ahogarse en ella. Hubo dos ranas que saltaron a un recipiente abierto de leche en el porche trasero de una se\u00f1ora. Una rana dijo: \u00ab\u00a1Ay de m\u00ed, no puedo salir!\u00bb y luego se hundi\u00f3 hasta el fondo del recipiente de leche y se ahog\u00f3. La otra rana, sin embargo, empez\u00f3 a nadar en la leche. \u00a1Simplemente pate\u00f3 y rem\u00f3 hasta que convirti\u00f3 la leche en mantequilla y salt\u00f3 de inmediato! Mi punto aqu\u00ed es que cuando solo nos alimentamos de leche, es porque no tenemos ning\u00fan deseo de crecer. Un cristiano que no quiere crecer en una relaci\u00f3n y comprensi\u00f3n m\u00e1s profunda de Dios es complaciente; y la complacencia conducir\u00e1 a la muerte espiritual. Sin embargo, si buscamos algo mucho m\u00e1s s\u00f3lido, entonces podremos seguir saltando por la vida.<\/p>\n<p>Tiempo de reflexi\u00f3n<\/p>\n<p>Me gustar\u00eda concluir nuestro mensaje de esta ma\u00f1ana con tres preguntas Primero, \u00ab\u00bfTienes vida?\u00bb \u00bfHas probado la bondad de Dios y has encontrado que \u00c9l es verdaderamente maravilloso? \u00bfHas confesado a Jesucristo como tu Se\u00f1or y Salvador y probado la dulzura del amor incondicional y la vida eterna?<\/p>\n<p>En segundo lugar, \u00ab\u00bfTienes leche?\u00bb Si eres un cristiano nuevo, \u00bfhas intentado probar la santa Palabra de Dios? \u00bfEst\u00e1s siendo alimentado y nutrido espiritualmente por las palabras de la Biblia, para que puedas crecer fuerte y saludable en el Se\u00f1or?<\/p>\n<p>Y en tercer lugar, \u00ab\u00bfTienes pan?\u00bb \u00bfHa sido creyente durante muchos a\u00f1os y todav\u00eda se est\u00e1 alimentando solo de leche? \u00bfTe has negado a pasar tiempo con el Se\u00f1or, el tiempo que podr\u00edas haber ganado leyendo Su Palabra? Si ha sido cristiano durante bastante tiempo, entonces ya deber\u00eda haber comenzado a comer alimentos s\u00f3lidos, busc\u00e1ndolos profundamente a trav\u00e9s de la meditaci\u00f3n y la reflexi\u00f3n sobre las verdades que se encuentran en las p\u00e1ginas de la Biblia.<\/p>\n<p> La Palabra de Dios es pan del que debemos tener hambre. En Juan 1:14 leemos: \u201cY el Verbo se hizo carne y habit\u00f3 entre nosotros, y vimos su gloria, gloria como del unig\u00e9nito del Padre, lleno de gracia y de verdad\u201d. Por tanto, el pan que da vida se encuentra tambi\u00e9n en el conocimiento del \u201cunig\u00e9nito del Padre\u201d, el Hijo de Dios, Jesucristo. Jes\u00fas declar\u00f3: \u201cYo soy el pan de vida. El que a m\u00ed viene, nunca tendr\u00e1 hambre, y el que en m\u00ed cree, no tendr\u00e1 sed jam\u00e1s\u201d (Juan 6:35). Quiero animarte a participar del pan de vida hoy y a confiar en Jesucristo como tu Se\u00f1or y Salvador.<\/p>\n<p>NOTAS<\/p>\n<p>(1) Mark J. Occhipinti, Does Milk \u00bfRealmente le hace bien al cuerpo?, tomado de Internet en mayo de 2003 en http:\/\/www.afpafitness.com\/articles\/MILK.HTM.<\/p>\n<p>(2) Warren Wiersbe, The Strategy of Satan (Wheaton: Tyndale, 1979), p\u00e1g. 27.<\/p>\n<p>(3) Cedric Portis, \u201cMore Milk or Meat\u201d, tomado de Internet en mayo de 2003 en http:\/\/www.sermoncentral.com.<\/p>\n<p>(4) John Werhas, \u201cBeb\u00e9s en Cristo\u201d, tomado de Internet en mayo de 2003 en http:\/\/www.ylfc.org\/ministries\/encore\/1corinthians\/1corinthians_15.html.<\/p>\n<p>(5) Portis.&lt;\/p <\/p>\n<p>(6) Michael P. Green, Ilustraciones para la predicaci\u00f3n b\u00edblica (Grand Rapids: Baker, 1997), p\u00e1g. 44.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estoy seguro de que la mayor\u00eda de ustedes ha visto los comerciales de televisi\u00f3n que anuncian leche con el eslogan pegadizo que dice: \u00ab\u00bfTienes leche?\u00bb Tal vez recuerdes los comerciales de a\u00f1os pasados que dec\u00edan: \u201cLeche, le hace bien al cuerpo\u201d. Lo que se puede deducir de estos esl\u00f3ganes es que la leche es buena &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/tienes-leche\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfTienes leche?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4021","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/4021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=4021"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/4021\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=4021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=4021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=4021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}