{"id":4057,"date":"2022-08-18T04:17:12","date_gmt":"2022-08-18T09:17:12","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/echar-perlas-delante-de-los-cerdos\/"},"modified":"2022-08-18T04:17:12","modified_gmt":"2022-08-18T09:17:12","slug":"echar-perlas-delante-de-los-cerdos","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/echar-perlas-delante-de-los-cerdos\/","title":{"rendered":"Echar perlas delante de los cerdos"},"content":{"rendered":"<p>Echar perlas delante de los cerdos<\/p>\n<p>Mateo 7:6<\/p>\n<p>Cuando comenc\u00e9 a considerar las palabras de nuestro Se\u00f1or en nuestro texto, estaba record\u00f3 su santidad. Cuando consideramos a Cristo el Se\u00f1or, nos vienen a la mente muchos atributos, pero Su santidad debe estar en la parte superior de la lista. Su misma esencia est\u00e1 compuesta de santidad. Todo lo que \u00c9l es, todo lo que ha hecho, contin\u00faa haciendo y realizar\u00e1 en el futuro es consistente con Su santidad. Si uno mira a Cristo aparte de Su santidad, se ha perdido la esencia de qui\u00e9n es \u00c9l. Cristo no puede ser separado de Su santidad.<\/p>\n<p>Hemos le\u00eddo un pasaje controvertido para muchos en nuestros d\u00edas. Tendr\u00e1 que admitir que las palabras de nuestro Se\u00f1or aqu\u00ed no son \u00abpol\u00edticamente correctas\u00bb. De hecho, est\u00e1n en claro contraste con las ense\u00f1anzas de muchos hoy. Al considerar lo que nuestro Se\u00f1or ha dicho, debemos tener en mente Su santidad. La santidad de Cristo exige un est\u00e1ndar justo del que este mundo sabe muy poco. Vivimos en una \u00e9poca en la que todo vale, y esa actitud incluso ha llegado a la iglesia. Si vamos a vivir como Cristo quiere que vivamos, debemos ser conscientes de Su santidad y promover Su justo est\u00e1ndar en todos los aspectos de la vida.<\/p>\n<p>S\u00e9 que estamos llamados a ser sal y luz en este mundo oscuro y pecaminoso. Debemos compartir el evangelio con aquellos que no han o\u00eddo. Sin embargo, debemos usar sabidur\u00eda y discreci\u00f3n mientras servimos al Se\u00f1or entre el mundo. Quiero considerar los principios que nuestro Se\u00f1or presenta mientras pensamos en: Echar perlas delante de los cerdos.<\/p>\n<p>I. La Presentaci\u00f3n de esta Verdad (6) \u2013 No deis lo santo a los perros, ni ech\u00e9is vuestras perlas delante de los cerdos, no sea que las pisoteen, y se vuelvan y os despedacen. Aviso:<\/p>\n<p>A. El Discernimiento \u2013 A medida que comenzamos a considerar lo que nuestro Se\u00f1or ha presentado, debemos entender que \u00c9l est\u00e1 tratando con nuestro testimonio y conversaci\u00f3n dentro del mundo. Se est\u00e1 refiriendo a c\u00f3mo vemos, respetamos y guardamos lo que hemos recibido de \u00c9l. \u00c9l vino a este mundo para proveer redenci\u00f3n a la humanidad. Predic\u00f3 un mensaje que era radicalmente diferente de lo que ense\u00f1aban los escribas y fariseos. \u00c9l est\u00e1 proporcionando instrucci\u00f3n para nuestra interacci\u00f3n con los incr\u00e9dulos.<\/p>\n<p>Debemos entender la gran aplicaci\u00f3n espiritual que se da. Podr\u00eda haber una aplicaci\u00f3n para ser buenos administradores de nuestras posesiones, pero si eso es todo lo que vemos en estas palabras, nos hemos perdido la verdad fundamental que nuestro Se\u00f1or ha ense\u00f1ado. Este pasaje trata de c\u00f3mo consideramos y compartimos el evangelio glorioso.<\/p>\n<p>B. Los Deseables \u2013 No deis lo santo a los perros, ni ech\u00e9is vuestras perlas delante de los cerdos. Jes\u00fas habla de perlas y de lo santo, cosas de gran valor. Las perlas de las que habl\u00f3 Jes\u00fas tienen aplicaci\u00f3n para una perla genuina. Incluso en ese d\u00eda, las perlas eran muy apreciadas. Tambi\u00e9n hablan de \u201cproverbios, palabras de gran valor\u201d. Jes\u00fas se est\u00e1 refiriendo al mensaje del evangelio, la Palabra del Se\u00f1or, e incluso nuestro car\u00e1cter santo y est\u00e1ndar justo.<\/p>\n<p>De todas las cosas, estas deben ser las m\u00e1s valiosas para el creyente. Debemos valorar el mensaje del evangelio, la Palabra infalible de Dios y nuestra relaci\u00f3n con Cristo. La mayor\u00eda de la gente guarda y protege las cosas que son valiosas. El creyente debe guardar y proteger aquellas cosas que son dadas por el Se\u00f1or. Como consideramos hace unas semanas, estos son los \u00fanicos que durar\u00e1n. Las bendiciones del Se\u00f1or y nuestra relaci\u00f3n con \u00c9l son las posesiones m\u00e1s valiosas que poseemos.<\/p>\n<p>C. Los contaminados: no debemos dar lo que es santo a los perros, ni arrojar nuestras perlas delante de los cerdos. Jes\u00fas presenta un marcado contraste. Ha contrastado las posesiones m\u00e1s preciadas con las m\u00e1s profanadas. Los perros en ese d\u00eda no eran considerados como lo son hoy. No fueron domesticados y mantenidos como mascotas dom\u00e9sticas. Con la excepci\u00f3n de aquellos que fueron entrenados para pastorear y cuidar ovejas, los perros eran considerados animales inmundos, sucios y contaminados. El jud\u00edo promedio no necesitaba un perro. De hecho, el t\u00e9rmino se usaba a menudo para describir a hombres de mente y motivos impuros. Los cerdos eran inmundos y considerados los m\u00e1s viles de todos los animales. Los jud\u00edos consideraban a los cerdos menos que a un perro.<\/p>\n<p>Estos representan lo m\u00e1s contaminado de la humanidad. S\u00e9 que todos nacen en pecado, contaminados por su pecado y condenados por Dios. No podemos \u201cagrupar\u201d a todas las personas perdidas en esta categor\u00eda, pero muchas son tan depravadas que han perdido todo respeto por cualquier cosa santa. Desprecian la Palabra de Dios y la sola menci\u00f3n de Jes\u00fas. Han rehuido las s\u00faplicas del Esp\u00edritu por tanto tiempo que han llegado a ser reprobados, Rom.1: 21-31.<\/p>\n<p>Conozco a algunos que est\u00e1n perdidos y lo admitir\u00e1n f\u00e1cilmente, pero no son poco receptivos ni desagradecidos. de aquellos que comparten el evangelio. Estos no son perros, sino aquellos que permanecen cegados por el pecado. He conocido a algunos que parecen haber rechazado las misericordias de Dios por tanto tiempo que parece que se han entregado a una mente reprobada.<\/p>\n<p>D. El Peligro (6) \u2013 No deis lo santo a los perros, ni ech\u00e9is vuestras perlas delante de los cerdos, no sea que las pisoteen, y se vuelvan y os despedacen. Cuando uno determina dar lo que es santo a los hombres profanados o perlas a los cerdos, est\u00e1n en una posici\u00f3n peligrosa. Los cerdos simplemente pisotear\u00e1n lo que es santo. No hay consideraci\u00f3n por la gracia de Dios o el sacrificio que nuestro Se\u00f1or hizo por su pecado. Muchos hoy han pisoteado la gracia de Dios y la han contado como nada. No hay ning\u00fan beneficio en arrojar las cosas santas ante aquellos que no las tienen en cuenta y solo las pisar\u00e1n.<\/p>\n<p>Estos tambi\u00e9n presentan el peligro de volverse contra ti y desgarrarte. La palabra desgarrar tiene la idea de \u201cdesgarrar o tirar al suelo\u201d. No hay respeto por el Se\u00f1or o aquellos que buscan compartir Su mensaje. Nada les gustar\u00eda m\u00e1s que destrozarte. Buscan avergonzar y profanar el testimonio de los verdaderos creyentes. Quieren avergonzaros y escarneceros a causa de vuestra fe. Estos est\u00e1n tan contaminados con el pecado que no te respetan a ti ni al Se\u00f1or.<\/p>\n<p>II. La Verificaci\u00f3n de esta Verdad \u2013 Estas palabras pueden ser dif\u00edciles de recibir, pero son la verdad. Jes\u00fas los proclam\u00f3 y eso es suficiente para m\u00ed, pero para aquellos que necesiten m\u00e1s verificaci\u00f3n, consideremos un par de aspectos revelados en las Escrituras. Primero considere:<\/p>\n<p>A. El ministerio del Salvador: Jes\u00fas vino a esta tierra para proporcionarse a s\u00ed mismo como el sacrificio expiatorio por la humanidad, brindando redenci\u00f3n a todos los que creen. Era amigo de los pecadores, buscaba a los enfermos, afligidos y perdidos. Eso no indica que Jes\u00fas arroj\u00f3 lo santo a los perros. \u00c9l mantuvo Su ense\u00f1anza lejos de aquellos que eran tan viles que no la recibir\u00edan. A menudo hablaba en par\u00e1bolas, discernidas solo por aquellos que genuinamente ten\u00edan un deseo de aprender de \u00e9l. Mat.13:13 \u2013 Por eso les hablo en par\u00e1bolas: porque viendo no ven; y oyendo no oyen, ni entienden. [15] Porque el coraz\u00f3n de este pueblo se ha engrosado, y sus o\u00eddos oyeron con dificultad, y sus ojos se han cerrado; no sea que en cualquier momento vean con sus ojos, y oigan con sus o\u00eddos, y entiendan con su coraz\u00f3n, y se conviertan, y yo los sane.<\/p>\n<p>Considera la Transfiguraci\u00f3n de nuestro Se\u00f1or. Se llev\u00f3 solamente a Pedro, Santiago y Juan a la monta\u00f1a con \u00c9l. Eso no quiere decir que los otros disc\u00edpulos fueran perros, pero s\u00ed confirma que Jes\u00fas no revel\u00f3 Su verdadera gloria ante aquellos que de todos modos no lo habr\u00edan recibido. Cristo se neg\u00f3 a \u201cactuar\u201d para Herodes cuando pidi\u00f3 ver milagros durante Su juicio. La copa y los incr\u00e9dulos no experimentaron Su presencia despu\u00e9s de la resurrecci\u00f3n ni fueron testigos de Su ascensi\u00f3n. Esta gran perla estaba reservada para aquellos que hab\u00edan confiado en \u00c9l como el Cristo.<\/p>\n<p>B. El Ministerio de los Santos \u2013 Aquellos que siguieron al Se\u00f1or y compartieron el evangelio tambi\u00e9n siguieron este principio. Mat.10:14 \u2013 Y cualquiera que no os reciba, ni oiga vuestras palabras, saliendo de aquella casa o ciudad, sacudid el polvo de vuestros pies. Hechos 13:46 \u2013 Entonces Pablo y Bernab\u00e9 se atrevieron y dijeron: Era necesario que la palabra de Dios se os hablara primero a vosotros; pero puesto que la desech\u00e1is y os juzg\u00e1is indignos de la vida eterna, he aqu\u00ed, vu\u00e9lvete a los gentiles. Hechos 18:6 \u2013 Y cuando ellos se opon\u00edan y blasfemaban, \u00e9l (Pablo) sacudi\u00f3 sus vestiduras y les dijo: Vuestra sangre sea sobre vuestra cabeza; Estoy limpio; desde ahora me ir\u00e9 a los gentiles. A trav\u00e9s de la ense\u00f1anza de nuestro Se\u00f1or y estos ejemplos b\u00edblicos, se nos exhorta a ser cautelosos al testificar y vivir entre este mundo. No estoy diciendo que debamos guardar el evangelio para nosotros mismos, pero tambi\u00e9n debemos usar la sabidur\u00eda y el discernimiento.<\/p>\n<p>III. La obligaci\u00f3n de esta verdad: al concluir nuestro estudio, quiero recordarnos que no solo estamos obligados a guardar nuestro testimonio del evangelio, sino tambi\u00e9n nuestro testimonio de ese evangelio. El testimonio de los creyentes es una de las posesiones m\u00e1s preciadas que tenemos. Debemos asegurarnos de no arrojar nuestro testimonio ante los cerdos para que sean pisoteados y profanados. Tomemos un momento para considerar algunas \u00e1reas en las que estamos obligados.<\/p>\n<p>A. En conversaci\u00f3n: de ninguna manera estoy defendiendo que no debamos compartir nuestra fe con todos los que podamos. Estamos llamados a ser testigos del Se\u00f1or. Sin embargo, he conocido a algunos que eran tan viles y pecaminosos que no ser\u00edan de beneficio. Algunos no recibir\u00e1n su testimonio y lo \u00fanico que puede hacer es orar por ese individuo. Discutir no servir\u00e1 de nada para alcanzarlos para Cristo.<\/p>\n<p>Tambi\u00e9n debemos cuidar nuestro testimonio en la conversaci\u00f3n. No debemos ser culpables de dar nuestro testimonio ante los cerdos al participar en conversaciones vanas o vulgares. Una vez que nos hemos involucrado en ese tipo de conversaci\u00f3n, hemos perdido para siempre nuestra influencia con aquellos que necesitan escuchar desesperadamente.<\/p>\n<p>B. En Compa\u00f1erismo \u2013 Tambi\u00e9n debemos cuidar la compa\u00f1\u00eda que mantenemos. He enfatizado muchas veces que debemos continuar dando testimonio a los perdidos, pero el creyente no debe rodearse continuamente de incr\u00e9dulos, participando en sus actividades pecaminosas. Se espera que mantengamos un est\u00e1ndar santo, y eso es casi imposible si siempre est\u00e1s cerca de aquellos que no tienen respeto por el Se\u00f1or. La mayor\u00eda de las veces, te derribar\u00e1n, en lugar de que t\u00fa los levantes.<\/p>\n<p>Esto tambi\u00e9n se aplica a nuestras relaciones, incluido el matrimonio. Si eres salvo, es peligroso entablar una relaci\u00f3n con un incr\u00e9dulo o con uno que est\u00e1 en un curso doctrinalmente diferente. Si su visi\u00f3n de Cristo y la salvaci\u00f3n no es b\u00edblica, le insto a que reconsidere su compromiso con la relaci\u00f3n. 2 Cor.6:14 \u2013 No os un\u00e1is en yugo desigual con los incr\u00e9dulos; porque \u00bfqu\u00e9 compa\u00f1erismo tiene la justicia con la injusticia? \u00bfY qu\u00e9 comuni\u00f3n la luz con las tinieblas?<\/p>\n<p>C. En la Iglesia \u2013 Tambi\u00e9n debemos tener cuidado de no arrojar nuestras perlas a los cerdos de la iglesia. No estoy insinuando que nuestra congregaci\u00f3n est\u00e9 llena de perros y cerdos, sino que debemos guardar las verdades de la Palabra de Dios y continuar asegur\u00e1ndonos de edificarlo y adorarlo en todo lo que hacemos.<\/p>\n<p>Las verdades de la Palabra de Dios Word no atraer\u00e1 a todas las personas. Si nuestro deseo es ser \u201camigable con los buscadores\u201d y asegurarnos de que la ense\u00f1anza y la predicaci\u00f3n nunca ofendan a nadie, ya hemos echado nuestras perlas delante de los cerdos. \u00a1No comprometer\u00e9 esta Palabra por la aprobaci\u00f3n o aceptaci\u00f3n de los hombres! Estamos obligados a asegurar que cada aspecto de esta iglesia est\u00e9 de acuerdo con la Palabra de Dios. Si no se alinea con la Palabra, debe ser removido y abandonado.<\/p>\n<p>Conclusi\u00f3n: Este es un pasaje que muchos preferir\u00edan no considerar o tratar, pero se da para nuestro beneficio. Al considerar todo lo que mi Se\u00f1or soport\u00f3 por m\u00ed y lo que he recibido de \u00c9l, me veo obligado a vivir de una manera que le agrade. No podemos servir al Se\u00f1or si buscamos minimizar Su santidad. Si vamos a ser lo que el Se\u00f1or desea de nosotros, nunca debemos ser culpables de echar nuestras perlas delante de los cerdos.<\/p>\n<p>Para algunos, este pasaje es dif\u00edcil de aceptar y vivir. Debemos asegurarnos de desarrollar un equilibrio adecuado. Este pasaje no ense\u00f1a que no debemos confrontar el pecado o buscar alcanzar a los perdidos, sino que debemos hacerlo todo con sabidur\u00eda. Mat.10:16 \u2013 He aqu\u00ed, yo os env\u00edo como ovejas en medio de lobos; sed, pues, astutos como serpientes y sencillos como palomas. Todo lo que hacemos por Cristo debe estar ba\u00f1ado en oraci\u00f3n, buscando la sabidur\u00eda de Dios. Si buscas al Se\u00f1or y sigues la direcci\u00f3n del Esp\u00edritu, no te equivocar\u00e1s.<\/p>\n<p>\u00bfHay alguna necesidad en tu vida esta noche? \u00bfNecesitas la sabidur\u00eda que solo Dios puede dar? \u00bfEst\u00e1 preocupado por alguien que es particularmente resistente a la verdad de Dios? Tal vez te des cuenta de que nunca has sido salvo y quieres venir a Cristo. Si es as\u00ed, te animo a que lo hagas. Resistir al Se\u00f1or y Su llamado es peligroso. Por favor, ven como el Se\u00f1or te gu\u00ede.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Echar perlas delante de los cerdos Mateo 7:6 Cuando comenc\u00e9 a considerar las palabras de nuestro Se\u00f1or en nuestro texto, estaba record\u00f3 su santidad. Cuando consideramos a Cristo el Se\u00f1or, nos vienen a la mente muchos atributos, pero Su santidad debe estar en la parte superior de la lista. Su misma esencia est\u00e1 compuesta de &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/echar-perlas-delante-de-los-cerdos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEchar perlas delante de los cerdos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4057","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/4057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=4057"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/4057\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=4057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=4057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=4057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}