{"id":45497,"date":"2022-10-01T09:47:27","date_gmt":"2022-10-01T14:47:27","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/super-tazon-o-estupor-recipiente-estudio-biblico\/"},"modified":"2022-10-01T09:47:27","modified_gmt":"2022-10-01T14:47:27","slug":"super-tazon-o-estupor-recipiente-estudio-biblico","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/super-tazon-o-estupor-recipiente-estudio-biblico\/","title":{"rendered":"&#8220;S\u00faper&#8221; Taz\u00f3n O &#8220;Estupor&#8221; \u00bfRecipiente? &#8211; Estudio b\u00edblico"},"content":{"rendered":"<p>La exageraci\u00f3n de los medios de comunicaci\u00f3n sobre el pr\u00f3ximo Super Bowl n\u00famero 47 causa m\u00e1s una sensaci\u00f3n de <strong>estupor<\/strong> en lugar de algo que es <strong>s\u00faper<\/strong> (despu\u00e9s de todo, es solo otro juego de f\u00fatbol con jugadores muy pagados, \u00bfno es as\u00ed?).<\/p>\n<p>La palabra estupor se define como, <strong><em>suspensi\u00f3n o gran disminuci\u00f3n de la sensibilidad, como en una enfermedad o causada por narc\u00f3ticos, intoxicantes , etc<\/em><\/strong>., mientras <strong><em>\u00c9l yac\u00eda all\u00ed en un estupor ebrio.<\/em><\/strong><\/p>\n<p>As\u00ed, este escritor clasificar\u00eda el pr\u00f3ximo <strong>Super<\/strong> Bowl como el <strong>Stupor<\/strong> Bowl.<\/p>\n<p>El costo de un boleto para el Super Bowl no solo ser\u00e1 astron\u00f3mico (el boleto con el precio m\u00e1s bajo es de $2,387 y el m\u00e1s alto el boleto tiene un precio de $13,120), pero el consumo de cerveza tambi\u00e9n ser\u00e1 astron\u00f3mico. Seg\u00fan Saveonbrew.com, <strong>se consumir\u00e1n 50 millones de cajas de cerveza, lo que dar\u00e1 como resultado que se utilicen m\u00e1s de 2 mil millones de galones de agua para eliminar la cantidad de cerveza consumida, con aproximadamente 7 millones de personas report\u00e1ndose enfermas despu\u00e9s del Super Bowl<\/strong> (fuente).<\/p>\n<p>Si las estad\u00edsticas anteriores son correctas, no solo los fan\u00e1ticos del Super (&#8220;<strong>Stupor&#8221;<\/strong>) Bowl estar\u00e1n muy ebrios (ver art\u00edculo) , tambi\u00e9n causar\u00e1n una gran p\u00e9rdida de ingresos para las empresas para las que trabajan debido a su ausencia el lunes posterior al Super (&#8220;<strong>Stupor<\/strong>&#8220;) Bowl.<\/p>\n<p>Es triste contemplar que algunos miembros de la iglesia del Se\u00f1or tambi\u00e9n se ausentar\u00e1n de la asamblea el domingo por la noche debido al Super Bowl (Hebreos 10:25); y a\u00fan m\u00e1s triste es que algunas congregaciones del pueblo del Se\u00f1or no llevar\u00e1n a cabo servicios vespertinos debido al &#8220;<strong>Stupor<\/strong>&#8221; evento (el juego comienza a las 4:30 p. horas en una cruz de madera para que no tengamos que enfrentar un infierno de fuego eterno?<\/p>\n<p>\u00bfEs el <strong>Stupor<\/strong>&#8220;Cuenco m\u00e1s importante para nosotros que dar una hora en alabanza y adorar a nuestro Padre Celestial el domingo por la noche?<\/p>\n<p><strong>\u00a1Pensemos seriamente en ello!<\/strong> (Mateo 16:24-27).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La exageraci\u00f3n de los medios de comunicaci\u00f3n sobre el pr\u00f3ximo Super Bowl n\u00famero 47 causa m\u00e1s una sensaci\u00f3n de estupor en lugar de algo que es s\u00faper (despu\u00e9s de todo, es solo otro juego de f\u00fatbol con jugadores muy pagados, \u00bfno es as\u00ed?). La palabra estupor se define como, suspensi\u00f3n o gran disminuci\u00f3n de la &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/super-tazon-o-estupor-recipiente-estudio-biblico\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab&#8220;S\u00faper&#8221; Taz\u00f3n O &#8220;Estupor&#8221; \u00bfRecipiente? &#8211; Estudio b\u00edblico\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-45497","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/45497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=45497"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/45497\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=45497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=45497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=45497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}