{"id":45503,"date":"2022-10-01T09:47:36","date_gmt":"2022-10-01T14:47:36","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/today-is-my-choice-estudio-biblico\/"},"modified":"2022-10-01T09:47:36","modified_gmt":"2022-10-01T14:47:36","slug":"today-is-my-choice-estudio-biblico","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/today-is-my-choice-estudio-biblico\/","title":{"rendered":"Today Is My Choice &#8211; Estudio b\u00edblico"},"content":{"rendered":"<p>Es tranquilo. Es temprano. Mi caf\u00e9 est\u00e1 caliente. El cielo sigue negro. El mundo sigue dormido. El d\u00eda se acerca. En unos momentos llegar\u00e1 el d\u00eda. Rugir\u00e1 por la pista con la salida del sol. la quietud del alba ser\u00e1 cambiada por el ruido del d\u00eda. La calma de la soledad ser\u00e1 reemplazada por el paso acelerado de la raza humana. El refugio de la madrugada ser\u00e1 invadido por decisiones a tomar y plazos a cumplir. Durante las pr\u00f3ximas doce horas, estar\u00e9 expuesto a las demandas del d\u00eda. Ahora es cuando debo hacer una elecci\u00f3n. Por el Calvario soy libre de elegir. Y por eso elijo:<\/p>\n<p><strong>Elijo el Amor<\/strong>..Ninguna ocasi\u00f3n justifica el odio; ninguna injusticia justifica la amargura. Elijo el amor. Hoy amar\u00e9 a Dios y lo que Dios ama.<\/p>\n<p><strong>Elijo la alegr\u00eda<\/strong>..Reconocer\u00e9 a mi Dios como el Dios de las circunstancias. Rechazar\u00e9 la tentaci\u00f3n de ser c\u00ednico. La herramienta del pensador perezoso. Me negar\u00e9 a ver a las personas como algo menos que seres humanos, creados por Dios. Me negar\u00e9 a ver cualquier problema como algo menos que una oportunidad de ver a Dios.<\/p>\n<p><strong>Elijo la paz<\/strong>..Vivir\u00e9 perdonado. Perdonar\u00e9 para poder vivir.<\/p>\n<p><strong>Elijo la paciencia<\/strong>..Pasar\u00e9 por alto los inconvenientes del mundo. En lugar de maldecir a Aquel que toma mi lugar, lo invitar\u00e9 a hacerlo. En lugar de quejarme de que la espera es demasiado larga, agradecer\u00e9 a Dios por un momento para orar. En lugar de apretar el pu\u00f1o ante las nuevas asignaciones, las enfrentar\u00e9 con alegr\u00eda y coraje.<\/p>\n<p><strong>Elijo la bondad<\/strong>.. Ser\u00e9 bondadoso con los pobres, porque est\u00e1n solos; bondadoso con los ricos, porque tienen miedo; y amable con el cruel, porque as\u00ed es como Dios me ha tratado.<\/p>\n<p><strong>Elijo la bondad<\/strong>..Me quedar\u00e9 sin un d\u00f3lar antes de tomar uno deshonesto. Ser\u00e9 pasado por alto antes de gloriarme. Confesar\u00e9 antes de acusar. \u00a1Elijo la bondad!<\/p>\n<p><strong>Elijo la fidelidad<\/strong>..Hoy cumplir\u00e9 mis promesas. Mis deudores no se arrepentir\u00e1n de su confianza. Mis asociados no cuestionar\u00e1n mi palabra. Mi esposa no cuestionar\u00e1 mi amor. Y mis hijos nunca temer\u00e1n que su padre no vuelva a casa.<\/p>\n<p><strong>Elijo la mansedumbre<\/strong>..Nada se gana por la fuerza. Elijo ser amable. Si alzo mi voz, que sea s\u00f3lo en alabanza. Si aprieto el pu\u00f1o, que sea s\u00f3lo en oraci\u00f3n. Si hago una demanda, que sea solo de m\u00ed mismo.<\/p>\n<p><strong>Elijo el autocontrol<\/strong>..Soy un ser espiritual. Despu\u00e9s de que este cuerpo est\u00e9 muerto, mi esp\u00edritu se elevar\u00e1. Me niego a dejar que lo que se pudra gobierne lo eterno. Elijo el autocontrol. Me embriagar\u00e9 s\u00f3lo de alegr\u00eda. S\u00f3lo me apasionar\u00e1 mi fe. S\u00f3lo ser\u00e9 influenciado por Dios. Ser\u00e9 ense\u00f1ado solamente por Cristo. Amor, gozo, paz, paciencia, benignidad, bondad, fe, mansedumbre y templanza (G\u00e1latas 5:22-23). A estos encomiendo mi d\u00eda. Si lo consigo, dar\u00e9 las gracias. Si fallo, buscar\u00e9 Su gracia. Y luego, cuando termine este d\u00eda, pondr\u00e9 mi cabeza en mi almohada y descansar\u00e9.<\/p>\n<p><strong>Conclusi\u00f3n:<\/strong><\/p>\n<p>Las palabras y pensamientos anteriores son verdaderamente hermosos . Si no te traen un nudo en la garganta y una l\u00e1grima en el ojo, \u00a1ora para que Dios ablande tu coraz\u00f3n! No nos endurezcamos por el enga\u00f1o del pecado (Hebreos 3:12-13), sino m\u00e1s bien anim\u00e9monos unos a otros en tanto que todav\u00eda hoy.<\/p>\n<p>Trabajemos juntos como compa\u00f1eros de Cristo y manteng\u00e1monos firmes hasta \u00a1el fin! La pregunta no es, <strong><em>\u00bfQu\u00e9 tipo de cristianos e iglesia \u00e9ramos ayer?<\/em><\/strong> La verdadera pregunta es: <strong><em>\u00bfQu\u00e9 tipo de cristianos e iglesias seremos hoy? ?<\/em><\/strong><\/p>\n<p><strong><em>Lester P. Bagley<\/em><\/strong>, a trav\u00e9s del bolet\u00edn de Montana Street<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es tranquilo. Es temprano. Mi caf\u00e9 est\u00e1 caliente. El cielo sigue negro. El mundo sigue dormido. El d\u00eda se acerca. En unos momentos llegar\u00e1 el d\u00eda. Rugir\u00e1 por la pista con la salida del sol. la quietud del alba ser\u00e1 cambiada por el ruido del d\u00eda. La calma de la soledad ser\u00e1 reemplazada por el &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/today-is-my-choice-estudio-biblico\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abToday Is My Choice &#8211; Estudio b\u00edblico\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-45503","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/45503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=45503"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/45503\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=45503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=45503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=45503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}