{"id":46636,"date":"2022-10-01T10:13:16","date_gmt":"2022-10-01T15:13:16","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/mostrando-un-comportamiento-sabio-estudio-biblico\/"},"modified":"2022-10-01T10:13:16","modified_gmt":"2022-10-01T15:13:16","slug":"mostrando-un-comportamiento-sabio-estudio-biblico","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/mostrando-un-comportamiento-sabio-estudio-biblico\/","title":{"rendered":"Mostrando un comportamiento sabio &#8211; Estudio b\u00edblico"},"content":{"rendered":"<p>En 1 Samuel 18:5; 1 Samuel 18:14-15 y 1 Samuel 18:30, el escritor nos dice que David &#8220;se comport\u00f3 sabiamente.&#8221; De hecho, se comport\u00f3 &#8220;m\u00e1s sabiamente que todos los siervos de Sa\u00fal, de modo que su nombre lleg\u00f3 a ser muy estimado&#8221; (1 Samuel 18:30).<\/p>\n<p>La frase &#8220;muy estimado&#8221; sugiere la idea de un respeto inusual. David no solo fue honrado por todo el pueblo, sino que, lo que es m\u00e1s significativo, fue muy respetado por aquellos en la corte de Saulo que quedaron impresionados por su car\u00e1cter noble.<\/p>\n<p>A medida que los cristianos llegan a conocer a Jes\u00fas a trav\u00e9s de la obediencia a Sus mandamientos (1 Juan 2:3-5), comenzar\u00e1n a mostrar cualidades de car\u00e1cter que los diferencien de los dem\u00e1s, porque la verdadera sabidur\u00eda es vivir como Cristo (1 Juan 2:6; cf. G\u00e1latas 2:20). ). Esta sabidur\u00eda es m\u00e1s que sentido com\u00fan, es un comportamiento poco com\u00fan.<\/p>\n<p>James nos dice:<\/p>\n<blockquote>\n<p>&#8220;<strong><em>La sabidur\u00eda que es de lo alto es primeramente pura, luego pac\u00edfica, mansa, generosa, llena de misericordia y de buenos frutos, sin parcialidad y sin hipocres\u00eda<\/em><\/strong>&#8221; (Santiago 3:17).<\/p>\n<\/blockquote>\n<p>Como seguidores de Cristo, la verdadera sabidur\u00eda solo se puede adquirir &#8220;desde arriba&#8221; (cf. Santiago 1:5; Proverbios 2:1-6).<\/p>\n<p>La promesa de Dios a David con respecto a la sabidur\u00eda espiritual tambi\u00e9n es cierta para los cristianos de hoy. \u00c9l dijo:<\/p>\n<blockquote>\n<p>&#8220;<strong><em>Te instruir\u00e9 [har\u00e9 que seas sabio] y te ense\u00f1ar\u00e9 el camino en que debes andar<\/em><\/strong>&#8221; (Salmo 32:8).<\/p>\n<\/blockquote>\n<p>La pregunta es, \u00bfestamos aprendiendo a exhibir un comportamiento sabio? (cf. 1 Pedro 2:11-12; Filipenses 2:14-16; Mateo 5:16).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 1 Samuel 18:5; 1 Samuel 18:14-15 y 1 Samuel 18:30, el escritor nos dice que David &#8220;se comport\u00f3 sabiamente.&#8221; De hecho, se comport\u00f3 &#8220;m\u00e1s sabiamente que todos los siervos de Sa\u00fal, de modo que su nombre lleg\u00f3 a ser muy estimado&#8221; (1 Samuel 18:30). La frase &#8220;muy estimado&#8221; sugiere la idea de un respeto &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/mostrando-un-comportamiento-sabio-estudio-biblico\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abMostrando un comportamiento sabio &#8211; Estudio b\u00edblico\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-46636","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/46636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=46636"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/46636\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=46636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=46636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=46636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}