{"id":46640,"date":"2022-10-01T10:13:20","date_gmt":"2022-10-01T15:13:20","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-biblicos\/las-gallinas-vuelven-a-casa-para-dormir-estudio-biblico\/"},"modified":"2022-10-01T10:13:20","modified_gmt":"2022-10-01T15:13:20","slug":"las-gallinas-vuelven-a-casa-para-dormir-estudio-biblico","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-biblicos\/las-gallinas-vuelven-a-casa-para-dormir-estudio-biblico\/","title":{"rendered":"Las gallinas vuelven a casa para dormir &#8211; Estudio b\u00edblico"},"content":{"rendered":"<p>El siguiente poema es un recordatorio para que cada uno de nosotros sea consciente de &#8220;qu\u00e9&#8221; palabras que usamos y &#8220;c\u00f3mo&#8221; nosotros los usamos. Es posible que regresen para atormentarnos (Mateo 12:34-37; cf. Salmo 32:9; Salmo 39:1; Proverbios 13:3; Proverbios 21:23).<\/p>\n<p><em><strong>Mi madre siempre me dec\u00eda,<\/strong><\/em><br \/> <em><strong> (Mis entrenamientos son para impulsar),<\/strong><\/em><br \/> <em><strong> Cuidado con las palabras despreciativas, querida,<\/strong><\/em><br \/> <em><strong> Porque las gallinas vienen a casa a posarse (significado).<\/strong><\/em><\/p>\n<p> <em><strong>\u00a1Ah! Eso fue hace muchos a\u00f1os,<\/strong><\/em><br \/> <em><strong> Pero desde entonces he observado,<\/strong><\/em><br \/> <em><strong> C\u00f3mo la gente con lenguas han segado,<\/strong><\/em><br \/> <em><strong> El destino que se merecen.<\/strong><\/em><\/p>\n<p><em><strong>Han gente bien intencionada,<\/strong><\/em><br \/> <em><strong> que ni siquiera pens\u00f3,<\/strong><\/em><br \/> <em><strong> que a un coraz\u00f3n ya triste ,<\/strong><\/em><br \/> <em><strong> Un dolor adicional que trajeron.<\/strong><\/em><\/p>\n<p><em><strong>Quiz\u00e1s vieron una clavija -pierna hombre,<\/strong><\/em><br \/> <em><strong> Y pens\u00f3 que era una broma,<\/strong><\/em><br \/> <em><strong> Mientras \u00e9l, por desgracia, se fue en su camino,<\/strong><\/em><br \/> <em><strong> y llev\u00f3 su pesado yugo.<\/strong><\/em><\/p>\n<p><em><strong>Como sordos como cualquier publicaci\u00f3n, dijeron,<\/strong><\/em><br \/> <em><strong> Ciego como cualquier murci\u00e9lago,<\/strong><\/em><br \/> <em><strong> Tan loco como cualquier conejo es,<\/strong><\/em><br \/> <em><strong> O palabras desagradables como esa.<\/strong><\/em><\/p>\n<p><em><strong>El camino es joven, el camino es duro,<\/em><br \/> <em><strong> Y la juventud tendr\u00e1 su aventura,<\/strong><\/em><br \/> <em><strong> Escasa atenci\u00f3n en su gozoso vuelo,<\/strong> <\/em><br \/> <em><strong> \u00bfQu\u00e9 futuro traer\u00e1n?<\/strong><\/em><\/p>\n<p><em><strong>Pero las gallinas vienen a casa a dormir, querida, <\/strong><\/em><br \/> <em><strong> Siempre me parece;<\/strong><\/em><br \/> <em><strong> Es bueno pensar un poco,<\/strong><\/em><br \/> <em><strong>Sobre cu\u00e1l puede ser tu destino<\/strong><\/em><em><strong>.<\/strong><\/em><\/p>\n<p><em><strong>Esperanza Spencer<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El siguiente poema es un recordatorio para que cada uno de nosotros sea consciente de &#8220;qu\u00e9&#8221; palabras que usamos y &#8220;c\u00f3mo&#8221; nosotros los usamos. Es posible que regresen para atormentarnos (Mateo 12:34-37; cf. Salmo 32:9; Salmo 39:1; Proverbios 13:3; Proverbios 21:23). Mi madre siempre me dec\u00eda, (Mis entrenamientos son para impulsar), Cuidado con las palabras &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-biblicos\/las-gallinas-vuelven-a-casa-para-dormir-estudio-biblico\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLas gallinas vuelven a casa para dormir &#8211; Estudio b\u00edblico\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-46640","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/46640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/comments?post=46640"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/posts\/46640\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/media?parent=46640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/categories?post=46640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-biblicos\/wp-json\/wp\/v2\/tags?post=46640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}