{"id":11458,"date":"2022-08-30T07:54:50","date_gmt":"2022-08-30T12:54:50","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/un-nuevo-mecanismo-de-aprendizaje-del-cerebro-requiere-una-revision-de-la-hipotesis-de-la-neurociencia-de-larga-data\/"},"modified":"2022-08-30T07:54:50","modified_gmt":"2022-08-30T12:54:50","slug":"un-nuevo-mecanismo-de-aprendizaje-del-cerebro-requiere-una-revision-de-la-hipotesis-de-la-neurociencia-de-larga-data","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/un-nuevo-mecanismo-de-aprendizaje-del-cerebro-requiere-una-revision-de-la-hipotesis-de-la-neurociencia-de-larga-data\/","title":{"rendered":"Un nuevo mecanismo de aprendizaje del cerebro requiere una revisi\u00f3n de la hip\u00f3tesis de la neurociencia de larga data"},"content":{"rendered":"<p>Un cambio de paradigma en la investigaci\u00f3n del cerebro: la nueva neurona y el nuevo tipo de aprendizaje. Cr\u00e9dito: Prof. Ido Kanter, Universidad Bar-Ilan <\/p>\n<p>El cerebro es una red compleja que contiene miles de millones de neuronas. Cada una de estas neuronas se comunica simult\u00e1neamente con miles de otras a trav\u00e9s de sus sinapsis (enlaces) y recoge las se\u00f1ales entrantes a trav\u00e9s de varios \u00abbrazos\u00bb extremadamente largos y ramificados, llamados \u00e1rboles dendr\u00edticos. <\/p>\n<p>Durante los \u00faltimos 70 a\u00f1os, una hip\u00f3tesis central de la neurociencia ha sido que el aprendizaje del cerebro se produce modificando la fuerza de las sinapsis, siguiendo la actividad de activaci\u00f3n relativa de sus neuronas conectadas. Esta hip\u00f3tesis ha sido la base de los algoritmos de aprendizaje autom\u00e1tico y profundo que afectan cada vez m\u00e1s a casi todos los aspectos de nuestras vidas. Pero despu\u00e9s de siete d\u00e9cadas, esta hip\u00f3tesis de larga duraci\u00f3n ahora se ha puesto en duda.<\/p>\n<p>En un art\u00edculo publicado hoy en Scientific Reports, investigadores de la Universidad Bar-Ilan en Israel revelan que el cerebro aprende de manera completamente diferente a como lo ha hecho antes. asumido desde el siglo XX. Las nuevas observaciones experimentales sugieren que el aprendizaje se realiza principalmente en \u00e1rboles dendr\u00edticos neuronales, donde el tronco y las ramas del \u00e1rbol modifican su fuerza, en lugar de modificar \u00fanicamente la fuerza de las sinapsis (hojas dendr\u00edticas), como se pensaba anteriormente. Estas observaciones tambi\u00e9n indican que la neurona es en realidad un elemento mucho m\u00e1s complejo, din\u00e1mico y computacional que un elemento binario que puede dispararse o no. Solo una sola neurona puede realizar algoritmos de aprendizaje profundo, que anteriormente requer\u00edan una red artificial compleja que constaba de miles de neuronas y sinapsis conectadas.<\/p>\n<p>\u00abHemos demostrado que el aprendizaje eficiente en \u00e1rboles dendr\u00edticos de una sola neurona puede artificialmente lograr tasas de \u00e9xito cercanas a la unidad para el reconocimiento de d\u00edgitos escritos a mano. Este hallazgo allana el camino para un nuevo tipo eficiente de hardware y algoritmos de inteligencia artificial inspirados biol\u00f3gicamente\u00bb, dijo el profesor Ido Kanter, del Departamento de F\u00edsica de Bar-Ilan y Gonda (Goldschmied) Multidisciplinario Brain Research. Centro, que dirigi\u00f3 la investigaci\u00f3n. \u00abEste mecanismo de aprendizaje simplificado representa un paso hacia una realizaci\u00f3n biol\u00f3gica plausible de algoritmos de retropropagaci\u00f3n, que actualmente son la t\u00e9cnica central en IA\u00bb, agreg\u00f3 Shiri Hodassman, Ph.D. estudiante y uno de los contribuyentes clave de este trabajo.<\/p>\n<p> Un cambio de paradigma en la investigaci\u00f3n del cerebro: la nueva neurona y el nuevo tipo de aprendizaje. Cr\u00e9dito: Prof. Ido Kanter, Universidad de Bar-Ilan <\/p>\n<p>El aprendizaje eficiente en \u00e1rboles dendr\u00edticos se basa en la evidencia experimental de Kanter y su equipo de investigaci\u00f3n para la adaptaci\u00f3n subdendr\u00edtica utilizando cultivos neuronales, junto con otras propiedades anisotr\u00f3picas de las neuronas, como diferentes picos formas de onda, per\u00edodos refractarios y tasas de transmisi\u00f3n m\u00e1ximas.<\/p>\n<p>El reloj del cerebro es mil millones de veces m\u00e1s lento que las GPU paralelas existentes, pero con tasas de \u00e9xito comparables en muchas tareas de percepci\u00f3n.<\/p>\n<p>La nueva demostraci\u00f3n de el aprendizaje eficiente en \u00e1rboles dendr\u00edticos exige nuevos enfoques en la investigaci\u00f3n del cerebro, as\u00ed como la generaci\u00f3n de hardware equivalente con el objetivo de implementar algoritmos avanzados de IA. Si uno puede implementar din\u00e1micas cerebrales lentas en computadoras ultrarr\u00e1pidas, el cielo es el l\u00edmite. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> El cerebro aprende de forma completamente diferente a lo que hemos asumido desde el siglo XX <strong>M\u00e1s informaci\u00f3n:<\/strong> Shiri Hodassman et al, Aprendizaje dendr\u00edtico eficiente como alternativa a la hip\u00f3tesis de la plasticidad sin\u00e1ptica, Scientific Informes (2022). DOI: 10.1038\/s41598-022-10466-8 <\/p>\n<p>Shira Sardi et al, Los nodos adaptativos enriquecen el aprendizaje cooperativo no lineal m\u00e1s all\u00e1 de la adaptaci\u00f3n tradicional mediante enlaces, Scientific Reports (2018). DOI: 10.1038\/s41598-018-23471-7 <\/p>\n<p>Shira Sardi et al, New Types of Experiments Reveal that a Neuron Functions as Multiple Independent Threshold Units, Scientific Reports (2017). DOI: 10.1038\/s41598-017-18363-1 <\/p>\n<p>Shira Sardi et al, Per\u00edodos refractarios absolutos anisotr\u00f3picos largos con tiempos de aumento r\u00e1pidos para una capacidad de respuesta confiable, Physical Review E (2022). DOI: 10.1103\/PhysRevE.105.014401<\/p>\n<p>Roni Vardi et al, Plasticidad significativa del per\u00edodo refractario neuronal anisotr\u00f3pico, EPL (Europhysics Letters) (2021). DOI: 10.1209\/0295-5075\/ac177a<\/p>\n<p>Roni Vardi et al, Aprendizaje reversible r\u00e1pido basado en neuronas que funcionan como centros multiplex anisotr\u00f3picos, EPL (Europhysics Letters) (2017). DOI: 10.1209\/0295-5075\/118\/46002 <strong>Informaci\u00f3n de la revista:<\/strong> Scientific Reports , Physical Review E <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un cambio de paradigma en la investigaci\u00f3n del cerebro: la nueva neurona y el nuevo tipo de aprendizaje. Cr\u00e9dito: Prof. Ido Kanter, Universidad Bar-Ilan El cerebro es una red compleja que contiene miles de millones de neuronas. Cada una de estas neuronas se comunica simult\u00e1neamente con miles de otras a trav\u00e9s de sus sinapsis (enlaces) &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/un-nuevo-mecanismo-de-aprendizaje-del-cerebro-requiere-una-revision-de-la-hipotesis-de-la-neurociencia-de-larga-data\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abUn nuevo mecanismo de aprendizaje del cerebro requiere una revisi\u00f3n de la hip\u00f3tesis de la neurociencia de larga data\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11458","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/11458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=11458"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/11458\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=11458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=11458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=11458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}