{"id":11460,"date":"2022-08-30T07:54:56","date_gmt":"2022-08-30T12:54:56","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/el-sesgo-de-seleccion-puede-conducir-a-la-subestimacion-del-riesgo-de-encefalopatia-traumatica-cronica-en-exjugadores-de-futbol\/"},"modified":"2022-08-30T07:54:56","modified_gmt":"2022-08-30T12:54:56","slug":"el-sesgo-de-seleccion-puede-conducir-a-la-subestimacion-del-riesgo-de-encefalopatia-traumatica-cronica-en-exjugadores-de-futbol","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/el-sesgo-de-seleccion-puede-conducir-a-la-subestimacion-del-riesgo-de-encefalopatia-traumatica-cronica-en-exjugadores-de-futbol\/","title":{"rendered":"El sesgo de selecci\u00f3n puede conducir a la subestimaci\u00f3n del riesgo de encefalopat\u00eda traum\u00e1tica cr\u00f3nica en exjugadores de f\u00fatbol"},"content":{"rendered":"<p>Cr\u00e9dito: Pixabay\/CC0 Dominio p\u00fablico <\/p>\n<p>Desde 2008, los investigadores de la Facultad de Medicina de la Universidad de Boston (BUSM) han estado estudiando la encefalopat\u00eda traum\u00e1tica cr\u00f3nica (ETC) y si bien se ha aprendido mucho, el diagn\u00f3stico de la enfermedad a\u00fan debe realizarse post-mortem en cerebros autopsiados donados a un banco de cerebros. Una cr\u00edtica a la investigaci\u00f3n es que los resultados del estudio del banco de cerebros tienen un sesgo de selecci\u00f3n porque se basan en un subconjunto de jugadores m\u00e1s afectados por CTE y, por lo tanto, no son representativos de la poblaci\u00f3n de jugadores de f\u00fatbol. <\/p>\n<p>Ahora, un nuevo estudio realizado por investigadores de la BUSM y la Escuela de Salud P\u00fablica de la Universidad de Boston (BUSPH) proporciona m\u00e1s evidencia que sugiere una relaci\u00f3n dosis-respuesta entre el f\u00fatbol y la CTE, incluso despu\u00e9s de ajustar el sesgo de selecci\u00f3n. <\/p>\n<p>CTE es una enfermedad cerebral progresiva asociada con impactos repetitivos en la cabeza. Se ha diagnosticado despu\u00e9s de la muerte en jugadores de f\u00fatbol americano y otros atletas de deportes de contacto, as\u00ed como en miembros de las fuerzas armadas y v\u00edctimas de abuso f\u00edsico.<\/p>\n<p>\u00abSe ha cuestionado la validez de la investigaci\u00f3n que implica CTE debido a la inherente sesgo en el proceso de selecci\u00f3n de los estudios de donaci\u00f3n de cerebro Se ha ignorado un estudio anterior de BUSM que identific\u00f3 una fuerte relaci\u00f3n dosis-respuesta entre los a\u00f1os de juego de f\u00fatbol y la probabilidad de desarrollar CTE, lo que respalda una relaci\u00f3n de causa-efecto entre impactos repetidos en la cabeza y CTE. por algunas organizaciones deportivas debido a reclamos de sesgo de selecci\u00f3n. Para responder a tales cr\u00edticas, existe una necesidad significativa de ajustarlas en las fases anal\u00edticas de estos estudios \u00ab, explica el autor correspondiente Yorghos Tripodis, Ph.D., profesor de bioestad\u00edstica en BUSPH.<\/p>\n<p>Utilizando datos del banco de cerebros Veterans Affairs-Boston University-Concussion Legacy Foundation (VA-BU-CLF), los investigadores llevaron a cabo un nuevo estudio para analizar 290 formas masculinas r jugadores de f\u00fatbol para aclarar a\u00fan m\u00e1s la relaci\u00f3n dosis-respuesta. Despu\u00e9s de desarrollar m\u00faltiples modelos estad\u00edsticos para ajustar el sesgo de selecci\u00f3n, se encontr\u00f3 que los jugadores de f\u00fatbol universitario y profesional, respectivamente, ten\u00edan un riesgo 2,38 y 2,47 veces mayor de ser diagnosticados con CTE en comparaci\u00f3n con los jugadores de secundaria.<\/p>\n<p>\u00abSorprendentemente, estos los \u00edndices de riesgo en realidad aumentaron despu\u00e9s de tener en cuenta el sesgo de selecci\u00f3n.<\/p>\n<p>Esto contrasta con las cr\u00edticas anteriores recibidas, ya que sugiere que los datos anteriores en realidad pueden subestimar el riesgo de CTE en estas poblaciones\u00bb, dijo Tripodis. <\/p>\n<p>Los investigadores tambi\u00e9n calcularon la incidencia acumulada m\u00ednima de CTE para diferentes niveles de juego. Descubrieron que la incidencia acumulada m\u00ednima posible para jugadores profesionales es uno en 10, uno en 250 para jugadores universitarios de f\u00fatbol y 1 en 20,000 para jugadores de secundaria. Sin embargo, anticipan que los estudios futuros revelar\u00e1n que el riesgo real es muchas veces mayor para cada nivel de juego.<\/p>\n<p>Los autores terminan se\u00f1alando la necesidad de una mayor investigaci\u00f3n sobre el tipo de participantes que est\u00e1n subrepresentados en el banco de cerebros que conduce a este sesgo de selecci\u00f3n y la necesidad de esfuerzos de reclutamiento adicionales dirigidos a estas poblaciones para permitir estudios adicionales. <\/p>\n<p>\u00abNuestro nuevo estudio proporciona evidencia adicional para respaldar una relaci\u00f3n dosis-respuesta entre jugar al f\u00fatbol y desarrollar CTE. Esperamos que la comunidad del f\u00fatbol acelere las reformas destinadas a prevenir la CTE al limitar los impactos en la cabeza de los jugadores y que los padres utilizar esta informaci\u00f3n para tomar decisiones m\u00e1s informadas sobre la participaci\u00f3n deportiva de sus hijos\u00bb, agrega.<\/p>\n<p>Estos hallazgos aparecen en l\u00ednea en el American Journal of Epidemiology. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Un estudio de exjugadores de f\u00fatbol americano de Notre Dame encuentra que los jugadores universitarios son m\u00e1s propensos a tener trastornos cerebrales <strong>M\u00e1s informaci\u00f3n:<\/strong> Yorghos Tripodis et al, el an\u00e1lisis de sesgo de selecci\u00f3n respalda la relaci\u00f3n dosis-respuesta entre niveles de Juego de F\u00fatbol Americano y Diagn\u00f3stico de Encefalopat\u00eda Traum\u00e1tica Cr\u00f3nica, American Journal of Epidemiology (2022). DOI: 10.1093\/aje\/kwac075\/6569178 <strong>Informaci\u00f3n de la revista:<\/strong> American Journal of Epidemiology <\/p>\n<p> Proporcionado por la Facultad de Medicina de la Universidad de Boston <strong>Cita<\/strong>: El sesgo de selecci\u00f3n puede conducir a la subestimaci\u00f3n de riesgo de encefalopat\u00eda traum\u00e1tica cr\u00f3nica en ex futbolistas (28 de abril de 2022) consultado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-04-bias-underestimation-chronic-traction-encephalopathy.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Pixabay\/CC0 Dominio p\u00fablico Desde 2008, los investigadores de la Facultad de Medicina de la Universidad de Boston (BUSM) han estado estudiando la encefalopat\u00eda traum\u00e1tica cr\u00f3nica (ETC) y si bien se ha aprendido mucho, el diagn\u00f3stico de la enfermedad a\u00fan debe realizarse post-mortem en cerebros autopsiados donados a un banco de cerebros. Una cr\u00edtica a &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/el-sesgo-de-seleccion-puede-conducir-a-la-subestimacion-del-riesgo-de-encefalopatia-traumatica-cronica-en-exjugadores-de-futbol\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl sesgo de selecci\u00f3n puede conducir a la subestimaci\u00f3n del riesgo de encefalopat\u00eda traum\u00e1tica cr\u00f3nica en exjugadores de f\u00fatbol\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11460","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/11460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=11460"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/11460\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=11460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=11460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=11460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}