{"id":11540,"date":"2022-08-30T07:57:49","date_gmt":"2022-08-30T12:57:49","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/las-aguas-residuales-pueden-revelar-cuantos-de-nosotros-hemos-contraido-covid-19\/"},"modified":"2022-08-30T07:57:49","modified_gmt":"2022-08-30T12:57:49","slug":"las-aguas-residuales-pueden-revelar-cuantos-de-nosotros-hemos-contraido-covid-19","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/las-aguas-residuales-pueden-revelar-cuantos-de-nosotros-hemos-contraido-covid-19\/","title":{"rendered":"Las aguas residuales pueden revelar cu\u00e1ntos de nosotros hemos contra\u00eddo COVID-19"},"content":{"rendered":"<p>Cr\u00e9dito: Pixabay\/CC0 Public Domain <\/p>\n<p>Desde las primeras semanas de la pandemia de COVID-19 en los Estados Unidos, un grupo de investigadores de Yale ha rastreado diligentemente el virus a trav\u00e9s de una fuente \u00fatil pero decididamente poco glamorosa: las aguas residuales. <\/p>\n<p>Las mediciones diarias de la planta de tratamiento de aguas residuales de New Haven han arrojado una serie de informaci\u00f3n importante sobre el curso de la pandemia. En un estudio, un grupo de investigadores de Yale, incluido Edward H. Kaplan de Yale SOM, profesor de investigaci\u00f3n operativa, salud p\u00fablica e ingenier\u00eda, y Jordan Peccia, profesor de ingenier\u00eda qu\u00edmica y ambiental, demostraron que la concentraci\u00f3n de ARN de COVID-19 por el mililitro de lodo de depuradora sube y baja con la tasa de infecci\u00f3n observada en los datos de pruebas y hospitalizaci\u00f3n. En otro, descubrieron que analizar las aguas residuales puede proporcionar una se\u00f1al de advertencia temprana de un brote que empeora, de tres a cinco d\u00edas antes de que comiencen a aumentar las hospitalizaciones.<\/p>\n<p>Ahora han descubierto otro secreto m\u00e1s en el lodo. En su \u00faltimo art\u00edculo, Kaplan, Peccia y los estudiantes coautores de Yale, Alessandro Zulli y Marcela Sanchez, utilizan datos de aguas residuales para calcular la tasa de incidencia acumulada de COVID-19 en New Haven y presentan una f\u00f3rmula que permitir\u00eda a otros municipios hacer lo mismo. Sus resultados sugieren que casi un tercio de las personas en el \u00e1rea de New Haven se infectaron en mayo de 2021, un hallazgo que es consistente con otras tres estimaciones estad\u00edsticas independientes, pero notablemente mayor que la cifra del 12 % derivada de los recuentos oficiales de casos.<\/p>\n<p>Para desarrollar su estimaci\u00f3n, Kaplan y Peccia necesitaban solo una medida confiable de cu\u00e1ntas personas hab\u00edan sido infectadas contra la cual calibrar sus mediciones de aguas residuales. Tuvieron la suerte de contar con datos de los Centros para el Control de Enfermedades, que realizaron pruebas de anticuerpos en sangre en Connecticut en el verano de 2020. Esas pruebas de los CDC, que se realizaron antes de la llegada de las vacunas, les dijeron a los investigadores cu\u00e1ntas personas hab\u00edan sido infectadas hasta ese punto. Despu\u00e9s de hacer coincidir la estimaci\u00f3n de los CDC con la concentraci\u00f3n de ARN en las aguas residuales al mismo tiempo, podr\u00edan extrapolar hacia mayo de 2021.<\/p>\n<p>En teor\u00eda, cualquier ciudad podr\u00eda hacer lo mismo, ya sea utilizando los datos de los CDC del \u00e1rea o pruebas de anticuerpos de otra fuente. \u00abEl principio es lo importante\u00bb, explica Kaplan. Con datos de aguas residuales frecuentes y una estimaci\u00f3n precisa de las infecciones en un momento dado, el mismo enfoque b\u00e1sico puede funcionar en cualquier lugar.<\/p>\n<p>Saber cu\u00e1ntas personas se han infectado con COVID-19 a lo largo del tiempo \u00abes importante para saber qu\u00e9 nuestra inmunidad real al SARS-CoV-2 podr\u00eda ser\u00bb, explica Peccia, pero obtener una buena comprensi\u00f3n de la tasa de incidencia acumulada ha resultado ser un desaf\u00edo. (Las pruebas de anticuerpos de los CDC de 2020 fueron \u00fatiles, pero no representativas a nivel nacional y quedaron obsoletas r\u00e1pidamente).<\/p>\n<p>Los recuentos oficiales de casos, que se derivan de las pruebas, reflejan inconsistencias en las pruebas en los EE. UU. Al principio de la pandemia, las pruebas eran escasas; m\u00e1s recientemente, el uso generalizado de pruebas en el hogar significa que no todos los resultados positivos se informan a las autoridades de salud p\u00fablica como un nuevo caso de COVID-19. Tratar de aplicar ingenier\u00eda inversa al n\u00famero de otras se\u00f1ales, como las hospitalizaciones, es igualmente complicado: algunas variantes han llevado a m\u00e1s personas al hospital que otras.<\/p>\n<p>Pero donde fallan las pruebas y otras medidas, los inodoros tienen \u00e9xito. Las personas que contraen COVID-19 van al ba\u00f1o, se hagan la prueba o no, lo que convierte a las aguas residuales en una de las pocas fuentes de informaci\u00f3n directas a nivel de la poblaci\u00f3n sobre el flujo y reflujo de la pandemia. \u00ab\u00bfCu\u00e1ntas infecciones est\u00e1n ocurriendo? Eso es lo oculto que quieres ver\u00bb, dice Kaplan. \u00abCreemos que la se\u00f1al de las aguas residuales nos brinda la mejor visi\u00f3n de eso\u00bb.<\/p>\n<p>En New Haven, la tasa de incidencia derivada de las aguas residuales sugiere que \u00abhay mucha inmunidad\u00bb, dice Peccia. \u00abNo todos estamos tan vacunados como deber\u00edamos ni tan reforzados como deber\u00edamos, pero hay muchas personas que han sido infectadas. Si regresas y miras [el n\u00famero de casos], realmente subestime eso\u00bb.<\/p>\n<p>Kaplan y Peccia se apresuran a se\u00f1alar que el monitoreo de aguas residuales, a pesar de todos sus m\u00e9ritos, no sustituye a las pruebas. Despu\u00e9s de todo, \u00abno se puede rastrear los contactos de las aguas residuales\u00bb, dice Kaplan. Las pruebas ayudan a las personas a saber si deben aislarse y permiten que los funcionarios de salud p\u00fablica vinculen los casos con el estado de vacunaci\u00f3n, por ejemplo. Pero los programas de prueba tambi\u00e9n son muy costosos y, a medida que la pandemia se extiende, \u00abvamos a tener que aumentarlos de alguna manera\u00bb.<\/p>\n<p>El monitoreo de aguas residuales ofrece un complemento poderoso y econ\u00f3mico para un sistema COVID- 19 programa de prueba. Adem\u00e1s de calcular las tasas de incidencia acumulada, los datos de aguas residuales permiten que los funcionarios detecten brotes emergentes. Kaplan cita el ejemplo de Norwich, Connecticut, que us\u00f3 datos de aguas residuales para identificar un grupo de casos e intervenir antes de que se extendiera m\u00e1s.<\/p>\n<p>Kaplan y Peccia tambi\u00e9n ven potencial en el monitoreo basado en aguas residuales para enfermedades m\u00e1s all\u00e1 de COVID-19 . Est\u00e1n en las primeras etapas del estudio de la influenza en New Haven; las aguas residuales se han utilizado anteriormente para rastrear la poliomielitis en el mundo en desarrollo. El trabajo que ellos y otros han estado haciendo, dice Peccia, \u00absienta las bases para muchos, muchos otros tipos de virus\u00bb. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Las pruebas de aguas residuales pueden proporcionar una advertencia temprana de los brotes de COVID-19: estudio <strong>M\u00e1s informaci\u00f3n:<\/strong> Edward H. Kaplan et al, Scaling SARS-CoV-2 Wastewater Concentrations to Population estimaciones de infecci\u00f3n, Scientific Reports (2022). DOI: 10.1038\/s41598-022-07523-7 <strong>Informaci\u00f3n de la revista:<\/strong> Scientific Reports <\/p>\n<p> Proporcionado por la Universidad de Yale <strong>Cita<\/strong>: Las aguas residuales pueden revelar cu\u00e1ntos de nosotros hemos contra\u00eddo COVID -19 (2022, 27 de abril) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-04-wastewater-reveal-covid-.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Pixabay\/CC0 Public Domain Desde las primeras semanas de la pandemia de COVID-19 en los Estados Unidos, un grupo de investigadores de Yale ha rastreado diligentemente el virus a trav\u00e9s de una fuente \u00fatil pero decididamente poco glamorosa: las aguas residuales. Las mediciones diarias de la planta de tratamiento de aguas residuales de New Haven &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/las-aguas-residuales-pueden-revelar-cuantos-de-nosotros-hemos-contraido-covid-19\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLas aguas residuales pueden revelar cu\u00e1ntos de nosotros hemos contra\u00eddo COVID-19\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11540","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/11540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=11540"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/11540\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=11540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=11540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=11540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}