{"id":12071,"date":"2022-08-30T09:15:40","date_gmt":"2022-08-30T14:15:40","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/estudio-encuentra-que-covid-19-obstaculiza-la-productividad-academica-de-profesores-con-ninos-pequenos-en-ee-uu\/"},"modified":"2022-08-30T09:15:40","modified_gmt":"2022-08-30T14:15:40","slug":"estudio-encuentra-que-covid-19-obstaculiza-la-productividad-academica-de-profesores-con-ninos-pequenos-en-ee-uu","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/estudio-encuentra-que-covid-19-obstaculiza-la-productividad-academica-de-profesores-con-ninos-pequenos-en-ee-uu\/","title":{"rendered":"Estudio encuentra que COVID-19 obstaculiza la productividad acad\u00e9mica de profesores con ni\u00f1os peque\u00f1os en EE. UU."},"content":{"rendered":"<p>La productividad acad\u00e9mica de profesores de educaci\u00f3n superior en los Estados Unidos en los campos de ciencia, tecnolog\u00eda, ingenier\u00eda, matem\u00e1ticas y medicina (STEMM) con ni\u00f1os muy j\u00f3venes ni\u00f1os sufrieron como resultado de las \u00f3rdenes de quedarse en casa durante los primeros meses de la pandemia de coronavirus, seg\u00fan un nuevo estudio realizado por investigadores del Centro de Ciencias de la Salud de la Universidad de Tennessee, la Facultad de Medicina de la Universidad de Florida y la Universidad de Escuela de Medicina de Michigan. <\/p>\n<p>Titulado, \u00abDiferencias de productividad acad\u00e9mica por g\u00e9nero y edad infantil en la facultad de STEMM durante la pandemia de COVID-19\u00bb, el estudio se publica en el Journal of Women&#8217;s Health. Se cree que es uno de los primeros en cuantificar la productividad acad\u00e9mica durante la pandemia.<\/p>\n<p>Encuestando a 284 profesores, hombres y mujeres, con una mediana de edad de 42 a\u00f1os en varias instituciones de todo el pa\u00eds, el estudio compar\u00f3 los dos meses antes de la pandemia, de mediados de enero a mediados de marzo, a los primeros dos meses de la pandemia, de mediados de marzo a mediados de mayo, dijo Becca Krukowski, Ph.D., profesora asociada del Centro de Ciencias de la Salud de la Universidad de Tennessee en el Departamento de Medicina Preventiva y primer autor. Se pidi\u00f3 a los miembros de la facultad que autoinformaran la productividad durante los dos per\u00edodos de tiempo en una serie de categor\u00edas, incluidas las presentaciones de manuscritos del primer autor\/correspondiente y coautor, asignaciones de revisi\u00f3n por pares, solicitudes de subvenciones y asistencia a reuniones del panel de financiaci\u00f3n, todos los cuales son marcadores de productividad acad\u00e9mica y son m\u00e9tricas para promoci\u00f3n y permanencia.<\/p>\n<p>No hubo diferencias significativas en el n\u00famero de horas trabajadas por semana por g\u00e9nero, 45.8 para hombres y 43.1 para mujeres, durante los per\u00edodos de tiempo. Sin embargo, durante los dos primeros meses de la pandemia, los profesores con ni\u00f1os de 5 a\u00f1os o menos informaron que trabajaban significativamente menos horas a la semana, 33,7. Considerando que, seg\u00fan el estudio, los profesores con ni\u00f1os de 6 a\u00f1os o m\u00e1s o sin ni\u00f1os viviendo en casa informaron un aumento de las horas de trabajo durante la pandemia.<\/p>\n<p>\u00abPor lo general, los padres de ni\u00f1os peque\u00f1os tienen todos sus apoyos alineados- guarder\u00eda o una ni\u00f1era, as\u00ed como el apoyo adicional de familiares, incluidos los padres mayores. Ese no ha sido el caso durante la pandemia\u00bb, dijo el Dr. Krukowski.<\/p>\n<p>\u00abLa pandemia est\u00e1 teniendo un impacto en la productividad del cuerpo docente y el mayor impacto parece estar en el cuerpo docente con ni\u00f1os peque\u00f1os; esto tiene implicaciones potenciales para la titularidad y la promoci\u00f3n\u00bb, dijo. \u00abPuede verse agravado por otros impactos relacionados con la pandemia en la investigaci\u00f3n, como tener que cerrar un laboratorio o tener que cambiar la forma en que se realiza la investigaci\u00f3n para mantener seguros a los participantes y al personal\u00bb.<\/p>\n<p>Porque los profesores aumentan , las promociones y la titularidad est\u00e1n ligadas a la productividad, la pandemia puede tener efectos duraderos en las carreras acad\u00e9micas. Es importante que las instituciones sean conscientes de estos efectos a largo plazo al evaluar a los docentes, dijo.<\/p>\n<p>\u00abCreo que esta va a ser una situaci\u00f3n dif\u00edcil, en particular para los docentes que son pretitulares, porque las extensiones de tenencia no son necesariamente la mejor respuesta para todos, ya que eso significa que los aumentos se retrasan\u00bb, dijo el Dr. Krukowski. \u00abY no sabemos cu\u00e1nto durar\u00e1 la pandemia, por lo que no est\u00e1 claro cu\u00e1nto demorar estos procesos\u00bb.<\/p>\n<p>El estudio tambi\u00e9n apunta a la posibilidad de que la pandemia tenga el potencial de aumentar desigualdades de g\u00e9nero ya evidentes en los campos STEMM, ya que las mujeres realizan la mayor parte del cuidado de los ni\u00f1os m\u00e1s peque\u00f1os. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Diferencias de g\u00e9nero en la productividad acad\u00e9mica durante la pandemia de COVID-19 <strong>Informaci\u00f3n de la revista:<\/strong> Journal of Women&#8217;s Health <\/p>\n<p> Proporcionado por el Centro de Ciencias de la Salud de la Universidad de Tennessee <strong>Cita<\/strong>: El estudio encuentra que COVID-19 obstaculiza la productividad acad\u00e9mica de los profesores con ni\u00f1os peque\u00f1os en EE. UU. (2 de diciembre de 2020) consultado el 30 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-12-covid-hindering-academic-productivity -faculty.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La productividad acad\u00e9mica de profesores de educaci\u00f3n superior en los Estados Unidos en los campos de ciencia, tecnolog\u00eda, ingenier\u00eda, matem\u00e1ticas y medicina (STEMM) con ni\u00f1os muy j\u00f3venes ni\u00f1os sufrieron como resultado de las \u00f3rdenes de quedarse en casa durante los primeros meses de la pandemia de coronavirus, seg\u00fan un nuevo estudio realizado por investigadores del &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/estudio-encuentra-que-covid-19-obstaculiza-la-productividad-academica-de-profesores-con-ninos-pequenos-en-ee-uu\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEstudio encuentra que COVID-19 obstaculiza la productividad acad\u00e9mica de profesores con ni\u00f1os peque\u00f1os en EE. UU.\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12071","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/12071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=12071"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/12071\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=12071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=12071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=12071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}