{"id":19037,"date":"2022-08-30T13:06:09","date_gmt":"2022-08-30T18:06:09","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/los-cientificos-descubren-por-que-el-tipo-de-sangre-puede-ser-importante-para-la-infeccion-por-covid\/"},"modified":"2022-08-30T13:06:09","modified_gmt":"2022-08-30T18:06:09","slug":"los-cientificos-descubren-por-que-el-tipo-de-sangre-puede-ser-importante-para-la-infeccion-por-covid","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/los-cientificos-descubren-por-que-el-tipo-de-sangre-puede-ser-importante-para-la-infeccion-por-covid\/","title":{"rendered":"Los cient\u00edficos descubren por qu\u00e9 el tipo de sangre puede ser importante para la infecci\u00f3n por COVID"},"content":{"rendered":"<p>(HealthDay)Un nuevo estudio proporciona m\u00e1s evidencia de que las personas con ciertos tipos de sangre pueden ser m\u00e1s propensas a contraer COVID-19. <\/p>\n<p>Espec\u00edficamente, descubri\u00f3 que el nuevo coronavirus (SARS-CoV-2) se siente particularmente atra\u00eddo por el ant\u00edgeno del grupo sangu\u00edneo A que se encuentra en las c\u00e9lulas respiratorias.<\/p>\n<p>Los investigadores se centraron en una prote\u00edna en la superficie del El virus SARS-CoV-2 se llama dominio de uni\u00f3n al receptor (RBD), que es la parte del virus que se adhiere a las c\u00e9lulas hu\u00e9sped. Eso lo convierte en un objetivo importante para los cient\u00edficos que intentan aprender c\u00f3mo el virus infecta a las personas.<\/p>\n<p>En este estudio de laboratorio, el equipo evalu\u00f3 c\u00f3mo el SARS-CoV-2 RBD interactuaba con los gl\u00f3bulos rojos y respiratorios en A, Tipos de sangre B y O.<\/p>\n<p>Los resultados mostraron que el SARS-CoV-2 RBD ten\u00eda una fuerte preferencia por unirse al grupo sangu\u00edneo A que se encuentra en las c\u00e9lulas respiratorias, pero no ten\u00eda preferencia por los gl\u00f3bulos rojos del grupo sangu\u00edneo A. , u otros grupos sangu\u00edneos que se encuentran en las c\u00e9lulas respiratorias o en los gl\u00f3bulos rojos.<\/p>\n<p>La preferencia del SARS-CoV-2 RBD de reconocer y unirse al ant\u00edgeno del tipo A de la sangre que se encuentra en los pulmones de las personas con el tipo de sangre A puede proporcionar informaci\u00f3n en el v\u00ednculo potencial entre el grupo sangu\u00edneo A y la infecci\u00f3n por COVID-19, seg\u00fan los autores del estudio. Se public\u00f3 el 3 de marzo en la revista Blood Advances.<\/p>\n<p>\u00abEs interesante que el RBD viral solo prefiera el tipo de ant\u00edgenos del grupo sangu\u00edneo A que se encuentran en las c\u00e9lulas respiratorias, que presumiblemente es la forma en que el virus ingresa mayor\u00eda de los pacientes e infectarlos\u00bb, dijo el autor del estudio, el Dr. Sean Stowell, del Brigham and Women&#8217;s Hospital en Boston.<\/p>\n<p>\u00abEl tipo de sangre es un desaf\u00edo porque se hereda y no es algo que podamos cambiar\u00bb, dijo Stowell en un comunicado de prensa de la revista. \u00abPero si podemos entender mejor c\u00f3mo el virus interact\u00faa con los grupos sangu\u00edneos en las personas, podremos encontrar nuevos medicamentos o m\u00e9todos de prevenci\u00f3n\u00bb.<\/p>\n<p>Estos hallazgos por s\u00ed solos no pueden describir o predecir completamente c\u00f3mo los coronavirus afectar\u00eda a pacientes de varios tipos de sangre, anotaron los investigadores.<\/p>\n<p>\u00abNuestra observaci\u00f3n no es el \u00fanico mecanismo responsable de lo que estamos viendo cl\u00ednicamente, pero podr\u00eda explicar parte de la influencia del tipo de sangre en COVID-19 infecci\u00f3n\u00bb, dijeron Stowell y su equipo. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Siga las \u00faltimas noticias sobre el brote de coronavirus (COVID-19) <strong>M\u00e1s informaci\u00f3n:<\/strong> Los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE. UU. tienen m\u00e1s informaci\u00f3n sobre el COVID-19. <\/p>\n<p> Derechos de autor 2020 HealthDay. Reservados todos los derechos. <\/p>\n<p> <strong>Cita<\/strong>: Los cient\u00edficos descubren por qu\u00e9 el tipo de sangre puede ser importante para la infecci\u00f3n por COVID (3 de marzo de 2021) recuperado el 30 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2021-03-scientists- blood-covid-infection.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(HealthDay)Un nuevo estudio proporciona m\u00e1s evidencia de que las personas con ciertos tipos de sangre pueden ser m\u00e1s propensas a contraer COVID-19. Espec\u00edficamente, descubri\u00f3 que el nuevo coronavirus (SARS-CoV-2) se siente particularmente atra\u00eddo por el ant\u00edgeno del grupo sangu\u00edneo A que se encuentra en las c\u00e9lulas respiratorias. Los investigadores se centraron en una prote\u00edna en &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/los-cientificos-descubren-por-que-el-tipo-de-sangre-puede-ser-importante-para-la-infeccion-por-covid\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLos cient\u00edficos descubren por qu\u00e9 el tipo de sangre puede ser importante para la infecci\u00f3n por COVID\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19037","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/19037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=19037"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/19037\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=19037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=19037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=19037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}