{"id":19819,"date":"2022-08-30T13:30:59","date_gmt":"2022-08-30T18:30:59","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/los-investigadores-cuestionan-la-eficacia-de-las-vacunas-de-arnm-contra-el-covid-19-para-el-trasplante-de-organos-solidos\/"},"modified":"2022-08-30T13:30:59","modified_gmt":"2022-08-30T18:30:59","slug":"los-investigadores-cuestionan-la-eficacia-de-las-vacunas-de-arnm-contra-el-covid-19-para-el-trasplante-de-organos-solidos","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/los-investigadores-cuestionan-la-eficacia-de-las-vacunas-de-arnm-contra-el-covid-19-para-el-trasplante-de-organos-solidos\/","title":{"rendered":"Los investigadores cuestionan la eficacia de las vacunas de ARNm contra el COVID-19 para el trasplante de \u00f3rganos s\u00f3lidos"},"content":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain <\/p>\n<p>Un peque\u00f1o estudio de los investigadores de Mayo Clinic plantea la preocupaci\u00f3n de que algunos pacientes trasplantados pueden tener una respuesta inmunitaria limitada despu\u00e9s de ser vacunados contra el COVID-19. 19 con una vacuna de ARNm. Sus hallazgos se publican como una carta al editor en el American Journal of Transplantation. <\/p>\n<p>La carta cubre siete receptores de trasplantes de \u00f3rganos diagnosticados con COVID-19 en Mayo Clinic en Florida entre seis y 44 d\u00edas despu\u00e9s de recibir cualquiera de las vacunas de ARNm contra el COVID-19 que la Administraci\u00f3n de Alimentos y Medicamentos (FDA, por sus siglas en ingl\u00e9s) autoriz\u00f3 para uso de emergencia. Dos pacientes hab\u00edan recibido una dosis y cinco pacientes hab\u00edan recibido ambas dosis.<\/p>\n<p>La infecci\u00f3n por COVID-19 se confirm\u00f3 en todos los pacientes con una prueba de hisopado nasal de reacci\u00f3n en cadena de la polimerasa. El equipo del estudio, dirigido por Hani Wadei, MD, nefr\u00f3logo del Centro de Trasplantes de Mayo Clinic, informa que cinco de los pacientes ten\u00edan una infecci\u00f3n lo suficientemente grave como para ser hospitalizados y tres requirieron ox\u00edgeno cuando fueron dados de alta.<\/p>\n<p>Dr. Wadei y su equipo analizaron la sangre de pacientes que hab\u00edan recibido un \u00f3rgano s\u00f3lido en busca de anticuerpos contra el COVID-19, que ser\u00eda el tipo de anticuerpo generado por la vacuna. De los seis pacientes a los que se les hizo la prueba, solo se encontraron anticuerpos contra la prote\u00edna espiga en uno. Ese paciente hab\u00eda recibido ambas dosis de la vacuna de ARNm 44 d\u00edas antes y ten\u00eda un t\u00edtulo bajo de anticuerpos contra la espiga. Utilizando los datos de vacunaci\u00f3n disponibles, el Dr. Wadei y su equipo calcularon que la tasa de infecci\u00f3n en los receptores de trasplantes de \u00f3rganos s\u00f3lidos vacunados era 10 veces mayor que la poblaci\u00f3n general: 0,6 % frente a 0,05 %.<\/p>\n<p>\u00abEste estudio es ojo- apertura para la comunidad de trasplantes\u00bb, dice el Dr. Wadei. \u00abNuestro estudio sugiere que los pacientes trasplantados no tienen la misma respuesta inmunitaria que la poblaci\u00f3n general. Se infectaron despu\u00e9s de vacunarse y levantar las medidas de protecci\u00f3n, pensando que eran inmunes al virus\u00bb.<\/p>\n<p>Los investigadores se\u00f1alan que los pacientes trasplantados fueron excluidos de los estudios de vacunas actuales. Los investigadores de Mayo no revisaron en este estudio otra vacuna, basada en un vector de adenovirus y autorizada para su uso por la FDA, ya que no estaba disponible para los pacientes de Mayo.<\/p>\n<p>\u00abA\u00fan se debe implementar cuidado en vacunados pacientes inmunocomprometidos trasplantados de \u00f3rganos s\u00f3lidos hasta que tengamos mejores estrategias de vacunas\u00bb, dice el Dr. Wadei. \u00abTodas las personas, especialmente los pacientes trasplantados, deben seguir las medidas de protecci\u00f3n, como el distanciamiento social, el uso de mascarillas y la higiene regular de las manos\u00bb.<\/p>\n<p>Los investigadores piden m\u00e1s estudios para probar la eficacia de la vacuna en el trasplante. pacientes, examinar la tasa de infecci\u00f3n posterior a la vacuna e identificar m\u00e9todos para estimular la respuesta inmunitaria relacionada con la vacuna en estos pacientes. El pr\u00f3ximo paso en su investigaci\u00f3n es evaluar a todos los receptores de trasplantes de \u00f3rganos s\u00f3lidos vacunados en Mayo Clinic en Florida para detectar anticuerpos contra la espiga, con el objetivo de ampliar los estudios a m\u00e1s pacientes de trasplantes en los otros campus de Mayo en Arizona y Minnesota. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Siga las \u00faltimas noticias sobre el brote de coronavirus (COVID-19) <strong>M\u00e1s informaci\u00f3n:<\/strong> Hani M Wadei et al. Infecci\u00f3n por COVID19 en receptores de trasplantes de \u00f3rganos s\u00f3lidos despu\u00e9s de la vacunaci\u00f3n contra el SARSCoV2, American Journal of Transplantation (2021). DOI: 10.1111\/ajt.16618 <strong>Informaci\u00f3n de la revista:<\/strong> American Journal of Transplantation <\/p>\n<p> Proporcionado por Mayo Clinic <strong>Cita<\/strong>: Los investigadores cuestionan la eficacia de las vacunas de mRNA COVID-19 para \u00f3rganos s\u00f3lidos transplant (2021, 26 de abril) recuperado el 30 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2021-04-efectividad-mrna-covid-vaccines-solid.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain Un peque\u00f1o estudio de los investigadores de Mayo Clinic plantea la preocupaci\u00f3n de que algunos pacientes trasplantados pueden tener una respuesta inmunitaria limitada despu\u00e9s de ser vacunados contra el COVID-19. 19 con una vacuna de ARNm. Sus hallazgos se publican como una carta al editor en el American Journal of Transplantation. &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/los-investigadores-cuestionan-la-eficacia-de-las-vacunas-de-arnm-contra-el-covid-19-para-el-trasplante-de-organos-solidos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLos investigadores cuestionan la eficacia de las vacunas de ARNm contra el COVID-19 para el trasplante de \u00f3rganos s\u00f3lidos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19819","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/19819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=19819"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/19819\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=19819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=19819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=19819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}