{"id":19825,"date":"2022-08-30T13:31:11","date_gmt":"2022-08-30T18:31:11","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/reinicio-de-la-vacuna-johnson-johnson-covid-19-un-medico-explica-por-que-los-beneficios-superan-con-creces-los-riesgos\/"},"modified":"2022-08-30T13:31:11","modified_gmt":"2022-08-30T18:31:11","slug":"reinicio-de-la-vacuna-johnson-johnson-covid-19-un-medico-explica-por-que-los-beneficios-superan-con-creces-los-riesgos","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/reinicio-de-la-vacuna-johnson-johnson-covid-19-un-medico-explica-por-que-los-beneficios-superan-con-creces-los-riesgos\/","title":{"rendered":"Reinicio de la vacuna Johnson &amp; Johnson COVID-19: un m\u00e9dico explica por qu\u00e9 los beneficios superan con creces los riesgos"},"content":{"rendered":"<p>Cr\u00e9dito: Unsplash\/CC0 Dominio p\u00fablico <\/p>\n<p>Nota del editor: Los Centros para el Control y la Prevenci\u00f3n de Enfermedades y la Administraci\u00f3n de Alimentos y Medicamentos levantaron la pausa en la vacuna Johnson &amp; Johnson COVID-19 el 23 de abril de 2021, pero las etiquetas y las hojas informativas que se entregan a los pacientes incluir\u00e1n una advertencia sobre el riesgo extremadamente bajo de desarrollar co\u00e1gulos de sangre. Adem\u00e1s, continuar\u00e1 la vigilancia estrecha de la vacuna J&amp;J junto con las vacunas Moderna y Pfizer que recibieron autorizaci\u00f3n de uso de emergencia. El Dr. William Petri, m\u00e9dico especialista en enfermedades infecciosas e inmun\u00f3logo de la Facultad de Medicina de la Universidad de Virginia, explica este desarrollo y por qu\u00e9 las agencias decidieron que los beneficios de la vacuna superan con creces los riesgos. <\/p>\n<p>\u00bfCu\u00e1l fue la preocupaci\u00f3n con la vacuna Johnson &amp; Johnson COVID-19?<\/p>\n<p>La FDA y los CDC detuvieron el uso de la vacuna J&amp;J el 13 de abril de 2021 debido a seis casos iniciales de una rara y peligrosa co\u00e1gulo de sangre que involucra los senos venosos cerebrales, vasos sangu\u00edneos grandes en el cerebro. Esta coagulaci\u00f3n, tambi\u00e9n llamada trombosis, tambi\u00e9n puede ocurrir en los vasos sangu\u00edneos grandes del abdomen y las piernas y est\u00e1 asociada con recuentos bajos de plaquetas o trombocitopenia. Esta condici\u00f3n se llama trombosis con s\u00edndrome de trombocitopenia (TTS). <\/p>\n<p>Un aspecto inusual de estos co\u00e1gulos es que ocurren con un recuento bajo de plaquetas. Las plaquetas son c\u00e9lulas en la sangre que t\u00edpicamente ayudan en la coagulaci\u00f3n. Es probable que el TTS sea causado por la vacuna J&amp;J, que rara vez provoca la producci\u00f3n de un anticuerpo contra una parte de una plaqueta llamado heparina-factor plaquetario 4. Estos anticuerpos inducen a las plaquetas a formar co\u00e1gulos. El TTS parece similar a un efecto secundario raro de la heparina anticoagulante llamada trombocitopenia inducida por heparina.<\/p>\n<p>Un panel de m\u00e9dicos y cient\u00edficos independientes conocido como el Comit\u00e9 Asesor sobre Pr\u00e1cticas de Inmunizaci\u00f3n (ACIP) revis\u00f3 exhaustivamente los datos despu\u00e9s de la pausa . Luego de una revisi\u00f3n adicional del total de 7 millones de dosis de la vacuna J&amp;J administradas, se identificaron nueve casos adicionales de este tipo de co\u00e1gulo de sangre, todos en mujeres. <\/p>\n<p>\u00bfQu\u00e9 hicieron los CDC y la FDA el 23 de abril?<\/p>\n<p>Los CDC y la FDA anunciaron que era seguro reiniciar el uso de la vacuna Johnson &amp; Johnson COVID-19 porque la Los beneficios de la protecci\u00f3n contra el COVID-19 superan con creces los riesgos. Lo hicieron tras reunirse dos veces con los expertos independientes en vacunas de la ACIP, que tambi\u00e9n recomendaron reiniciar. <\/p>\n<p>\u00bfPor qu\u00e9 los CDC y la FDA reiniciaron el uso de la vacuna contra el COVID-19 de Johnson &amp; Johnson?<\/p>\n<p>Primero, el efecto secundario es raro. Seg\u00fan las agencias, se ha producido como m\u00e1ximo en una de cada 100.000 mujeres j\u00f3venes que reciben la vacuna de Johnson &amp; Johnson. Se cree que ning\u00fan hombre ni mujer mayor de 50 a\u00f1os ha tenido este efecto secundario. En segundo lugar, la vacuna J&amp;J es muy eficaz para prevenir la COVID-19, que es una infecci\u00f3n com\u00fan y grave que ha matado a 1 de cada 500 estadounidenses. <\/p>\n<p> Una conferencia de prensa conjunta con funcionarios de los CDC y la FDA en la que explican su decisi\u00f3n. <\/p>\n<p>En tercer lugar, la vacuna J&amp;J tiene ventajas sobre las vacunas de ARNm fabricadas por Pfizer y Moderna en el sentido de que solo requiere una dosis \u00fanica. Tambi\u00e9n es m\u00e1s f\u00e1cil de transportar y almacenar, ya que no requiere temperaturas muy bajas como las vacunas de Pfizer y Moderna. <\/p>\n<p>Cuarto y m\u00e1s importante, ahora que se conoce el efecto secundario, las personas pueden tomar decisiones informadas sobre qu\u00e9 vacuna contra el COVID-19 recibir. Una mujer joven que toma anticonceptivos orales, que tambi\u00e9n pueden promover la formaci\u00f3n de co\u00e1gulos de sangre, l\u00f3gicamente podr\u00eda elegir una de las vacunas de ARNm, mientras que un hombre podr\u00eda elegir la vacuna J&amp;J, ya que es una dosis \u00fanica. Las mujeres j\u00f3venes son el grupo de mayor riesgo.<\/p>\n<p>\u00bfSe observa este efecto secundario con las otras vacunas contra el COVID-19?<\/p>\n<p>TTS no es un efecto secundario de las vacunas de ARNm fabricadas por Moderna y Pfizer BioNTech . No se han identificado casos en los 97,9 millones de dosis de Pfizer BioNTech ni en los 85 millones de dosis de la vacuna Moderna. Cinco receptores de las vacunas de ARNm ten\u00edan trombosis del seno venoso cerebral, pero no con trombocitopenia, por lo que no era STT. El TTS parece ser un efecto secundario de solo dos vacunas contra el COVID, las cuales usan un virus del resfriado com\u00fan llamado adenovirus como parte de la vacuna: la vacuna J&amp;J en los EE. UU. y la vacuna Oxford-Astrazeneca que se usa en Europa pero no en los EE. UU. <\/p>\n<p>\u00bfC\u00f3mo puedo saber si tengo STT?<\/p>\n<p>El STT se ha producido s\u00f3lo en mujeres y en el per\u00edodo de seis a 15 d\u00edas despu\u00e9s de la vacunaci\u00f3n. Los s\u00edntomas pueden incluir dolor de cabeza intenso, n\u00e1useas, v\u00f3mitos y dolor abdominal seguidos de debilidad en un lado del cuerpo, dificultad para hablar, convulsiones y p\u00e9rdida del conocimiento. <\/p>\n<p>\u00bfC\u00f3mo se trata el STT?<\/p>\n<p>Los co\u00e1gulos del STT se tratan con lo que se denomina anticoagulantes de acci\u00f3n directa y no con heparina. Esta fue parte de la raz\u00f3n de la pausa, para que los proveedores de atenci\u00f3n m\u00e9dica pudieran saber c\u00f3mo tratar adecuadamente esta rara forma de co\u00e1gulos de sangre. <\/p>\n<p>\u00bfDebo ponerme la vacuna J&amp;J?<\/p>\n<p>Mi recomendaci\u00f3n si eres una mujer menor de 50 a\u00f1os que te vacunes con las vacunas Pfizer o Moderna, y no con la vacuna J&amp;J. Esto se debe a que este efecto secundario raro se ha observado solo en mujeres j\u00f3venes; 13 de las 15 mujeres que desarrollaron TTS est\u00e1n en este grupo de edad. Para todos los dem\u00e1s, la vacuna J&amp;J ofrece la comodidad de necesitar una y no las dos dosis de las otras vacunas. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Los beneficios de la vacuna de AstraZeneca aumentan con la edad: EMA Proporcionado por The Conversation <\/p>\n<p> Este art\u00edculo se vuelve a publicar de The Conversation bajo una licencia Creative Commons. Lea el art\u00edculo original. <\/p>\n<p> <strong>Cita<\/strong>: Reinicio de la vacuna Johnson &amp; Johnson COVID-19: un m\u00e9dico explica por qu\u00e9 los beneficios superan con creces los riesgos (2021, 26 de abril) recuperado el 30 de agosto de 2022 de https:\/\/medicalxpress.com \/noticias\/2021-04-restart-johnson-covid-vaccine-doctor.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Unsplash\/CC0 Dominio p\u00fablico Nota del editor: Los Centros para el Control y la Prevenci\u00f3n de Enfermedades y la Administraci\u00f3n de Alimentos y Medicamentos levantaron la pausa en la vacuna Johnson &amp; Johnson COVID-19 el 23 de abril de 2021, pero las etiquetas y las hojas informativas que se entregan a los pacientes incluir\u00e1n una &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/reinicio-de-la-vacuna-johnson-johnson-covid-19-un-medico-explica-por-que-los-beneficios-superan-con-creces-los-riesgos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abReinicio de la vacuna Johnson &amp; Johnson COVID-19: un m\u00e9dico explica por qu\u00e9 los beneficios superan con creces los riesgos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-19825","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/19825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=19825"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/19825\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=19825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=19825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=19825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}