{"id":20604,"date":"2022-08-30T13:55:58","date_gmt":"2022-08-30T18:55:58","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/recibi-la-vacuna-johnson-johnson-covid-19-y-ahora-que\/"},"modified":"2022-08-30T13:55:58","modified_gmt":"2022-08-30T18:55:58","slug":"recibi-la-vacuna-johnson-johnson-covid-19-y-ahora-que","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/recibi-la-vacuna-johnson-johnson-covid-19-y-ahora-que\/","title":{"rendered":"Recib\u00ed la vacuna Johnson &amp; Johnson COVID-19. \u00bfY ahora qu\u00e9?"},"content":{"rendered":"<p>(Ilustraci\u00f3n AP\/Peter Hamlin) <\/p>\n<p>Recib\u00ed la vacuna contra el COVID-19 de Johnson &amp; Johnson. \u00bfAhora que? <\/p>\n<p>No se asuste. Los funcionarios de salud de EE. UU. recomendaron el martes pausar las vacunas con la inyecci\u00f3n de J&amp;J mientras analizan los informes de seis co\u00e1gulos de casi 7 millones de dosis administradas en el pa\u00eds.<\/p>\n<p>Los funcionarios de salud dicen que hay que estar atentos, pero recordar que los informes de los co\u00e1gulos de sangre que pueden estar asociados con la vacuna de dosis \u00fanica de J&amp;J son extremadamente raros.<\/p>\n<p>\u00abEs menos de uno en un mill\u00f3n\u00bb, dijo el Dr. Anthony Fauci, el principal especialista en enfermedades infecciosas de EE. UU.<\/p>\n<p>Los efectos secundarios comunes despu\u00e9s de recibir una vacuna contra el COVID-19 pueden incluir dolor en el brazo y s\u00edntomas similares a los de la gripe durante un par de d\u00edas despu\u00e9s. Esos no son agradables, pero no son lo que preocupa a los funcionarios.<\/p>\n<p>En cambio, est\u00e9 atento a s\u00edntomas diferentes y m\u00e1s graves asociados con los co\u00e1gulos, particularmente entre una y tres semanas despu\u00e9s de la inyecci\u00f3n. . Estos incluyen dolor de cabeza intenso, dolor de espalda, dolor abdominal, dificultad para respirar, hinchaz\u00f3n de las piernas, peque\u00f1as manchas rojas en la piel o hematomas.<\/p>\n<p>Si aparecen esos s\u00edntomas, busque tratamiento m\u00e9dico de inmediato. Los Centros para el Control y la Prevenci\u00f3n de Enfermedades han emitido recomendaciones para ayudar a los m\u00e9dicos a detectar estos raros co\u00e1gulos y tratarlos de manera segura. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Siga las \u00faltimas noticias sobre el brote de coronavirus (COVID-19) <\/p>\n<p> 2021 The Associated Press. Reservados todos los derechos. Este material no puede ser publicado, transmitido, reescrito o redistribuido sin permiso. <\/p>\n<p> <strong>Cita<\/strong>: Recib\u00ed la vacuna contra el COVID-19 de Johnson &amp; Johnson. \u00bfAhora que? (2021, 14 de abril) recuperado el 30 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2021-04-johnson-covid-vaccine.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Ilustraci\u00f3n AP\/Peter Hamlin) Recib\u00ed la vacuna contra el COVID-19 de Johnson &amp; Johnson. \u00bfAhora que? No se asuste. Los funcionarios de salud de EE. UU. recomendaron el martes pausar las vacunas con la inyecci\u00f3n de J&amp;J mientras analizan los informes de seis co\u00e1gulos de casi 7 millones de dosis administradas en el pa\u00eds. Los funcionarios &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/recibi-la-vacuna-johnson-johnson-covid-19-y-ahora-que\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abRecib\u00ed la vacuna Johnson &amp; Johnson COVID-19. \u00bfY ahora qu\u00e9?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20604","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/20604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=20604"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/20604\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=20604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=20604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=20604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}