{"id":25392,"date":"2022-08-31T13:19:45","date_gmt":"2022-08-31T18:19:45","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/francia-informa-un-record-de-588-muertes-mas-por-coronavirus\/"},"modified":"2022-08-31T13:19:45","modified_gmt":"2022-08-31T18:19:45","slug":"francia-informa-un-record-de-588-muertes-mas-por-coronavirus","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/francia-informa-un-record-de-588-muertes-mas-por-coronavirus\/","title":{"rendered":"Francia informa un r\u00e9cord de 588 muertes m\u00e1s por coronavirus"},"content":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain <\/p>\n<p>Francia inform\u00f3 el viernes 588 muertes m\u00e1s por coronavirus en el hospital, su mayor n\u00famero de 24 horas en el pa\u00eds desde que comenz\u00f3 la epidemia. <\/p>\n<p>Las nuevas muertes elevan a 5.091 el n\u00famero total de personas que han muerto en el hospital de COVID-19 en Francia, dijo a los periodistas el alto funcionario de salud Jerome Salomon.<\/p>\n<p>No hay un peaje diario para los que han muri\u00f3 de COVID-19 en residencias de ancianos en Francia. Pero Salomon dijo que un total de 1.416 personas hab\u00edan muerto en dichos establecimientos por COVID-19 durante la epidemia. Esto eleva el n\u00famero total de muertos en Francia a al menos 6507.<\/p>\n<p>Francia ha estado bloqueada desde el 17 de marzo en un intento por frenar la propagaci\u00f3n de la epidemia, y solo se permiten viajes esenciales al exterior que deben justificarse con un pedazo de papel firmado.<\/p>\n<p>En un rayo de esperanza, Salomon dijo que 1186 personas m\u00e1s hab\u00edan sido hospitalizadas por el coronavirus y 263 m\u00e1s ingresaron a cuidados intensivos, el aumento m\u00e1s bajo en m\u00e1s de una semana.<\/p>\n<p>Dijo que hab\u00eda un total de 64.338 casos confirmados en Francia, un aumento de 5.233 con respecto al d\u00eda anterior. Pero esto no incluye todos los casos, ya que las pruebas no son universales.<\/p>\n<p>Seg\u00fan Salomon, hubo una reducci\u00f3n en las llamadas telef\u00f3nicas de emergencia y, aunque era demasiado pronto para decir que era una tendencia, eran \u00abbuenas noticias\u00bb. <\/p>\n<p>\u00abNo podemos analizar la situaci\u00f3n en base a un n\u00famero y un d\u00eda, pero hemos notado esta disminuci\u00f3n\u00bb, dijo.<\/p>\n<p>A pesar de la disminuci\u00f3n en el crecimiento de los pacientes de cuidados intensivos \u00abhemos Todav\u00eda no se ha llegado al pico de esta ola y menos a\u00fan a su disminuci\u00f3n\u201d, agreg\u00f3.<\/p>\n<p>En lo que en tiempos habituales ser\u00eda un fin de semana donde las familias francesas se marchar\u00edan en masa para las vacaciones de Semana Santa, Salomon repiti\u00f3 las advertencias oficiales que las vacaciones estaban fuera de discusi\u00f3n.<\/p>\n<p>\u00abEsta noche sobre todo. Qu\u00e9dese en casa si quiere salvar vidas\u00bb, dijo.<\/p>\n<p>Cuando se le pregunt\u00f3 acerca de los aparentes mensajes contradictorios durante el curso de la crisis sobre si las personas deben usar m\u00e1scaras sanitarias, Salomon dijo que podr\u00edan ayudar, pero no indic\u00f3 si esto ser\u00eda obligatorio.<\/p>\n<p>\u00abEn Francia, como en Eur Ope, no tenemos la tradici\u00f3n de usar la m\u00e1scara. Hay una tradici\u00f3n en Asia.\u00bb<\/p>\n<p>\u00abEstas m\u00e1scaras te permiten protegerte. Si hay acceso a m\u00e1scaras, alentamos al p\u00fablico a usar m\u00e1scaras si as\u00ed lo desean\u00bb, dijo. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Siga las \u00faltimas noticias sobre el brote de coronavirus (COVID-19) <\/p>\n<p> 2020 AFP <\/p>\n<p> <strong>Cita<\/strong>: Francia informa un r\u00e9cord de 588 muertes m\u00e1s por coronavirus (3 de abril de 2020) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-04-france-coronavirus-deaths-hospital .html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain Francia inform\u00f3 el viernes 588 muertes m\u00e1s por coronavirus en el hospital, su mayor n\u00famero de 24 horas en el pa\u00eds desde que comenz\u00f3 la epidemia. Las nuevas muertes elevan a 5.091 el n\u00famero total de personas que han muerto en el hospital de COVID-19 en Francia, dijo a los periodistas &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/francia-informa-un-record-de-588-muertes-mas-por-coronavirus\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abFrancia informa un r\u00e9cord de 588 muertes m\u00e1s por coronavirus\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25392","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/25392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=25392"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/25392\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=25392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=25392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=25392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}