{"id":25400,"date":"2022-08-31T13:20:13","date_gmt":"2022-08-31T18:20:13","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/en-el-hospital-de-campana-de-madrid-el-personal-busca-brindar-un-toque-humano\/"},"modified":"2022-08-31T13:20:13","modified_gmt":"2022-08-31T18:20:13","slug":"en-el-hospital-de-campana-de-madrid-el-personal-busca-brindar-un-toque-humano","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/en-el-hospital-de-campana-de-madrid-el-personal-busca-brindar-un-toque-humano\/","title":{"rendered":"En el hospital de campa\u00f1a de Madrid, el personal busca brindar un toque humano"},"content":{"rendered":"<p>En esta foto tomada el jueves 2 de abril de 2020, un bombero habla por tel\u00e9fono mientras descansa en un hospital de campa\u00f1a temporal ubicado en la convenci\u00f3n y exposici\u00f3n Ifema en Madrid, Espa\u00f1a . La mayor\u00eda de los 1.850 pacientes trasladados al hospital de campa\u00f1a de Ifema no se encuentran en estado grave. De hecho, 800 hab\u00edan sido dados de alta hasta el jueves, aunque seis hab\u00edan muerto desde que abrieron puertas hace 12 d\u00edas. El nuevo coronavirus causa s\u00edntomas leves o moderados en la mayor\u00eda de las personas, pero para algunas, especialmente los adultos mayores y las personas con problemas de salud existentes, puede causar una enfermedad m\u00e1s grave o la muerte. (Foto AP\/Manu Fernandez) <\/p>\n<p>Hay una estanter\u00eda llena de novelas donadas. Los art\u00edculos de tocador del hotel descansan sobre cajas de cart\u00f3n convertidas en mesitas de noche. Las comidas se sirven con notas personalizadas del personal. Y un ej\u00e9rcito de voluntarios hace todo lo posible para mantener un aire de optimismo en medio de la pandemia. <\/p>\n<p>En un cavernoso centro de convenciones que se ha convertido en el hospital improvisado m\u00e1s grande de Espa\u00f1a, estos toques de amabilidad y camarader\u00eda est\u00e1n ayudando a que los d\u00edas y las noches sean m\u00e1s llevaderos para los pacientes afectados por COVID-19.<\/p>\n<p>\u00abA pesar de la distancia que mantenemos unos de otros, hay un sentido de comunidad\u00bb, dijo Jonan Basterra mientras esperaba que el ox\u00edgeno en su sangre alcanzara un nivel lo suficientemente alto para poder irse a casa.<\/p>\n<p>El 50- paciente de un a\u00f1o sue\u00f1a con vencer al virus para poder afeitarse la barba que le ha crecido y celebrar con helado. Mientras tanto, descansa en la cama n\u00b0 15.18, haciendo amistad con otros o leyendo los libros que una enfermera trajo de casa y ofreci\u00f3 en una improvisada biblioteca abierta.<\/p>\n<p>\u201cEstamos todos juntos en esto y nos todos van a salir de aqu\u00ed juntos\u201d, dijo a The Associated Press a trav\u00e9s de una videollamada poco antes de que le entregaran una tortilla de papas de los platos nacionales de Espa\u00f1a con una nota personalizada de la cocina improvisada del hospital. Los cocineros se enteraron en las redes sociales sobre el antojo de Basterra por la comida.<\/p>\n<p> En esta foto tomada el jueves 2 de abril de 2020, los m\u00e9dicos trabajan en un hospital de campa\u00f1a temporal ubicado en la convenci\u00f3n y exposici\u00f3n Ifema en Madrid, Espa\u00f1a. La mayor\u00eda de los 1.850 pacientes trasladados al hospital de campa\u00f1a de Ifema no se encuentran en estado grave. De hecho, 800 hab\u00edan sido dados de alta hasta el jueves, aunque seis hab\u00edan muerto desde que abrieron puertas hace 12 d\u00edas. El nuevo coronavirus causa s\u00edntomas leves o moderados en la mayor\u00eda de las personas, pero para algunas, especialmente los adultos mayores y las personas con problemas de salud existentes, puede causar una enfermedad m\u00e1s grave o la muerte. (Foto AP\/Manu Fernandez) <\/p>\n<p>La mayor\u00eda de los 1.850 pacientes trasladados al hospital de campa\u00f1a de Ifema no se encuentran en estado grave. De hecho, el jueves hab\u00edan recibido el alta 800, aunque seis han muerto desde que se abrieron las puertas hace 12 d\u00edas. <\/p>\n<p>Pero la instalaci\u00f3n est\u00e1 ayudando a liberar espacio en hospitales cercanos sobrecargados. Madrid ha registrado casi 4.500 de los 11.000 muertos en Espa\u00f1a, tantos que el viernes se acondicionaba una nueva pista de patinaje sobre hielo para recibir cad\u00e1veres, la tercera morgue temporal de la regi\u00f3n.<\/p>\n<p>Los dos grandes pabellones que normalmente albergan a los comerciantes y los stands con exhibiciones corporativas ahora cuentan con 1.300 camas regulares y 16 unidades de cuidados intensivos. Las filas de camas est\u00e1n separadas por paneles, algunos de los cuales a\u00fan muestran fotograf\u00edas de maquinaria o complejos tur\u00edsticos de convenciones pasadas. Afuera, los trabajadores m\u00e9dicos toman descansos tomando el sol cerca de tres camiones de comida. Un soldado fuma un cigarrillo mientras suena m\u00fasica pop en los parlantes.<\/p>\n<p>Hace solo cuatro meses, pol\u00edticos y activistas como Greta Thunberg recorrieron los mismos terrenos para una cumbre sobre el cambio clim\u00e1tico patrocinada por la ONU que se traslad\u00f3 a Madrid despu\u00e9s de las protestas. Chile. <\/p>\n<p> En esta foto tomada el jueves 2 de abril de 2020, un m\u00e9dico sostiene documentos en un hospital de campa\u00f1a temporal ubicado en la convenci\u00f3n y exhibici\u00f3n de Ifema en Madrid, Espa\u00f1a. La mayor\u00eda de los 1.850 pacientes trasladados al hospital de campa\u00f1a de Ifema no se encuentran en estado grave. De hecho, 800 hab\u00edan sido dados de alta hasta el jueves, aunque seis hab\u00edan muerto desde que abrieron puertas hace 12 d\u00edas. El nuevo coronavirus causa s\u00edntomas leves o moderados en la mayor\u00eda de las personas, pero para algunas, especialmente los adultos mayores y las personas con problemas de salud existentes, puede causar una enfermedad m\u00e1s grave o la muerte. (Foto AP\/Manu Fernandez) <\/p>\n<p>Eso parece estar a un mundo de distancia ahora. Cuando los espa\u00f1oles se acercan a sus ventanas todas las noches para honrar a los m\u00e9dicos y enfermeras cansados que corren el riesgo de infectarse, el silencio en el hospital improvisado se rompe con los aplausos de los pacientes. En una noche reciente, los oradores tocaron la canci\u00f3n pop espa\u00f1ola de la d\u00e9cada de 1960 \u00abResistir\u00bb que se ha convertido en un himno durante el brote.<\/p>\n<p>Entre los que aplaud\u00edan estaba Esteban Pinadero, en la cama No. 01.18 . El hombre de 87 a\u00f1os fue trasladado este mi\u00e9rcoles de un hospital abarrotado a Ifema. Pero su familia no pudo encontrarlo hasta que un voluntario finalmente le trajo pilas nuevas para su aud\u00edfono. Su hija, Vicki, cont\u00f3 a AP c\u00f3mo contact\u00f3 a Basterra a trav\u00e9s de las redes sociales y logr\u00f3 concertar una videollamada con su padre.<\/p>\n<p>\u00abEstoy muy bien, los amo\u00bb, dijo Pinadero a media docena de familiares. en la llamada en un video grabado que la hija comparti\u00f3 con AP. Con el rostro semioculto por una mascarilla quir\u00fargica, Pinadero brome\u00f3: \u00abMe escapar\u00e9 en cuanto pueda\u00bb. Al otro lado de la pantalla, se pod\u00eda ver a los familiares sollozando.<\/p>\n<p>\u00abTodos aqu\u00ed extra\u00f1an el lenguaje no verbal, el contacto f\u00edsico, las sonrisas que ocultan las m\u00e1scaras\u00bb, dijo el Dr. Jess San Romn, que dirige un centro de llamadas improvisado en la instalaci\u00f3n. <\/p>\n<ul>\n<li data-thumb=\"https:\/\/scx1.b-cdn.net\/csz\/news\/tmb\/2020\/3-atmadridfiel.jpg\" data-src=\"https:\/\/scx2 .b-cdn.net\/gfx\/news\/hires\/2020\/3-atmadridfiel.jpg\" data-sub-html=\"En esta foto tomada el jueves 2 de abril de 2020, trabajadores m\u00e9dicos hablan en un hospital de campa\u00f1a temporal ubicado en Convenci\u00f3n y exposici\u00f3n de Ifema en Madrid (Espa\u00f1a). La mayor\u00eda de los 1.850 pacientes llevados al hospital de campa\u00f1a de Ifema no se encuentran en estado grave. De hecho, 800 hab\u00edan sido dados de alta hasta el jueves, aunque seis hab\u00edan muerto desde que se abrieron las puertas hace 12 d\u00edas. El nuevo coronavirus causa s\u00edntomas leves o moderados en la mayor\u00eda de las personas, pero para algunas, especialmente los adultos mayores y las personas con problemas de salud existentes, puede causar una enfermedad m\u00e1s grave o la muerte. (AP Photo\/Manu Fernandez)\"> En esta foto tomada el jueves 2 de abril , 2020, trabajadores m\u00e9dicos hablan en un hospital de campa\u00f1a temporal ubicado en la convenci\u00f3n y exhibici\u00f3n de Ifema en Madrid, Espa\u00f1a. La mayor\u00eda de los 1.850 pacientes trasladados al hospital de campa\u00f1a de Ifema no se encuentran en estado grave. De hecho, 800 hab\u00edan sido dados de alta hasta el jueves, aunque seis hab\u00edan muerto desde que abrieron puertas hace 12 d\u00edas. El nuevo coronavirus causa s\u00edntomas leves o moderados en la mayor\u00eda de las personas, pero para algunas, especialmente los adultos mayores y las personas con problemas de salud existentes, puede causar una enfermedad m\u00e1s grave o la muerte. (Foto AP\/Manu Fern\u00e1ndez) <\/li>\n<li data-thumb=\"https:\/\/scx1.b-cdn.net\/csz\/news\/tmb\/2020\/4-atmadridfiel.jpg\" data-src=\"https :\/\/scx2.b-cdn.net\/gfx\/news\/hires\/2020\/4-atmadridfiel.jpg\" data-sub-html=\"Esta foto tomada el jueves 2 de abril de 2020 muestra una vista general de un campo temporal hospital ambientado en la convenci\u00f3n y exposici\u00f3n de Ifema en Madrid, Espa\u00f1a.La mayor\u00eda de los 1.850 pacientes trasladados al hospital de campa\u00f1a de Ifema no se encuentran en estado grave.De hecho, 800 hab\u00edan sido dados de alta hasta el jueves, aunque seis hab\u00edan fallecido desde que se abrieron sus puertas hace 12 d\u00edas. El nuevo coronavirus causa s\u00edntomas leves o moderados en la mayor\u00eda de las personas, pero para algunas, especialmente los adultos mayores y las personas con problemas de salud existentes, puede causar una enfermedad m\u00e1s grave o la muerte. (AP Photo\/Manu Fernandez)\"> Esta foto tomada el jueves, El 2 de abril de 2020 muestra una vista general de un hospital de campa\u00f1a temporal en la convenci\u00f3n y exhibici\u00f3n de Ifema en Madrid, Espa\u00f1a. La mayor\u00eda de los 1.850 pacientes trasladados al hospital de campa\u00f1a de Ifema no se encuentran en estado grave. De hecho, 800 hab\u00edan sido dados de alta hasta el jueves, aunque seis hab\u00edan muerto desde que abrieron puertas hace 12 d\u00edas. El nuevo coronavirus causa s\u00edntomas leves o moderados en la mayor\u00eda de las personas, pero para algunas, especialmente los adultos mayores y las personas con problemas de salud existentes, puede causar una enfermedad m\u00e1s grave o la muerte. (Foto AP\/Manu Fern\u00e1ndez) <\/li>\n<li data-thumb=\"https:\/\/scx1.b-cdn.net\/csz\/news\/tmb\/2020\/5-atmadridfiel.jpg\" data-src=\"https :\/\/scx2.b-cdn.net\/gfx\/news\/hires\/2020\/5-atmadridfiel.jpg\" data-sub-html=\"Trabajadores de una funeraria trasladan un cad\u00e1ver de la residencia de ancianos Vitalia en Legan\u00e9s, Espa\u00f1a, el viernes , 3 de abril de 2020. El nuevo coronavirus causa s\u00edntomas leves o moderados en la mayor\u00eda de las personas, pero para algunas, especialmente los adultos mayores y las personas con problemas de salud existentes, puede causar una enfermedad m\u00e1s grave o la muerte. (AP Photo\/Manu Fernandez)\"> Trabajadores de una funeraria llevan un cad\u00e1ver desde las residencias de ancianos Vitalia en Legan\u00e9s, Espa\u00f1a, el viernes 3 de abril de 2020. El nuevo coronavirus causa s\u00edntomas leves o moderados en la mayor\u00eda de las personas, pero en algunas, especialmente en los adultos mayores y las personas con problemas de salud existentes, puede causar una enfermedad m\u00e1s grave o la muerte. (Foto AP\/Manu Fernandez) <\/li>\n<\/ul>\n<p>Recientes graduados de la escuela de medicina se ofrecen como voluntarios para mantener informados a los familiares de los pacientes sobre su condici\u00f3n por tel\u00e9fono, muy lejos de la comunicaci\u00f3n cara a cara que San Romn est\u00e1 acostumbrado en su trabajo habitual en el hospital.<\/p>\n<p>\u00abPero aqu\u00ed hacemos todo lo posible para superar eso, con videollamadas y mucha participaci\u00f3n personal\u00bb, dijo.<\/p>\n<p>A pesar de esos esfuerzos , la tragedia del brote nunca est\u00e1 lejos.<\/p>\n<p>Cuatro habitaciones en las instalaciones est\u00e1n etiquetadas con letreros que dicen \u00abInformaci\u00f3n para familiares\u00bb. La puerta conduce a un espacio dividido por una cortina, de un lado con una cama, del otro con sillas.<\/p>\n<p>Aqu\u00ed es donde se lleva a los moribundos para un \u00faltimo momento de privacidad con su familia, explic\u00f3 el Dr. Antonio Zapatero, director del hospital de campa\u00f1a, a\u00f1ade que es el \u00fanico momento en el que se permiten visitas en las instalaciones.<\/p>\n<p>Las habitaciones se han utilizado por primera vez esta semana.<\/p>\n<p>\u00abEs mi esperanza que no tengamos que volver a usarlos\u00bb, dijo Zapatero. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Siga las \u00faltimas noticias sobre el brote de coronavirus (COVID-19) <\/p>\n<p> 2020 The Associated Press. Reservados todos los derechos. Este material no puede ser publicado, transmitido, reescrito o redistribuido sin permiso. <\/p>\n<p> <strong>Cita<\/strong>: En el hospital de campa\u00f1a de Madrid, el personal busca brindar un toque humano (3 de abril de 2020) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-04-madrid -field-hospital-staff-human.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta foto tomada el jueves 2 de abril de 2020, un bombero habla por tel\u00e9fono mientras descansa en un hospital de campa\u00f1a temporal ubicado en la convenci\u00f3n y exposici\u00f3n Ifema en Madrid, Espa\u00f1a . La mayor\u00eda de los 1.850 pacientes trasladados al hospital de campa\u00f1a de Ifema no se encuentran en estado grave. De &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/en-el-hospital-de-campana-de-madrid-el-personal-busca-brindar-un-toque-humano\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEn el hospital de campa\u00f1a de Madrid, el personal busca brindar un toque humano\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25400","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/25400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=25400"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/25400\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=25400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=25400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=25400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}