{"id":26184,"date":"2022-08-31T14:08:59","date_gmt":"2022-08-31T19:08:59","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/parques-llenos-terrazas-abiertas-mientras-madrid-y-barcelona-celebran-la-flexibilizacion\/"},"modified":"2022-08-31T14:08:59","modified_gmt":"2022-08-31T19:08:59","slug":"parques-llenos-terrazas-abiertas-mientras-madrid-y-barcelona-celebran-la-flexibilizacion","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/parques-llenos-terrazas-abiertas-mientras-madrid-y-barcelona-celebran-la-flexibilizacion\/","title":{"rendered":"Parques llenos, terrazas abiertas mientras Madrid y Barcelona celebran la flexibilizaci\u00f3n"},"content":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain <\/p>\n<p>Cientos de residentes de Madrid inundaron los parques de la ciudad cuando finalmente se relajaron las medidas de cierre en la capital espa\u00f1ola y en Barcelona, mientras que las playas reabrieron en algunas partes del pa\u00eds despu\u00e9s de meses de cierre. <\/p>\n<p>Adem\u00e1s de reabrir las puertas de los parques de la capital por primera vez desde mediados de marzo, los vecinos de las dos ciudades ya pueden reunirse en grupos de hasta 10 personas en viviendas o en las terrazas de bares y restaurantes.<\/p>\n<p> p&gt; <\/p>\n<p>Las medidas de flexibilizaci\u00f3n se producen cuando la regi\u00f3n de Madrid, la ciudad de Barcelona y gran parte de Castilla y Le\u00f3n en el noroeste entran formalmente en la primera fase de reversi\u00f3n de uno de los confinamientos m\u00e1s estrictos del mundo.<\/p>\n<p>Estas \u00e1reas han ido m\u00e1s lentamente, ya que fueron las m\u00e1s afectadas por la pandemia en Espa\u00f1a, que ha causado la muerte de m\u00e1s de 28\u00a0700 personas, una de las m\u00e1s altas del mundo.<\/p>\n<p>En Madrid, cientos de personas result\u00f3 disfrutar de un paseo matutino bajo el sol en el famoso Parque del Retiro de la ciudad, con decenas de corredores trotando por sus amplias avenidas y pasando por el lago navegable. <\/p>\n<p>\u00abLa reapertura de Retiro me trae una sensaci\u00f3n de serenidad, me da consuelo\u00bb, dijo Rosa San Jos\u00e9, una maestra de 50 a\u00f1os vestida con ropa de gimnasia y una m\u00e1scara que sali\u00f3 a caminar antes de comenzar. el d\u00eda escolar en l\u00ednea.<\/p>\n<p>En otra parte de la ciudad, la cafeter\u00eda San Gin\u00e9s, famosa por sus churros y chocolate, coloc\u00f3 seis mesas en la acera, menos de las 13 habituales para garantizar el distanciamiento social. <\/p>\n<p>Por ahora, las \u00e1reas de asientos interiores deben permanecer cerradas. <\/p>\n<p>\u00abLlevamos 125 a\u00f1os abiertos y es la primera vez que hemos tenido que cerrar\u00bb, dijo a la AFP el gerente Daniel Real. <\/p>\n<p>\u00abPronto volveremos a estar abiertos las 24 horas como antes, pero por ahora no estamos trabajando de noche porque no hay turistas y porque la discoteca que nos trae mucha clientela es cerrado\u00bb.<\/p>\n<p>Libertad, con l\u00edmites<\/p>\n<p>En otros lugares, las regiones que agrupan a poco menos de la mitad de los casi 47 millones de habitantes de Espa\u00f1a estaban entrando en la fase dos de la reversi\u00f3n de tres etapas que se espera que sea completado a finales de junio.<\/p>\n<p>Por ahora, todas las nuevas libertades en p\u00fablico deben llevarse a cabo con una m\u00e1scara donde no es posible mantener una distancia de dos metros (seis pies).<\/p>\n<p>Con el aumento del calor del verano, las playas a lo largo de la costa norte de Espa\u00f1a, as\u00ed como algunas \u00e1reas en el sur, incluidas las Islas Canarias y Baleares, ahora est\u00e1n abiertas para nadar, sujetas a medidas de seguridad.<\/p>\n<p> El ministerio de salud recomienda limitar el n\u00famero de ba\u00f1istas, crear l\u00edmites y colocar sombrillas a cuatro metros de distancia.<\/p>\n<p>Pero por ahora, solo los locales se beneficiar\u00e1n, con viajes entre n regiones a\u00fan est\u00e1n prohibidas y cualquier visitante extranjero que llegue a Espa\u00f1a est\u00e1 obligado a someterse a una cuarentena de 14 d\u00edas.<\/p>\n<p>Espa\u00f1a ha dicho que abrir\u00e1 las fronteras a los turistas extranjeros en julio.<\/p>\n<p>Pero la lentitud del gobierno proceso de levantamiento de las restricciones tiene una reacci\u00f3n pol\u00edtica de los partidos de derecha, as\u00ed como una creciente ola de protestas en las calles. <\/p>\n<p>El s\u00e1bado, miles de personas se unieron a las protestas en sus autom\u00f3viles en las principales ciudades espa\u00f1olas a la llamada de la ultraderecha Vox, con conductores tocando la bocina, ondeando banderas espa\u00f1olas y golpeando cacerolas para denunciar el manejo de la crisis por parte del gobierno. . <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Se ordena a los espa\u00f1oles mayores de seis a\u00f1os que usen m\u00e1scaras <\/p>\n<p> 2020 AFP <\/p>\n<p> <strong>Cita<\/strong>: Parques llenos, terrazas abiertas mientras Madrid y Barcelona celebran la flexibilizaci\u00f3n (2020, 25 de mayo) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-05-terraces-madrid-barcelona-celebrate-easing.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain Cientos de residentes de Madrid inundaron los parques de la ciudad cuando finalmente se relajaron las medidas de cierre en la capital espa\u00f1ola y en Barcelona, mientras que las playas reabrieron en algunas partes del pa\u00eds despu\u00e9s de meses de cierre. Adem\u00e1s de reabrir las puertas de los parques de la &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/parques-llenos-terrazas-abiertas-mientras-madrid-y-barcelona-celebran-la-flexibilizacion\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abParques llenos, terrazas abiertas mientras Madrid y Barcelona celebran la flexibilizaci\u00f3n\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-26184","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/26184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=26184"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/26184\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=26184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=26184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=26184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}