{"id":28018,"date":"2022-08-31T16:02:08","date_gmt":"2022-08-31T21:02:08","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/el-electrocardiograma-muestra-valor-en-las-pantallas-de-los-atletas-universitarios\/"},"modified":"2022-08-31T16:02:08","modified_gmt":"2022-08-31T21:02:08","slug":"el-electrocardiograma-muestra-valor-en-las-pantallas-de-los-atletas-universitarios","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/el-electrocardiograma-muestra-valor-en-las-pantallas-de-los-atletas-universitarios\/","title":{"rendered":"El electrocardiograma muestra valor en las pantallas de los atletas universitarios"},"content":{"rendered":"<p>Este ECG marcadamente anormal condujo a un diagn\u00f3stico de miocardiopat\u00eda hipertr\u00f3fica, una afecci\u00f3n card\u00edaca peligrosa. Cr\u00e9dito: UW Medicine <\/p>\n<p>Durante los \u00faltimos 30 a\u00f1os, los colegios y universidades han evaluado cada vez m\u00e1s a los atletas en busca de condiciones de salud que puedan representar un riesgo indebido para la participaci\u00f3n deportiva. La muerte card\u00edaca s\u00fabita es la principal causa de muerte entre los atletas universitarios, por lo que la funci\u00f3n principal de estos ex\u00e1menes es revelar afecciones card\u00edacas desconocidas. <\/p>\n<p>La National Collegiate Athletic Association requiere un examen f\u00edsico inicial previo a la participaci\u00f3n y el historial del paciente; algunas escuelas tambi\u00e9n administran un electrocardiograma (ECG), que mide la salida el\u00e9ctrica del latido del coraz\u00f3n de una persona. Sin embargo, existe desacuerdo sobre el valor de los ECG. Si bien los expertos generalmente est\u00e1n de acuerdo en que un ECG puede se\u00f1alar problemas card\u00edacos preocupantes, los detractores dicen que genera demasiados resultados positivos falsos, lo que lleva a costos y pruebas adicionales innecesarias.<\/p>\n<p>La investigaci\u00f3n publicada hoy indica que las pruebas de detecci\u00f3n que incorporan un Los ECG son m\u00e1s efectivos para detectar afecciones card\u00edacas que ponen en riesgo a los atletas, y m\u00e1s eficientes en t\u00e9rminos de costo por diagn\u00f3stico de jugadores en riesgo, que las evaluaciones que involucran solo un examen f\u00edsico y el historial del paciente.<\/p>\n<p> La revista Heart Rhythm public\u00f3 la investigaci\u00f3n multiinstitucional. Fue dirigido por la Dra. Kimberly Harmon, jefa de secci\u00f3n de medicina deportiva en la Facultad de Medicina de la Universidad de Washington y m\u00e9dica principal del equipo de f\u00fatbol de la UW.<\/p>\n<p>Harmon y sus colegas encontraron que, a trav\u00e9s de 8602 registros de Pacific- 12 atletas de conferencias, los ex\u00e1menes cardiovasculares con un ECG adem\u00e1s del historial del paciente y un examen f\u00edsico ten\u00edan seis veces m\u00e1s probabilidades de detectar una afecci\u00f3n card\u00edaca de riesgo que los ex\u00e1menes que involucraban solo el historial y el examen f\u00edsico del paciente. Paralelamente, el uso de ECG mejor\u00f3 cinco veces la rentabilidad por diagn\u00f3stico.<\/p>\n<p>\u00abEsta es una evaluaci\u00f3n del mundo real de los descubrimientos resultantes de diferentes estrategias de detecci\u00f3n y cu\u00e1nto cuestan\u00bb, dijo Harmon. \u00abEste estudio muestra que la detecci\u00f3n con ECG no solo es significativamente m\u00e1s efectiva, sino que es cada vez m\u00e1s costosa en general y cuesta mucho menos por diagn\u00f3stico. Se puede implementar por mucho menos que el costo de un par de zapatos deportivos\u00bb.<\/p>\n<p>Los investigadores buscaron comparar los hallazgos positivos, la prevalencia de la enfermedad y los costos de dos estrategias de detecci\u00f3n. Recopilaron nueve a\u00f1os de datos anonimizados de atletas de las instituciones de la Conferencia Pac-12, que emplean estrategias variadas para las evaluaciones f\u00edsicas previas a la participaci\u00f3n. Tambi\u00e9n se analizaron las pruebas secundarias, los diagn\u00f3sticos card\u00edacos, los resultados del regreso al juego y las complicaciones de las pruebas.<\/p>\n<p>De 8602 evaluaciones, se identificaron 11 atletas con afecciones cardiovasculares:<\/p>\n<ul>\n<li> Historial y examen f\u00edsico: dos atletas (de 4955) fueron identificados como en riesgo, lo que equivale a una prevalencia del 0,05 % (1 en 2454). El costo de la evaluaci\u00f3n por atleta promedi\u00f3 $130; el costo por diagn\u00f3stico fue de $312 407.<\/li>\n<li>Antecedentes, examen f\u00edsico y ECG: nueve atletas (de 3647) fueron identificados como en riesgo, lo que equivale a una prevalencia del 0,024 % (1 en 410). El costo de la prueba de detecci\u00f3n por atleta fue de $152; el costo por diagn\u00f3stico fue de $61,712.<\/li>\n<\/ul>\n<p>Los costos de las pruebas de detecci\u00f3n y las pruebas secundarias se basaron en el programa de tarifas m\u00e9dicas de los Centros de Servicios de Medicare y Medicaid.<\/p>\n<p>\u00abEsta es la primera estudio para comparar ex\u00e1menes mediante el uso de resultados de la vida real en lugar de modelos te\u00f3ricos y suposiciones variables\u00bb, dijo Harmon, profesor de medicina familiar y de ortopedia y medicina deportiva de la UW.<\/p>\n<p>No todas las escuelas pueden incorporar pruebas de ECG en evaluaciones de atletas, dijo Harmon. Se trata menos de cubrir el costo de una prueba de $22 y m\u00e1s de si los m\u00e9dicos est\u00e1n disponibles para interpretar los ECG.<\/p>\n<p>El estudio incluy\u00f3 evaluaciones de atletas en todos los deportes universitarios, aunque el baloncesto y el f\u00fatbol masculino representan m\u00e1s de 50% de las muertes card\u00edacas s\u00fabitas entre los atletas universitarios, dijo. Varias escuelas Pac-12 han priorizado esos deportes para la evaluaci\u00f3n. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> No hay respuestas f\u00e1ciles sobre el mejor chequeo card\u00edaco para atletas j\u00f3venes <strong>M\u00e1s informaci\u00f3n:<\/strong> Kimberly G. Harmon et al, Comparaci\u00f3n de ex\u00e1menes de detecci\u00f3n cardiovasculares en atletas universitarios por historial y examen f\u00edsico con y sin Electrocardiograma: Eficacia y Costo, Ritmo Card\u00edaco (2020). DOI: 10.1016\/j.hrthm.2020.04.032 Proporcionado por la Universidad de Washington <strong>Cita<\/strong>: El electrocardiograma muestra valor en las pantallas de atletas universitarios (4 de mayo de 2020) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress. com\/news\/2020-05-electrocardiogram-college-athletes-screens.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este ECG marcadamente anormal condujo a un diagn\u00f3stico de miocardiopat\u00eda hipertr\u00f3fica, una afecci\u00f3n card\u00edaca peligrosa. Cr\u00e9dito: UW Medicine Durante los \u00faltimos 30 a\u00f1os, los colegios y universidades han evaluado cada vez m\u00e1s a los atletas en busca de condiciones de salud que puedan representar un riesgo indebido para la participaci\u00f3n deportiva. La muerte card\u00edaca s\u00fabita &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/el-electrocardiograma-muestra-valor-en-las-pantallas-de-los-atletas-universitarios\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl electrocardiograma muestra valor en las pantallas de los atletas universitarios\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-28018","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/28018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=28018"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/28018\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=28018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=28018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=28018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}