{"id":28034,"date":"2022-08-31T16:03:04","date_gmt":"2022-08-31T21:03:04","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/la-combinacion-de-datos-de-ratones-y-humanos-descubre-un-nuevo-gen-que-regula-el-colesterol\/"},"modified":"2022-08-31T16:03:04","modified_gmt":"2022-08-31T21:03:04","slug":"la-combinacion-de-datos-de-ratones-y-humanos-descubre-un-nuevo-gen-que-regula-el-colesterol","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/la-combinacion-de-datos-de-ratones-y-humanos-descubre-un-nuevo-gen-que-regula-el-colesterol\/","title":{"rendered":"La combinaci\u00f3n de datos de ratones y humanos descubre un nuevo gen que regula el colesterol"},"content":{"rendered":"<p>El trabajo de Brian Parks y sus colaboradores proporciona un nuevo objetivo para comprender el riesgo gen\u00e9tico del colesterol alto, que est\u00e1 relacionado con las enfermedades del coraz\u00f3n. Cr\u00e9dito: CDC <\/p>\n<p>La medicina de precisi\u00f3n tiene el potencial de adaptar los tratamientos a la secuencia gen\u00e9tica \u00fanica de un paciente. Pero lograr esta precisi\u00f3n o desarrollar nuevos f\u00e1rmacos requiere saber qu\u00e9 genes est\u00e1n involucrados en la enfermedad. <\/p>\n<p>\u00abDesafortunadamente, en realidad no tenemos una buena comprensi\u00f3n de c\u00f3mo estas diferencias gen\u00e9ticas pueden generar diferencias en los rasgos, ya sea colesterol u obesidad\u00bb, dice Brian Parks, profesor de ciencias de la nutrici\u00f3n en la Universidad de Wisconsin-Madison. <\/p>\n<p>Para superar estas limitaciones, Parks y sus colaboradores han desarrollado un nuevo m\u00e9todo que puede sacar de la oscuridad genes previamente desconocidos. Al combinar los detalles detallados disponibles de los estudios en animales con el poder estad\u00edstico de los estudios gen\u00e9ticos que involucran cientos de miles de genomas humanos, los investigadores han descubierto un nuevo gen involucrado en la regulaci\u00f3n del colesterol del cuerpo.<\/p>\n<p>El trabajo proporciona una nuevo objetivo para comprender el riesgo gen\u00e9tico del colesterol alto, que est\u00e1 relacionado con las enfermedades del coraz\u00f3n. Igual de importante, el estudio proporciona una nueva forma de revelar c\u00f3mo la variaci\u00f3n gen\u00e9tica subyace en una serie de enfermedades humanas, que es el primer paso para tratarlas.<\/p>\n<p>Parks y los miembros de su equipo en otras universidades publicaron recientemente sus hallazgos. en la revista Cell Metabolism. El gen recientemente identificado, Sestrin1, regula los niveles de colesterol al detener la producci\u00f3n de colesterol en el h\u00edgado cuando los alimentos proporcionan suficiente nutriente esencial.<\/p>\n<p>La clave de sus hallazgos fue la fortaleza relativa de los estudios en animales y humanos. El equipo de Parks podr\u00eda usar h\u00edgados de rat\u00f3n para investigar redes gen\u00e9ticas involucradas en la s\u00edntesis de colesterol, proporcionando datos que rara vez est\u00e1n disponibles en humanos. Identificaron 112 genes vinculados a redes gen\u00e9ticas de colesterol conocidas.<\/p>\n<p>Luego, los investigadores observaron cu\u00e1les de esos 112 genes se superpon\u00edan con secuencias de ADN potencialmente vinculadas al colesterol en humanos. Los datos humanos provinieron de enormes estudios gen\u00e9ticos que acumulan datos de salud para tratar de encontrar un v\u00ednculo entre los genes y la enfermedad.<\/p>\n<p>\u00abPodemos hacer estos estudios muy grandes en humanos de 500\u00a0000 personas, y podemos identificar regiones de el genoma que est\u00e1n asociados con, digamos, diferencias en el colesterol en la sangre\u00bb, dice Parks. \u00abPero eso solo nos da una especie de farola para encender una luz. No nos dice qu\u00e9 gen o v\u00eda subyacente est\u00e1 contribuyendo potencialmente a esa asociaci\u00f3n\u00bb.<\/p>\n<p>De los 112 genes con los que comenzaron, 54 ten\u00eda v\u00ednculos con datos humanos. \u00abY se sabe que la mayor\u00eda de ellos est\u00e1n involucrados en el colesterol o el metabolismo de los l\u00edquidos. Pero est\u00e1bamos interesados en los que eran desconocidos\u00bb, dice Parks.<\/p>\n<p>Veinticinco de esos genes no se hab\u00edan identificado previamente. vinculado a los niveles de colesterol en humanos, lo que los convirti\u00f3 en nuevos objetivos potenciales. El equipo de Parks estudi\u00f3 esos 25 genes en modelos de rat\u00f3n y los compar\u00f3 con nuevos lotes de datos gen\u00f3micos humanos. Sestrin1 se destac\u00f3.<\/p>\n<p>El gen nunca antes se hab\u00eda asociado con el colesterol, pero el equipo de investigaci\u00f3n descubri\u00f3 que Sestrin1 ayuda a regular los niveles de colesterol en la sangre. Promueve la s\u00edntesis de colesterol hasta que es bloqueado por el colesterol de la dieta. Los ratones a los que les faltaba el gen no pod\u00edan regular adecuadamente los niveles de colesterol. Desarrollaron colesterol alto cuando consum\u00edan dietas que conten\u00edan niveles normales de colesterol porque sus h\u00edgados no respond\u00edan adecuadamente.<\/p>\n<p>Los investigadores dicen que ten\u00edan una ventaja al investigar el colesterol, que est\u00e1 controlado principalmente por un solo tejido, el h\u00edgado. Pero su m\u00e9todo que combina datos de ratones y humanos tiene el potencial de ayudar a descubrir otros genes previamente desconocidos, una gran ayuda para comprender y tratar enfermedades.<\/p>\n<p>\u00abCiertamente existe la posibilidad de extender esta t\u00e9cnica a otros rasgos como la obesidad\u00bb. dice Parques. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Lo que necesita saber sobre el colesterol <strong>M\u00e1s informaci\u00f3n:<\/strong> Zhonggang Li et al, Integraci\u00f3n de datos gen\u00e9ticos humanos y de rat\u00f3n para ir m\u00e1s all\u00e1 de GWAS e identificar genes causales en el metabolismo del colesterol, Cell Metabolismo (2020). DOI: 10.1016\/j.cmet.2020.02.015 <strong>Informaci\u00f3n de la revista:<\/strong> Cell Metabolism <\/p>\n<p> Proporcionado por la Universidad de Wisconsin-Madison <strong>Cita<\/strong>: La combinaci\u00f3n de datos humanos y de ratones descubre nuevos gen que regula el colesterol (4 de mayo de 2020) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-05-combining-mouse-human-uncovers-gene.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El trabajo de Brian Parks y sus colaboradores proporciona un nuevo objetivo para comprender el riesgo gen\u00e9tico del colesterol alto, que est\u00e1 relacionado con las enfermedades del coraz\u00f3n. Cr\u00e9dito: CDC La medicina de precisi\u00f3n tiene el potencial de adaptar los tratamientos a la secuencia gen\u00e9tica \u00fanica de un paciente. Pero lograr esta precisi\u00f3n o desarrollar &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/la-combinacion-de-datos-de-ratones-y-humanos-descubre-un-nuevo-gen-que-regula-el-colesterol\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa combinaci\u00f3n de datos de ratones y humanos descubre un nuevo gen que regula el colesterol\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-28034","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/28034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=28034"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/28034\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=28034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=28034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=28034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}