{"id":30323,"date":"2022-08-31T18:11:17","date_gmt":"2022-08-31T23:11:17","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/puedo-contagiarme-de-covid-19-a-traves-de-los-ojos-o-los-oidos\/"},"modified":"2022-08-31T18:11:17","modified_gmt":"2022-08-31T23:11:17","slug":"puedo-contagiarme-de-covid-19-a-traves-de-los-ojos-o-los-oidos","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/puedo-contagiarme-de-covid-19-a-traves-de-los-ojos-o-los-oidos\/","title":{"rendered":"\u00bfPuedo contagiarme de COVID-19 a trav\u00e9s de los ojos o los o\u00eddos?"},"content":{"rendered":"<p>Ilustraci\u00f3n de Peter Hamlin <\/p>\n<p>\u00bfPuedo contagiarme de COVID-19 a trav\u00e9s de los ojos o los o\u00eddos? <\/p>\n<p>Es posible a trav\u00e9s de los ojos, pero no es probable a trav\u00e9s de los o\u00eddos.<\/p>\n<p>Al igual que con la nariz y la boca, los m\u00e9dicos dicen que los ojos pueden ser una ruta de infecci\u00f3n si alguien con el virus tose o estornuda cerca. La infecci\u00f3n tambi\u00e9n es posible al frotarse los ojos con las manos que han estado expuestas al virus.<\/p>\n<p>Las l\u00e1grimas de una persona infectada se propagan, incluso a trav\u00e9s de los ojos.<\/p>\n<p>Los anteojos tambi\u00e9n pueden ofrecer protecci\u00f3n adicional , seg\u00fan la Academia Americana de Oftalmolog\u00eda. Se recomienda a los trabajadores de la salud que usen gafas de seguridad cuando traten a pacientes potencialmente infectados. <\/p>\n<p>Las orejas, por otro lado, no se cree que sean una v\u00eda de infecci\u00f3n por COVID-19, seg\u00fan los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE. UU.<\/p>\n<p>La piel de la parte externa El canal auditivo se parece m\u00e1s a la piel normal, a diferencia del tejido de la boca, la nariz y los senos paranasales. Eso crea una barrera que dificulta la entrada del virus, seg\u00fan el Dr. Benjamin Bleier de Massachusetts Eye and Ear en Boston. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Siga las \u00faltimas noticias sobre el brote de coronavirus (COVID-19) <\/p>\n<p> 2020 The Associated Press. Reservados todos los derechos. Este material no puede ser publicado, transmitido, reescrito o redistribuido sin permiso. <\/p>\n<p> <strong>Cita<\/strong>: \u00bfPuedo contagiarme de COVID-19 a trav\u00e9s de los ojos o los o\u00eddos? (4 de junio de 2020) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-06-covid-eyes-ears.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ilustraci\u00f3n de Peter Hamlin \u00bfPuedo contagiarme de COVID-19 a trav\u00e9s de los ojos o los o\u00eddos? Es posible a trav\u00e9s de los ojos, pero no es probable a trav\u00e9s de los o\u00eddos. Al igual que con la nariz y la boca, los m\u00e9dicos dicen que los ojos pueden ser una ruta de infecci\u00f3n si alguien &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/puedo-contagiarme-de-covid-19-a-traves-de-los-ojos-o-los-oidos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u00bfPuedo contagiarme de COVID-19 a trav\u00e9s de los ojos o los o\u00eddos?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30323","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30323"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30323\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}