{"id":30342,"date":"2022-08-31T18:12:22","date_gmt":"2022-08-31T23:12:22","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/la-primicia-mundial-en-impresion-3d-le-da-un-toque-personal-para-mantener-el-flujo-de-sangre\/"},"modified":"2022-08-31T18:12:22","modified_gmt":"2022-08-31T23:12:22","slug":"la-primicia-mundial-en-impresion-3d-le-da-un-toque-personal-para-mantener-el-flujo-de-sangre","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/la-primicia-mundial-en-impresion-3d-le-da-un-toque-personal-para-mantener-el-flujo-de-sangre\/","title":{"rendered":"La primicia mundial en impresi\u00f3n 3D le da un toque personal para mantener el flujo de sangre"},"content":{"rendered":"<p>Los stents de prueba de concepto ofrecen el potencial de personalizaci\u00f3n para los requisitos individuales del paciente, pero son igualmente adecuados para la producci\u00f3n en masa. Cr\u00e9dito: CSIRO <\/p>\n<p>Investigadores de CSIRO, la agencia cient\u00edfica nacional de Australia, han hecho posible la impresi\u00f3n en 3D de stents hechos a medida, un dispositivo biom\u00e9dico fundamental que se utiliza para tratar arterias estrechas o bloqueadas. <\/p>\n<p>El avance, realizado en asociaci\u00f3n con Medical Innovation Hub con sede en Wollongong, representa un cambio de paradigma en la producci\u00f3n de stents de nitinol autoexpandibles para la enfermedad arterial perif\u00e9rica (EAP), que afecta a m\u00e1s del 10 % de los australianos.<\/p>\n<p>PAD es una afecci\u00f3n en la que se acumulan dep\u00f3sitos de grasa y reducen el flujo sangu\u00edneo en las arterias fuera del coraz\u00f3n, m\u00e1s com\u00fanmente en las piernas. Las personas con PAD generalmente experimentan dolor al caminar y, en casos graves, pueden desarrollar gangrena.<\/p>\n<p>La ministra de Industria, Ciencia y Tecnolog\u00eda, Karen Andrews, dijo que la tecnolog\u00eda desarrollada internamente ten\u00eda el potencial de revolucionar el stent global de $ 16 mil millones industria manufacturera.<\/p>\n<p>\u00abEste es un gran ejemplo de la industria que trabaja con nuestros investigadores para desarrollar un producto innovador que aborda una necesidad global y se basa en nuestra capacidad soberana\u00bb, dijo el ministro Andrews.<\/p>\n<p>Hasta ahora, los cirujanos se han limitado a acceder a stents \u00ablistos para usar\u00bb para operaciones.<\/p>\n<p>Se espera que la capacidad de imprimir stents en 3D mejore las opciones de tama\u00f1o, conserve la anatom\u00eda esencial y permita di\u00e1metros y formas para adaptarse a los requisitos individuales de los pacientes.<\/p>\n<p>El proceso tambi\u00e9n podr\u00eda permitir la fabricaci\u00f3n de stents individuales en el sitio, bajo la direcci\u00f3n del cirujano, reduciendo el inventario y ahorrando dinero.<\/p>\n<p>Encontrar un forma de imprimir en 3D un stent de nitinol autoexpandible sin comprometer la Las propiedades \u00fanicas del metal han desafiado a los metal\u00fargicos de todo el mundo.<\/p>\n<p>El equipo de cient\u00edficos del Lab22 de CSIRO en Melbourne resolvi\u00f3 el problema utilizando un proceso de impresi\u00f3n 3D de vanguardia llamado fusi\u00f3n selectiva por l\u00e1ser.<\/p>\n<p>El cient\u00edfico principal de investigaci\u00f3n de CSIRO, el Dr. Sri Lathabai, dijo que el proceso les permiti\u00f3 crear productos complejos con alta precisi\u00f3n geom\u00e9trica que son espec\u00edficos para cada paciente.<\/p>\n<p>\u00abEl nitinol es una aleaci\u00f3n con memoria de forma y propiedades superel\u00e1sticas\u00bb, dijo el Dr. Lathabai dijo.<\/p>\n<p>\u00abEs una aleaci\u00f3n complicada para trabajar en condiciones de impresi\u00f3n 3D, debido a su sensibilidad al estr\u00e9s y al calor.<\/p>\n<p>\u00abTuvimos que seleccionar el 3D adecuado -imprimir par\u00e1metros para obtener la estructura de malla ultrafina necesaria para un stent endovascular, as\u00ed como administrar cuidadosamente los tratamientos t\u00e9rmicos para que el producto terminado pueda expandirse seg\u00fan sea necesario, una vez dentro del cuerpo\u00bb.<\/p>\n<p>Director ejecutivo de Medical Innovation Hub El Dr. Arthur Stanton es un cirujano vascular que ha tratado a miles de pacientes y vio la necesidad de mejorar ed.<\/p>\n<p>\u00abActualmente, los cirujanos usan stents est\u00e1ndar y, aunque vienen en varias formas y tama\u00f1os, en general existen limitaciones en la gama de stents disponibles\u00bb, dijo el Dr. Stanton.<\/p>\n<p>\u00abCreemos que nuestros nuevos stents de nitinol autoexpandibles impresos en 3D ofrecen una mejor experiencia para el paciente a trav\u00e9s de mejores dispositivos de ajuste, mejor conformidad con los vasos sangu\u00edneos y mejores tiempos de recuperaci\u00f3n.<\/p>\n<p>\u00abHay tambi\u00e9n es la oportunidad para que la tecnolog\u00eda se utilice para la producci\u00f3n masiva de stents, potencialmente a un costo m\u00e1s bajo\u00bb. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Los stents de pol\u00edmero impresos en 3D crecen con los pacientes pedi\u00e1tricos y se biodegradan con el tiempo Proporcionado por CSIRO <strong>Cita<\/strong>: La primicia mundial en impresi\u00f3n 3D da un toque personal para mantener el flujo de sangre (4 de junio de 2020) consultado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-06-world -d-personal-blood.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los stents de prueba de concepto ofrecen el potencial de personalizaci\u00f3n para los requisitos individuales del paciente, pero son igualmente adecuados para la producci\u00f3n en masa. Cr\u00e9dito: CSIRO Investigadores de CSIRO, la agencia cient\u00edfica nacional de Australia, han hecho posible la impresi\u00f3n en 3D de stents hechos a medida, un dispositivo biom\u00e9dico fundamental que se &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/la-primicia-mundial-en-impresion-3d-le-da-un-toque-personal-para-mantener-el-flujo-de-sangre\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa primicia mundial en impresi\u00f3n 3D le da un toque personal para mantener el flujo de sangre\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30342","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30342"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30342\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}