{"id":30349,"date":"2022-08-31T18:12:45","date_gmt":"2022-08-31T23:12:45","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/se-avecina-otra-crisis-de-salud-que-sucedera-cuando-las-maquinas-de-poquer-vuelvan-a-encenderse\/"},"modified":"2022-08-31T18:12:45","modified_gmt":"2022-08-31T23:12:45","slug":"se-avecina-otra-crisis-de-salud-que-sucedera-cuando-las-maquinas-de-poquer-vuelvan-a-encenderse","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/se-avecina-otra-crisis-de-salud-que-sucedera-cuando-las-maquinas-de-poquer-vuelvan-a-encenderse\/","title":{"rendered":"Se avecina otra crisis de salud: \u00bfqu\u00e9 suceder\u00e1 cuando las m\u00e1quinas de p\u00f3quer vuelvan a encenderse?"},"content":{"rendered":"<p>Cr\u00e9dito: Shutterstock <\/p>\n<p>Cuando las restricciones por el COVID-19 entraron en vigor hace m\u00e1s de dos meses, las 200\u00a0000 m\u00e1quinas de p\u00f3quer del pa\u00eds se apagaron. . <\/p>\n<p>Ahora, las m\u00e1quinas tragamonedas se est\u00e1n volviendo a encender lentamente en todo el pa\u00eds. Esta semana, NSW se convirti\u00f3 en el primer estado en permitir la reapertura de los lugares, con ciertas reglas que obligan a los clientes a mantener una distancia de 1,5 metros. <\/p>\n<p>Aunque es necesario considerar los riesgos para la salud, parece que se piensa poco o nada en la gesti\u00f3n de los riesgos de da\u00f1os en el juego que podr\u00edan derivarse de reiniciar las m\u00e1quinas despu\u00e9s de una pausa tan extensa. <\/p>\n<p>La recesi\u00f3n econ\u00f3mica y la p\u00e9rdida masiva de puestos de trabajo hacen que la situaci\u00f3n sea a\u00fan m\u00e1s preocupante. Sabemos que cuando las personas experimentan dificultades financieras, es m\u00e1s probable que apuesten. Y los jugadores en riesgo, en particular, tienen m\u00e1s probabilidades de experimentar dificultades financieras significativas a largo plazo.<\/p>\n<p>Un descanso obligatorio del juego<\/p>\n<p>Cuando los clubes, casinos y hoteles fueron cerrados A fines de marzo, exist\u00eda el temor de que los jugadores de \u00abtragamonedas\u00bb pudieran hacer la transici\u00f3n a formas de juego en l\u00ednea. <\/p>\n<p>Tenemos evidencia limitada, hasta el momento, en cuanto a la aceptaci\u00f3n real de otras formas de juego durante el cierre. Sin embargo, una encuesta de jugadores realizada en el ACT el a\u00f1o pasado encontr\u00f3 que solo el 0.8% de los jugadores participaban en juegos de casino o m\u00e1quinas tragamonedas en el extranjero. <\/p>\n<p>La investigaci\u00f3n en NSW tambi\u00e9n encontr\u00f3 que solo el 2,3 % de los j\u00f3venes de 18 a 24 a\u00f1os jugaba juegos de casino en Internet y solo el 0,8 % jugaba al p\u00f3quer en l\u00ednea. Estos porcentajes disminuyeron entre los tramos de mayor edad. <\/p>\n<p>Una de las principales razones es que los juegos de casino en l\u00ednea y las m\u00e1quinas de p\u00f3quer son ilegales en Australia. <\/p>\n<p>Entonces, para el jugador de tragamonedas australiano promedio, el cierre actual de los lugares de tragamonedas es un momento de descanso obligatorio en el que el constante debate de \u00ablo hago\u00bb o \u00abno lo hago\u00bb en la mente de las personas se suspende temporalmente. <\/p>\n<p>Ser\u00e1n muchos los jugadores de tragamonedas que aprovechar\u00e1n esta oportunidad para dar la espalda a las m\u00e1quinas de una vez por todas. <\/p>\n<p>\u00bfQu\u00e9 pasar\u00eda si se prohibiera la venta de alcohol y luego se reintrodujera?<\/p>\n<p>Aunque las cifras difieren marginalmente entre jurisdicciones, aproximadamente el 10 % de la poblaci\u00f3n adulta en Australia podr\u00eda considerarse en riesgo o jugador con problemas.<\/p>\n<p>Adem\u00e1s, una de cada tres personas que juegan EGM se expanden en la primera referencia se consideran jugadores en riesgo o jugadores con problemas. Esto se eval\u00faa de manera consistente en todos los estados utilizando el \u00cdndice de gravedad del juego problem\u00e1tico, que hace preguntas como \u00ab\u00bfha sentido que podr\u00eda tener un problema con el juego?\u00bb y \u00ab\u00bfEl juego le ha causado problemas financieros a usted o a su hogar?\u00bb<\/p>\n<p>El an\u00e1lisis anterior a la COVID-19 realizado por el Centro de Investigaci\u00f3n del Juego de ANU encontr\u00f3 que los jugadores con problemas experimentan resultados sociales y econ\u00f3micos significativamente peores que las personas que no juegan. problemas y estos peores resultados son a largo plazo. <\/p>\n<p>Adem\u00e1s, el aislamiento y la incertidumbre causados por el COVID-19 han desencadenado o exacerbado muchos problemas de salud mental en nuestras comunidades, particularmente entre los jugadores en riesgo. <\/p>\n<p>Es por eso que la reapertura de las puertas de los lugares es tan preocupante: podr\u00eda desencadenar meses de angustia reprimida para los jugadores en riesgo. Los gobiernos deben pensar en estrategias de reducci\u00f3n de da\u00f1os ahora. <\/p>\n<p>Si las compras de alcohol se hubieran restringido durante el per\u00edodo de confinamiento, por ejemplo, ser\u00eda razonable suponer que se necesitar\u00edan implementar estrategias de minimizaci\u00f3n de da\u00f1os para gestionar la reintroducci\u00f3n del alcohol. <\/p>\n<p>Esto no es diferente a la reintroducci\u00f3n de m\u00e1quinas tragamonedas. <\/p>\n<p>Recomendaciones para minimizar el da\u00f1o<\/p>\n<p>Como resultado de las restricciones de distanciamiento social de COVID-19, es probable que haya requisitos en los lugares para hacer cumplir el distanciamiento social (como en NSW) o limitar el tiempo de los clientes puede gastar en una m\u00e1quina o en el lugar. <\/p>\n<p>Restringir el tiempo de sesi\u00f3n en las m\u00e1quinas a un m\u00e1ximo de una hora, por ejemplo, ayudar\u00eda a reducir el da\u00f1o del juego. Sabemos por la encuesta sobre juegos de apuestas de ACT de 2019 que las personas que normalmente pasan una hora o m\u00e1s en una sola sesi\u00f3n tienen m\u00e1s probabilidades de ser jugadores de riesgo.<\/p>\n<p>Otras sugerencias para minimizar el da\u00f1o del juego al reiniciar las m\u00e1quinas incluyen:<\/p>\n<ul>\n<li>campa\u00f1as de informaci\u00f3n p\u00fablica que detallan los riesgos asociados con el juego EGM. Esto ayudar\u00eda a las personas a tomar decisiones informadas sobre si volver a jugar y lo que eso significa para sus vidas. seguir haci\u00e9ndolo. La investigaci\u00f3n en ACT ha encontrado que la gran mayor\u00eda de las personas (90 %) que han apostado en los \u00faltimos 12 meses quer\u00edan apoyo para reducir o detener<\/li>\n<li>los reguladores deben estar m\u00e1s atentos a los incentivos y la publicidad que se utilizar\u00e1n por lugares para traer de vuelta a los jugadores. Necesitamos asegurarnos de que esto no sea depredador.<\/li>\n<\/ul>\n<p>Esta es una oportunidad de oro para que los gobiernos estatales y territoriales brinden apoyo a los clubes para diversificar sus modelos comerciales y reducir la cantidad de m\u00e1quinas en sus instalaciones. . <\/p>\n<p>Tambi\u00e9n ser\u00e1 crucial monitorear el da\u00f1o cuando las m\u00e1quinas vuelvan a funcionar. La mayor\u00eda de las jurisdicciones han realizado recientemente encuestas sobre la prevalencia del juego y deber\u00eda haber un proceso de recopilaci\u00f3n de datos por etapas para monitorear cualquier tendencia en el comportamiento. <\/p>\n<p>El sector de la industria del juego en todos los dem\u00e1s estados y territorios probablemente presionar\u00e1 a los gobiernos para que reabran pronto. Y es probable que los gobiernos est\u00e9n ansiosos por ver que el flujo de ingresos de los impuestos EGM comience a fluir nuevamente. <\/p>\n<p>Sin embargo, sin la implementaci\u00f3n de estrategias sustanciales de minimizaci\u00f3n de da\u00f1os para gestionar la reintroducci\u00f3n de m\u00e1quinas tragamonedas en nuestras comunidades, es probable que veamos un aumento significativo en los da\u00f1os causados por los juegos de azar en Australia. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Un estudio encuentra que los raspaditos y los boletos de loter\u00eda pueden generar problemas con el juego Proporcionado por The Conversation <\/p>\n<p> Este art\u00edculo se vuelve a publicar de The Conversation bajo una licencia Creative Commons. Lea el art\u00edculo original. <\/p>\n<p> <strong>Cita<\/strong>: Hay otra crisis de salud que se avecina, \u00bfqu\u00e9 suceder\u00e1 cuando las m\u00e1quinas de p\u00f3quer se vuelvan a encender? (4 de junio de 2020) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-06-health-crisis-looming-poker-machines.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Shutterstock Cuando las restricciones por el COVID-19 entraron en vigor hace m\u00e1s de dos meses, las 200\u00a0000 m\u00e1quinas de p\u00f3quer del pa\u00eds se apagaron. . Ahora, las m\u00e1quinas tragamonedas se est\u00e1n volviendo a encender lentamente en todo el pa\u00eds. Esta semana, NSW se convirti\u00f3 en el primer estado en permitir la reapertura de los &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/se-avecina-otra-crisis-de-salud-que-sucedera-cuando-las-maquinas-de-poquer-vuelvan-a-encenderse\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abSe avecina otra crisis de salud: \u00bfqu\u00e9 suceder\u00e1 cuando las m\u00e1quinas de p\u00f3quer vuelvan a encenderse?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30349","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30349"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30349\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}