{"id":30358,"date":"2022-08-31T18:13:17","date_gmt":"2022-08-31T23:13:17","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/respiradores-y-covid-19-lo-que-necesita-saber\/"},"modified":"2022-08-31T18:13:17","modified_gmt":"2022-08-31T23:13:17","slug":"respiradores-y-covid-19-lo-que-necesita-saber","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/respiradores-y-covid-19-lo-que-necesita-saber\/","title":{"rendered":"Respiradores y COVID-19: lo que necesita saber"},"content":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain <\/p>\n<p>La pandemia de COVID-19 ha puesto de relieve los ventiladores, pero pocos saben mucho sobre lo que hacen o c\u00f3mo funcionan. <\/p>\n<p>Un ventilador bombea aire por lo general con ox\u00edgeno adicional en las v\u00edas respiratorias de los pacientes cuando no pueden respirar adecuadamente por s\u00ed mismos. Si la funci\u00f3n pulmonar se ha visto gravemente afectada debido a una lesi\u00f3n o una enfermedad como la COVID-19, es posible que los pacientes necesiten un ventilador. Tambi\u00e9n se usa para apoyar la respiraci\u00f3n durante la cirug\u00eda.<\/p>\n<p>Los ventiladores, tambi\u00e9n conocidos como m\u00e1quinas de soporte vital, no curar\u00e1n una enfermedad, pero pueden mantener vivos a los pacientes mientras luchan contra una infecci\u00f3n o su cuerpo se cura de una lesi\u00f3n.<\/p>\n<p>Lauren Ferrante, MD, MHS de Yale Medicine, especialista en cuidados cr\u00edticos y pulmonares, explica c\u00f3mo funcionan los ventiladores y por qu\u00e9 a veces son necesarios para combatir una infecci\u00f3n por COVID-19.<\/p>\n<p>\u00bfC\u00f3mo afecta el COVID-19 a los pulmones?<\/p>\n<p>Hay mucho que los investigadores a\u00fan no entienden sobre el COVID-19, pero sabemos que muchas personas infectadas con el nuevo coronavirus tienen fiebre, tos, y dolor de garganta, entre otros s\u00edntomas.<\/p>\n<p>Si el sistema inmunitario del cuerpo no combate la infecci\u00f3n, esta puede viajar a los pulmones y causar una afecci\u00f3n potencialmente fatal llamada s\u00edndrome de dificultad respiratoria aguda (SDRA). En el SDRA, los alv\u00e9olos (peque\u00f1os sacos de aire que permiten que el ox\u00edgeno llegue al torrente sangu\u00edneo y eliminen el di\u00f3xido de carbono) se llenan de l\u00edquido, lo que disminuye la capacidad de los pulmones para proporcionar suficiente ox\u00edgeno a los \u00f3rganos vitales.<\/p>\n<p>\u00abEl SDRA implica inflamaci\u00f3n severa de los pulmones, pero el problema principal es que inutiliza partes de los pulmones\u00bb, explica el Dr. Ferrante. \u00abPuede ser muy grave y muchos de estos pacientes necesitar\u00e1n un ventilador\u00bb.<\/p>\n<p>\u00bfC\u00f3mo funciona un ventilador?<\/p>\n<p>Normalmente, cuando alguien respira, su la pared tor\u00e1cica se expande, lo que genera una presi\u00f3n negativa (es decir, un vac\u00edo) dentro de los pulmones que atrae el aire. Cuando una persona est\u00e1 enferma y d\u00e9bil y no puede inhalar por s\u00ed misma, un ventilador genera una presi\u00f3n positiva que obliga al aire a entrar. los pulmones.<\/p>\n<p>Por lo general, un ventilador se usa en la unidad de cuidados intensivos (UCI) de un hospital, aunque aquellos que lo necesitan durante un per\u00edodo de tiempo m\u00e1s largo pueden estar en una parte diferente del hospital, en un centro de rehabilitaci\u00f3n. , o incluso en casa.<\/p>\n<p>El primer paso para poner a un paciente en un ventilador es la anestesia general. Luego, un profesional m\u00e9dico colocar\u00e1 un tubo en la boca o la nariz y lo introducir\u00e1 en la tr\u00e1quea. Esto se llama intubaci\u00f3n.<\/p>\n<p>El tubo est\u00e1 conectado a una m\u00e1quina externa que inyecta aire y ox\u00edgeno en los pulmones. La m\u00e1quina puede ayudar a realizar toda o solo una parte de la respiraci\u00f3n, seg\u00fan el estado del paciente. El ventilador tambi\u00e9n puede ayudar a mantener los pulmones abiertos para que los alv\u00e9olos no colapsen.<\/p>\n<p>Mientras los pacientes est\u00e1n conectados a un ventilador, los m\u00e9dicos controlar\u00e1n su ritmo card\u00edaco y respiratorio, la presi\u00f3n arterial y la saturaci\u00f3n de ox\u00edgeno. Se pueden realizar otras pruebas, como radiograf\u00edas y extracciones de sangre, para medir los niveles de ox\u00edgeno y di\u00f3xido de carbono (a veces llamados gases en sangre).<\/p>\n<p>\u00bfC\u00f3mo es estar conectado a un ventilador?<\/p>\n<p>El objetivo es que los pacientes est\u00e9n despiertos y tranquilos mientras est\u00e1n conectados a un ventilador, pero eso a veces puede ser dif\u00edcil; muchos requieren una sedaci\u00f3n ligera para sentirse c\u00f3modos, dice el Dr. Ferrante.<\/p>\n<p>\u00abA veces, los pacientes desarrollan delirio o un estado agudo de confusi\u00f3n. Y cuando los pacientes se confunden, pueden tratar de sacarse el tubo endotraqueal, que los conecta al ventilador\u00bb, dice ella. \u00abLos pacientes con delirio pueden estar l\u00facidos en un momento y confusos al siguiente. Aunque tratamos de evitar la sedaci\u00f3n tanto como sea posible, particularmente en pacientes con delirio, es posible que tengamos que administrar un poco de sedaci\u00f3n para evitar que las personas se autolesionen, como arrancarse el tubo de respiraci\u00f3n\u00bb.<\/p>\n<p>Adem\u00e1s, los pacientes con ARDS a menudo sienten un instinto natural de tomar respiraciones muy profundas, agrega el Dr. Ferrante. \u00abLas respiraciones muy grandes pueden ser da\u00f1inas para los pulmones de un paciente con ARDS, por lo que tratamos de que el tama\u00f1o de la respiraci\u00f3n coincida con el que hemos configurado en el ventilador\u00bb, dice ella. <\/p>\n<p>Por lo general, la mayor\u00eda de los pacientes con ventilador est\u00e1n entre despiertos y ligeramente sedados. Sin embargo, el Dr. Ferrante se\u00f1ala que los pacientes con ARDS en la UCI con COVID-19 pueden necesitar una sedaci\u00f3n m\u00e1s fuerte para que puedan proteger sus pulmones y permitirles sanar.<\/p>\n<p>\u00bfQu\u00e9 es la posici\u00f3n boca abajo?<\/p>\n<p>A medida que los m\u00e9dicos adquirieron m\u00e1s experiencia en el tratamiento de pacientes con COVID-19, descubrieron que muchos pueden evitar la ventilaci\u00f3n o les va mejor con ventiladores cuando se les da la vuelta para acostarse boca abajo. A esto se le llama posici\u00f3n boca abajo, dice el Dr. Ferrante.<\/p>\n<p>\u00abEn lugar de acostarse boca arriba, le pedimos que se acueste boca abajo. Debido a la posici\u00f3n de los pulmones, esto le permite usar partes de los pulmones que no se utilizan cuando est\u00e1 boca arriba\u00bb, explica, y agrega que reduce la presi\u00f3n del coraz\u00f3n y el diafragma sobre los pulmones. \u00abA menudo, vemos que la oxigenaci\u00f3n mejora r\u00e1pidamente. Lo estamos usando mucho para pacientes con COVID en un ventilador y para aquellos que est\u00e1n en el hospital con ox\u00edgeno. Puede ayudar a que los pacientes con COVID no necesiten el ventilador\u00bb.<\/p>\n<p>\u00bfCu\u00e1nto tiempo suele permanecer alguien conectado a un ventilador?<\/p>\n<p>Algunas personas pueden necesitar un ventilador durante algunas horas, mientras que otras pueden necesitar una, dos o tres semanas. Si una persona necesita estar conectada a un ventilador durante un per\u00edodo de tiempo m\u00e1s prolongado, es posible que se requiera una traqueotom\u00eda. Durante este procedimiento, un cirujano hace un agujero en la parte delantera del cuello e inserta un tubo en la tr\u00e1quea. El tubo se conecta al ventilador.<\/p>\n<p>El tubo de traqueostom\u00eda se inserta debajo de las cuerdas vocales, lo que dificulta hablar. A medida que los pacientes son retirados del ventilador, pueden comenzar a hablar nuevamente, usando un dispositivo llamado v\u00e1lvula de habla.<\/p>\n<p>La mayor\u00eda de las traqueostom\u00edas no son permanentes; a menudo se usan para ayudar a desconectar a un paciente de un ventilador despu\u00e9s de un uso prolongado, dice el Dr. Ferrante. Sin embargo, no todos podr\u00e1n desconectarse de un respirador y respirar con \u00e9xito por su cuenta, y esa realidad puede generar discusiones importantes para las familias, dice el Dr. Ferrante.<\/p>\n<p>\u00abMuchas personas pueden estar de acuerdo con estar en el respirador durante algunas semanas, tratando de mejorar de una enfermedad aguda, pero es posible que no est\u00e9n dispuestos a permanecer conectados a un respirador de forma permanente\u00bb, dice. \u00abA muchos les parece inaceptable. Por eso es bueno que los pacientes y sus familias tengan conversaciones anticipadas sobre la planificaci\u00f3n de la atenci\u00f3n\u00bb.<\/p>\n<p>\u00bfC\u00f3mo se desconecta alguien de un ventilador?<\/p>\n<p>Un paciente puede ser desconectados de un ventilador cuando se hayan recuperado lo suficiente como para volver a respirar por s\u00ed mismos. El destete comienza gradualmente, lo que significa que permanecen conectados al ventilador pero se les da la oportunidad de intentar respirar por s\u00ed mismos.<\/p>\n<p>\u00abCuando alguien est\u00e1 conectado a un ventilador, especialmente con ARDS inducido por COVID, a menudo est\u00e1 conectado niveles muy altos de apoyo\u00bb, explica el Dr. Ferrante. \u00abA medida que mejora, el soporte se reduce a lo que llamamos &#8216;ajustes m\u00ednimos de ventilaci\u00f3n&#8217;, lo que significa que no necesita mucho ox\u00edgeno a trav\u00e9s del ventilador y no necesita presiones m\u00e1s altas\u00bb.<\/p>\n<p> Cuando se alcanza cierto umbral, los m\u00e9dicos har\u00e1n que los pacientes prueben pruebas diarias de respiraci\u00f3n espont\u00e1nea. \u00abLa forma en que probamos es haci\u00e9ndote respirar durante 30 minutos por tu cuenta mientras a\u00fan est\u00e1s conectado al ventilador\u00bb, dice ella. \u00abHay ciertos n\u00fameros que rastreamos para informarnos si ha pasado la prueba de respiraci\u00f3n espont\u00e1nea. Tambi\u00e9n debe estar despierto e, idealmente, interactuando con nosotros\u00bb.<\/p>\n<p>Cuando se alcanzan esos hitos, los m\u00e9dicos puede decidir intentar sacar al paciente del ventilador para una prueba. Si no tiene \u00e9xito, se puede intentar el destete en otro momento.<\/p>\n<p>Para los pacientes con insuficiencia respiratoria o cardiopulmonar aguda, puede ser necesaria otra terapia llamada ECMO (oxigenaci\u00f3n por membrana extracorp\u00f3rea). ECMO es una forma altamente especializada de soporte vital que puede hacerse cargo del trabajo del coraz\u00f3n y los pulmones, permiti\u00e9ndoles descansar y sanar.<\/p>\n<p>\u00bfCu\u00e1les son los riesgos de estar conectado a un ventilador?<\/p>\n<p>Existen riesgos asociados con el uso del ventilador. \u00abNo es natural tener presi\u00f3n positiva forzando el aire en los pulmones\u00bb, se\u00f1ala el Dr. Ferrante. \u00abPero una gran parte de nuestra capacitaci\u00f3n como m\u00e9dicos de cuidados intensivos se basa en el uso adecuado de un ventilador, de modo que le brindemos al paciente el mayor beneficio posible y al mismo tiempo minimicemos el da\u00f1o\u00bb.<\/p>\n<p>La infecci\u00f3n es una de ellas. riesgo potencial asociado con estar en un ventilador; el tubo de respiraci\u00f3n en las v\u00edas respiratorias puede permitir que las bacterias ingresen a los pulmones, lo que puede provocar neumon\u00eda. Un ventilador tambi\u00e9n puede da\u00f1ar los pulmones, ya sea por demasiada presi\u00f3n o niveles excesivos de ox\u00edgeno, lo que puede ser t\u00f3xico para los pulmones.<\/p>\n<p>El delirio es otra preocupaci\u00f3n y encaja con lo que se llama s\u00edndrome post-UCI ( PICS), una colecci\u00f3n de problemas que pueden presentarse y persistir despu\u00e9s de una enfermedad cr\u00edtica.<\/p>\n<p>Con una enfermedad cr\u00edtica, y particularmente con el uso de ventiladores, \u00ablos tres dominios que nos preocupan son las deficiencias en la funci\u00f3n f\u00edsica, la funci\u00f3n cognitiva y salud mental\u00bb, dice la Dra. Ferrante, y agrega que la falta de movimiento durante la hospitalizaci\u00f3n puede presentar otros desaf\u00edos despu\u00e9s de que se le da de alta a un paciente.<\/p>\n<p>\u00abLa recuperaci\u00f3n puede llevar meses\u00bb, explica. \u00abContinuar con la fisioterapia y la terapia ocupacional despu\u00e9s de irse a casa es muy importante\u00bb. (En el Yale New Haven Hospital, un programa de movilidad basado en la UCI tiene terapeutas f\u00edsicos y ocupacionales que trabajan con los pacientes para que se muevan, incluso cuando est\u00e1n conectados a un ventilador).<\/p>\n<p>Dr. Ferrante dice que los pacientes mayores, en particular, son m\u00e1s propensos a experimentar una disminuci\u00f3n en su funci\u00f3n f\u00edsica y cognitiva. \u00abLos sobrevivientes de la UCI pueden sentir que su pensamiento y procesamiento no son tan r\u00e1pidos como antes de estar en la UCI\u00bb, dice ella. \u00abCuando sacas a alguien de su entorno familiar, lo pones en un lugar desconocido y le das medicamentos que normalmente no toma, puede ponerlo en un mayor riesgo de delirio. Y si experiment\u00f3 delirio o necesitaba sedantes en el UCI, que puede conducir a problemas cognitivos despu\u00e9s de una estad\u00eda en la UCI. Los pacientes tambi\u00e9n pueden experimentar problemas de salud mental, como PTSD [trastorno de estr\u00e9s postraum\u00e1tico]\u00bb.<\/p>\n<p>Sin embargo, los ventiladores pueden salvar vidas y, de hecho, es poco probable que muchos de los que han sobrevivido a casos graves de COVID-19 lo hayan hecho sin uno. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Siga las \u00faltimas noticias sobre el brote de coronavirus (COVID-19) Proporcionado por la Universidad de Yale <strong>Cita<\/strong>: Ventiladores y COVID-19: lo que necesita saber (2020, junio 4) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-06-ventilators-covid-.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain La pandemia de COVID-19 ha puesto de relieve los ventiladores, pero pocos saben mucho sobre lo que hacen o c\u00f3mo funcionan. Un ventilador bombea aire por lo general con ox\u00edgeno adicional en las v\u00edas respiratorias de los pacientes cuando no pueden respirar adecuadamente por s\u00ed mismos. Si la funci\u00f3n pulmonar se &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/respiradores-y-covid-19-lo-que-necesita-saber\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abRespiradores y COVID-19: lo que necesita saber\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30358","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30358"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30358\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}