{"id":30367,"date":"2022-08-31T18:13:49","date_gmt":"2022-08-31T23:13:49","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/finlandia-alcanza-el-hito-del-virus-sin-registrar-nuevos-casos\/"},"modified":"2022-08-31T18:13:49","modified_gmt":"2022-08-31T23:13:49","slug":"finlandia-alcanza-el-hito-del-virus-sin-registrar-nuevos-casos","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/finlandia-alcanza-el-hito-del-virus-sin-registrar-nuevos-casos\/","title":{"rendered":"Finlandia alcanza el hito del virus, sin registrar nuevos casos"},"content":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain <\/p>\n<p>Los funcionarios de salud en Finlandia anunciaron que no hay nuevas infecciones por coronavirus el jueves por primera vez en m\u00e1s de tres meses. <\/p>\n<p>\u00abEste es el primer &#8216;d\u00eda cero&#8217; desde el 26 de febrero\u00bb, dijo a la AFP un portavoz del Instituto de Salud y Bienestar.<\/p>\n<p>Sin embargo, una persona muri\u00f3 a causa del virus el jueves, dijo el instituto. , elevando el n\u00famero de muertos a 322 en la naci\u00f3n n\u00f3rdica de 5,5 millones de personas. <\/p>\n<p>Se estima que 5800 de los 7000 casos de COVID-19 registrados en Finlandia ya se han recuperado.<\/p>\n<p>Un total de 50 personas permanecen hospitalizadas, siete de ellas en cuidados intensivos.<\/p>\n<p>La tasa de reproducci\u00f3n del virus ha ca\u00eddo en las \u00faltimas dos semanas a entre 0,75 y 0,80, dijeron las autoridades, y agregaron que m\u00e1s de un tercio de los distritos hospitalarios no registraron un solo caso durante la \u00faltima semana de mayo. <\/p>\n<p>Desde mediados de mayo, el gobierno de Finlandia comenz\u00f3 a levantar las restricciones de emergencia que se impusieron el 18 de marzo. <\/p>\n<p>Las escuelas reabrieron durante dos semanas antes de que comenzaran las vacaciones de verano a principios de junio, y a principios de esta semana se permiti\u00f3 la reapertura de bares, restaurantes, instalaciones deportivas e instituciones culturales bajo las normas de distanciamiento social. <\/p>\n<p>Sin embargo, los funcionarios y el gobierno dijeron que est\u00e1n preparados para una segunda ola de infecciones m\u00e1s adelante en el a\u00f1o, y advirtieron al p\u00fablico que contin\u00fae siguiendo los consejos de distanciamiento y que se autoa\u00edsle y busque pruebas si experimentan cualquier s\u00edntoma. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Siga las \u00faltimas noticias sobre el brote de coronavirus (COVID-19) <\/p>\n<p> 2020 AFP <\/p>\n<p> <strong>Cita<\/strong>: Finlandia alcanza el hito del virus, sin registrar nuevos casos ( 2020, 4 de junio) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-06-finland-virus-milestone-cases.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain Los funcionarios de salud en Finlandia anunciaron que no hay nuevas infecciones por coronavirus el jueves por primera vez en m\u00e1s de tres meses. \u00abEste es el primer &#8216;d\u00eda cero&#8217; desde el 26 de febrero\u00bb, dijo a la AFP un portavoz del Instituto de Salud y Bienestar. Sin embargo, una persona &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/finlandia-alcanza-el-hito-del-virus-sin-registrar-nuevos-casos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abFinlandia alcanza el hito del virus, sin registrar nuevos casos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30367","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30367"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30367\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}