{"id":30369,"date":"2022-08-31T18:13:55","date_gmt":"2022-08-31T23:13:55","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/investigador-pide-pruebas-individuales-para-medicina-personalizada\/"},"modified":"2022-08-31T18:13:55","modified_gmt":"2022-08-31T23:13:55","slug":"investigador-pide-pruebas-individuales-para-medicina-personalizada","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/investigador-pide-pruebas-individuales-para-medicina-personalizada\/","title":{"rendered":"Investigador pide pruebas individuales para medicina personalizada"},"content":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain <\/p>\n<p>\u00abTodas las cosas son veneno, y nada es sin veneno, la dosis por s\u00ed sola hace que una cosa no sea veneno\u00bb. Estas fueron las palabras de Paracelso, un m\u00e9dico suizo que reconoci\u00f3 all\u00e1 por el siglo XVI que cada medicamento tiene sus beneficios y riesgos, y que para que un medicamento funcione, la dosis individual es crucial. <\/p>\n<p>Esto sigue siendo muy relevante hoy en d\u00eda, ya que la mayor\u00eda de los medicamentos en el mercado son de \u00abtalla \u00fanica\u00bb, lo que significa que los pacientes con la misma afecci\u00f3n a menudo reciben la misma dosis, aunque los estudios muestran que esto solo es \u00f3ptimo para una fracci\u00f3n de ellos. . En algunos casos, los m\u00e9dicos ajustan la dosis por ensayo y error. Este enfoque es ineficiente y conduce a reacciones adversas innecesarias y mayores costos de atenci\u00f3n m\u00e9dica.<\/p>\n<p>Al identificar el medicamento correcto, en la dosis correcta, en el momento adecuado para cada paciente, la medicina de precisi\u00f3n tiene el potencial de hacer que la atenci\u00f3n m\u00e9dica sistema m\u00e1s eficiente y para tratar a los pacientes con mayor eficacia. Esencialmente, la medicina de precisi\u00f3n combina los datos gen\u00e9ticos de un paciente con informaci\u00f3n cl\u00ednica, ambiental y de estilo de vida para guiar las decisiones para la prevenci\u00f3n, el diagn\u00f3stico y el tratamiento \u00f3ptimos de las afecciones.<\/p>\n<p>La farmacogen\u00f3mica se ocupa de la influencia del genoma individual de un paciente en el efecto de las drogas. Usando las pruebas apropiadas, los m\u00e9dicos pueden determinar de antemano para los pacientes individualmente qu\u00e9 medicamentos probablemente funcionen para ellos. Las pruebas analizan genes clave de nuestro organismo implicados en el metabolismo, transporte y eliminaci\u00f3n del f\u00e1rmaco. Dado que la gen\u00e9tica no cambia con el tiempo, un informe de farmacogen\u00f3mica que enumera todos los medicamentos que probablemente funcionen para nosotros es v\u00e1lido durante toda nuestra vida.<\/p>\n<p>Si bien estas pruebas sol\u00edan ser costosas, ahora son mucho m\u00e1s baratas. . Tambi\u00e9n existen gu\u00edas claras de pr\u00e1ctica cl\u00ednica internacional para estas pruebas. A pesar de esto, rara vez se llevan a cabo. Se necesita evidencia y conciencia para convencer a los reguladores, m\u00e9dicos y pagadores de que el uso de informaci\u00f3n gen\u00e9tica marca una diferencia en los resultados de los pacientes y esta evidencia debe generarse continuamente. Los estudios que muestren la efectividad y rentabilidad de este enfoque ser\u00edan \u00fatiles aqu\u00ed.<\/p>\n<p>Las mujeres se benefician particularmente<\/p>\n<p>Esto requiere ciudadanos comprometidos. Supongo que el futuro de la farmacogen\u00f3mica y la medicina de precisi\u00f3n se construir\u00e1 sobre una masa cr\u00edtica de partes interesadas y comprometidas, incluidos pacientes y m\u00e9dicos lo suficientemente informados como para solicitarlo. Los pacientes aqu\u00ed se asocian estrechamente con los m\u00e9dicos y otras partes interesadas, y participan en las decisiones de tratamiento sobre sus propios problemas de salud.<\/p>\n<p>Los grupos marginados que actualmente est\u00e1n subrepresentados en los ensayos cl\u00ednicos se beneficiar\u00edan particularmente de dicha cooperaci\u00f3n. Las mujeres tambi\u00e9n. Hay toda una gama de enfermedades cuya incidencia entre las mujeres es igual o superior a la de los hombres, pero las mujeres son superadas en los ensayos cl\u00ednicos, como ha demostrado un estudio estadounidense. Este es el caso de las enfermedades cardiovasculares, la hepatitis, el VIH, la enfermedad renal cr\u00f3nica y las enfermedades digestivas.<\/p>\n<p>Una cohorte como chispa inicial<\/p>\n<p>Dado que las diferencias gen\u00e9ticas en los farmacogenes representan entre un cuarto y la mitad de la respuesta de un individuo a la medicina, tal subrepresentaci\u00f3n podr\u00eda significar que los medicamentos pueden funcionar con menos eficacia en las mujeres que en los hombres. Es por eso que Women&#8217;s Brain Project, una organizaci\u00f3n que defiende la salud neurol\u00f3gica y mental de las mujeres, est\u00e1 presentando un nuevo enfoque personalizado para las mujeres. Esto requiere la participaci\u00f3n activa de las ciudadanas, cuyos datos de salud ayudar\u00e1n a optimizar estos tratamientos.<\/p>\n<p>Los datos son la base para la medicina de precisi\u00f3n y centrada en el paciente. Sin embargo, mientras los datos est\u00e9n atrapados en \u00absilos\u00bb o en organizaciones sin incentivos para compartir, nunca llegar\u00e1n a los destinatarios que se beneficiar\u00edan de ellos. Causa de la Salud, una iniciativa suiza en la que estoy involucrado, tiene como objetivo poner en red estos datos de salud. Construir\u00e1 una cohorte de personas para proporcionar datos de salud y abordar\u00e1, entre otras cosas, preguntas sobre farmacogen\u00f3mica. Los participantes seguir\u00e1n siendo propietarios de sus datos y recibir\u00e1n una copia de su propio informe de farmacogen\u00f3mica. Esto permitir\u00e1 a las personas involucrarse m\u00e1s en sus decisiones de tratamiento y beneficiarse de las ventajas de la medicina de precisi\u00f3n y la farmacogen\u00f3mica, de mejores opciones de tratamiento y menos efectos secundarios. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> La medicina de precisi\u00f3n gu\u00eda la elecci\u00f3n de una mejor terapia farmacol\u00f3gica en enfermedades card\u00edacas graves Proporcionado por ETH Zurich <strong>Cita<\/strong>: Investigador pide ensayos de una sola persona para medicina personalizada (2020, 4 de junio) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-06-one-person-trials-personalized-medicine.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain \u00abTodas las cosas son veneno, y nada es sin veneno, la dosis por s\u00ed sola hace que una cosa no sea veneno\u00bb. Estas fueron las palabras de Paracelso, un m\u00e9dico suizo que reconoci\u00f3 all\u00e1 por el siglo XVI que cada medicamento tiene sus beneficios y riesgos, y que para que un &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/investigador-pide-pruebas-individuales-para-medicina-personalizada\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abInvestigador pide pruebas individuales para medicina personalizada\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30369","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30369"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30369\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}