{"id":30370,"date":"2022-08-31T18:13:58","date_gmt":"2022-08-31T23:13:58","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/explorando-la-naturaleza-de-las-experiencias-psicodelicas-anomalas\/"},"modified":"2022-08-31T18:13:58","modified_gmt":"2022-08-31T23:13:58","slug":"explorando-la-naturaleza-de-las-experiencias-psicodelicas-anomalas","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/explorando-la-naturaleza-de-las-experiencias-psicodelicas-anomalas\/","title":{"rendered":"Explorando la naturaleza de las experiencias psicod\u00e9licas an\u00f3malas"},"content":{"rendered":"<p>Cr\u00e9dito: Cr\u00e9dito: Emma Miller \/ Unsplash <\/p>\n<p>Los psicod\u00e9licos se encuentran entre las sustancias psicoactivas m\u00e1s intrigantes y misteriosas, ya que pueden alterar radicalmente las percepciones, los procesos cognitivos y las emociones de las personas. Sus cualidades \u00fanicas y sus efectos sobre el cerebro humano han hecho de estas sustancias un tema de estudio atractivo para varios investigadores de todo el mundo. <\/p>\n<p>Si bien los psicod\u00e9licos se han estudiado ampliamente a lo largo de la historia, muchos gobiernos prohibieron de hecho la investigaci\u00f3n que involucraba el uso de estas sustancias tanto fuera como dentro de laboratorios, lo que obstaculiz\u00f3 las investigaciones detalladas sobre sus efectos en el cerebro y el comportamiento humano. En los \u00faltimos a\u00f1os, sin embargo, ha habido un renovado inter\u00e9s acad\u00e9mico en estas sustancias y sus singulares propiedades. <\/p>\n<p>David Luke, investigador de la Universidad de Greenwich, llev\u00f3 a cabo recientemente un estudio que investiga la naturaleza de las experiencias an\u00f3malas inducidas por sustancias psicod\u00e9licas desde un punto de vista human\u00edstico, neurocient\u00edfico y parapsicol\u00f3gico. Su art\u00edculo m\u00e1s reciente sobre este tema se public\u00f3 en una edici\u00f3n especial de Journal of Humanistic Psychology llamada \u00abMundos de vida an\u00f3malos: misticismo, magia y conciencia expandida\u00bb.<\/p>\n<p>El objetivo clave del estudio de Luke era examinar de cerca los mundos an\u00f3malos experiencias a menudo relatadas por personas bajo la influencia de psicod\u00e9licos o despu\u00e9s de un viaje psicod\u00e9lico. El investigador deseaba ofrecer una descripci\u00f3n general de la prevalencia y los efectos de estas sustancias, resumiendo los hallazgos de investigaciones anteriores y, al mismo tiempo, introduciendo informaci\u00f3n sobre la neurobiolog\u00eda de experiencias similares que pueden ocurrir espont\u00e1neamente (es decir, sin psicod\u00e9licos), como las experiencias cercanas a la muerte.<\/p>\n<p>\u00abSiempre me han intrigado las experiencias extraordinarias que las personas reportan durante sus viajes psicod\u00e9licos, que han adornado la literatura desde los primeros descubrimientos de estas sustancias en el &#8216;mundo desarrollado&#8217;, como el nombre original del principal alcaloide de la ayahuasca &#8216; telepathine&#8217; en la d\u00e9cada de 1920, o la demostraci\u00f3n de aparente clarividencia en el primer uso observado de psilocibina, o la experiencia extracorporal del qu\u00edmico Albert Hofmann en el viaje seminal del LSD del mundo\u00bb, dijo Luke a Medical Xpress. \u00abEstas experiencias an\u00f3malas todav\u00eda son reportadas com\u00fanmente por personas bajo la influencia de psicod\u00e9licos, pero lamentablemente han sido descuidadas acad\u00e9micamente en los \u00faltimos 100 a\u00f1os\u00bb.<\/p>\n<p>Luke ha estado realizando investigaciones que exploran experiencias psicod\u00e9licas an\u00f3malas durante m\u00e1s de 20 a\u00f1os. ahora, abordando el tema desde una perspectiva antropol\u00f3gica, psicol\u00f3gica y neurocient\u00edfica. En su trabajo, a menudo adopta un enfoque interdisciplinario, fusionando ideas de la psicolog\u00eda cognitiva y conductual con m\u00e9todos experimentales de laboratorio, al mismo tiempo que realiza encuestas, entrevistas, revisiones de literatura y estudios etnogr\u00e1ficos con tribus ind\u00edgenas conocidas por usar estas sustancias.<\/p>\n<p>\u00abGran parte de la investigaci\u00f3n disponible en esta \u00e1rea es extremadamente incipiente, a pesar de que estas sustancias se han estudiado durante m\u00e1s de 100 a\u00f1os en algunos casos\u00bb, dijo Luke. \u00abLa prohibici\u00f3n paraliz\u00f3 casi toda la investigaci\u00f3n psicod\u00e9lica humana durante unos 50 a\u00f1os, lo que inevitablemente ralentiz\u00f3 las cosas\u00bb.<\/p>\n<p>Entrevistas anteriores con personas que tomaron psicod\u00e9licos revelaron patrones en experiencias an\u00f3malas que son mucho m\u00e1s comunes en personas bajo la influencia de estas sustancias que la de otras drogas psicoactivas. Curiosamente, algunos entrevistados tambi\u00e9n dijeron que las sustancias psicod\u00e9licas ten\u00edan efectos positivos profundos y duraderos en sus vidas y percepciones generales del mundo.<\/p>\n<p>\u00abUna encuesta reciente, por ejemplo, encontr\u00f3 que m\u00e1s de la mitad de todos los los ateos informaron que ya no eran ateos despu\u00e9s de que una entidad se encontrara con la experiencia del potente qu\u00edmico end\u00f3geno DMT\u00bb, dijo Luke. \u00abAdem\u00e1s, las experiencias se calificaron como unas de las experiencias de vida m\u00e1s significativas, espirituales y psicol\u00f3gicamente perspicaces, con cambios positivos persistentes en la satisfacci\u00f3n con la vida, el prop\u00f3sito y el significado que se les atribuye\u00bb.<\/p>\n<p>En su art\u00edculo, Luke revisa y examina 10 experiencias an\u00f3malas reportadas por muchas personas que usaron psicod\u00e9licos. Estos incluyen sinestesia (p. ej., ver sonidos como patrones coloridos), percepciones extradimensionales, experiencias fuera del cuerpo, experiencias cercanas a la muerte, encuentros con entidades aparentemente conscientes, experiencias de abducci\u00f3n extraterrestre, par\u00e1lisis del sue\u00f1o, comunicaci\u00f3n entre especies, posesi\u00f3n y experiencias ps\u00edquicas ( ej., telepat\u00eda, precognici\u00f3n, clarividencia o psicoquinesis).<\/p>\n<p>Luke investig\u00f3 estas experiencias en relaci\u00f3n con los resultados recopilados en estudios neurocient\u00edficos y neurobiol\u00f3gicos anteriores, que se llevaron a cabo en personas que ten\u00edan viajes psicod\u00e9licos y en estados de conciencia. En su art\u00edculo, concluye que las experiencias an\u00f3malas, como las reportadas por los usuarios de psicod\u00e9licos, parecen ser inducidas por estados alterados de conciencia en lugar de sustancias qu\u00edmicas psicod\u00e9licas per se, ya que todas las experiencias examinadas en su trabajo tambi\u00e9n fueron reportadas por algunos individuos. que no hab\u00eda tomado psicod\u00e9licos ni ninguna otra droga psicoactiva. <\/p>\n<p>Adem\u00e1s, se ha descubierto que los efectos temporales de los psicod\u00e9licos en el cerebro se asemejan a los observados durante los estados alterados de conciencia que ocurren naturalmente, por ejemplo, al so\u00f1ar, tocar la bater\u00eda o durante un &#8216;trance creativo&#8217;. Seg\u00fan Luke, si bien las experiencias an\u00f3malas inducidas por psicod\u00e9licos y las que ocurren naturalmente pueden ser de naturaleza similar y producir patrones an\u00e1logos en la actividad cerebral, cada una tendr\u00e1 su propio \u00absabor\u00bb en \u00faltima instancia, dependiendo de c\u00f3mo se induzca o c\u00f3mo surja.<\/p>\n<p>\u00abCreo que las experiencias an\u00f3malas con psicod\u00e9licos tienen implicaciones de gran alcance para el estudio de la conciencia y sus aplicaciones, incluidas la neurociencia, la psiquiatr\u00eda, la psicolog\u00eda e incluso la filosof\u00eda, en lo que respecta a la mente, y las ramas de la metaf\u00edsica que se ocupan de la ontolog\u00eda y la epistemolog\u00eda. \u00ab, dijo Luke.<\/p>\n<p>En general, el estudio reciente de Luke proporciona un resumen detallado y un an\u00e1lisis de los hallazgos de investigaciones anteriores asociados con 10 de las experiencias psicod\u00e9licas an\u00f3malas m\u00e1s comunes. En el futuro, su trabajo podr\u00eda inspirar nuevas investigaciones que examinen los efectos y los fundamentos neurobiol\u00f3gicos del uso de psicod\u00e9licos o que investiguen m\u00e1s a fondo la naturaleza de los estados alterados de conciencia informados por personas bajo la influencia de los psicod\u00e9licos.<\/p>\n<p>\u00abTengo varios nuevos proyectos en curso, como el mapeo de algunos de los correlatos psicol\u00f3gicos de una variedad de estados alterados psicod\u00e9licos y no relacionados con las drogas, para descubrir puntos en com\u00fan y explorar la naturaleza de las experiencias visionarias precognitivas y compartidas con DMT en condiciones controladas\u00bb, dijo Luke. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Una nueva investigaci\u00f3n confirma que los psicod\u00e9licos persisten en el estado de \u00e1nimo. <strong>M\u00e1s informaci\u00f3n:<\/strong> David Luke. Experiencias psicod\u00e9licas an\u00f3malas: en la uni\u00f3n neuroqu\u00edmica de lo human\u00edstico y lo parapsicol\u00f3gico, Journal of Humanistic Psychology (2020). DOI: 10.1177\/0022167820917767 <\/p>\n<p> 2020 Science X Network <\/p>\n<p> <strong>Cita<\/strong>: Explorando la naturaleza de las experiencias psicod\u00e9licas an\u00f3malas (4 de junio de 2020) consultado el 31 de agosto de 2022 en https:\/\/medicalxpress.com \/news\/2020-06-exploring-nature-anomalous-psychedelic.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Cr\u00e9dito: Emma Miller \/ Unsplash Los psicod\u00e9licos se encuentran entre las sustancias psicoactivas m\u00e1s intrigantes y misteriosas, ya que pueden alterar radicalmente las percepciones, los procesos cognitivos y las emociones de las personas. Sus cualidades \u00fanicas y sus efectos sobre el cerebro humano han hecho de estas sustancias un tema de estudio atractivo para &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/explorando-la-naturaleza-de-las-experiencias-psicodelicas-anomalas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abExplorando la naturaleza de las experiencias psicod\u00e9licas an\u00f3malas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30370","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30370"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30370\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}