{"id":30392,"date":"2022-08-31T18:15:15","date_gmt":"2022-08-31T23:15:15","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/la-comprension-del-plegamiento-incorrecto-de-proteinas-podria-abrir-nuevos-enfoques-para-tratar-la-enfermedad-de-parkinson\/"},"modified":"2022-08-31T18:15:15","modified_gmt":"2022-08-31T23:15:15","slug":"la-comprension-del-plegamiento-incorrecto-de-proteinas-podria-abrir-nuevos-enfoques-para-tratar-la-enfermedad-de-parkinson","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/la-comprension-del-plegamiento-incorrecto-de-proteinas-podria-abrir-nuevos-enfoques-para-tratar-la-enfermedad-de-parkinson\/","title":{"rendered":"La comprensi\u00f3n del plegamiento incorrecto de prote\u00ednas podr\u00eda abrir nuevos enfoques para tratar la enfermedad de Parkinson"},"content":{"rendered":"<p>La inmunohistoqu\u00edmica para la alfa-sinucle\u00edna muestra una tinci\u00f3n positiva (marr\u00f3n) de un cuerpo de Lewy intraneural en la sustancia negra en la enfermedad de Parkinson. Cr\u00e9dito: Wikipedia <\/p>\n<p>Los investigadores han descubierto un v\u00ednculo entre la estructura de la prote\u00edna alfa-sinucle\u00edna y su probabilidad de plegarse incorrectamente y agregarse. <\/p>\n<p>Los agregados de alfa-sinucle\u00edna son el sello distintivo de los trastornos neurodegenerativos, como la enfermedad de Parkinson. Sus hallazgos, publicados hoy en Nature Communications, identifican nuevos objetivos terap\u00e9uticos potenciales en el tratamiento de la enfermedad de Parkinson.<\/p>\n<p>El cerebro humano contiene una prote\u00edna llamada alfa-sinucle\u00edna (aSyn), que se encuentra principalmente en las puntas de los neuronas en estructuras llamadas terminales presin\u00e1pticas. En la enfermedad de Parkinson y algunos otros trastornos neurodegenerativos, la prote\u00edna aSyn se desestabiliza, se pliega mal y se agrega en fibrillas insolubles, que son un sello distintivo de la enfermedad. Actualmente no entendemos por qu\u00e9 aSyn falla o c\u00f3mo evitar que lo haga. Esto significa que enfermedades como el Parkinson, que afecta a uno de cada 350 adultos en el Reino Unido, sigue siendo incurable.<\/p>\n<p>\u00abQuer\u00edamos entender por qu\u00e9 el aSyn monom\u00e9rico y soluble, que normalmente es saludable, de repente comienza a plegarse mal\u00bb, dice el Dr. Amberley Stephens, primera coautora del art\u00edculo de investigaci\u00f3n, en el Departamento de Ingenier\u00eda Qu\u00edmica y Biotecnolog\u00eda de la Universidad de Cambridge.<\/p>\n<p>\u00abComprender estos pasos iniciales en la v\u00eda del plegamiento incorrecto significa que podemos identificar nuevos objetivos terap\u00e9uticos para tratar aSyn Sin embargo, esto se hace muy dif\u00edcil porque aSyn no tiene una estructura real, sino que existe como muchas estructuras intermedias o conformaciones que son altamente din\u00e1micas\u00bb.<\/p>\n<p>Para entender c\u00f3mo evitar que aSyn se agregue en las neuronas, el Los investigadores tuvieron que investigar qu\u00e9 conformaciones iniciales forma monom\u00e9rica aSyn cuando es propensa a la agregaci\u00f3n en comparaci\u00f3n con cuando no es propensa a la agregaci\u00f3n y, por lo tanto, sigue siendo monom\u00e9rica. Los investigadores hicieron deliberadamente que el agregado aSyn fuera m\u00e1s r\u00e1pido al agregar un ion inductor de agregaci\u00f3n conocido, calcio, para investigar estas peque\u00f1as diferencias en la estructura din\u00e1mica del mon\u00f3mero.<\/p>\n<p>El equipo utiliz\u00f3 una colecci\u00f3n de t\u00e9cnicas anal\u00edticas de vanguardia para investigar las diversas interacciones intramoleculares en juego cuando aSyn estaba en un estado propenso a la agregaci\u00f3n o no propenso a la agregaci\u00f3n.<\/p>\n<p>\u00abEn este estudio, utilizamos espectrometr\u00eda de masas de intercambio de hidr\u00f3geno-deuterio, una t\u00e9cnica biof\u00edsica poderosa y vers\u00e1til que puede dar informaci\u00f3n sobre la estructura y la din\u00e1mica de las prote\u00ednas, como aSyn. En t\u00e9rminos simples, estamos capturando las diferencias en la postura de la prote\u00edna en diferentes entornos. Nuestros colaboradores de la Universidad de Exeter han estado trabajando en el desarrollo de instrumentos, de modo que somos capaces de detectar diferencias cada vez m\u00e1s peque\u00f1as entre las poblaciones de prote\u00ednas, lo que es particularmente importante para una prote\u00edna tan flexible como aSyn\u00bb, dice Maria Zacharopoulou, primera coautor del art\u00edculo de investigaci\u00f3n del Departamento de Ingenier\u00eda Qu\u00edmica y Biotecnolog\u00eda de la Universidad de Cambridge.<\/p>\n<p>Observaron que una regi\u00f3n espec\u00edfica llamada N-terminal de aSyn, que se encuentra al comienzo de la secuencia de la prote\u00edna, se vuelve m\u00e1s expuesta y la prote\u00edna se abre estructuralmente cuando se agrega el ion que induce la agregaci\u00f3n, el calcio. Adem\u00e1s, la extensi\u00f3n de la exposici\u00f3n se correlacion\u00f3 con la velocidad a la que se agreg\u00f3 aSyn, mientras que las estructuras m\u00e1s cerradas no se agregaron.<\/p>\n<p>Mediante el uso de espectrometr\u00eda de masas de intercambio de hidr\u00f3geno-deuterio, los investigadores pudieron determinar que las modificaciones en la secuencia de la prote\u00edna, o la presencia de mutaciones hereditarias que causan la enfermedad de Parkinson de inicio temprano, conducen a un cambio en las estructuras del mon\u00f3mero din\u00e1mico aSyn. Este estudio aporta nuevos conocimientos sobre la enfermedad de Parkinson al principio del proceso, cuando se produce la transici\u00f3n de mon\u00f3mero a agregado.<\/p>\n<p>Los hallazgos podr\u00edan conducir a nuevos objetivos terap\u00e9uticos, ya que la estabilizaci\u00f3n de la estructura cerrada de una prote\u00edna Syn puede evitar que se agregue. Los pr\u00f3ximos pasos incluir\u00e1n el aislamiento de estructuras propensas a la agregaci\u00f3n y no propensas a la agregaci\u00f3n espec\u00edficas del grupo de estructuras monom\u00e9ricas din\u00e1micas para dise\u00f1ar terapias para estabilizar o neutralizar el mon\u00f3mero aSyn antes de que comience a plegarse incorrectamente. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> La prote\u00edna se muestra prometedora en el tratamiento de la enfermedad de Parkinson <strong>M\u00e1s informaci\u00f3n:<\/strong> Amberley D. Stephens et al, La extensi\u00f3n de la exposici\u00f3n N-terminal de la alfa-sinucle\u00edna monom\u00e9rica determina su propensi\u00f3n a la agregaci\u00f3n, Nature Comunicaciones (2020). DOI: 10.1038\/s41467-020-16564-3 <strong>Informaci\u00f3n de la revista:<\/strong> Nature Communications <\/p>\n<p> Proporcionado por la Universidad de Cambridge <strong>Cita<\/strong>: La comprensi\u00f3n del plegamiento incorrecto de prote\u00ednas podr\u00eda abrir nuevos enfoques para tratar la enfermedad de Parkinson (4 de junio de 2020) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-06-insight-protein-misfolding-approaches-parkinson.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La inmunohistoqu\u00edmica para la alfa-sinucle\u00edna muestra una tinci\u00f3n positiva (marr\u00f3n) de un cuerpo de Lewy intraneural en la sustancia negra en la enfermedad de Parkinson. Cr\u00e9dito: Wikipedia Los investigadores han descubierto un v\u00ednculo entre la estructura de la prote\u00edna alfa-sinucle\u00edna y su probabilidad de plegarse incorrectamente y agregarse. Los agregados de alfa-sinucle\u00edna son el sello &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/la-comprension-del-plegamiento-incorrecto-de-proteinas-podria-abrir-nuevos-enfoques-para-tratar-la-enfermedad-de-parkinson\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLa comprensi\u00f3n del plegamiento incorrecto de prote\u00ednas podr\u00eda abrir nuevos enfoques para tratar la enfermedad de Parkinson\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30392","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30392"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30392\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}