{"id":30394,"date":"2022-08-31T18:15:22","date_gmt":"2022-08-31T23:15:22","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/observatorio-covid-19-la-respuesta-fallida-agrava-la-miseria-en-brasil\/"},"modified":"2022-08-31T18:15:22","modified_gmt":"2022-08-31T23:15:22","slug":"observatorio-covid-19-la-respuesta-fallida-agrava-la-miseria-en-brasil","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/observatorio-covid-19-la-respuesta-fallida-agrava-la-miseria-en-brasil\/","title":{"rendered":"Observatorio COVID-19: La respuesta fallida agrava la miseria en Brasil"},"content":{"rendered":"<p>Cr\u00e9dito: Universidad de Miami <\/p>\n<p>Brasil, que ha seguido el inepto ejemplo de M\u00e9xico al no promulgar r\u00e1pidamente pol\u00edticas nacionales de salud p\u00fablica para contener la pandemia del coronavirus, ahora se ha convertido en l\u00edder mundial en contagios y muertes diarias, seg\u00fan la \u00faltima ronda de datos proporcionada por el Observatorio Latinoam\u00e9rica COVID-19. <\/p>\n<p>En un seminario web triling\u00fce el martes, los miembros de la iniciativa dirigida por la Universidad de Miami que proporciona datos oportunos en un esfuerzo por mejorar las respuestas de las pol\u00edticas de salud p\u00fablica del gobierno y salvar vidas, junto con un destacado epidemi\u00f3logo brasile\u00f1o, analizaron el estudio del observatorio sobre Brasil. <\/p>\n<p>\u00abEsta es una discusi\u00f3n muy oportuna ya que Am\u00e9rica Latina se ha convertido en el punto cr\u00edtico del mundo para las infecciones y muertes por COVID-19, representando el 40 por ciento de las muertes diarias registradas a nivel mundial, y Brasil ha llegado a una fase cr\u00edtica en su respuesta a la pandemia de COVID-19\u00bb, dijo el presidente de la Universidad de Miami, Julio Frenk, estableciendo el contexto de la sesi\u00f3n.<\/p>\n<p>Frenk, exministro de salud en M\u00e9xico y experto en salud p\u00fablica mundial, destac\u00f3 el \u00bb enormes expresiones de solidaridad, servicio y sacrificio en la regi\u00f3n, particularmente por parte de los trabajadores e investigadores de salud de primera l\u00ednea\u00bb en la b\u00fasqueda de combatir el contagio.<\/p>\n<p>\u00abEn ese esp\u00edritu de solidaridad, presentamos estos datos ,\u00bb \u00e9l dijo, \u00absin embargo, lamentablemente, estamos siendo testigos del peligro de la acci\u00f3n tard\u00eda de los gobiernos populistas que tienden a devaluar la ciencia y la evidencia y que ha puesto en riesgo millones de vidas\u00bb.<\/p>\n<p>El Observatorio COVID-19 de Am\u00e9rica Latina fue desarrollado por el Instituto de Estudios Avanzados de las Am\u00e9ricas, la Escuela de Medicina Miller, la Facultad de Artes y Ciencias y la Escuela de Comunicaci\u00f3n, en colaboraci\u00f3n con socios de investigaci\u00f3n en toda Am\u00e9rica Latina. Una primera ronda de datos publicada hace varias semanas se centr\u00f3 en M\u00e9xico, y esta segunda publicaci\u00f3n se centr\u00f3 en Brasil con un an\u00e1lisis de datos regionales comparativos.<\/p>\n<p>El observatorio proporciona actualizaciones diarias sobre pol\u00edticas de salud p\u00fablica y distanciamiento f\u00edsico10 variables en total implementadas en a nivel nacional y subnacional, el \u00fanico consorcio que ofrece datos regionales a nivel estatal de este alcance, explic\u00f3 Felicia Marie Knaul, directora del Instituto de Estudios Avanzados de las Am\u00e9ricas y profesora del Departamento de Ciencias de la Salud P\u00fablica de la Escuela Miller.<\/p>\n<p>Knaul se\u00f1al\u00f3 que el observatorio planea continuar con su evaluaci\u00f3n de otros pa\u00edses de la regi\u00f3n y tambi\u00e9n fortalecer su colaboraci\u00f3n con Brasil. Hizo hincapi\u00e9 en el valor de proporcionar datos a nivel estatal que se pueden visualizar f\u00e1cilmente en el sitio web.<\/p>\n<p>\u00abDesde el punto de vista de la investigaci\u00f3n, podremos observar las diferencias entre estados y pa\u00edses para ayudarnos a explicar lo que funciona y lo que no funciona frente a una pandemia y eso deber\u00eda ayudar con la preparaci\u00f3n futura y tambi\u00e9n lo que podr\u00edamos ver en t\u00e9rminos de segundas oleadas de la pandemia actual\u00bb, dijo Knaul, quien ha sido fundamental en el avance de la iniciativa.<\/p>\n<p>\u00abAdem\u00e1s\u00bb, continu\u00f3, \u00ablo que hemos visto en M\u00e9xico, Brasil y otros pa\u00edses con una variaci\u00f3n importante es que si demuestras que algunos estados se est\u00e1n desempe\u00f1ando mejor que otros, puedes alentar a esos estados que tienen una pol\u00edtica p\u00fablica d\u00e9bil o incluso aquellos que han promulgado una pol\u00edtica fuerte, pero a\u00fan est\u00e1n viendo movilidad, que necesitan ajustar sus pol\u00edticas p\u00fablicas\u00bb. Tal an\u00e1lisis, dijo, puede brindar \u00abuna oportunidad para una mejora general a nivel nacional al pedirles a los estados que se unan y lo hagan tan bien como los estados con mejor desempe\u00f1o\u00bb.<\/p>\n<p>Knaul se\u00f1al\u00f3 que Brasil, con ahora con casi 1000 muertes por d\u00eda y una trayectoria que est\u00e1 en alza, ahora es el punto caliente de la pandemia mundial.<\/p>\n<p>\u00abNuestros corazones y almas est\u00e1n con todos los que viven en Brasil en el epicentro y para ver c\u00f3mo est\u00e1 evolucionando esto, y estamos aqu\u00ed para hacer todo lo posible para brindar apoyo\u00bb, dijo.<\/p>\n<p>Alberto Cairo, presidente de Knight en Periodismo Visual y profesor asociado de la Escuela de Comunicaci\u00f3n, moder\u00f3 el seminario web. Cairo form\u00f3 parte de un s\u00f3lido esfuerzo de colaboraci\u00f3n de la escuela que desempe\u00f1\u00f3 un papel importante en la traducci\u00f3n ling\u00fc\u00edstica, textual y visual de los datos y la visualizaci\u00f3n del sitio web.<\/p>\n<p>En los hallazgos preliminares sobre Brasil, el consorcio observ\u00f3 que la administraci\u00f3n de El presidente de Brasil, Jair Bolsonaro, perdi\u00f3 un tiempo valioso mientras el COVID-19 se propagaba por todo el pa\u00eds, un retraso que oblig\u00f3 a los gobiernos estatales y locales a valerse por s\u00ed mismos.<\/p>\n<p>Michael Touchton, profesor asistente de ciencias pol\u00edticas y profesor asociado de salud global l\u00edder del instituto con experiencia en Brasil, destac\u00f3 el impacto de las disparidades en las diferentes respuestas de los estados brasile\u00f1os y otras tendencias m\u00e1s recientes en su presentaci\u00f3n.<\/p>\n<p>Los mejores resultados estatales no se limitaron a los estados m\u00e1s ricos, ni a los que a menudo se consideran los mejor gobernados, se\u00f1al\u00f3 Touchton. En cambio, las explicaciones pol\u00edticas de si el gobernador del estado se opuso o apoy\u00f3 al presidente brasile\u00f1o fueron un mejor indicador de qu\u00e9 tan bien control\u00f3 el estado el contagio.<\/p>\n<p>Los estados relativamente marginados del noreste del pa\u00eds han respondido de manera m\u00e1s agresiva y les ha ido mejor, al igual que algunos estados del norte. Y los gobernadores de los partidos de oposici\u00f3n lideran estos estados y han impuesto medidas mucho m\u00e1s estrictas que las recomendadas por la administraci\u00f3n de Bolsonaro, se\u00f1al\u00f3 Touchton.<\/p>\n<p>Cesar Victora, epidemi\u00f3logo brasile\u00f1o y director del Centro Internacional para la Equidad en Salud de la Universidade Federal de Pelotas, proporcion\u00f3 un an\u00e1lisis detallado basado en encuestas de hogares de 133 ciudades centinela en los 27 estados de Brasil. En respuesta a una pregunta de la audiencia, Frenk dijo que el elemento com\u00fan tanto para controlar la pandemia como para abrir la econom\u00eda en Am\u00e9rica Latina y en otros lugares es hacer pruebas, tanto para vigilancia como para diagn\u00f3stico.<\/p>\n<p>\u00abNo es una compensaci\u00f3n: los dos objetivos de control y apertura tienen que ir de la mano\u00bb, dijo Frenk. \u00abSi reabre la econom\u00eda de una manera acelerada e imprudente, tendr\u00e1 un aumento en los casos. Y es posible que tenga que cerrar la econom\u00eda por segunda vez\u00bb.<\/p>\n<p>\u00abY la tercera pieza es clara , comunicaci\u00f3n clara\u00bb, continu\u00f3 Frenk. \u201cComunicar a la gente para que se apegue al distanciamiento f\u00edsico, la protecci\u00f3n del espacio personal mediante el uso de mascarillas y amplias medidas de higiene personal, esa es la combinaci\u00f3n que te permite abrir la econom\u00eda de forma segura y controlar la pandemia\u201d. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Siga las \u00faltimas noticias sobre el brote de coronavirus (COVID-19) Proporcionado por la Universidad de Miami <strong>Cita<\/strong>: Observatorio COVID-19: La respuesta fallida agrava la miseria en Brasil (2020, 4 de junio) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-06-covid-observatory-bungled-response-compounds.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Universidad de Miami Brasil, que ha seguido el inepto ejemplo de M\u00e9xico al no promulgar r\u00e1pidamente pol\u00edticas nacionales de salud p\u00fablica para contener la pandemia del coronavirus, ahora se ha convertido en l\u00edder mundial en contagios y muertes diarias, seg\u00fan la \u00faltima ronda de datos proporcionada por el Observatorio Latinoam\u00e9rica COVID-19. En un seminario &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/observatorio-covid-19-la-respuesta-fallida-agrava-la-miseria-en-brasil\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abObservatorio COVID-19: La respuesta fallida agrava la miseria en Brasil\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30394","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30394"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30394\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}