{"id":30403,"date":"2022-08-31T18:15:52","date_gmt":"2022-08-31T23:15:52","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/nueva-zelanda-tiene-un-95-de-posibilidades-de-eliminar-el-coronavirus-pero-predecimos-que-surgiran-nuevos-casos\/"},"modified":"2022-08-31T18:15:52","modified_gmt":"2022-08-31T23:15:52","slug":"nueva-zelanda-tiene-un-95-de-posibilidades-de-eliminar-el-coronavirus-pero-predecimos-que-surgiran-nuevos-casos","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/nueva-zelanda-tiene-un-95-de-posibilidades-de-eliminar-el-coronavirus-pero-predecimos-que-surgiran-nuevos-casos\/","title":{"rendered":"Nueva Zelanda tiene un 95 % de posibilidades de eliminar el coronavirus, pero predecimos que surgir\u00e1n nuevos casos"},"content":{"rendered":"<p>Cr\u00e9dito: Daniele Cossu\/Shutterstock <\/p>\n<p>Ahora hay un 95 % de posibilidades de que el COVID-19 haya sido eliminado en Nueva Zelanda, seg\u00fan nuestro modelado, basado en datos oficiales del Ministerio de Salud. <\/p>\n<p>Hasta el 4 de junio, Nueva Zelanda ha tenido 20 d\u00edas consecutivos sin casos nuevos y solo queda un caso activo. El \u00faltimo caso nuevo informado de COVID-19 fue el 15 de mayo (seg\u00fan la fecha en que se sospech\u00f3 por primera vez en lugar de confirmarse m\u00e1s tarde). <\/p>\n<p>Esto a\u00fan deja una peque\u00f1a posibilidad de casos no detectados, y sabemos que el COVID-19 se transmite en eventos de superpropagaci\u00f3n. <\/p>\n<p>Nueva Zelanda ahora se est\u00e1 preparando para relajar sus restricciones de COVID-19 para alertar el nivel 1 desde el pr\u00f3ximo mi\u00e9rcoles, lo que pondr\u00eda fin al distanciamiento f\u00edsico y las restricciones de tama\u00f1o en las reuniones. Sin embargo, nuestro modelo sugiere que eliminar los l\u00edmites de las grandes reuniones aumentar\u00e1 el riesgo de un nuevo brote muy grande del 3 % al 8 %.<\/p>\n<p>Para reducir este riesgo, los neozelandeses deber\u00e1n seguir evitando las tres C de posibles infecci\u00f3n: espacios cerrados, lugares concurridos y contacto cercano.<\/p>\n<p>A medida que regresan las multitudes, los riesgos aumentar\u00e1n<\/p>\n<p>Nueva Zelanda est\u00e1 ahora muy cerca de su objetivo de eliminaci\u00f3n. Pero todav\u00eda hay un 5% de posibilidades de casos no detectados. <\/p>\n<p>El 3 de junio, la primera ministra Jacinda Ardern anunci\u00f3 los detalles de las reglas del nivel 1 de alerta inminente. Los cierres de fronteras se mantendr\u00e1n en gran medida (excepto para los neozelandeses que regresan), pero todas las dem\u00e1s restricciones importantes sobre el movimiento de personas dentro de Nueva Zelanda terminar\u00e1n.<\/p>\n<p>Desde la perspectiva del virus, el cambio m\u00e1s significativo ser\u00e1 el fin de las restricciones. sobre el tama\u00f1o de las reuniones. Las aerol\u00edneas pueden volver a llenar la clase econ\u00f3mica, los clubes nocturnos pueden llenar sus pistas de baile y las universidades pueden abrir sus salas de conferencias. <\/p>\n<p>Es posible que alguien que haya contra\u00eddo el virus hace tres o cuatro semanas no haya desarrollado s\u00edntomas graves (lo que sucede en alrededor del 30 % de las personas) y no se haya hecho una prueba. Podr\u00edan haberle transmitido el virus a otra persona, que tambi\u00e9n se perdi\u00f3 una prueba. <\/p>\n<p>Una cadena de infecciones como esta podr\u00eda continuar durante un tiempo antes de que se detecte. Algunos segmentos de la poblaci\u00f3n, como las personas m\u00e1s j\u00f3venes, tienen menos probabilidades de desarrollar s\u00edntomas y, por lo tanto, es m\u00e1s probable que mantengan cadenas de infecci\u00f3n ocultas. <\/p>\n<p>COVID-19 es un virus de superpropagaci\u00f3n. El n\u00famero de reproducci\u00f3n (R0) nos dice que en promedio cada persona infectada infecta a otras 2,5 personas. Pero de cada diez personas que se contagian de COVID-19, nueve probablemente no lo transmitir\u00e1n, mientras que la d\u00e9cima persona puede presentarse en un evento e infectar a otras 25. <\/p>\n<p> Probabilidad de eliminaci\u00f3n suponiendo que no se notifiquen nuevos casos despu\u00e9s del 15 de mayo. <\/p>\n<p>Riesgo de los viajeros que regresan<\/p>\n<p>Tambi\u00e9n existe la posibilidad de que el COVID-19 entre en Nueva Zelanda con un viajero internacional. La semana pasada, alrededor de 200 personas, casi todos kiwis que regresaban, aterrizaron en Nueva Zelanda todos los d\u00edas. <\/p>\n<p>Muchos proced\u00edan de lugares como Australia, Hong Kong o Tonga, todos pa\u00edses relativamente libres de COVID-19. Algunos tambi\u00e9n llegaron de Estados Unidos, donde el virus est\u00e1 muy extendido. Entre febrero y abril, sabemos que entre el 0,1% y el 0,2% de todas las llegadas dieron positivo. Con estos n\u00fameros, deber\u00edamos esperar que lleguen uno o dos casos nuevos cada semana. <\/p>\n<p>Los reci\u00e9n llegados deben permanecer en cuarentena durante al menos 14 d\u00edas. El per\u00edodo de incubaci\u00f3n de la COVID-19 suele ser de cinco a seis d\u00edas y es raro que los s\u00edntomas comiencen m\u00e1s de 14 d\u00edas despu\u00e9s de la exposici\u00f3n. <\/p>\n<p>El mayor riesgo es que una persona sin s\u00edntomas llegue y transmita el virus a alguien en el mismo hotel de cuarentena, que luego se va antes de que aparezcan los s\u00edntomas. <\/p>\n<p>Los datos del Ministerio de Salud muestran que ocho de los 500 casos importados de Nueva Zelanda desarrollaron sus primeros s\u00edntomas m\u00e1s de dos semanas despu\u00e9s de llegar. Tal vez lo atraparon antes de llegar o tal vez lo atraparon durante la cuarentena. De cualquier manera, habr\u00edan sido infecciosos despu\u00e9s de salir de la cuarentena.<\/p>\n<p>Las personas que trabajan en la tripulaci\u00f3n de cabina de la aerol\u00ednea fronteriza, el personal de bioseguridad o inmigraci\u00f3n y el personal de los hoteles de cuarentena corren un riesgo similar. <\/p>\n<p>El inevitable nuevo caso<\/p>\n<p>Nuestros modelos muestran que el riesgo de nuevos casos provenientes de Nueva Zelanda ahora es comparable al de los viajeros internacionales. El riesgo de llegadas internacionales sigue siendo el mismo ya sea que estemos en el nivel 1 o 2, mientras que el riesgo de transmisi\u00f3n nacional est\u00e1 disminuyendo. <\/p>\n<p>La pregunta m\u00e1s importante es c\u00f3mo nos las arreglaremos cuando llegue el inevitable nuevo caso. <\/p>\n<p>Cada caso activo es como una peque\u00f1a chispa esperando para iniciar un incendio. La teor\u00eda de la superpropagaci\u00f3n nos dice que la mayor\u00eda de esas chispas se apagan, pero un peque\u00f1o n\u00famero se encender\u00e1. Estas chispas son el problema: podr\u00eda ser una persona infectada en un ensayo del coro, en un club nocturno o animando a su equipo deportivo. <\/p>\n<p>Nueva Zelanda tiene la suerte de contar con rastreadores de contactos altamente capacitados y experimentados. Pero necesitan nuestra ayuda. Si tuviera un resultado positivo, \u00bfpodr\u00eda recordar todos los lugares en los que estuvo durante la \u00faltima semana y qui\u00e9n m\u00e1s estuvo all\u00ed? La pesadilla de un rastreador de contactos es una gran reuni\u00f3n sin registro de qui\u00e9n asisti\u00f3.<\/p>\n<p>Para pasar al nivel 1, primero debemos asegurarnos de que nuestros sistemas de rastreo de contactos, incluida la aplicaci\u00f3n NZ COVID Tracer, los c\u00f3digos QR y la firma. en s\u00e1banas en comercios, est\u00e1n a la altura. Necesitamos estar seguros de que podemos manejar los riesgos cuando cientos de personas se re\u00fanen o asisten a marchas de protesta. Tenemos que ser capaces de hacer estas cosas de manera segura mientras el COVID-19 todav\u00eda est\u00e9 presente. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Siga las \u00faltimas noticias sobre el brote de coronavirus (COVID-19) Proporcionado por The Conversation <\/p>\n<p> Este art\u00edculo se vuelve a publicar de The Conversation bajo una licencia Creative Commons. Lea el art\u00edculo original. <\/p>\n<p> <strong>Cita<\/strong>: Nueva Zelanda tiene un 95 % de posibilidades de eliminar el coronavirus, pero predecimos que surgir\u00e1n nuevos casos (4 de junio de 2020) consultado el 31 de agosto de 2022 en https:\/\/medicalxpress.com\/news\/ 2020-06-zealand-chance-coronavirusbut-cases-emerge.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Daniele Cossu\/Shutterstock Ahora hay un 95 % de posibilidades de que el COVID-19 haya sido eliminado en Nueva Zelanda, seg\u00fan nuestro modelado, basado en datos oficiales del Ministerio de Salud. Hasta el 4 de junio, Nueva Zelanda ha tenido 20 d\u00edas consecutivos sin casos nuevos y solo queda un caso activo. El \u00faltimo caso &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/nueva-zelanda-tiene-un-95-de-posibilidades-de-eliminar-el-coronavirus-pero-predecimos-que-surgiran-nuevos-casos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abNueva Zelanda tiene un 95 % de posibilidades de eliminar el coronavirus, pero predecimos que surgir\u00e1n nuevos casos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30403","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30403"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30403\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}