{"id":30410,"date":"2022-08-31T18:16:18","date_gmt":"2022-08-31T23:16:18","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/el-estudio-mas-grande-hasta-la-fecha-de-registros-dentales-electronicos-revisa-poblaciones-poco-estudiadas\/"},"modified":"2022-08-31T18:16:18","modified_gmt":"2022-08-31T23:16:18","slug":"el-estudio-mas-grande-hasta-la-fecha-de-registros-dentales-electronicos-revisa-poblaciones-poco-estudiadas","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/el-estudio-mas-grande-hasta-la-fecha-de-registros-dentales-electronicos-revisa-poblaciones-poco-estudiadas\/","title":{"rendered":"El estudio m\u00e1s grande hasta la fecha de registros dentales electr\u00f3nicos revisa poblaciones poco estudiadas"},"content":{"rendered":"<p>El estudio m\u00e1s grande hasta la fecha de registros dentales electr\u00f3nicos (EDR) profundiza tanto en datos previamente inaccesibles como en datos de poblaciones poco estudiadas con el objetivo final de mejorar los resultados del tratamiento oral. En el innovador estudio, investigadores del Instituto Regenstrief y la Facultad de Odontolog\u00eda de la Universidad de Indiana evaluaron datos no identificados de EDR de pacientes asegurados y no asegurados que conten\u00edan m\u00e1s de 11 millones de observaciones, con per\u00edodos de observaci\u00f3n de hasta 37 a\u00f1os. Cr\u00e9dito: Regenstrief Institute <\/p>\n<p>El estudio m\u00e1s grande hasta la fecha sobre registros dentales electr\u00f3nicos profundiza tanto en datos previamente inaccesibles como en datos de poblaciones poco estudiadas con el objetivo final de mejorar los resultados del tratamiento oral. El trabajo presenta un mecanismo de sistema de salud de aprendizaje para que los dentistas aprendan de su propia experiencia y de las experiencias de los compa\u00f1eros practicantes. <\/p>\n<p>Los investigadores dirigidos por el cient\u00edfico investigador del Instituto Regenstrief, Thankam Thyvalikakath, DMD, Ph.D., profesor asociado y director del N\u00facleo de Inform\u00e1tica Dental de la Facultad de Odontolog\u00eda de la Universidad de Indiana, evaluaron datos no identificados de los registros dentales electr\u00f3nicos (EDR) de 217,887 pacientes de 99 consultorios dentales individuales o peque\u00f1os en los Estados Unidos. Estos EDR conten\u00edan m\u00e1s de 11 millones de observaciones, con per\u00edodos de observaci\u00f3n de hasta 37 a\u00f1os.<\/p>\n<p>El estudio determin\u00f3 que es factible extraer y utilizar enormes cantidades de datos de EDR para saber qu\u00e9 terapias dentales funcionan y cu\u00e1les no. no, empoderando la mejora de la calidad por parte de dentistas individuales. Los datos de EDR son lo suficientemente fiables para fines que van m\u00e1s all\u00e1 de la atenci\u00f3n cl\u00ednica de pacientes individuales.<\/p>\n<p>Aprender de la agregaci\u00f3n de datos entre pr\u00e1cticas le da a cada odont\u00f3logo la oportunidad de adquirir conocimientos no solo de los datos de sus propios pacientes, sino tambi\u00e9n la oportunidad para comparar su pr\u00e1ctica con la de sus compa\u00f1eros. La informaci\u00f3n obtenida durante la visita de cada paciente contribuye as\u00ed a una mejor atenci\u00f3n para todos, creando un verdadero sistema de salud de aprendizaje.<\/p>\n<p>Ahora que han completado la prueba de concepto; Los investigadores utilizar\u00e1n los datos para evaluar la efectividad a largo plazo de dos procedimientos dentales comunes realizados en dientes permanentes, terapia de conducto radicular y empastes del color del diente en los dientes posteriores. El an\u00e1lisis de datos para esa parte del estudio, que determinar\u00e1 qu\u00e9 tan bien y durante cu\u00e1nto tiempo contin\u00faan funcionando los dientes tratados con el conducto radicular y los dientes posteriores con empastes del color del diente, ayudar\u00e1 tanto a los dentistas como a los pacientes a tomar decisiones de atenci\u00f3n basadas en evidencia. El an\u00e1lisis de datos est\u00e1 a punto de finalizar y los hallazgos se publicar\u00e1n en el futuro.<\/p>\n<p>\u00abAqu\u00ed, en el mundo real del consultorio del dentista, estamos viendo pacientes con todo tipo de condiciones del mundo real, condiciones m\u00e9dicas subyacentes, falta de atenci\u00f3n de salud oral adecuada en el pasado, por lo que este gran conjunto de datos proporciona una visi\u00f3n \u00fanica de los tratamientos ofrecidos en el tipo de consultorios dentales donde la mayor\u00eda de los estadounidenses reciben atenci\u00f3n\u00bb, dijo el Dr. Thyvalikakath, director fundador del programa de inform\u00e1tica dental de la Facultad de Odontolog\u00eda de Regenstrief-IU. .<\/p>\n<p>Se recopil\u00f3 informaci\u00f3n sobre datos demogr\u00e1ficos, motivo de la visita, historial m\u00e9dico y dental, historial social, caracter\u00edsticas dentales y tratamiento, as\u00ed como las caracter\u00edsticas de la pr\u00e1ctica y del m\u00e9dico para cada visita del paciente.<\/p>\n<p> Dr. Thyvalikakath describe el trabajo como innovador en cuatro \u00e1reas:<\/p>\n<p>1. Los dentistas pudieron compartir sus datos para la investigaci\u00f3n en un proceso an\u00f3nimo con la ayuda de sus proveedores de EDR, porque un dentista independiente t\u00edpico o incluso una pr\u00e1ctica peque\u00f1a no tienen personal de TI dedicado.<\/p>\n<p>2. Se combinaron datos de dos sistemas de registros dentales electr\u00f3nicos con diferentes formatos y sistemas operativos. La interoperabilidad ha resultado dif\u00edcil con los datos de los sistemas de registros m\u00e9dicos electr\u00f3nicos.<\/p>\n<p>3. Es el estudio m\u00e1s grande para evaluar la calidad de los datos en un entorno de pacientes regulares.<\/p>\n<p>4. opciones de salud y tratamiento de pacientes asegurados y no asegurados. Estudios anteriores se basaron en registros de seguros y, por lo tanto, no proporcionaron informaci\u00f3n sobre pacientes sin seguro.<\/p>\n<p>\u00abLos hallazgos derivados de los datos de los pacientes en condiciones del mundo real suelen ser menos dif\u00edciles de traducir para los m\u00e9dicos en el punto de atenci\u00f3n que los estudios realizado en grandes sistemas de salud que a menudo representan una poblaci\u00f3n de pacientes que no refleja la comunidad que los dentistas ven en sus pr\u00e1cticas\u00bb, dijo el Dr. Thyvalikakath. \u00abPresentamos un mecanismo para que los dentistas, muchos de los cuales ejercen solos o con solo uno o dos, aprendan de su propia experiencia y de las experiencias de sus compa\u00f1eros para ayudarlos a mejorar sus habilidades y enfrentar problemas\u00bb.<\/p>\n<p>\u00abAprovechamiento de los datos de registros dentales electr\u00f3nicos para la investigaci\u00f3n cl\u00ednica en las pr\u00e1cticas PBRN dentales nacionales\u00bb se publica en la revista revisada por pares Applied Clinical Informatics. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Estudio: atenci\u00f3n de urgencia, los m\u00e9dicos de urgencias prescribieron en exceso antibi\u00f3ticos para problemas dentales Proporcionado por el Instituto Regenstrief <strong>Cita<\/strong>: El estudio m\u00e1s grande hasta la fecha de registros dentales electr\u00f3nicos revisa poblaciones poco estudiadas (2020, 4 de junio) ) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-06-largest-date-electronic-dental-understudied.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El estudio m\u00e1s grande hasta la fecha de registros dentales electr\u00f3nicos (EDR) profundiza tanto en datos previamente inaccesibles como en datos de poblaciones poco estudiadas con el objetivo final de mejorar los resultados del tratamiento oral. En el innovador estudio, investigadores del Instituto Regenstrief y la Facultad de Odontolog\u00eda de la Universidad de Indiana evaluaron &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/el-estudio-mas-grande-hasta-la-fecha-de-registros-dentales-electronicos-revisa-poblaciones-poco-estudiadas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl estudio m\u00e1s grande hasta la fecha de registros dentales electr\u00f3nicos revisa poblaciones poco estudiadas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30410","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30410"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30410\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}