{"id":30413,"date":"2022-08-31T18:16:28","date_gmt":"2022-08-31T23:16:28","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/factores-de-crecimiento-y-enfermedad-de-parkinson-que-sigue\/"},"modified":"2022-08-31T18:16:28","modified_gmt":"2022-08-31T23:16:28","slug":"factores-de-crecimiento-y-enfermedad-de-parkinson-que-sigue","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/factores-de-crecimiento-y-enfermedad-de-parkinson-que-sigue\/","title":{"rendered":"Factores de crecimiento y enfermedad de Parkinson: \u00bfQu\u00e9 sigue?"},"content":{"rendered":"<p>Inmunohistoqu\u00edmica para alfa-sinucle\u00edna que muestra una tinci\u00f3n positiva (marr\u00f3n) de un cuerpo de Lewy intraneural en la sustancia negra en la enfermedad de Parkinson. Cr\u00e9dito: Wikipedia <\/p>\n<p>Inicialmente se pens\u00f3 que los factores de crecimiento, como el factor neurotr\u00f3fico derivado de la l\u00ednea de c\u00e9lulas gliales (GDNF, por sus siglas en ingl\u00e9s), ser\u00edan tratamientos nuevos y emocionantes para la enfermedad de Parkinson (EP), pero los ensayos han sido decepcionantes. Un panel de l\u00edderes prominentes en el campo se reuni\u00f3 para discutir si hay un futuro para este enfoque y qu\u00e9 deber\u00eda considerar cualquier ensayo de DP futuro que involucre GDNF y otros factores neurotr\u00f3ficos de la familia GDNF. Sus debates y recomendaciones se publican en el Journal of Parkinson&#8217;s Disease. <\/p>\n<p>\u00abExiste evidencia clara de que el GDNF y los factores de crecimiento relacionados pueden restaurar la v\u00eda nigroestriatal dopamin\u00e9rgica en varios modelos animales de EP\u00bb, explic\u00f3 el autor principal, Roger A. Barker, Ph.D., Centro de Reparaci\u00f3n Cerebral de Cambridge, Departamento de Medicina Cl\u00ednica. Neurociencia y WT-MRC Cambridge Stem Cell Institute, Cambridge, Reino Unido. \u00abSin embargo, esto a\u00fan tiene que traducirse en una respuesta s\u00f3lida y cl\u00ednicamente significativa en los pacientes\u00bb.<\/p>\n<p>Los factores de crecimiento respaldan el desarrollo, el crecimiento y la supervivencia de las c\u00e9lulas en el cuerpo y el cerebro. El concepto de reparar el cerebro con factores de crecimiento se ha buscado durante muchos a\u00f1os en una variedad de enfermedades neurodegenerativas, incluida principalmente la EP. Sus propiedades los convierten en una perspectiva interesante para el desarrollo de nuevos tratamientos que podr\u00edan ayudar a reparar el da\u00f1o causado en la EP.<\/p>\n<p>Un grupo internacional de expertos se reuni\u00f3 para analizar la historia y el estado actual del GDNF y el factor de crecimiento relacionado neurturina (NRTN ) terapia para la EP, revisando exhaustivamente los estudios precl\u00ednicos y cl\u00ednicos. La evaluaci\u00f3n cr\u00edtica llev\u00f3 a conclusiones sobre lo que se ha logrado y lo que no se ha demostrado utilizando estos agentes. En general, se acord\u00f3 que GDNF y NRTN han funcionado relativamente bien en modelos animales neurot\u00f3xicos de la EP, pero que su traducci\u00f3n a la cl\u00ednica hasta ahora no ha mostrado un impacto importante, lo que quiz\u00e1s destaca las limitaciones predictivas de los modelos animales de toxinas que se usan com\u00fanmente en el espacio precl\u00ednico en la EP para analizar las terapias modificadoras de la enfermedad.<\/p>\n<p>\u00abEn cuanto a c\u00f3mo deber\u00eda ser cualquier ensayo, todav\u00eda hay mucho debate sobre qu\u00e9 criterio principal de valoraci\u00f3n debe usarse y en qu\u00e9 momento, y Los aportes de la comunidad de pacientes sobre esto ser\u00e1n vitales en el futuro\u00bb, se\u00f1al\u00f3 el coautor Anders Bjorklund, MD, Ph.D., Wallenberg Neuroscience Center, Lund University, Lund, Suecia.<\/p>\n<p>Los participantes del taller acordaron que la cuesti\u00f3n de si GDNF tiene un futuro competitivo en el tratamiento de la EP a\u00fan no est\u00e1 clara. Ofrecieron recomendaciones sobre lo que deber\u00edan considerar los ensayos futuros con GDNF y c\u00f3mo podr\u00edan dise\u00f1arse. Por ejemplo, en comparaci\u00f3n con la relativa complejidad de la neurocirug\u00eda necesaria para implantar un sistema de administraci\u00f3n de infusiones y las infusiones en curso utilizadas en un ensayo reciente de GDNF, consideraron que un sistema de administraci\u00f3n viral que utiliza enfoques modificados m\u00e1s nuevos que requieren una cirug\u00eda menos compleja ser\u00eda m\u00e1s ventajoso. Adem\u00e1s, indicaron que los pacientes con EP en etapa temprana probablemente se beneficiar\u00edan de dicho tratamiento porque este grupo tendr\u00eda la mayor cantidad de neuronas y fibras para rescatar, con evidencia de p\u00e9rdida de fibras restringida al cuerpo estriado dorsal, donde el agente terap\u00e9utico podr\u00eda dirigirse. <\/p>\n<p>El taller concluy\u00f3 que se deben considerar ensayos futuros con GDNF y agentes relacionados, pero que se debe prestar mucha m\u00e1s atenci\u00f3n a todos los aspectos, incluido el tipo de paciente inscrito; la forma de factor de crecimiento dada; la dosis y el volumen del agente administrado; el modo de entrega y la duraci\u00f3n del seguimiento junto con herramientas de evaluaci\u00f3n \u00f3ptimas. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> El factor neurotr\u00f3fico GDNF es un importante regulador de las neuronas dopamin\u00e9rgicas en el cerebro. <strong>M\u00e1s informaci\u00f3n:<\/strong> Roger A. Barker et al, GDNF y la enfermedad de Parkinson: \u00bfQu\u00e9 sigue? Un resumen de un taller reciente, Journal of Parkinson&#8217;s Disease (2020). DOI: 10.3233\/JPD-202004 <strong>Informaci\u00f3n de la revista:<\/strong> Journal of Parkinson&#8217;s Disease <\/p>\n<p> Proporcionado por IOS Press <strong>Cita<\/strong>: Factores de crecimiento y enfermedad de Parkinson \u00bfQu\u00e9 sigue? (4 de junio de 2020) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-06-growth-factors-parkinson-diseasewhere.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inmunohistoqu\u00edmica para alfa-sinucle\u00edna que muestra una tinci\u00f3n positiva (marr\u00f3n) de un cuerpo de Lewy intraneural en la sustancia negra en la enfermedad de Parkinson. Cr\u00e9dito: Wikipedia Inicialmente se pens\u00f3 que los factores de crecimiento, como el factor neurotr\u00f3fico derivado de la l\u00ednea de c\u00e9lulas gliales (GDNF, por sus siglas en ingl\u00e9s), ser\u00edan tratamientos nuevos y &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/factores-de-crecimiento-y-enfermedad-de-parkinson-que-sigue\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abFactores de crecimiento y enfermedad de Parkinson: \u00bfQu\u00e9 sigue?\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30413","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30413"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30413\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}