{"id":30418,"date":"2022-08-31T18:16:46","date_gmt":"2022-08-31T23:16:46","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/vencer-al-covid-19-a-traves-de-la-investigacion-genomica\/"},"modified":"2022-08-31T18:16:46","modified_gmt":"2022-08-31T23:16:46","slug":"vencer-al-covid-19-a-traves-de-la-investigacion-genomica","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/vencer-al-covid-19-a-traves-de-la-investigacion-genomica\/","title":{"rendered":"Vencer al COVID-19 a trav\u00e9s de la investigaci\u00f3n gen\u00f3mica"},"content":{"rendered":"<p>Cr\u00e9dito: Mary Ann Liebert, Inc., editores <\/p>\n<p>La secuenciaci\u00f3n de pr\u00f3xima generaci\u00f3n del virus COVID-19 proporciona poderosos datos metagen\u00f3micos que, combinados con datos cl\u00ednicos, informar\u00e1n la b\u00fasqueda para tratamientos efectivos, como se informa en la revista revisada por pares Pediatric Allergy, Immunology, and Pulmonology. <\/p>\n<p>\u00abEl an\u00e1lisis gen\u00f3mico y epigen\u00f3mico continuo del SARS-CoV-2 es fundamental\u00bb, dicen los Dres. Dehority y Dinwiddie de la Facultad de Medicina de la Universidad de Nuevo M\u00e9xico, \u00abya que puede usarse para determinar la cantidad de cepas del virus, c\u00f3mo se introduce el virus en nuevas regiones, la cantidad de introducciones del virus, si hay propagaci\u00f3n comunitaria de virus, si los brotes est\u00e1n vinculados y c\u00f3mo est\u00e1 evolucionando el virus\u00bb.<\/p>\n<p>El an\u00e1lisis gen\u00e9tico tambi\u00e9n guiar\u00e1 e informar\u00e1 los esfuerzos para desarrollar vacunas y agentes terap\u00e9uticos nuevos y reutilizados, mediante pruebas de susceptibilidad viral o resistencia a estos intervenciones.<\/p>\n<p>La editora en jefe de Alergia pedi\u00e1trica, inmunolog\u00eda y neumolog\u00eda, Mary Cataletto, MD, profesora de pediatr\u00eda cl\u00ednica, Facultad de medicina de la Universidad de Stony Brook, afirma que: \u00abAl 25 de mayo de 2020, 1\u00a0637\u00a0456 Se informaron casos de COVID-19 a los Centros para el Control de Enfermedades con 97\u00a0669 muertes. El uso de estas nuevas t\u00e9cnicas no solo para la identificaci\u00f3n sino tambi\u00e9n para la vigilancia continua de nuevos pat\u00f3genos virales puede contribuir a respuestas estrat\u00e9gicas tempranas de salud p\u00fablica\u00bb. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Siga las \u00faltimas noticias sobre el brote de coronavirus (COVID-19) <strong>M\u00e1s informaci\u00f3n:<\/strong> Walter Dehority et al, Severe Acute Respiratory Syndrome Coronavirus 2: Genomic Observations and Emerging Therapies, Alergia pedi\u00e1trica, inmunolog\u00eda y neumolog\u00eda (2020). DOI: 10.1089\/ped.2020.1179 Proporcionado por Mary Ann Liebert, Inc <strong>Cita<\/strong>: Beating COVID-19 through genomic research (4 de junio de 2020) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news \/2020-06-covid-genomic.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Mary Ann Liebert, Inc., editores La secuenciaci\u00f3n de pr\u00f3xima generaci\u00f3n del virus COVID-19 proporciona poderosos datos metagen\u00f3micos que, combinados con datos cl\u00ednicos, informar\u00e1n la b\u00fasqueda para tratamientos efectivos, como se informa en la revista revisada por pares Pediatric Allergy, Immunology, and Pulmonology. \u00abEl an\u00e1lisis gen\u00f3mico y epigen\u00f3mico continuo del SARS-CoV-2 es fundamental\u00bb, dicen los &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/vencer-al-covid-19-a-traves-de-la-investigacion-genomica\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abVencer al COVID-19 a trav\u00e9s de la investigaci\u00f3n gen\u00f3mica\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30418","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30418"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30418\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}