{"id":30435,"date":"2022-08-31T18:17:43","date_gmt":"2022-08-31T23:17:43","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/desmantelamiento-de-la-produccion-de-oxido-nitrico-los-complejos-beta-arrestin2-regulan-los-niveles-de-no\/"},"modified":"2022-08-31T18:17:43","modified_gmt":"2022-08-31T23:17:43","slug":"desmantelamiento-de-la-produccion-de-oxido-nitrico-los-complejos-beta-arrestin2-regulan-los-niveles-de-no","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/desmantelamiento-de-la-produccion-de-oxido-nitrico-los-complejos-beta-arrestin2-regulan-los-niveles-de-no\/","title":{"rendered":"Desmantelamiento de la producci\u00f3n de \u00f3xido n\u00edtrico: los complejos beta-arrestin2 regulan los niveles de NO"},"content":{"rendered":"<p>Beta-arrestin2 (verde) se localiza con eNOS (p\u00farpura) en c\u00e9lulas sanas (panel superior); sin embargo, tras la lesi\u00f3n (panel inferior), esta localizaci\u00f3n se pierde. Cr\u00e9dito: Dr. Don Rockey. <\/p>\n<p>El h\u00edgado filtra la sangre, desintoxica las sustancias qu\u00edmicas y metaboliza las drogas. La hepatitis, el alcohol y las enfermedades hep\u00e1ticas primarias son fuentes comunes de da\u00f1o en el h\u00edgado y pueden provocar cicatrices, conocidas como fibrosis. La fibrosis a largo plazo puede provocar un tejido hep\u00e1tico m\u00e1s grueso, lo que a su vez provoca otros problemas, como un aumento de la presi\u00f3n arterial en el h\u00edgado. Conocida como hipertensi\u00f3n portal, la presi\u00f3n arterial alta en el h\u00edgado a menudo no se reconoce y puede ser letal. <\/p>\n<p>Investigadores de la Universidad M\u00e9dica de Carolina del Sur (MUSC) que estudian la enfermedad hep\u00e1tica han diseccionado un mecanismo que regula la actividad de la \u00f3xido n\u00edtrico sintasa endotelial (eNOS), una enzima que produce \u00f3xido n\u00edtrico (NO). Sus resultados, publicados recientemente en Proceedings of the National Academy of Sciences, mostraron que la beta-arrestina2 (beta-Arr2) act\u00faa como una prote\u00edna de andamiaje para activar eNOS, lo que lleva a una mayor s\u00edntesis de NO. Tras el da\u00f1o hep\u00e1tico, los niveles de beta-Arr2 disminuyen en las c\u00e9lulas epiteliales, lo que provoca una interrupci\u00f3n en la s\u00edntesis de NO y un aumento de la hipertensi\u00f3n portal. Esta investigaci\u00f3n muestra que beta-Arr2 es un objetivo terap\u00e9utico potencial.<\/p>\n<p>\u00abLos mecanismos moleculares que regulan la funci\u00f3n de eNOS son complejos y probablemente var\u00eden en la normalidad y la enfermedad\u00bb, dijo Don C. Rockey, MD, profesor y presidente del Departamento de Medicina de MUSC, que estudia la fibrosis hep\u00e1tica y la hipertensi\u00f3n portal.<\/p>\n<p>El Rockey Lab se centra en comprender los mecanismos subyacentes de la hipertensi\u00f3n portal. Las c\u00e9lulas endoteliales sinusoidales hep\u00e1ticas (SEC) desempe\u00f1an un papel fundamental en la homeostasis del h\u00edgado. Los SEC controlan la presi\u00f3n arterial y el flujo a trav\u00e9s de la producci\u00f3n de NO, que es producido por eNOS. Como mol\u00e9cula de se\u00f1alizaci\u00f3n, se ha sugerido que beta-Arr2 influye en eNOS, pero no estaba claro c\u00f3mo interact\u00faan estas prote\u00ednas para influir en la producci\u00f3n de NO.<\/p>\n<p>El trabajo actual deline\u00f3 el papel de beta-Arr2 en la regulaci\u00f3n de la actividad de eNOS. En SEC normales y saludables, beta-Arr2 activ\u00f3 eNOS. Por el contrario, las SEC da\u00f1adas mostraron una reducci\u00f3n significativa en los niveles de beta-Arr2 y una disminuci\u00f3n de la actividad de eNOS. Curiosamente, la sobreexpresi\u00f3n de beta-Arr2 mejor\u00f3 la producci\u00f3n de NO tanto en SEC normales como lesionadas. Adem\u00e1s, los ratones que carec\u00edan de beta-Arr2 ten\u00edan una reducci\u00f3n significativa en el \u00e1rea sinusoidal, destacando los efectos fisiol\u00f3gicos de la actividad reducida de eNOS. Juntos, estos datos muestran que beta-Arr2 es un regulador cr\u00edtico de la actividad de eNOS.<\/p>\n<p>El trabajo anterior del laboratorio de Rockey ha demostrado que la prote\u00edna 1 que interact\u00faa con la quinasa GPCR (GIT-1) es un potente activador de eNOS . El examen de la localizaci\u00f3n de GIT-1 revel\u00f3 que GIT-1, beta-Arr2 y eNOS se localizan juntos en SEC. Es importante destacar que la p\u00e9rdida de beta-Arr2 impidi\u00f3 la activaci\u00f3n de GIT-1 y la posterior activaci\u00f3n de eNOS. Por lo tanto, beta-Arr2 act\u00faa como una prote\u00edna de andamiaje para ayudar a activar GIT-1 y, a su vez, activar eNOS.<\/p>\n<p>En resumen, las SEC sanas producen NO al estimular beta-Arr2, que luego forma un signalosoma, un activo complejo proteico que ayuda a transducir se\u00f1ales celulares, para activar GIT-1. El GIT-1 activo a su vez activa eNOS para producir \u00f3xido n\u00edtrico. Por el contrario, durante la lesi\u00f3n hep\u00e1tica, los niveles de beta-Arr2 se reducen y esta v\u00eda se altera.<\/p>\n<p>\u00abEl gran mensaje es que la se\u00f1alizaci\u00f3n de eNOS es compleja y est\u00e1 controlada por m\u00faltiples mecanismos y se desregula despu\u00e9s de una lesi\u00f3n en el endotelio\u00bb. c\u00e9lulas\u00bb, dijo Rockey.<\/p>\n<p>Como componente central del eje de se\u00f1alizaci\u00f3n de eNOS, beta-Arr2 tiene el potencial de ser un nuevo objetivo terap\u00e9utico para la restauraci\u00f3n de la funci\u00f3n SEC. Sin embargo, antes de que un potencial terap\u00e9utico llegue a la cl\u00ednica, todav\u00eda quedan varias preguntas sobre la biolog\u00eda de beta-Arr2. Como andamio de se\u00f1alizaci\u00f3n que activa eNOS, es importante determinar qu\u00e9 otras prote\u00ednas interact\u00faan con beta-Arr2. Adem\u00e1s, el laboratorio de Rockey est\u00e1 investigando los mecanismos que influyen en la localizaci\u00f3n y\/o actividad de beta-Arr2. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Bajo presi\u00f3n: comprender c\u00f3mo se produce la hipertensi\u00f3n portal despu\u00e9s de una lesi\u00f3n hep\u00e1tica <strong>M\u00e1s informaci\u00f3n:<\/strong> Songling Liu et al, -Arrestin2 es un componente cr\u00edtico del se\u00f1alosoma GPCReNOS, Actas de la National Academia de Ciencias (2020). DOI: 10.1073\/pnas.1922608117 <strong>Informaci\u00f3n de la revista:<\/strong> Procedimientos de la Academia Nacional de Ciencias <\/p>\n<p> Proporcionado por la Universidad M\u00e9dica de Carolina del Sur <strong>Cita<\/strong>: Producci\u00f3n de \u00f3xido n\u00edtrico sin esposas: Beta Los complejos -arrestin2 regulan los niveles de NO (4 de junio de 2020) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-06-uncuffing-nitric-oxide-production-beta-arrestin2.html Este documento est\u00e1 sujeto a derechos de autor . Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beta-arrestin2 (verde) se localiza con eNOS (p\u00farpura) en c\u00e9lulas sanas (panel superior); sin embargo, tras la lesi\u00f3n (panel inferior), esta localizaci\u00f3n se pierde. Cr\u00e9dito: Dr. Don Rockey. El h\u00edgado filtra la sangre, desintoxica las sustancias qu\u00edmicas y metaboliza las drogas. La hepatitis, el alcohol y las enfermedades hep\u00e1ticas primarias son fuentes comunes de da\u00f1o en &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/desmantelamiento-de-la-produccion-de-oxido-nitrico-los-complejos-beta-arrestin2-regulan-los-niveles-de-no\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abDesmantelamiento de la producci\u00f3n de \u00f3xido n\u00edtrico: los complejos beta-arrestin2 regulan los niveles de NO\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30435","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30435"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30435\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}