{"id":30465,"date":"2022-08-31T18:19:27","date_gmt":"2022-08-31T23:19:27","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/el-uso-de-benzodiazepinas-antes-de-la-concepcion-se-relaciona-con-un-mayor-riesgo-de-embarazo-ectopico\/"},"modified":"2022-08-31T18:19:27","modified_gmt":"2022-08-31T23:19:27","slug":"el-uso-de-benzodiazepinas-antes-de-la-concepcion-se-relaciona-con-un-mayor-riesgo-de-embarazo-ectopico","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/el-uso-de-benzodiazepinas-antes-de-la-concepcion-se-relaciona-con-un-mayor-riesgo-de-embarazo-ectopico\/","title":{"rendered":"El uso de benzodiazepinas antes de la concepci\u00f3n se relaciona con un mayor riesgo de embarazo ect\u00f3pico"},"content":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain <\/p>\n<p>Las mujeres que usan una clase de tranquilizantes llamados benzodiazepinas antes de quedar embarazadas tienen un mayor riesgo de embarazos ect\u00f3picos, seg\u00fan un estudio de casi 1,7 millones de mujeres. <\/p>\n<p>El estudio, que se publica hoy (mi\u00e9rcoles) en Human Reproduction, una de las principales revistas de medicina reproductiva del mundo, descubri\u00f3 que el riesgo de un embarazo ect\u00f3pico, en el que el embri\u00f3n comienza a desarrollarse fuera del \u00fatero, generalmente en una trompa de Falopio, fue un 50 % mayor en las mujeres que hab\u00edan completado una receta de benzodiazepinas en los 90 d\u00edas anteriores a la concepci\u00f3n.<\/p>\n<p>Los embarazos ect\u00f3picos ocurren en uno o dos por ciento de los embarazos cada a\u00f1o y son una emergencia de salud grave para las mujeres. Son responsables del 6-13% de las muertes relacionadas con el embarazo, y las muertes por hemorragia son la principal causa de muerte relacionada con el embarazo en el primer trimestre del embarazo. Tambi\u00e9n pueden provocar complicaciones graves e infertilidad.<\/p>\n<p>Aunque se sabe que las infecciones p\u00e9lvicas, el uso de tecnolog\u00eda reproductiva, los dispositivos intrauterinos, el tabaquismo y la edad avanzada son factores de riesgo de embarazos ect\u00f3picos, aproximadamente la mitad de las mujeres que tienen embarazo ect\u00f3pico no tienen un factor de riesgo conocido.<\/p>\n<p>Dr. Elizabeth Wall-Wieler, becaria de investigaci\u00f3n postdoctoral en la Facultad de Medicina de la Universidad de Stanford (California, EE. UU.), que dirigi\u00f3 la investigaci\u00f3n, dijo: \u00abLa mayor\u00eda de los estudios que analizan el uso de medicamentos como las benzodiazepinas en el embarazo se centran en el efecto sobre el ni\u00f1o Me interes\u00f3 el impacto que estos medicamentos tienen en la salud de la mujer, y encontr\u00e9 que si bien el uso de medicamentos espec\u00edficos alrededor de la concepci\u00f3n podr\u00eda estar afectando el sistema reproductivo, no hubo investigaciones sobre el uso de medicamentos psicotr\u00f3picos sobre el riesgo de ect\u00f3pico. embarazo. Esto es a pesar del hecho de que se ha encontrado que el uso de benzodiazepinas durante el embarazo est\u00e1 asociado con abortos espont\u00e1neos, resultados adversos en el parto y resultados en el desarrollo infantil\u00bb.<\/p>\n<p>Dr. Wall-Wieler y sus colegas analizaron datos de reclamos de seguros de salud de EE. UU. de 1\u00a0665\u00a0446 embarazos en mujeres de entre 15 y 44 a\u00f1os entre el 1 de noviembre de 2008 y el 30 de septiembre de 2015. De estos, el uno por ciento de las mujeres complet\u00f3 al menos dos recetas de benzodiacepinas por un total de al menos suministro de diez d\u00edas en los 90 d\u00edas previos a la concepci\u00f3n.<\/p>\n<p>Un total de 30,046 (2%) embarazos fueron ect\u00f3picos y 17,990 (1%) fueron de mujeres que ten\u00edan una receta de benzodiacepinas antes de la concepci\u00f3n.<\/p>\n<p>\u00abEsto se traduce en un exceso de 80 embarazos ect\u00f3picos por cada 10,000 embarazos entre las mujeres expuestas a las benzodiazepinas en comparaci\u00f3n con las que no estuvieron expuestas a las benzodiazepinas antes de la concepci\u00f3n\u00bb, dijo la Dra. Wall-Wieler.<\/p>\n<p>Para comprobar si podr\u00eda ya sea el uso de benzodiazepinas o la afecci\u00f3n m\u00e9dica en tratamiento que podr\u00eda estar involucrada en el riesgo de embarazo ect\u00f3pico, los investigadores llevaron a cabo dos an\u00e1lisis separados en mujeres diagnosticadas con ansiedad o insomnio.<\/p>\n<p>\u00abPara cada uno de estos an\u00e1lisis, vimos que th La asociaci\u00f3n no fue tan fuerte como la observada en el grupo como un todo. Esto podr\u00eda significar que la afecci\u00f3n subyacente tambi\u00e9n podr\u00eda ser un factor de riesgo de embarazos ect\u00f3picos, o que hay otros factores que comparten las mujeres con ansiedad o insomnio que tambi\u00e9n son factores de riesgo potenciales de embarazos ect\u00f3picos\u00bb, dijo.<\/p>\n<p>Los investigadores enfatizan que sus hallazgos muestran solo que el uso de benzodiacepinas est\u00e1 asociado con un mayor riesgo de embarazo ect\u00f3pico, no que provoque la afecci\u00f3n.<\/p>\n<p>\u00abPara las mujeres con condiciones de salud espec\u00edficas, como ansiedad o insomnio, las benzodiazepinas pueden ser una parte importante de su tratamiento; sin embargo, se desconoce mucho sobre qu\u00e9 tan seguro es usar estos medicamentos para las mujeres que quedan embarazadas. Este estudio muestra que las mujeres que usan benzodiazepinas cuando quedan embarazadas tienen un mayor riesgo de tener un embarazo ect\u00f3pico. Al identificar las opciones de tratamiento, las mujeres y sus proveedores de atenci\u00f3n deben comprender los beneficios y los riesgos asociados con las opciones de tratamiento, y deben estar disponibles m\u00e1s opciones que se haya demostrado que son seguras antes y durante el embarazo\u00bb, dijo la Dra. Wall-Wieler.<\/p>\n<p>La coautora, la Dra. Thalia Robakis, profesora asociada de psiquiatr\u00eda en la Escuela de Medicina Icahn en Mount Sinai (Nueva York, EE. UU.), dijo: \u00abCasi siempre es prematuro sacar conclusiones firmes de un un solo estudio observacional y se necesita llevar a cabo m\u00e1s investigaci\u00f3n. Sin embargo, es una intervenci\u00f3n de riesgo relativamente bajo recomendar el cese supervisado y gradual del uso de benzodiazepinas antes de suspender la anticoncepci\u00f3n, siempre que esto se pueda hacer de manera segura y adecuada bajo la supervisi\u00f3n de un m\u00e9dico. El potencial de impacto positivo es alto si se puede evitar incluso una peque\u00f1a cantidad de embarazos ect\u00f3picos\u00bb.<\/p>\n<p>Los investigadores sugieren que los proveedores de atenci\u00f3n m\u00e9dica podr\u00edan considerar realizar una ecograf\u00eda p\u00e9lvica temprana para las mujeres que han usado benzodiazepinas antes de la concepci\u00f3n, particularmente si tienen otros factores de riesgo para la afecci\u00f3n. Sin embargo, muchas mujeres no saben que tienen un embarazo ect\u00f3pico hasta que comienzan a experimentar dolor u otras complicaciones.<\/p>\n<p>Coautora, Dra. Deirdre Lyell, profesora de obstetricia y ginecolog\u00eda de la Facultad de Medicina de la Universidad de Stanford, dijo: \u00abPara las mujeres que usan benzodiazepinas, es importante que los proveedores sean conscientes del aumento potencialmente peque\u00f1o del riesgo de embarazo ect\u00f3pico, y se debe asesorar a las mujeres sobre los posibles s\u00edntomas del embarazo ect\u00f3pico, como la mancha temprana de sangre y dolor abdominal bajo. Los an\u00e1lisis de sangre tempranos de ultrasonido y hormonas del embarazo pueden ayudar a identificar si un embarazo es ect\u00f3pico o no\u00bb.<\/p>\n<p>Las limitaciones del estudio incluyen el hecho de que los investigadores se basaron en datos de prescripci\u00f3n de pacientes ambulatorios para identificar el uso de benzodiacepinas antes de la concepci\u00f3n, lo que podr\u00eda dar lugar a una sobreestimaci\u00f3n o subestimaci\u00f3n del consumo real de la droga. Tambi\u00e9n se basaron en datos de reclamaciones de seguros de salud de EE. UU. para identificar embarazos y fechas de concepci\u00f3n, lo que podr\u00eda dar lugar a una clasificaci\u00f3n err\u00f3nea de los resultados del embarazo y la duraci\u00f3n de la gestaci\u00f3n.<\/p>\n<p>Las benzodiazepinas incluyen alprazolam, clordiazep\u00f3xido, clobazam, clonazepam, clorazepato, diazepam, estazolam, flurazepam, lorazepam, oxazepam, quazepam, temazepam y triazolam. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Un medicamento contra el c\u00e1ncer de pulm\u00f3n podr\u00eda ayudar en la dif\u00edcil situaci\u00f3n del embarazo ect\u00f3pico pacientes <strong>M\u00e1s informaci\u00f3n:<\/strong> Elizabeth Wall-Wieler et al, Uso de benzodiazepinas antes de la concepci\u00f3n y riesgo de embarazo ect\u00f3pico, Reproducci\u00f3n humana (2020). DOI: 10.1093\/humrep\/d eaa082 <strong>Informaci\u00f3n de la revista:<\/strong> Reproducci\u00f3n humana <\/p>\n<p> Proporcionada por la Sociedad Europea de Reproducci\u00f3n Humana y Embriolog\u00eda <strong>Cita<\/strong>: El uso de benzodiacepinas antes de la concepci\u00f3n est\u00e1 relacionado con un mayor riesgo de embarazo ect\u00f3pico (2020, 3 de junio) recuperado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-06-benzodiazepine-conception-linked-ectopic-pregnancy.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: CC0 Public Domain Las mujeres que usan una clase de tranquilizantes llamados benzodiazepinas antes de quedar embarazadas tienen un mayor riesgo de embarazos ect\u00f3picos, seg\u00fan un estudio de casi 1,7 millones de mujeres. El estudio, que se publica hoy (mi\u00e9rcoles) en Human Reproduction, una de las principales revistas de medicina reproductiva del mundo, descubri\u00f3 &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/el-uso-de-benzodiazepinas-antes-de-la-concepcion-se-relaciona-con-un-mayor-riesgo-de-embarazo-ectopico\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl uso de benzodiazepinas antes de la concepci\u00f3n se relaciona con un mayor riesgo de embarazo ect\u00f3pico\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30465","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30465"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30465\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}