{"id":30471,"date":"2022-08-31T18:19:46","date_gmt":"2022-08-31T23:19:46","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/como-usar-la-bascula-de-bano-para-encontrar-la-estrategia-adecuada-para-perder-peso\/"},"modified":"2022-08-31T18:19:46","modified_gmt":"2022-08-31T23:19:46","slug":"como-usar-la-bascula-de-bano-para-encontrar-la-estrategia-adecuada-para-perder-peso","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/como-usar-la-bascula-de-bano-para-encontrar-la-estrategia-adecuada-para-perder-peso\/","title":{"rendered":"C\u00f3mo usar la b\u00e1scula de ba\u00f1o para encontrar la estrategia adecuada para perder peso"},"content":{"rendered":"<p>Cr\u00e9dito: Africa Studio\/Shutterstock <\/p>\n<p>Las personas que se pesan regularmente tienen m\u00e1s \u00e9xito para perder peso y no recuperarlo. Pero pararse en una b\u00e1scula, en s\u00ed mismo, no ayuda a las personas a perder peso m\u00e1gicamente. M\u00e1s bien, pararse en una b\u00e1scula de ba\u00f1o todos los d\u00edas puede alentar a algunas personas a pensar en sus h\u00e1bitos alimenticios y de ejercicio, planificar formas de perder peso y ayudarlos a resistir la tentaci\u00f3n. En otras palabras, la b\u00e1scula de ba\u00f1o podr\u00eda ayudar a las personas a autorregularse. <\/p>\n<p>Para averiguar si esto es cierto, les pedimos a 24 personas que registraran sus pensamientos durante el pesaje diario durante ocho semanas. Descubrimos que la mayor\u00eda de las personas no usaban la autorregulaci\u00f3n, pero las que s\u00ed lo hac\u00edan ten\u00edan m\u00e1s probabilidades de perder peso. Esto nos llev\u00f3 a preguntarnos si podr\u00edamos ense\u00f1ar a las personas habilidades de autorregulaci\u00f3n para que el pesaje sea m\u00e1s \u00fatil.<\/p>\n<p>Desarrollamos un programa llamado PREVAIL que tiene como objetivo guiar a las personas que quieren perder peso a trav\u00e9s del proceso de autorregulaci\u00f3n. . Los participantes recibieron instrucciones de pesarse diariamente y registrarlo en una aplicaci\u00f3n. Desarrollamos una lista de 53 acciones para perder peso, como comer solo vegetales, eliminar el alcohol o caminar 10,000 pasos. Les pedimos a las personas que probaran todas las acciones que consideraban relevantes para ellos y que usaran su cambio de peso a lo largo del tiempo para aprender qu\u00e9 comportamientos funcionaron. <\/p>\n<p>Les pedimos que hicieran esto en funci\u00f3n de sus tendencias de peso semanales, ya que el peso puede cambiar de un d\u00eda para otro por motivos que no est\u00e1n relacionados con la p\u00e9rdida o el aumento de grasa. Luego alentamos a las personas a continuar con las estrategias que funcionaron bien para ellos, construyendo su conjunto personal de herramientas efectivas para perder peso. <\/p>\n<p>Probamos este programa en un ensayo controlado aleatorio de ocho semanas con 100 personas. Los participantes fueron asignados aleatoriamente a uno de dos grupos. La mitad de los participantes sigui\u00f3 el programa PREVAIL y la otra mitad recibi\u00f3 instrucciones de pesarse sin m\u00e1s apoyo (el grupo de control). <\/p>\n<p>Media piedra<\/p>\n<p>Las personas que utilizaron el programa PREVAIL perdieron en promedio 3,2 kg (media piedra) m\u00e1s que las personas del grupo de control. Los comentarios que recibimos de los participantes que siguieron el programa PREVAIL fueron abrumadoramente positivos, y muchos dijeron que el programa les permiti\u00f3 tomar el control de su p\u00e9rdida de peso y manejar su peso de manera flexible junto con sus vidas ocupadas. <\/p>\n<p>Nos sorprendi\u00f3 mucho la cantidad de peso que las personas perdieron porque ninguna de las 53 estrategias de p\u00e9rdida de peso que se nos ocurrieron fue revolucionaria, y cada una probablemente habr\u00eda tenido solo un efecto modesto. Al combinar estas acciones y ponerlas en contexto con los datos de peso, las personas pudieron obtener informaci\u00f3n sobre c\u00f3mo su dieta y actividad f\u00edsica afectaban su peso. El proceso de autorregulaci\u00f3n y experimentaci\u00f3n les permiti\u00f3 desarrollar su propio plan de p\u00e9rdida de peso altamente personalizado. <\/p>\n<p>Algunas personas experimentan emociones negativas cuando se pesan. Esper\u00e1bamos que guiar a las personas a trav\u00e9s de un proceso para ayudarlos a hacer uso de sus medidas de peso los ayudar\u00eda a superar esto. Las respuestas de los participantes mostraron que, de hecho, pod\u00edan usar el pesaje diario de manera positiva, como retroalimentaci\u00f3n constructiva. Si algo no funcionaba, pod\u00edan pasar a una estrategia diferente en lugar de frustrarse por la falta de progreso. Parec\u00eda que nuestros participantes encontraron una manera de usar sus b\u00e1sculas como una herramienta \u00fatil para alcanzar sus objetivos.<\/p>\n<p>Nuestro ensayo mostr\u00f3 resultados prometedores durante las primeras ocho semanas, pero a menudo lleva un poco m\u00e1s de tiempo. para que las personas alcancen su peso ideal. Adem\u00e1s, las personas pueden tener dificultades para mantener el peso despu\u00e9s de perderlo. Esperamos probar este programa en una prueba m\u00e1s grande y m\u00e1s larga, para ver c\u00f3mo les va a las personas a largo plazo.<\/p>\n<p>Mientras tanto, dado que a muchas personas les resulta dif\u00edcil controlar su peso durante el encierro, nuestra lista de las acciones de p\u00e9rdida de peso pueden ser \u00fatiles. Usted puede encontrarlos aqu\u00ed. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Health Check: \u00bfdeber\u00eda pesarse regularmente? Proporcionado por The Conversation <\/p>\n<p> Este art\u00edculo se vuelve a publicar de The Conversation bajo una licencia Creative Commons. Lea el art\u00edculo original. <\/p>\n<p> <strong>Cita<\/strong>: C\u00f3mo usar su b\u00e1scula de ba\u00f1o para encontrar la estrategia de p\u00e9rdida de peso adecuada (3 de junio de 2020) consultado el 31 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2020-06- bathroom-scaleto-weight-loss-strategy.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Africa Studio\/Shutterstock Las personas que se pesan regularmente tienen m\u00e1s \u00e9xito para perder peso y no recuperarlo. Pero pararse en una b\u00e1scula, en s\u00ed mismo, no ayuda a las personas a perder peso m\u00e1gicamente. M\u00e1s bien, pararse en una b\u00e1scula de ba\u00f1o todos los d\u00edas puede alentar a algunas personas a pensar en sus &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/como-usar-la-bascula-de-bano-para-encontrar-la-estrategia-adecuada-para-perder-peso\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abC\u00f3mo usar la b\u00e1scula de ba\u00f1o para encontrar la estrategia adecuada para perder peso\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30471","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=30471"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/30471\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=30471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=30471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=30471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}