{"id":7571,"date":"2022-08-30T02:26:14","date_gmt":"2022-08-30T07:26:14","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/los-antropologos-estudian-la-energia-de-las-estrategias-de-subsistencia-exclusivamente-humanas\/"},"modified":"2022-08-30T02:26:14","modified_gmt":"2022-08-30T07:26:14","slug":"los-antropologos-estudian-la-energia-de-las-estrategias-de-subsistencia-exclusivamente-humanas","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/los-antropologos-estudian-la-energia-de-las-estrategias-de-subsistencia-exclusivamente-humanas\/","title":{"rendered":"Los antrop\u00f3logos estudian la energ\u00eda de las estrategias de subsistencia exclusivamente humanas"},"content":{"rendered":"<p>Una mujer Tsimane cosecha arroz en su campo. Cr\u00e9dito: Michael Gurven <\/p>\n<p>Entre nuestros parientes vivos m\u00e1s cercanos, los grandes simios, los humanos somos \u00fanicos: tenemos cerebros m\u00e1s grandes, nos reproducimos m\u00e1s r\u00e1pidamente y tenemos vidas m\u00e1s largas. Estos rasgos son obviamente valiosos, pero la energ\u00eda adicional requerida para mantenerlos es bastante significativa. Entonces, \u00bfc\u00f3mo logramos pagarlos? <\/p>\n<p>Un grupo de antrop\u00f3logos de la Universidad de California en Santa B\u00e1rbara, la Universidad de Utah y la Universidad de Duke se unieron en un estudio de investigaci\u00f3n para comprender las estrategias que desarrollaron los humanos para obtener esa energ\u00eda adicional. Sus hallazgos se publican en la edici\u00f3n actual de Science.<\/p>\n<p>El \u00e9xito evolutivo est\u00e1 determinado en gran medida por la medida en que un organismo es eficaz para extraer energ\u00eda (es decir, calor\u00edas) del medio ambiente y convertir esa energ\u00eda en descendencia. Pero la adquisici\u00f3n de energ\u00eda est\u00e1 limitada por una serie de factores, siendo el principal la cantidad de tiempo y energ\u00eda que uno puede gastar en la b\u00fasqueda de alimentos. Los presupuestos de energ\u00eda representan el equilibrio entre la ingesta y el gasto de energ\u00eda que todos los organismos deben navegar para sobrevivir y reproducirse.<\/p>\n<p>\u00abDebido a que la energ\u00eda es una moneda tan fundamental, la evoluci\u00f3n ha producido muchas adaptaciones asombrosas de ahorro de energ\u00eda en todo el \u00c1rbol de la vida\u00bb, dijo Thomas Kraft, autor principal del art\u00edculo. Actualmente profesor asistente en la Universidad de Utah, Kraft realiz\u00f3 la investigaci\u00f3n mientras era estudiante de posdoctorado con Michael Gurven, autor principal y profesor de antropolog\u00eda en UC Santa Barbara. \u00abPero eso no significa que la selecci\u00f3n natural siempre favorezca la reducci\u00f3n del gasto de energ\u00eda. De hecho, existe una tremenda variaci\u00f3n en el &#8216;tempo&#8217; de las estrategias energ\u00e9ticas. Un ejemplo dram\u00e1tico es la diferencia entre endot\u00e9rmico (sangre caliente) y ectot\u00e9rmico (sangre fr\u00eda) Los animales de sangre caliente tienden a usar mucha m\u00e1s energ\u00eda cada d\u00eda, pero son capaces de canalizar con \u00e9xito esa energ\u00eda en actividades que finalmente conducen a una reproducci\u00f3n exitosa\u00bb.<\/p>\n<p>Los investigadores comenzaron comparando la cantidad de energ\u00eda y tiempo que los humanos y otros grandes simios dedican a obtener todos los alimentos que normalmente incluyen en sus dietas. \u00abEstudiamos las sociedades de subsistencia contempor\u00e1neas de cazadores-recolectores y agricultores para examinar los tipos de estrategias energ\u00e9ticas que han existido durante milenios, incluidas las posteriores al advenimiento de la domesticaci\u00f3n de plantas\u00bb, dijo Kraft.<\/p>\n<p>El equipo de Los cient\u00edficos se basaron especialmente en su experiencia colectiva a largo plazo trabajando con los hadza, un grupo ind\u00edgena de recolectores en el noroeste de Tanzania, y los tsimane, un grupo ind\u00edgena de horticultores en la Amazon\u00eda boliviana.<\/p>\n<p>En comparaci\u00f3n con los chimpanc\u00e9s, los gorilas y los orangutanes, los cazadores-recolectores humanos no son particularmente eficientes en la adquisici\u00f3n de alimentos. \u00abResulta que gastamos una cantidad sorprendente de energ\u00eda en conseguir comida porque caminamos distancias muy largas y participamos en actividades intensas como cavar tub\u00e9rculos o talar \u00e1rboles\u00bb, explic\u00f3 Kraft. \u00abOtros grandes simios, por el contrario, no necesitan ir muy lejos todos los d\u00edas. La mayor parte de sus compras de alimentos consisten en recoger frutas y vegetaci\u00f3n tranquilamente\u00bb.<\/p>\n<p>Sin embargo, los humanos se benefician al ganar mucha m\u00e1s comida. energ\u00eda por hora. Mientras que otros grandes simios no cocinan sus alimentos y pasan cantidades exorbitantes de tiempo masticando y digiriendo, las actividades de subsistencia de alta intensidad de los humanos producen muchas calor\u00edas r\u00e1pidamente.<\/p>\n<p>\u00abEsto es como decir que a pesar de la intensidad de el trabajo, los humanos ganan un &#8216;salario&#8217; energ\u00e9tico mucho m\u00e1s alto que otros simios\u00bb, dijo Kraft. \u00abEsta capacidad de lograr una mayor tasa de retorno es lo que hace que los cazadores-recolectores sean tan exitosos\u00bb. Agregue la agricultura a la mezcla y esa tasa de retorno o &#8216;salario&#8217; solo aumenta. \u00abAquellos que mezclan la agricultura con la recolecci\u00f3n duplican o triplican lo que ganan los cazadores-recolectores\u00bb, continu\u00f3 Kraft. Pero las estrategias humanas de alto rendimiento, que implican gastar mucha energ\u00eda para obtener m\u00e1s alimentos m\u00e1s r\u00e1pido, tambi\u00e9n pueden ser bastante riesgosas si no obtiene alimentos en un d\u00eda determinado. \u00abSin embargo, los humanos parecen ser los \u00fanicos capaces de superar esto cooperando, compartiendo y almacenando alimentos para evitar peligrosas carencias\u00bb.<\/p>\n<p>Tal cooperaci\u00f3n tambi\u00e9n tiene otros beneficios. Ser capaz de cumplir con el requerimiento diario de alimentos en menos tiempo habr\u00eda brindado m\u00e1s oportunidades para otros esfuerzos. \u00abDesarrollar la rica vida social y cultural, tan com\u00fan en todas las sociedades humanas, primero puede haber requerido estrategias eficientes en el tiempo para alimentarse\u00bb, dijo Gurven, quien tambi\u00e9n es director de la Unidad de Ciencias Antropol\u00f3gicas Integrativas de UC Santa Barbara y codirector de Tsimane. Proyecto de Historia de Vida y Salud.<\/p>\n<p>Sin embargo, se\u00f1al\u00f3, tambi\u00e9n puede desviarnos, contribuyendo a problemas de salud como la actual epidemia de obesidad. \u00abParte de lo que nos hace a los humanos tan exitosos es ser realmente buenos para descubrir c\u00f3mo obtener el mayor rendimiento con el menor esfuerzo\u00bb, dijo Gurven. \u00abPuedes ver a d\u00f3nde nos lleva eso hoy en d\u00eda conduciendo autom\u00f3viles o tomando un autob\u00fas al Costco local para comprar esos sabrosos pollos rostizados de $ 4.99. Hemos reemplazado nuestro trabajo f\u00edsico en la caza o la agricultura con cadenas de suministro. Si evolucionamos para obtener calor\u00edas a bajo costo, entonces la necesidad de comer menos o moverse m\u00e1s puede ser una lucha por una buena raz\u00f3n\u00bb.<\/p>\n<p>Por otro lado, continu\u00f3, los hallazgos de la investigaci\u00f3n sugieren que los humanos tambi\u00e9n evolucionaron para ser muy activos f\u00edsicamente, al menos para obtener alimentos. . \u00abEsto no significa que debamos estar en\u00e9rgicamente activos todo el tiempo\u00bb, dijo. \u00abLa lecci\u00f3n de las poblaciones de subsistencia es, en cambio, ser menos sedentarios\u00bb.<\/p>\n<p>Un hallazgo del estudio que sorprendi\u00f3 a los investigadores involucr\u00f3 los altos costos energ\u00e9ticos de las estrategias de subsistencia humana. Caminar en forma erguida\/b\u00edpeda hace que los humanos se muevan m\u00e1s eficientemente que los otros grandes simios, y usamos herramientas sofisticadas para hacer que las tareas sean m\u00e1s f\u00e1ciles de realizar. Sin embargo, los humanos (tanto cazadores-recolectores como agricultores) en realidad gastan m\u00e1s energ\u00eda por d\u00eda en actividades relacionadas con la adquisici\u00f3n de alimentos que los chimpanc\u00e9s, los gorilas y los orangutanes. Esto hace que nuestras estrategias de subsistencia no sean muy eficientes en general.<\/p>\n<p>La antropolog\u00eda tiene una larga tradici\u00f3n de recopilar datos sobre los flujos de energ\u00eda en diferentes tipos de sociedades, p. cazadores-recolectores, horticultores, pastores. Los investigadores compilaron estos datos dispares en una sola base de datos para poder preguntar si los datos detallados que ten\u00edan de Hadza y Tsimane eran representativos de patrones m\u00e1s amplios en la energ\u00eda de subsistencia en todas las sociedades. Y lo fueron, pero tambi\u00e9n surgieron otras sorpresas de este ejercicio.<\/p>\n<p>\u00abNo esper\u00e1bamos que nuestra base de datos transcultural revelara una diferencia m\u00ednima en la cantidad de tiempo dedicado a trabajar entre cazadores-recolectores y poblaciones agr\u00edcolas\u00bb, continu\u00f3. Como lo ejemplifica el libro reciente de James Suzman, \u00abTrabajo: una historia profunda desde la edad de piedra hasta la era de los robots\u00bb, muchos antrop\u00f3logos han argumentado durante mucho tiempo que los cazadores-recolectores pasan muy poco tiempo trabajando en comparaci\u00f3n con otras sociedades humanas. Despu\u00e9s de compilar una lista exhaustiva de estudios, los investigadores no encontraron evidencia para respaldar la idea de que los agricultores de subsistencia contempor\u00e1neos pasan m\u00e1s tiempo trabajando en promedio que los cazadores-recolectores.<\/p>\n<p>\u00abEsperamos que tener toda esta nueva informaci\u00f3n en un place nos ayudar\u00e1 a comprender la relaci\u00f3n fundamental que los humanos tienen con la energ\u00eda. La forma en que obtenemos y gastamos la energ\u00eda se encuentra en el coraz\u00f3n de lo que nos hace humanos y de muchos de los problemas ambientales y de salud que enfrentamos hoy en d\u00eda\u00bb, explic\u00f3 Kraft. \u00abSer\u00eda prudente no olvidar nuestro legado evolutivo a medida que abordamos estos problemas\u00bb. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> Los primeros humanos ganaron presupuesto de energ\u00eda aumentando la tasa de adquisici\u00f3n de energ\u00eda, no adaptando el ahorro de energ\u00eda. , Ciencia (2021). DOI: 10.1126\/science.abf0130 <strong>Informaci\u00f3n de la revista:<\/strong> Science <\/p>\n<p> Proporcionado por la Universidad de California &#8211; Santa B\u00e1rbara <strong>Cita<\/strong>: Los antrop\u00f3logos estudian la energ\u00eda de las estrategias de subsistencia exclusivamente humanas (2022 , 3 de enero) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-01-anthropologists-energetics-uniquely-human-subsistence.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una mujer Tsimane cosecha arroz en su campo. Cr\u00e9dito: Michael Gurven Entre nuestros parientes vivos m\u00e1s cercanos, los grandes simios, los humanos somos \u00fanicos: tenemos cerebros m\u00e1s grandes, nos reproducimos m\u00e1s r\u00e1pidamente y tenemos vidas m\u00e1s largas. Estos rasgos son obviamente valiosos, pero la energ\u00eda adicional requerida para mantenerlos es bastante significativa. Entonces, \u00bfc\u00f3mo logramos &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/los-antropologos-estudian-la-energia-de-las-estrategias-de-subsistencia-exclusivamente-humanas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLos antrop\u00f3logos estudian la energ\u00eda de las estrategias de subsistencia exclusivamente humanas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7571","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7571"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7571\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}