{"id":7580,"date":"2022-08-30T02:26:29","date_gmt":"2022-08-30T07:26:29","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/hong-kong-afectado-por-el-virus-esta-considerando-el-confinamiento-jefe-de-salud\/"},"modified":"2022-08-30T02:26:29","modified_gmt":"2022-08-30T07:26:29","slug":"hong-kong-afectado-por-el-virus-esta-considerando-el-confinamiento-jefe-de-salud","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/hong-kong-afectado-por-el-virus-esta-considerando-el-confinamiento-jefe-de-salud\/","title":{"rendered":"Hong Kong afectado por el virus est\u00e1 considerando el confinamiento: jefe de salud"},"content":{"rendered":"<p>Cr\u00e9dito: CC0 Dominio p\u00fablico <\/p>\n<p>Hong Kong puede imponer un confinamiento estricto al estilo de China que confina a las personas en sus hogares, se\u00f1alaron las autoridades el lunes, con la estrategia cero-COVID de la ciudad en andrajos y cuerpos amontonados en los hospitales. <\/p>\n<p>Dos a\u00f1os de estrictas pol\u00edticas de cero-COVID mantuvieron en gran medida a raya al coronavirus, pero un avance de la variante Omicron altamente transmisible expuso lo poco que hab\u00edan hecho las autoridades para prepararse para un brote masivo.<\/p>\n<p>La l\u00edder de Hong Kong, Carrie Lam previamente descart\u00f3 un confinamiento en toda la ciudad y, en cambio, orden\u00f3 que los 7,4 millones de residentes se hicieran la prueba en marzo.<\/p>\n<p>Pero en un cambio de sentido, la secretaria de salud, Sophia Chan, confirm\u00f3 el lunes que todav\u00eda era una opci\u00f3n.<\/p>\n<p> p&gt; <\/p>\n<p>Cuando un presentador de Commercial Radio le pregunt\u00f3 si a\u00fan se descartaba un confinamiento, respondi\u00f3: \u00abNo. Todav\u00eda estamos discutiendo\u00bb.<\/p>\n<p>\u00abDesde una perspectiva de salud p\u00fablica, para sacar lo mejor Como efecto de las pruebas universales obligatorias, necesitamos reducir los movimientos de las personas hasta cierto punto\u00bb, agreg\u00f3.<\/p>\n<p>Los comentarios de Chan se produjeron un d\u00eda despu\u00e9s de que Li Dachuan, un alto funcionario del continente involucrado en un grupo de trabajo conjunto con las autoridades de Hong Kong, describi\u00f3 un bloqueo como \u00abel mejor y m\u00e1s ideal enfoque para lograr el mejor efecto de prueba universal ts\u00bb.<\/p>\n<p>La revelaci\u00f3n agrega nueva incertidumbre y ansiedad para los residentes y las empresas en una ciudad atrapada por el tipo de caos que era m\u00e1s familiar al comienzo de la pandemia. <\/p>\n<p>Hong Kong anunci\u00f3 26.000 nuevas infecciones y 83 muertes solo el domingo. Antes de la ola actual, la ciudad hab\u00eda registrado solo 12\u00a0000 casos desde el comienzo de la pandemia.<\/p>\n<p>Los hospitales han estado al l\u00edmite durante semanas y el domingo las autoridades revelaron que los cuerpos se acumulan en los hospitales porque las morgues est\u00e1n llenas. .<\/p>\n<p>\u00abEn este momento, enfrentamos un problema de transporte de cad\u00e1veres del hospital a la morgue p\u00fablica\u00bb, dijo a los periodistas el gerente jefe de la Autoridad Hospitalaria, Lau Ka-hin.<\/p>\n<p>\u00abEs por eso que hay algunos cuerpos que inicialmente se plane\u00f3 transportar a la morgue p\u00fablica, pero permanecieron en el hospital\u00bb.<\/p>\n<p>Alta tasa de mortalidad<\/p>\n<p>La tasa de mortalidad promedio de siete d\u00edas de Hong Kong est\u00e1 actualmente en alrededor de ocho por mill\u00f3n de personas. <\/p>\n<p>Eso se compara con cinco por mill\u00f3n para los Estados Unidos, 1,80 para Gran Breta\u00f1a y 1,36 para Singapur que, al igual que Hong Kong, inicialmente opt\u00f3 por cero-COVID pero cambi\u00f3 m\u00e1s recientemente a una estrategia de mitigaci\u00f3n y reapertura a un mayor mundo.<\/p>\n<p>El domingo, los funcionarios revelaron que el 91 por ciento de los que han muerto en la ola actual no estaban completamente vacunados. <\/p>\n<p>La gran mayor\u00eda de los muertos son ancianos y el virus est\u00e1 arrasando los hogares de ancianos en la ciudad densamente poblada.<\/p>\n<p>A pesar de los amplios suministros, Hong Kong ten\u00eda bajas tasas de vacunaci\u00f3n entre los mayores de 70 a\u00f1os antes de Omicron golpe\u00f3.<\/p>\n<p>China ahora est\u00e1 tomando cada vez m\u00e1s la \u00faltima palabra en la respuesta de Hong Kong con el grupo de trabajo conjunto que opera desde la ciudad vecina de Shenzhen.<\/p>\n<p>Los equipos del continente est\u00e1n trabajando en la construcci\u00f3n de una serie de hospitales y salas de aislamiento para los infectados, aunque el n\u00famero de casos actual supera con creces la oferta.<\/p>\n<p>Entre los que asesoran al gobierno se encuentra Liang Wannian, un alto funcionario de China continental que el South China Morning Post inform\u00f3 que llegaba a Hong Kong el lunes. .<\/p>\n<p>Liang fue un arquitecto clave del exitoso cierre de dos meses en Wuhan, donde surgi\u00f3 el coronavirus por primera vez, una estrategia que China ha seguido implementando en otras ciudades tan pronto como se detectan casos.<\/p>\n<p>Pero el peaje oficial de Wuhan fue de solo 53\u00a0000 casos, una fracci\u00f3n de t El n\u00famero de casos en Hong Kong, que tambi\u00e9n est\u00e1 luchando contra una variante mucho m\u00e1s infecciosa. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> El l\u00edder de Hong Kong dice que la ciudad est\u00e1 &#8216;abrumada&#8217; por la ola de Omicron , 28 de febrero) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02-virus-hit-hong-kong-lockdown-health.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: CC0 Dominio p\u00fablico Hong Kong puede imponer un confinamiento estricto al estilo de China que confina a las personas en sus hogares, se\u00f1alaron las autoridades el lunes, con la estrategia cero-COVID de la ciudad en andrajos y cuerpos amontonados en los hospitales. Dos a\u00f1os de estrictas pol\u00edticas de cero-COVID mantuvieron en gran medida a &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/hong-kong-afectado-por-el-virus-esta-considerando-el-confinamiento-jefe-de-salud\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abHong Kong afectado por el virus est\u00e1 considerando el confinamiento: jefe de salud\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7580","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7580"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7580\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}