{"id":7591,"date":"2022-08-30T02:26:50","date_gmt":"2022-08-30T07:26:50","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/experto-explica-el-enfoque-cambiante-de-los-problemas-cardiacos-en-los-atletas\/"},"modified":"2022-08-30T02:26:50","modified_gmt":"2022-08-30T07:26:50","slug":"experto-explica-el-enfoque-cambiante-de-los-problemas-cardiacos-en-los-atletas","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/experto-explica-el-enfoque-cambiante-de-los-problemas-cardiacos-en-los-atletas\/","title":{"rendered":"Experto explica el enfoque cambiante de los problemas card\u00edacos en los atletas"},"content":{"rendered":"<p>Cr\u00e9dito: Pixabay\/CC0 Dominio p\u00fablico <\/p>\n<p>Las afecciones card\u00edacas pueden poner fin al juego o incluso poner en peligro la vida de los atletas competitivos y recreativos por igual, pero los m\u00e9dicos se est\u00e1n dando cuenta de que, en muchos casos, los problemas card\u00edacos se pueden manejar para ayudar a los pacientes a continuar con los deportes. Elijah Behr, MD, cardi\u00f3logo de Mayo Clinic Healthcare en Londres, explica la tendencia de mantener en el juego a los atletas con problemas card\u00edacos. <\/p>\n<p>Una importante investigaci\u00f3n ha evaluado los riesgos reales de paro card\u00edaco en atletas j\u00f3venes con afecciones card\u00edacas, dice el Dr. Behr. Eso incluye descubrimientos en Mayo Clinic sobre el s\u00edndrome de QT prolongado, un trastorno del ritmo card\u00edaco que puede causar latidos card\u00edacos r\u00e1pidos y ca\u00f3ticos.<\/p>\n<p>\u00abExiste una tendencia a permitir m\u00e1s ejercicio a los pacientes que reciben un buen tratamiento para su afecci\u00f3n\u00bb. dice el Dr. Behr. \u00abEste tiene que ser un enfoque personalizado que aborde al paciente de una manera hol\u00edstica utilizando la experiencia de especialistas y puede involucrar a su club deportivo, escuela o universidad para garantizar el camino m\u00e1s seguro a seguir\u00bb.<\/p>\n<p>Un dispositivo que puede ayudar a los atletas volver a jugar despu\u00e9s de un paro card\u00edaco es un desfibrilador autom\u00e1tico implantable. Puede tomar lecturas electr\u00f3nicas del coraz\u00f3n y determinar si se est\u00e1 produciendo un problema de ritmo que amenaza la vida, y luego administrar una descarga el\u00e9ctrica para que el ritmo card\u00edaco vuelva a la normalidad, explica el Dr. Behr. En general, los dispositivos son muy efectivos para salvar vidas cuando ocurre un paro card\u00edaco, dice.<\/p>\n<p>El paro card\u00edaco a menudo es causado por una afecci\u00f3n card\u00edaca subyacente que puede dejar cicatrices en el coraz\u00f3n, predisponi\u00e9ndolo a un problema de ritmo que causa un paro card\u00edaco, dice el Dr. Behr.<\/p>\n<p>\u00abEs muy inusual que un paro card\u00edaco en s\u00ed mismo cause m\u00e1s da\u00f1o al coraz\u00f3n que el que tiene la afecci\u00f3n card\u00edaca subyacente. Tambi\u00e9n hay algunas afecciones que son principalmente el\u00e9ctricas y no est\u00e1 asociado con ning\u00fan da\u00f1o al m\u00fasculo card\u00edaco en s\u00ed mismo\u00bb, dice el Dr. Behr. \u00abEs posible, si solo ha habido un da\u00f1o menor en el coraz\u00f3n o ning\u00fan da\u00f1o, que un atleta regrese a su funcionamiento y rendimiento normales. Depende mucho de la condici\u00f3n y su gravedad\u00bb.<\/p>\n<p>La investigaci\u00f3n sobre la muerte s\u00fabita en deportistas j\u00f3venes y no deportistas ha sugerido que la muerte s\u00fabita puede ser el doble de frecuente en los deportistas; se cree que esto se debe al efecto del esfuerzo extremo en personas con afecciones card\u00edacas subyacentes, como la miocardiopat\u00eda, una enfermedad del m\u00fasculo card\u00edaco, dice el Dr. Behr. Todav\u00eda es raro, agrega, se\u00f1alando que la mayor\u00eda de las muertes card\u00edacas s\u00fabitas no ocurren durante la pr\u00e1ctica de deportes.<\/p>\n<p>En general, los atletas mayores que han realizado ejercicios de resistencia o de alta intensidad durante muchos a\u00f1os tienden a tener m\u00e1s ritmo y problemas de las arterias coronarias que los no atletas de edad similar, dice el Dr. Behr.<\/p>\n<p>\u00abCreemos que esto puede ser el efecto de la tensi\u00f3n excesiva en el coraz\u00f3n debido a per\u00edodos intermitentes de presi\u00f3n arterial alta y frecuencia card\u00edaca alta. Esto a\u00fan no se comprende bien y es necesario realizar m\u00e1s investigaciones\u00bb, dice el Dr. Behr. \u00abHay un beneficio general significativo del ejercicio en t\u00e9rminos de calidad de vida y longevidad que probablemente supera cualquier riesgo de problemas card\u00edacos\u00bb.<\/p>\n<p>Si el ejercicio empeora una afecci\u00f3n card\u00edaca o incluso aumenta el riesgo de paro card\u00edaco, los cardi\u00f3logos puede trabajar con los atletas para moderar la intensidad y la duraci\u00f3n de la actividad, dice el Dr. Behr. Para limitar la intensidad del ejercicio, se pueden usar medicamentos y monitoreo de la frecuencia card\u00edaca para lograr una frecuencia card\u00edaca m\u00e1s baja.<\/p>\n<p>Esas limitaciones pueden resultar demasiado para los atletas competitivos y pueden requerir que cambien de deporte si as\u00ed lo desean. seguir compitiendo. Pasar de ejercicios m\u00e1s exigentes y din\u00e1micos a deportes menos desafiantes puede ser la \u00fanica manera de equilibrar las necesidades psicol\u00f3gicas de los pacientes con los riesgos de sus condiciones, dice.<\/p>\n<p>\u00abEn general, los deportes son algo bueno y el ejercicio es saludable para el cuerpo y la mente. Debemos evitar restringir a los pacientes innecesariamente y, en cambio, lograr el equilibrio adecuado para ellos\u00bb, dice el Dr. Behr. \u00abEs m\u00e1s probable que cumplan con sus planes de tratamiento y que les vaya bien en general\u00bb. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> \u00bfDeben hacer ejercicio las personas con enfermedades card\u00edacas? Proporcionado por Mayo Clinic <strong>Cita<\/strong>: El experto explica el enfoque cambiante de los problemas card\u00edacos en los atletas (28 de febrero de 2022) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02-expert-approach -heart-issues-athletes.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: Pixabay\/CC0 Dominio p\u00fablico Las afecciones card\u00edacas pueden poner fin al juego o incluso poner en peligro la vida de los atletas competitivos y recreativos por igual, pero los m\u00e9dicos se est\u00e1n dando cuenta de que, en muchos casos, los problemas card\u00edacos se pueden manejar para ayudar a los pacientes a continuar con los deportes. &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/experto-explica-el-enfoque-cambiante-de-los-problemas-cardiacos-en-los-atletas\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abExperto explica el enfoque cambiante de los problemas card\u00edacos en los atletas\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7591","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7591"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7591\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}