{"id":7606,"date":"2022-08-30T02:27:15","date_gmt":"2022-08-30T07:27:15","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/los-ensayos-clinicos-de-covid-19-se-agotan-desproporcionadamente-en-los-paises-de-ingresos-altos\/"},"modified":"2022-08-30T02:27:15","modified_gmt":"2022-08-30T07:27:15","slug":"los-ensayos-clinicos-de-covid-19-se-agotan-desproporcionadamente-en-los-paises-de-ingresos-altos","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/los-ensayos-clinicos-de-covid-19-se-agotan-desproporcionadamente-en-los-paises-de-ingresos-altos\/","title":{"rendered":"Los ensayos cl\u00ednicos de COVID-19 se agotan desproporcionadamente en los pa\u00edses de ingresos altos"},"content":{"rendered":"<p>Proporci\u00f3n de reclutamiento de participantes para casos de COVID-19 por pa\u00eds y estado de ingresos en relaci\u00f3n con el total de casos de COVID-19. Gr\u00e1fico de burbujas que muestra la relaci\u00f3n entre el reclutamiento de participantes y los casos de COVID-19 estratificados por estado de ingresos y carga de COVID-19. Cada burbuja representa un pa\u00eds, con pa\u00edses codificados por colores seg\u00fan el nivel de ingresos. El tama\u00f1o de cada burbuja es proporcional a la relaci\u00f3n entre el reclutamiento de participantes y los casos de COVID-19 en ese pa\u00eds. Por lo tanto, una burbuja m\u00e1s grande significa que ese pa\u00eds ha reclutado una mayor cantidad de participantes en los ensayos en relaci\u00f3n con la cantidad total de casos de COVID-19 en ese pa\u00eds. En general, hab\u00eda 80 pa\u00edses de ingresos altos, 56 pa\u00edses de ingresos medianos altos, 55 pa\u00edses de ingresos medianos bajos y 27 pa\u00edses de ingresos bajos, de los cuales 23 eran de ingresos altos, 8 de ingresos medianos altos, 3 de ingresos medianos bajos. ingresos, y 0 pa\u00edses de bajos ingresos reclutaron pacientes. Los pa\u00edses restantes sin participantes reclutados en los ensayos de COVID-19 se representan como peque\u00f1os c\u00edrculos negros. Cr\u00e9dito: DOI: 10.1001\/jamanetworkopen.2022.0444 <\/p>\n<p>Una nueva investigaci\u00f3n ha demostrado que los ensayos cl\u00ednicos de COVID-19 se est\u00e1n agotando de manera desproporcionada en los pa\u00edses de ingresos altos. <\/p>\n<p>Publicado en Jama Network Open y dirigido por investigadores del Instituto Doherty y el Instituto George, el estudio encontr\u00f3 que la mayor\u00eda de los ensayos cl\u00ednicos aleatorios para COVID-19 se realizan en pa\u00edses de ingresos altos, lo que claramente tergiversa la carga global de la enfermedad.<\/p>\n<p>El profesor Steven Tong, m\u00e9dico cl\u00ednico de enfermedades infecciosas del Royal Melbourne Hospital, codirector de investigaci\u00f3n cl\u00ednica en el Instituto Doherty, investigador principal del ensayo AustralaSian COVID-19 (ASCOT) y autor principal del art\u00edculo , dijo que la desigualdad podr\u00eda poner en duda la validez y la generalizaci\u00f3n de los resultados de estos ensayos.<\/p>\n<p>\u00abUn tratamiento que funciona en una unidad de cuidados intensivos en los Estados Unidos no necesariamente va a funcionar en pa\u00edses de ingresos bajos y medios como India, donde existen diferencias sustanciales en la capacidad de atenci\u00f3n m\u00e9dica y otros factores de poblaci\u00f3n\u00bb, dijo el profesor Tong.<\/p>\n<p>\u00abEsto pone en duda cu\u00e1nto se pueden aplicar estos resultados a los pa\u00edses de ingresos bajos y medios. es.\u00bb<\/p>\n<p>De los 295\u00a0845 participantes que se inscribieron en un ensayo cl\u00ednico aleatorizado, el 84 % proced\u00edan de pa\u00edses de ingresos altos.<\/p>\n<p>Adem\u00e1s, del 16 % que no de pa\u00edses de ingresos altos, ninguno era de pa\u00edses de ingresos bajos, con estos participantes de pa\u00edses de ingresos medios bajos o medios altos.<\/p>\n<p>Esto contrasta marcadamente con el lugar donde cay\u00f3 la carga de la enfermedad por COVID-19, con El 58 % de los casos notificados proced\u00edan de pa\u00edses de ingresos bajos y medios hasta mediados de 2021.<\/p>\n<p>El profesor Bala Venkatesh del Instituto George y del comit\u00e9 directivo internacional de ensayos de ASCOT, dijo que, a pesar de la enorme carga de morbilidad por COVID-19 y las limitaciones de recursos, India ha hecho una contribuci\u00f3n importante a la investigaci\u00f3n de COVID-19.<\/p>\n<p>\u00abCOVID-19 ha amplificado las desigualdades en la salud mundial y esto se extiende claramente a qui\u00e9n lidera y qui\u00e9n participa en ensayos cl\u00ednicos aleatorios\u00bb. dijo el profesor Tong.<\/p>\n<p>\u00abAhora debemos considerar priorizar la investigaci\u00f3n que es relevante\u00bb. a los pa\u00edses de ingresos bajos y medianos, y construir una infraestructura de investigaci\u00f3n para respaldar la realizaci\u00f3n de dichos ensayos\u00bb. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> El estudio encuentra un acceso desigual a las vacunas contra el COVID-19 entre los pa\u00edses que organizaron los ensayos <strong>M\u00e1s informaci\u00f3n:<\/strong> Mahesh Ramanan et al, Representaci\u00f3n geogr\u00e1fica de pa\u00edses de ingresos bajos y medios en Ensayos Cl\u00ednicos para COVID-19, JAMA Network Open (2022). DOI: 10.1001\/jamanetworkopen.2022.0444 <strong>Informaci\u00f3n de la revista:<\/strong> JAMA Network Open <\/p>\n<p> Proporcionado por George Institute for Global Health <strong>Cita<\/strong>: Los ensayos cl\u00ednicos de COVID-19 se quedan sin pa\u00edses de ingresos (2022, 28 de febrero) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02-covid-clinical-trials-disproportionately-high-income.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proporci\u00f3n de reclutamiento de participantes para casos de COVID-19 por pa\u00eds y estado de ingresos en relaci\u00f3n con el total de casos de COVID-19. Gr\u00e1fico de burbujas que muestra la relaci\u00f3n entre el reclutamiento de participantes y los casos de COVID-19 estratificados por estado de ingresos y carga de COVID-19. Cada burbuja representa un pa\u00eds, &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/los-ensayos-clinicos-de-covid-19-se-agotan-desproporcionadamente-en-los-paises-de-ingresos-altos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLos ensayos cl\u00ednicos de COVID-19 se agotan desproporcionadamente en los pa\u00edses de ingresos altos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7606","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7606"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7606\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}