{"id":7607,"date":"2022-08-30T02:27:17","date_gmt":"2022-08-30T07:27:17","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/el-nuevo-sistema-de-dialisis-de-bajo-costo-puede-producir-agua-de-grado-medico-en-el-hogar-el-siguiente-paso-para-los-ensayos-clinicos\/"},"modified":"2022-08-30T02:27:17","modified_gmt":"2022-08-30T07:27:17","slug":"el-nuevo-sistema-de-dialisis-de-bajo-costo-puede-producir-agua-de-grado-medico-en-el-hogar-el-siguiente-paso-para-los-ensayos-clinicos","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/el-nuevo-sistema-de-dialisis-de-bajo-costo-puede-producir-agua-de-grado-medico-en-el-hogar-el-siguiente-paso-para-los-ensayos-clinicos\/","title":{"rendered":"El nuevo sistema de di\u00e1lisis de bajo costo puede producir agua de grado m\u00e9dico en el hogar, el siguiente paso para los ensayos cl\u00ednicos"},"content":{"rendered":"<p>Cr\u00e9dito: DOI: 10.1016\/j.ekir.2022.01.747 <\/p>\n<p>Los hallazgos de las pruebas preliminares de un nuevo sistema de di\u00e1lisis han confirmado su capacidad para producir agua est\u00e9ril de grado m\u00e9dico para proporcionar una opci\u00f3n de tratamiento asequible y accesible en el hogar para pacientes con insuficiencia renal. <\/p>\n<p>Esto significa que el sistema de di\u00e1lisis en el punto de atenci\u00f3n de Ellen Medical Devices puede crear l\u00edquido de di\u00e1lisis peritoneal (una mezcla de agua esterilizada, electrolitos y glucosa) de manera asequible donde m\u00e1s se necesita el tratamiento.<\/p>\n<p>Presentaci\u00f3n en el Congreso Mundial de Nefrolog\u00eda durante la \u00faltima sesi\u00f3n de ensayos cl\u00ednicos, el Dr. Ben Talbot, asesor cl\u00ednico de Ellen Medical Devices, dijo: \u00abLa fabricaci\u00f3n y el transporte del l\u00edquido de di\u00e1lisis peritoneal pueden ser costosos desde el punto de vista financiero y ambiental. Crear el l\u00edquido de tratamiento en el punto- of-care ofrece una nueva soluci\u00f3n de bajo costo para llegar a m\u00e1s personas que necesitan un tratamiento cr\u00edtico para la insuficiencia renal en todo el mundo, particularmente en los entornos m\u00e1s remotos y con menos recursos\u00bb.<\/p>\n<p>Millones de personas en todo el mundo mueren innecesariamente cada a\u00f1o porque no pueden acceder al tratamiento para la insuficiencia renal, y la mayor\u00eda de estas muertes prevenibles ocurren en China, India, Indonesia, Pakist\u00e1n y Nigeria. En 2010, 2,6 millones de personas estaban recibiendo terapia de reemplazo renal por insuficiencia renal terminal, pero hasta siete millones podr\u00edan estar perdiendo el tratamiento que les salvar\u00eda la vida. Estos n\u00fameros est\u00e1n creciendo un 7 % anualmente y se prev\u00e9 que aumenten dr\u00e1sticamente a 5,4 millones para 2030, con la mayor parte del aumento en los pa\u00edses en desarrollo.<\/p>\n<p>El equipo de investigaci\u00f3n prob\u00f3 el componente del destilador de agua pura del sistema de di\u00e1lisis utilizando agua del grifo en un laboratorio en Sydney, Australia. El agua destilada producida por un peque\u00f1o destilador de agua pura port\u00e1til patentado se recolect\u00f3 y analiz\u00f3 para determinar los niveles de conductividad y carbono org\u00e1nico total para evaluar la pureza del agua. Despu\u00e9s de un per\u00edodo de funcionamiento inicial, el destilador produjo agua que cumpli\u00f3 con los est\u00e1ndares adecuados para su uso en l\u00edquido de di\u00e1lisis.<\/p>\n<p>El sistema Point-of-Care de Ellen Medical Devices ha sido dise\u00f1ado para esterilizar agua de cualquier fuente para producir fluido de di\u00e1lisis peritoneal para ayudar a abordar la enorme necesidad no satisfecha de di\u00e1lisis a nivel mundial.<\/p>\n<p>El profesor John Knight, director gerente de Ellen Medical Devices, dijo: \u00abConstruiremos estos alentadores resultados iniciales mediante la realizaci\u00f3n de varios estudios cl\u00ednicos en los pr\u00f3ximos a\u00f1o y el primero comenzar\u00e1 en los pr\u00f3ximos meses. Ser\u00e1 muy emocionante ver a los pacientes renales usar nuestro sistema para crear l\u00edquido de di\u00e1lisis peritoneal en sus propios hogares\u00bb. <\/p>\n<p>Los hallazgos se publican en Kidney International Report. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> El uso de di\u00e1lisis peritoneal ha aumentado en los Estados Unidos despu\u00e9s de la reforma de pago de Medicare <strong>M\u00e1s informaci\u00f3n:<\/strong> B. Talbot et al, POS-713 prueba de concepto para un punto de atenci\u00f3n asequible sistema de di\u00e1lisis, Kidney International Reports (2022). DOI: 10.1016\/j.ekir.2022.01.747 Proporcionado por George Institute for Global Health <strong>Cita<\/strong>: Nuevo sistema de di\u00e1lisis de bajo costo puede producir agua de grado m\u00e9dico en el hogar, siguiente paso para ensayos cl\u00ednicos (2022, 28 de febrero) recuperado el 29 de agosto de 2022 de https:\/\/medicalxpress.com\/news\/2022-02-low-cost-dialysis-medical-grade-home.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cr\u00e9dito: DOI: 10.1016\/j.ekir.2022.01.747 Los hallazgos de las pruebas preliminares de un nuevo sistema de di\u00e1lisis han confirmado su capacidad para producir agua est\u00e9ril de grado m\u00e9dico para proporcionar una opci\u00f3n de tratamiento asequible y accesible en el hogar para pacientes con insuficiencia renal. Esto significa que el sistema de di\u00e1lisis en el punto de atenci\u00f3n &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/el-nuevo-sistema-de-dialisis-de-bajo-costo-puede-producir-agua-de-grado-medico-en-el-hogar-el-siguiente-paso-para-los-ensayos-clinicos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEl nuevo sistema de di\u00e1lisis de bajo costo puede producir agua de grado m\u00e9dico en el hogar, el siguiente paso para los ensayos cl\u00ednicos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7607","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7607"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7607\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}