{"id":7610,"date":"2022-08-30T02:27:22","date_gmt":"2022-08-30T07:27:22","guid":{"rendered":"https:\/\/www.biblia.work\/articulos-salud\/los-cosmeticos-a-base-de-plomo-envenenaron-a-la-alta-sociedad-europea-del-siglo-xviii-en-busca-de-una-piel-mas-blanca\/"},"modified":"2022-08-30T02:27:22","modified_gmt":"2022-08-30T07:27:22","slug":"los-cosmeticos-a-base-de-plomo-envenenaron-a-la-alta-sociedad-europea-del-siglo-xviii-en-busca-de-una-piel-mas-blanca","status":"publish","type":"post","link":"https:\/\/www.biblia.work\/articulos-salud\/los-cosmeticos-a-base-de-plomo-envenenaron-a-la-alta-sociedad-europea-del-siglo-xviii-en-busca-de-una-piel-mas-blanca\/","title":{"rendered":"Los cosm\u00e9ticos a base de plomo envenenaron a la alta sociedad europea del siglo XVIII en busca de una piel m\u00e1s blanca"},"content":{"rendered":"<p>Un actor que usa una versi\u00f3n contempor\u00e1nea del maquillaje a base de plomo del siglo XVIII. Cr\u00e9dito: Shutterstock <\/p>\n<p>Las personas de la alta sociedad del siglo XVIII han sido representadas como mujeres vanidosas y tontas que fueron envenenadas por su maquillaje de plomo blanco. Se dice que la condesa de Coventry, anfitriona de la sociedad Maria Gunninga, conocida por su belleza, se neg\u00f3 a dejar de usar una base que conten\u00eda plomo blanco, incluso mientras agonizaba. \u00bfPor qu\u00e9 las mujeres de esa \u00e9poca elegir\u00edan a sabiendas usar un maquillaje que las estaba matando? \u00bfVal\u00eda la pena morir por la belleza? \u00bfO el maquillaje no tuvo la culpa? <\/p>\n<p>Soy un cient\u00edfico que ha estado estudiando el envenenamiento por plomo durante 30 a\u00f1os, con un inter\u00e9s particular en la exposici\u00f3n de las mujeres al plomo. Mi investigaci\u00f3n muestra que las mujeres metabolizan el plomo de manera diferente que los hombres, las mujeres expuestas al plomo cuando eran ni\u00f1as tienen niveles elevados de plomo en la sangre 20 a\u00f1os despu\u00e9s, y las mujeres expuestas al plomo corren el riesgo de sufrir hipertensi\u00f3n y menopausia prematura. <\/p>\n<p>Las historias sobre el envenenamiento con maquillaje de plomo blanco no ten\u00edan sentido para m\u00ed, as\u00ed que hace dos a\u00f1os decid\u00ed comenzar a estudiar estos cosm\u00e9ticos.<\/p>\n<p>T\u00e9cnicas hist\u00f3ricas<\/p>\n<p> Mi grupo de investigaci\u00f3n elabora maquillaje de plomo blanco a partir de recetas que datan de los siglos XVI al XIX. Si observa los mostradores de maquillaje de una tienda por departamentos, ver\u00e1 palabras como \u00abiluminar\u00bb, \u00abresplandor\u00bb, \u00abresplandor\u00bb y \u00abluminoso\u00bb. Tambi\u00e9n ver\u00e1s productos que prometen reducir el brillo o difuminar las imperfecciones. Estos productos modernos cambian la forma en que la luz se refleja en la piel, lo que se percibe como un realce de la belleza. <\/p>\n<p>Quer\u00edamos saber si el maquillaje de plomo blanco ten\u00eda alguna de estas propiedades, por lo que estudiamos el color y el nivel de luz reflejado por el maquillaje utilizando un espectr\u00f3metro \u00f3ptico.<\/p>\n<p>Nuestro hallazgo m\u00e1s sorprendente ha sido que el maquillaje de plomo blanco puede verse bastante bonito y natural. No se parece a la m\u00e1scara blanca brillante que hemos visto representada en pantallas y escenarios; generalmente es mucho m\u00e1s sutil y sofisticada. <\/p>\n<p> Dying to be Beautiful: explorando el aspecto y la toxicidad del maquillaje del siglo XVIII. <\/p>\n<p>Probamos el maquillaje en piel de cerdo de origen \u00e9tico. Los cerdos que utilizamos tienen una tez p\u00e1lida muy parecida al color m\u00e1s claro de la piel humana, que se quema con facilidad y no se broncea bien. El maquillaje de albayalde no suele cambiar mucho el color de esta piel.<\/p>\n<p>El \u00f3xido de titanio es el sustituto moderno del albayalde. Cuando usamos \u00f3xido de titanio en las recetas de maquillaje, el cambio de color fue espectacular. Hubo un cambio hacia el azul y el maquillaje apareci\u00f3 sorprendentemente blanco. Los actores que usan formulaciones de maquillaje hechas con recetas antiguas de albayalde con un sustituto de titanio est\u00e1n usando el color incorrecto.<\/p>\n<p>Cambios de color<\/p>\n<p>Probamos diferentes recetas hist\u00f3ricas de maquillaje para ver c\u00f3mo se ver\u00eda afectado el color. . Una receta no hizo ning\u00fan cambio medible en el color, mientras que otra cambi\u00f3 ligeramente los tonos amarillos. Agregar un tono amarillo a la piel p\u00e1lida se percibe como m\u00e1s atractivo, debido a su conexi\u00f3n con el consumo de frutas y verduras. Una tercera mezcla de maquillaje redujo el enrojecimiento de la piel, algo que la base de maquillaje correctora de color actual intenta corregir.<\/p>\n<p>Todos los maquillajes de plomo blanco que probamos aumentaron la cantidad de luz que reflejaba la piel, lo que se conoce como su reflectancia. La piel se vuelve menos reflectante a medida que las mujeres envejecen, y una piel m\u00e1s reflectante se asocia con una tez m\u00e1s joven. <\/p>\n<p>En concreto, los maquillajes aumentaron la reflectancia difusa de la piel. La reflexi\u00f3n de la luz se produce de dos maneras. Primero, la luz puede reflejarse, como en un espejo. Viene en un \u00e1ngulo y se refleja en ese mismo \u00e1ngulo. A esto lo llamamos reflexi\u00f3n especular. Los objetos con un alto reflejo especular se ven lustrosos o brillantes. <\/p>\n<p>En segundo lugar, la luz puede reflejarse o dispersarse en superficies rugosas en varias direcciones. Esta es la reflexi\u00f3n difusa. Los objetos con un alto reflejo difuso se ven borrosos o ligeramente desenfocados. El aumento de la reflectancia difusa del maquillaje de plomo blanco le da a la piel una apariencia \u00abm\u00e1s suave\u00bb, difuminando las imperfecciones, otro efecto producido por los cosm\u00e9ticos modernos.<\/p>\n<p>Las recetas que recreamos en nuestro laboratorio crean una apariencia de enfoque suave que difumina arrugas y manchas, o el aspecto de una tez juvenil y h\u00fameda.<\/p>\n<p> Una comparaci\u00f3n de la piel desnuda con el maquillaje hecho con albayalde y con di\u00f3xido de titanio en sustituci\u00f3n del carbonato de plomo. Las recetas modernas que usan un reemplazo de titanio se ven m\u00e1s blancas y m\u00e1s opacas que el blanco amarillento m\u00e1s suave del maquillaje con plomo. Cr\u00e9dito: FE McNeill, proporcionado por el autor <\/p>\n<p>El feo precio de la belleza<\/p>\n<p>Sin embargo, la belleza viene con un lado feo: la celebraci\u00f3n de la piel blanca. Si bien los cambios de color medidos en general en la piel p\u00e1lida son peque\u00f1os, los cambios espectrales hacen que la piel se vea m\u00e1s clara. Estos eran productos que habr\u00edan mejorado la blancura de la piel. <\/p>\n<p>Los historiadores, antrop\u00f3logos y soci\u00f3logos han estudiado durante mucho tiempo el blanqueamiento de la piel y las razones por las que las personas pueden optar por hacerlo. Nuestra ciencia muestra c\u00f3mo el maquillaje de plomo blanco podr\u00eda lograr esto de una manera sutil, como una versi\u00f3n anterior del maquillaje \u00absin maquillaje\u00bb.<\/p>\n<p>Tambi\u00e9n hemos estado probando si algunas formulaciones de maquillaje permiten que el plomo se absorba a trav\u00e9s del piel. El plomo blanco no se puede absorber f\u00e1cilmente a trav\u00e9s de la piel, solo es t\u00f3xico si se ingiere o se inhala. Sin embargo, si las formulaciones de maquillaje cambiaron la forma del plomo o suavizaron la capa externa de la piel, parte del plomo podr\u00eda difundirse. Esto har\u00eda que esas formulaciones de maquillaje fueran m\u00e1s venenosas. <\/p>\n<p>Nuestra investigaci\u00f3n muestra algunas pruebas de diferencias en la absorci\u00f3n de la piel, lo que significa que algunas recetas fueron m\u00e1s t\u00f3xicas que otras. Es posible que algunas recetas se hayan podido utilizar sin problema. Otras recetas, que enfermaban de muerte a las mujeres j\u00f3venes, probablemente eran tan venenosas porque el plomo se absorb\u00eda a trav\u00e9s de la piel. <\/p>\n<p>Hasta ahora, nuestra investigaci\u00f3n sugiere que la mayor\u00eda de las recetas de maquillaje con plomo blanco probablemente no mataron a las personas de la alta sociedad del siglo XVIII al ser absorbidas a trav\u00e9s de la piel. Pero algunas recetas eran m\u00e1s t\u00f3xicas que otras.<\/p>\n<p>La mezcla m\u00e1s t\u00f3xica que hemos observado hasta ahora es la f\u00f3rmula muy simple que se dice que us\u00f3 la reina Isabel I de Inglaterra: una mezcla de albayalde y vinagre. Esta mezcla pas\u00f3 plomo a trav\u00e9s de la piel en cantidades mucho mayores que otras recetas. Esto plantea la pregunta de si vale la pena revisar si algunos de los problemas de salud de Isabel I se debieron al envenenamiento por plomo o se vieron exacerbados por \u00e9l. <\/p>\n<p>Explore m\u00e1s<\/p>\n<p> La tendencia #Nomakeup no logra desalentar el uso de cosm\u00e9ticos Proporcionado por The Conversation <\/p>\n<p> Este art\u00edculo se vuelve a publicar de The Conversation bajo una licencia Creative Commons. Lea el art\u00edculo original. <\/p>\n<p> <strong>Cita<\/strong>: Los cosm\u00e9ticos a base de plomo envenenaron a la alta sociedad europea del siglo XVIII en busca de una piel m\u00e1s blanca (2022, 28 de febrero) consultado el 29 de agosto de 2022 en https:\/\/medicalxpress.com\/news\/2022 -02-cosm\u00e9ticos-a-base-de-plomo-envenenado-siglo-xviii-europeo.html Este documento est\u00e1 sujeto a derechos de autor. Aparte de cualquier trato justo con fines de estudio o investigaci\u00f3n privados, ninguna parte puede reproducirse sin el permiso por escrito. El contenido se proporciona \u00fanicamente con fines informativos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un actor que usa una versi\u00f3n contempor\u00e1nea del maquillaje a base de plomo del siglo XVIII. Cr\u00e9dito: Shutterstock Las personas de la alta sociedad del siglo XVIII han sido representadas como mujeres vanidosas y tontas que fueron envenenadas por su maquillaje de plomo blanco. Se dice que la condesa de Coventry, anfitriona de la sociedad &hellip; <a href=\"https:\/\/www.biblia.work\/articulos-salud\/los-cosmeticos-a-base-de-plomo-envenenaron-a-la-alta-sociedad-europea-del-siglo-xviii-en-busca-de-una-piel-mas-blanca\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abLos cosm\u00e9ticos a base de plomo envenenaron a la alta sociedad europea del siglo XVIII en busca de una piel m\u00e1s blanca\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7610","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/comments?post=7610"}],"version-history":[{"count":0,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/posts\/7610\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/media?parent=7610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/categories?post=7610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.biblia.work\/articulos-salud\/wp-json\/wp\/v2\/tags?post=7610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}